﻿{"id":17782,"date":"2010-12-03T15:43:06","date_gmt":"2010-12-03T14:43:06","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=17782"},"modified":"2010-12-03T15:48:58","modified_gmt":"2010-12-03T14:48:58","slug":"ucraina-sono-oltre-100-mila-i-bambini-senza-genitori","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/ucraina-sono-oltre-100-mila-i-bambini-senza-genitori\/","title":{"rendered":"Ucraina: sono oltre 100 mila i bambini senza genitori"},"content":{"rendered":"<p><a href=\"https:\/\/www.aibi.it\/ita\/images\/Ai.Bi.-bambini-in-un-internat-di-Kiev.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-10034\" style=\"margin: 5px;\" title=\"Ai.Bi. - bambini in un internat di Kiev\" src=\"https:\/\/www.aibi.it\/ita\/images\/Ai.Bi.-bambini-in-un-internat-di-Kiev.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>E\u2019 stata una settimana ricca di appuntamenti in Ucraina, in occasione dell\u2019anniversario della ratifica della Convenzione di New York sui Diritti dell\u2019Infanzia.<br \/>\nLuned\u00ec 29 novembre si \u00e8 svolta un\u2019importante conferenza, alla quale hanno partecipato anche i rappresentanti di Ai.Bi., dove erano presenti: <strong>Ravil Safiullin, il ministro del Ministero della Famiglia, Giovent\u00f9 e dello Sport<\/strong>, con Svetlana Tolstoukhova, la Vice-ministro del Ministero della Famiglia, Giovent\u00f9 e dello Sport, Yuke Mokuo, il Rappresentante dell\u2019UNICEF in Ucraina e Natalia Ivanova, il Rappresentante del Parlamento dell\u2019Ucraina per i diritti umani.<\/p>\n<p>Nel corso della conferenza si \u00e8 parlato della <strong>situazione attuale in Ucraina nel settore della tutela dei diritti dei bambini e soprattutto delle problematiche che devono essere ancora risolte<\/strong>.<br \/>\nLe Organizzazioni Non Governative che erano presenti all\u2019incontro hanno avanzato domande provocatorie al Ministro Safiullin, invitandolo non solo ad occuparsi concretamente dei bisogni dei bambini, ma soprattutto ad <strong>intervenire per cambiare l\u2019approccio di lavoro dei servizi sociali<\/strong> <strong>che si occupano di minori<\/strong>.<br \/>\nAttualmente in Ucraina<strong>, oltre 100 mila bambini sono senza la tutela dei genitori.<br \/>\n<\/strong>Durante i primi dieci mesi di quest\u2019anno pi\u00f9 di 2.500 orfani ucraini hanno trovato nuove famiglie, <strong>1.780 bambini sono stati adottati dalle famiglie ucraine e 840 da famiglie straniere<\/strong>.<\/p>\n<p>Il governo auspica che questa proporzione si conservi anche nel 2011 e per far questo aumenter\u00e0 i finanziamenti per la tutela dell\u2019infanzia. <strong>Gi\u00e0 nel prossimo bilancio sono previsti 70 milioni di hryvne per la protezione dei diritti dei minori.<br \/>\n<\/strong>La settimana e\u2019 continuata con varie tavole rotonde alle quali hanno partecipato diverse ONG locali di volontariato, si sono svolti anche seminari per le Fondazioni di Beneficienza durante i quali \u00e8 stato possibile raccontare le attivit\u00e0 svolte nel Paese e condividere le esperienze.<strong><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>E\u2019 stata una settimana ricca di appuntamenti in Ucraina, in occasione dell\u2019anniversario della ratifica della Convenzione di New York sui Diritti dell\u2019Infanzia. Attualmente in Ucraina<strong>, oltre 100 mila bambini sono senza la tutela dei genitori. <\/strong>Durante i primi dieci mesi di quest\u2019anno pi\u00f9 di 2.500 orfani ucraini hanno trovato nuove famiglie, <strong>1.780 bambini sono stati adottati dalle famiglie ucraine e 840 da famiglie straniere<\/strong>. <strong><a href=\"https:\/\/www.aibi.it\/ita\/ucraina-sono-oltre-100-mila-i-bambini-senza-genitori\/\">LEGGI TUTTO&#8230;<br \/>\n<\/a><\/strong><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-17782","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ucraina: sono oltre 100 mila i bambini senza genitori - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/ucraina-sono-oltre-100-mila-i-bambini-senza-genitori\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ucraina: sono oltre 100 mila i bambini senza genitori\" \/>\n<meta property=\"og:description\" content=\"E\u2019 stata una settimana ricca di appuntamenti in Ucraina, in occasione dell\u2019anniversario della ratifica della Convenzione di New York sui Diritti dell\u2019Infanzia. Attualmente in Ucraina, oltre 100 mila bambini sono senza la tutela dei genitori. Durante i primi dieci mesi di quest\u2019anno pi\u00f9 di 2.500 orfani ucraini hanno trovato nuove famiglie, 1.780 bambini sono stati adottati dalle famiglie ucraine e 840 da famiglie straniere. LEGGI TUTTO...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/ucraina-sono-oltre-100-mila-i-bambini-senza-genitori\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2010-12-03T14:43:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2010-12-03T14:48:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/Ai.Bi.-bambini-in-un-internat-di-Kiev.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ucraina-sono-oltre-100-mila-i-bambini-senza-genitori\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ucraina-sono-oltre-100-mila-i-bambini-senza-genitori\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Ucraina: sono oltre 100 mila i bambini senza genitori\",\"datePublished\":\"2010-12-03T14:43:06+00:00\",\"dateModified\":\"2010-12-03T14:48:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ucraina-sono-oltre-100-mila-i-bambini-senza-genitori\\\/\"},\"wordCount\":289,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ucraina-sono-oltre-100-mila-i-bambini-senza-genitori\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Ai.Bi.-bambini-in-un-internat-di-Kiev.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ucraina-sono-oltre-100-mila-i-bambini-senza-genitori\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ucraina-sono-oltre-100-mila-i-bambini-senza-genitori\\\/\",\"name\":\"Ucraina: sono oltre 100 mila i bambini senza genitori - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ucraina-sono-oltre-100-mila-i-bambini-senza-genitori\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ucraina-sono-oltre-100-mila-i-bambini-senza-genitori\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Ai.Bi.-bambini-in-un-internat-di-Kiev.jpg\",\"datePublished\":\"2010-12-03T14:43:06+00:00\",\"dateModified\":\"2010-12-03T14:48:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ucraina-sono-oltre-100-mila-i-bambini-senza-genitori\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ucraina-sono-oltre-100-mila-i-bambini-senza-genitori\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ucraina-sono-oltre-100-mila-i-bambini-senza-genitori\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Ai.Bi.-bambini-in-un-internat-di-Kiev.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Ai.Bi.-bambini-in-un-internat-di-Kiev.jpg\",\"width\":150,\"height\":150},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ucraina-sono-oltre-100-mila-i-bambini-senza-genitori\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ucraina: sono oltre 100 mila i bambini senza genitori\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ucraina: sono oltre 100 mila i bambini senza genitori - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/ucraina-sono-oltre-100-mila-i-bambini-senza-genitori\/","og_locale":"it_IT","og_type":"article","og_title":"Ucraina: sono oltre 100 mila i bambini senza genitori","og_description":"E\u2019 stata una settimana ricca di appuntamenti in Ucraina, in occasione dell\u2019anniversario della ratifica della Convenzione di New York sui Diritti dell\u2019Infanzia. Attualmente in Ucraina, oltre 100 mila bambini sono senza la tutela dei genitori. Durante i primi dieci mesi di quest\u2019anno pi\u00f9 di 2.500 orfani ucraini hanno trovato nuove famiglie, 1.780 bambini sono stati adottati dalle famiglie ucraine e 840 da famiglie straniere. LEGGI TUTTO...","og_url":"https:\/\/www.aibi.it\/ita\/ucraina-sono-oltre-100-mila-i-bambini-senza-genitori\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2010-12-03T14:43:06+00:00","article_modified_time":"2010-12-03T14:48:58+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/Ai.Bi.-bambini-in-un-internat-di-Kiev.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/ucraina-sono-oltre-100-mila-i-bambini-senza-genitori\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/ucraina-sono-oltre-100-mila-i-bambini-senza-genitori\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Ucraina: sono oltre 100 mila i bambini senza genitori","datePublished":"2010-12-03T14:43:06+00:00","dateModified":"2010-12-03T14:48:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/ucraina-sono-oltre-100-mila-i-bambini-senza-genitori\/"},"wordCount":289,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/ucraina-sono-oltre-100-mila-i-bambini-senza-genitori\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Ai.Bi.-bambini-in-un-internat-di-Kiev.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/ucraina-sono-oltre-100-mila-i-bambini-senza-genitori\/","url":"https:\/\/www.aibi.it\/ita\/ucraina-sono-oltre-100-mila-i-bambini-senza-genitori\/","name":"Ucraina: sono oltre 100 mila i bambini senza genitori - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/ucraina-sono-oltre-100-mila-i-bambini-senza-genitori\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/ucraina-sono-oltre-100-mila-i-bambini-senza-genitori\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Ai.Bi.-bambini-in-un-internat-di-Kiev.jpg","datePublished":"2010-12-03T14:43:06+00:00","dateModified":"2010-12-03T14:48:58+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/ucraina-sono-oltre-100-mila-i-bambini-senza-genitori\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/ucraina-sono-oltre-100-mila-i-bambini-senza-genitori\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/ucraina-sono-oltre-100-mila-i-bambini-senza-genitori\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/Ai.Bi.-bambini-in-un-internat-di-Kiev.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/Ai.Bi.-bambini-in-un-internat-di-Kiev.jpg","width":150,"height":150},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/ucraina-sono-oltre-100-mila-i-bambini-senza-genitori\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Ucraina: sono oltre 100 mila i bambini senza genitori"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 18:10:57","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/17782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=17782"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/17782\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=17782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=17782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=17782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}