﻿


{"id":178081,"date":"2020-07-31T17:36:06","date_gmt":"2020-07-31T15:36:06","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=178081"},"modified":"2022-07-25T18:01:21","modified_gmt":"2022-07-25T16:01:21","slug":"siria-i-bambini-nel-dramma-della-guerra-e-del-covid-hanno-bisogno-di-te-per-aiutarli-basta-un-caffe-al-giorno","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/siria-i-bambini-nel-dramma-della-guerra-e-del-covid-hanno-bisogno-di-te-per-aiutarli-basta-un-caffe-al-giorno\/","title":{"rendered":"Siria. I bambini nel dramma della guerra e del Covid hanno bisogno di te. Per aiutarli basta un &#8220;caff\u00e8&#8221; al giorno"},"content":{"rendered":"<h2><a href=\"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/sostegno-a-distanza-in-siria\/\">Con il Sostegno a Distanza<\/a> dal 2014 Ai.Bi. supporta i nuclei fragili con minori nel Nord-Ovest del Paese<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-178082\" src=\"https:\/\/www.aibi.it\/ita\/images\/2020\/07\/child-2612923_960_720-572x300.jpg\" alt=\"\" width=\"572\" height=\"300\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2020\/07\/child-2612923_960_720-572x300.jpg 572w, https:\/\/www.aibi.it\/ita\/images\/2020\/07\/child-2612923_960_720-150x79.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/2020\/07\/child-2612923_960_720-768x403.jpg 768w, https:\/\/www.aibi.it\/ita\/images\/2020\/07\/child-2612923_960_720.jpg 1200w\" sizes=\"auto, (max-width: 572px) 100vw, 572px\" \/><\/p>\n<p>La<strong> Siria<\/strong> \u00e8 un Paese martoriato da nove anni di guerra e, ora, purtroppo, anche dalle conseguenze del <strong>Coronavirus.<\/strong> Per gli sfollati interni del Nord-Ovest, l&#8217;area di Idlib, ancora alle prese con un interminabile conflitto, le condizioni di vita sono durissime. Da dicembre 2019 a marzo 2020 si sono susseguiti i bombardamenti sia a Idlib che nella zona a Ovest di Aleppo, costringendo circa 980mila persone a spostarsi. La maggior parte di loro ha trovato riparo solamente grazie all&#8217;aiuto delle organizzazioni umanitarie in tendopoli e campi informali. Complessivamente nel Nord-Ovest siriano ci sono 2,8 milioni di sfollati su 4 milioni di abitanti, di cui la gran parte vive in condizioni terribili. Soprattutto perch\u00e9 il clima, in questa zona, vede il susseguirsi di inverni rigidi ed estati caldissime.<\/p>\n<p>Dopo il cessate il fuoco del 6 marzo 2020 molte persone sono tornate alle loro abitazioni ma questo non ha purtroppo significato un miglioramento delle condizioni di vita. A questo dramma si \u00e8 aggiunto quello della pandemia, che ha provocato una crisi economica veramente devastante, perch\u00e9 da marzo sono stati decretati periodi di lockdown che hanno ridotto fortemente il movimento delle persone e la possibilit\u00e0 di queste di accedere a fonti di sostentamento dignitose.<\/p>\n<h3>Sostegno a Distanza in Siria: dal 2014 Ai.Bi. presente nell&#8217;area del Nord-Ovest<\/h3>\n<p>Dal 2014<strong> Ai.Bi. &#8211; Amici dei Bambini<\/strong> \u00e8 presente in quest&#8217;area, e oggi opera in piccoli campi composti da 150-200 famiglie. Molti nuclei famigliari sono guidati da donne sole, a volte vedove, che faticano a trovare mezzi di sussistenza.<\/p>\n<p><a href=\"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/sostegno-a-distanza-in-siria\/\">Grazie al Sostegno a Distanza<\/a>, Ai.Bi. \u00e8 riuscita in questi anni a supportare questi nuclei fragili con minori per evitare strategie di sopravvivenza negative come il lavoro minorile o il matrimonio precoce, offrendo progetti per favorire il sostentamento famigliare (nel 2019 \u00e8 stato distribuito mezzo milione di pezzi di pane alle famiglie, prodotto acquistando il grando da mulini e panetterie del territorio). Dall&#8217;inizio dell&#8217;emergenza Coronavirus, Ai.Bi. ha provveduto anche a distribuire kit igienico-sanitari a oltre 330 nuclei familiari composti in media da sei componenti (di cui almeno il 50% minori) per un totale di 1980 persone, appartenenti a popolazione profuga in situazione di incertezza abitativa, carenza alimentare e sanitaria, ospiti in campi profughi nei distretti di <strong>Ma\u2019arat Misrin<\/strong> e <strong>Harim<\/strong>.<\/p>\n<p>Queste attivit\u00e0 sono possibili grazie al supporto degli amici italiani di Ai.Bi. Anche tu puoi fare la tua parte, <a href=\"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/sostegno-a-distanza-in-siria\/\">attivando un Sostegno a Distanza in Siria<\/a> al costo di <strong>25 euro al mese, meno di un caff\u00e8 al giorno<\/strong>. <strong>Non lasciarli soli.\u00a0<\/strong><\/p>\n\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*168342-start*\/\n#btnsx-168342{margin-top:0px;margin-bottom:20px;margin-left:0px;margin-right:0px;padding-top:20px;padding-bottom:20px;padding-left:40px;padding-right:40px;}\n#btnsx-168342 .btnsx-text-primary{font-size:30px;line-height:30px;font-family:Montserrat;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-168342:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-168342{background-color:#ef7b0b!important;}\n#btnsx-168342:hover{background-color:#eab20b!important;}\n#btnsx-168342{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-168342:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*168342-end*\/\n<\/style><div id=\"btnsx-168342-wrap\" class=\"btnsx-wrap-center\" align=\"center\"><div id=\"btnsx-168342-container\" class=\"btnsx-btn-container\">\n<a href=\"https:\/\/www.aibi.it\/ita\/adotta-a-distanza-25\/\" id=\"btnsx-168342\" target=\"_blank\" class=\"btnsx-btn btnsx-btn-embossed\"  data-font-primary=\"Montserrat\">\n\t<span class=\"btnsx-text-primary \">Scopri di pi\u00f9<\/span><\/a>\n<\/div><\/div>\n<!-- Buttons X - End -->\n\n","protected":false},"excerpt":{"rendered":"<p>Con il Sostegno a Distanza dal 2014 Ai.Bi. supporta i nuclei fragili con minori nel Nord-Ovest del Paese La Siria &egrave; un Paese martoriato da nove anni di guerra e, ora, purtroppo, anche dalle conseguenze del Coronavirus. Per gli sfollati interni del Nord-Ovest, l&rsquo;area di Idlib, ancora alle prese con [&hellip;]<\/p>\n","protected":false},"author":91,"featured_media":178082,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[209],"tags":[404,300],"class_list":["post-178081","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-a-distanza","tag-siria","tag-sostegno-a-distanza"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Siria. Il Sostegno a Distanza di Ai.Bi. per i bimbi sfollati<\/title>\n<meta name=\"description\" content=\"Siria. Il Sostegno a Distanza di Ai.Bi. per i bimbi sfollati del Nord Ovest. Siria e Sostegno a Distanza con Amici dei Bambini\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/siria-i-bambini-nel-dramma-della-guerra-e-del-covid-hanno-bisogno-di-te-per-aiutarli-basta-un-caffe-al-giorno\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Siria. I bambini nel dramma della guerra e del Covid hanno bisogno di te. Per aiutarli basta un &quot;caff\u00e8&quot; al giorno\" \/>\n<meta property=\"og:description\" content=\"Con il Sostegno a Distanza dal 2014 Ai.Bi. supporta i nuclei fragili con minori nel Nord-Ovest del Paese\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/siria-i-bambini-nel-dramma-della-guerra-e-del-covid-hanno-bisogno-di-te-per-aiutarli-basta-un-caffe-al-giorno\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-31T15:36:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-25T16:01:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/07\/child-2612923_960_720.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"629\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cristianoP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Siria. I bambini nel dramma della guerra e del Covid hanno bisogno di te. Per aiutarli basta un &quot;caff\u00e8&quot; al giorno\" \/>\n<meta name=\"twitter:description\" content=\"Con il Sostegno a Distanza dal 2014 Ai.Bi. supporta i nuclei fragili con minori nel Nord-Ovest del Paese\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/07\/child-2612923_960_720.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"cristianoP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-i-bambini-nel-dramma-della-guerra-e-del-covid-hanno-bisogno-di-te-per-aiutarli-basta-un-caffe-al-giorno\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-i-bambini-nel-dramma-della-guerra-e-del-covid-hanno-bisogno-di-te-per-aiutarli-basta-un-caffe-al-giorno\\\/\"},\"author\":{\"name\":\"cristianoP\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/b9065848ca5b5cf9a80fad6f849d2c17\"},\"headline\":\"Siria. I bambini nel dramma della guerra e del Covid hanno bisogno di te. Per aiutarli basta un &#8220;caff\u00e8&#8221; al giorno\",\"datePublished\":\"2020-07-31T15:36:06+00:00\",\"dateModified\":\"2022-07-25T16:01:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-i-bambini-nel-dramma-della-guerra-e-del-covid-hanno-bisogno-di-te-per-aiutarli-basta-un-caffe-al-giorno\\\/\"},\"wordCount\":463,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-i-bambini-nel-dramma-della-guerra-e-del-covid-hanno-bisogno-di-te-per-aiutarli-basta-un-caffe-al-giorno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/07\\\/child-2612923_960_720.jpg\",\"keywords\":[\"Siria\",\"sostegno a distanza\"],\"articleSection\":[\"Adozione a Distanza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-i-bambini-nel-dramma-della-guerra-e-del-covid-hanno-bisogno-di-te-per-aiutarli-basta-un-caffe-al-giorno\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-i-bambini-nel-dramma-della-guerra-e-del-covid-hanno-bisogno-di-te-per-aiutarli-basta-un-caffe-al-giorno\\\/\",\"name\":\"Siria. Il Sostegno a Distanza di Ai.Bi. per i bimbi sfollati\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-i-bambini-nel-dramma-della-guerra-e-del-covid-hanno-bisogno-di-te-per-aiutarli-basta-un-caffe-al-giorno\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-i-bambini-nel-dramma-della-guerra-e-del-covid-hanno-bisogno-di-te-per-aiutarli-basta-un-caffe-al-giorno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/07\\\/child-2612923_960_720.jpg\",\"datePublished\":\"2020-07-31T15:36:06+00:00\",\"dateModified\":\"2022-07-25T16:01:21+00:00\",\"description\":\"Siria. Il Sostegno a Distanza di Ai.Bi. per i bimbi sfollati del Nord Ovest. Siria e Sostegno a Distanza con Amici dei Bambini\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-i-bambini-nel-dramma-della-guerra-e-del-covid-hanno-bisogno-di-te-per-aiutarli-basta-un-caffe-al-giorno\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-i-bambini-nel-dramma-della-guerra-e-del-covid-hanno-bisogno-di-te-per-aiutarli-basta-un-caffe-al-giorno\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-i-bambini-nel-dramma-della-guerra-e-del-covid-hanno-bisogno-di-te-per-aiutarli-basta-un-caffe-al-giorno\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/07\\\/child-2612923_960_720.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/07\\\/child-2612923_960_720.jpg\",\"width\":1200,\"height\":629},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-i-bambini-nel-dramma-della-guerra-e-del-covid-hanno-bisogno-di-te-per-aiutarli-basta-un-caffe-al-giorno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione a Distanza\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-a-distanza\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Siria. I bambini nel dramma della guerra e del Covid hanno bisogno di te. Per aiutarli basta un &#8220;caff\u00e8&#8221; al giorno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/b9065848ca5b5cf9a80fad6f849d2c17\",\"name\":\"cristianoP\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cristianop\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Siria. Il Sostegno a Distanza di Ai.Bi. per i bimbi sfollati","description":"Siria. Il Sostegno a Distanza di Ai.Bi. per i bimbi sfollati del Nord Ovest. Siria e Sostegno a Distanza con Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/siria-i-bambini-nel-dramma-della-guerra-e-del-covid-hanno-bisogno-di-te-per-aiutarli-basta-un-caffe-al-giorno\/","og_locale":"it_IT","og_type":"article","og_title":"Siria. I bambini nel dramma della guerra e del Covid hanno bisogno di te. Per aiutarli basta un \"caff\u00e8\" al giorno","og_description":"Con il Sostegno a Distanza dal 2014 Ai.Bi. supporta i nuclei fragili con minori nel Nord-Ovest del Paese","og_url":"https:\/\/www.aibi.it\/ita\/siria-i-bambini-nel-dramma-della-guerra-e-del-covid-hanno-bisogno-di-te-per-aiutarli-basta-un-caffe-al-giorno\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2020-07-31T15:36:06+00:00","article_modified_time":"2022-07-25T16:01:21+00:00","og_image":[{"width":1200,"height":629,"url":"https:\/\/www.aibi.it\/ita\/images\/2020\/07\/child-2612923_960_720.jpg","type":"image\/jpeg"}],"author":"cristianoP","twitter_card":"summary_large_image","twitter_title":"Siria. I bambini nel dramma della guerra e del Covid hanno bisogno di te. Per aiutarli basta un \"caff\u00e8\" al giorno","twitter_description":"Con il Sostegno a Distanza dal 2014 Ai.Bi. supporta i nuclei fragili con minori nel Nord-Ovest del Paese","twitter_image":"https:\/\/www.aibi.it\/ita\/images\/2020\/07\/child-2612923_960_720.jpg","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"cristianoP","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/siria-i-bambini-nel-dramma-della-guerra-e-del-covid-hanno-bisogno-di-te-per-aiutarli-basta-un-caffe-al-giorno\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/siria-i-bambini-nel-dramma-della-guerra-e-del-covid-hanno-bisogno-di-te-per-aiutarli-basta-un-caffe-al-giorno\/"},"author":{"name":"cristianoP","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/b9065848ca5b5cf9a80fad6f849d2c17"},"headline":"Siria. I bambini nel dramma della guerra e del Covid hanno bisogno di te. Per aiutarli basta un &#8220;caff\u00e8&#8221; al giorno","datePublished":"2020-07-31T15:36:06+00:00","dateModified":"2022-07-25T16:01:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/siria-i-bambini-nel-dramma-della-guerra-e-del-covid-hanno-bisogno-di-te-per-aiutarli-basta-un-caffe-al-giorno\/"},"wordCount":463,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/siria-i-bambini-nel-dramma-della-guerra-e-del-covid-hanno-bisogno-di-te-per-aiutarli-basta-un-caffe-al-giorno\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2020\/07\/child-2612923_960_720.jpg","keywords":["Siria","sostegno a distanza"],"articleSection":["Adozione a Distanza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/siria-i-bambini-nel-dramma-della-guerra-e-del-covid-hanno-bisogno-di-te-per-aiutarli-basta-un-caffe-al-giorno\/","url":"https:\/\/www.aibi.it\/ita\/siria-i-bambini-nel-dramma-della-guerra-e-del-covid-hanno-bisogno-di-te-per-aiutarli-basta-un-caffe-al-giorno\/","name":"Siria. Il Sostegno a Distanza di Ai.Bi. per i bimbi sfollati","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/siria-i-bambini-nel-dramma-della-guerra-e-del-covid-hanno-bisogno-di-te-per-aiutarli-basta-un-caffe-al-giorno\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/siria-i-bambini-nel-dramma-della-guerra-e-del-covid-hanno-bisogno-di-te-per-aiutarli-basta-un-caffe-al-giorno\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2020\/07\/child-2612923_960_720.jpg","datePublished":"2020-07-31T15:36:06+00:00","dateModified":"2022-07-25T16:01:21+00:00","description":"Siria. Il Sostegno a Distanza di Ai.Bi. per i bimbi sfollati del Nord Ovest. Siria e Sostegno a Distanza con Amici dei Bambini","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/siria-i-bambini-nel-dramma-della-guerra-e-del-covid-hanno-bisogno-di-te-per-aiutarli-basta-un-caffe-al-giorno\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/siria-i-bambini-nel-dramma-della-guerra-e-del-covid-hanno-bisogno-di-te-per-aiutarli-basta-un-caffe-al-giorno\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/siria-i-bambini-nel-dramma-della-guerra-e-del-covid-hanno-bisogno-di-te-per-aiutarli-basta-un-caffe-al-giorno\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2020\/07\/child-2612923_960_720.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2020\/07\/child-2612923_960_720.jpg","width":1200,"height":629},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/siria-i-bambini-nel-dramma-della-guerra-e-del-covid-hanno-bisogno-di-te-per-aiutarli-basta-un-caffe-al-giorno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione a Distanza","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-a-distanza\/"},{"@type":"ListItem","position":3,"name":"Siria. I bambini nel dramma della guerra e del Covid hanno bisogno di te. Per aiutarli basta un &#8220;caff\u00e8&#8221; al giorno"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/b9065848ca5b5cf9a80fad6f849d2c17","name":"cristianoP","url":"https:\/\/www.aibi.it\/ita\/author\/cristianop\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 17:26:13","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/178081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/91"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=178081"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/178081\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/178082"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=178081"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=178081"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=178081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}