﻿


{"id":178470,"date":"2020-08-17T17:02:05","date_gmt":"2020-08-17T15:02:05","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=178470"},"modified":"2020-08-17T17:02:55","modified_gmt":"2020-08-17T15:02:55","slug":"genitori-separati-in-caso-di-contrasto-sulla-religione-dei-figli-e-il-giudice-a-decidere","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/genitori-separati-in-caso-di-contrasto-sulla-religione-dei-figli-e-il-giudice-a-decidere\/","title":{"rendered":"Genitori separati. In caso di contrasto sulla religione dei figli \u00e8 il giudice a decidere"},"content":{"rendered":"<blockquote><p>Gentilissima Redazione,<\/p>\n<p>mi chiamo Paolo e sono padre di una bambina di 10 anni. La mia ex moglie, madre della piccola, da alcuni anni ha iniziato a frequentare il movimento religioso dei Testimoni di Geova, mentre io sono cattolico praticante. Sono iniziati cos\u00ec a sorgere contrasti su chi abbia diritto di impartire l\u2019educazione religiosa di nostra figlia. Non riuscendo a raggiungere un accordo a chi spetta la decisione?<\/p>\n<p>Grazie per l\u2019aiuto che mi saprete dare<\/p>\n<p>Paolo<\/p><\/blockquote>\n<p>Gentilissimo Paolo,<\/p>\n<p>secondo il nostro ordinamento \u00e8 diritto e dovere dei genitori mantenere, istruire ed educare i figli tenendo conto delle loro personali inclinazioni ed aspirazioni (anche religiose).<\/p>\n<p>Certamente, educare un figlio, vuol dire anche prendersi cura della sua sfera spirituale ed accompagnarlo verso un percorso religioso che molto spesso, per ovvie ragioni, sar\u00e0 almeno in giovane et\u00e0, quello professato dai genitori stessi.<\/p>\n<h3>Ma cosa accade, se tra gli ex coniugi nascano contrasti sull\u2019argomento?<\/h3>\n<p>In caso di dissidi tra mamma e pap\u00e0 sull\u2019educazione dei figli ci si potr\u00e0 sicuramente rivolgere in tribunale.<\/p>\n<p>Il giudice valuter\u00e0 i fatti e si esprimer\u00e0 mettendo sempre in primo piano, l\u2019interesse prevalente del minore ad una crescita sana ed equilibrata e al suo benessere psico fisico.<\/p>\n<p>Un esempio riportato dal sito web \u201cLa Legge per tutti\u201d, potr\u00e0 chiarire meglio il punto.<\/p>\n<p>Una mamma separata, appartenente al movimento dei Testimoni di Geova, decide di rivolgersi al tribunale di Pesaro con l\u2019obiettivo di modificare le condizioni di affidamento della figlia, previste della sentenza di separazione dall\u2019ex marito, di religione cattolica.<\/p>\n<p>Tali condizioni prevedevano il divieto per la mamma di portare con s\u00e9 alle riunioni religiose la piccola.<\/p>\n<p>La donna pressata dall\u2019ex marito, che era arrivato a chiederle di non frequentare pi\u00f9 il gruppo religioso, si era rivolta al giudice domandando che la bimba potesse partecipare ad entrambe le funzioni religiose, sia dei testimoni di Geova, sia quelle cattoliche del padre.<\/p>\n<p>Il tribunale ravvisando, nel contrasto tra i genitori, una compromissione della tranquillit\u00e0 della piccola, ha\u00a0 ritenuto che il superiore interesse del minore, si ritrovasse nell\u2019accettare le richieste della madre e nella possibilit\u00e0 di \u00a0frequentare entrambi i credo religiosi con l\u2019obiettivo di sviluppare una mentalit\u00e0 aperta e tollerante.<\/p>\n<p>Detto ci\u00f2, \u00e8 anche vero che, se monitorando la situazione del minore si ravvisino sintomi di disagio e si riscontri un\u2019imposizione pregiudizievole per lui, sar\u00e0 possibile per il tribunale vietare la partecipazione del bambino alle riunioni religiose ritenute pregiudizievoli per la sua tranquillit\u00e0. Stessa cosa qualora il minore dimostri preferenze verso una tipologia religiosa piuttosto che un\u2019altra.<\/p>\n<p><strong>Staff Ai.Bi.<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gentilissima Redazione, mi chiamo Paolo e sono padre di una bambina di 10 anni. La mia ex moglie, madre della piccola, da alcuni anni ha iniziato a frequentare il movimento religioso dei Testimoni di Geova, mentre io sono cattolico praticante. Sono iniziati cos&igrave; a sorgere contrasti su chi abbia diritto [&hellip;]<\/p>\n","protected":false},"author":97,"featured_media":178472,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[50],"tags":[629],"class_list":["post-178470","post","type-post","status-publish","format-standard","has-post-thumbnail","category-lettere-al-direttore","tag-genitori-separati"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Genitori separati. In caso di contrasto sulla religione dei figli \u00e8 il giudice a decidere - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"Genitori separati. In caso di contrasto tra ex coniugi sull&#039;educazione religiosa da impartire ai figli chi decide? Lo staff di Ai.Bi. risponde\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/genitori-separati-in-caso-di-contrasto-sulla-religione-dei-figli-e-il-giudice-a-decidere\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Genitori separati. In caso di contrasto sulla religione dei figli \u00e8 il giudice a decidere\" \/>\n<meta property=\"og:description\" content=\"Genitori separati. In caso di contrasto tra ex coniugi sull&#039;educazione religiosa da impartire ai figli chi decide? Lo staff di Ai.Bi. risponde\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/genitori-separati-in-caso-di-contrasto-sulla-religione-dei-figli-e-il-giudice-a-decidere\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-17T15:02:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-17T15:02:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/08\/religione.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mc.sabatini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/08\/religione.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mc.sabatini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/genitori-separati-in-caso-di-contrasto-sulla-religione-dei-figli-e-il-giudice-a-decidere\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/genitori-separati-in-caso-di-contrasto-sulla-religione-dei-figli-e-il-giudice-a-decidere\\\/\"},\"author\":{\"name\":\"mc.sabatini\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\"},\"headline\":\"Genitori separati. In caso di contrasto sulla religione dei figli \u00e8 il giudice a decidere\",\"datePublished\":\"2020-08-17T15:02:05+00:00\",\"dateModified\":\"2020-08-17T15:02:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/genitori-separati-in-caso-di-contrasto-sulla-religione-dei-figli-e-il-giudice-a-decidere\\\/\"},\"wordCount\":440,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/genitori-separati-in-caso-di-contrasto-sulla-religione-dei-figli-e-il-giudice-a-decidere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/08\\\/religione.jpg\",\"keywords\":[\"genitori separati\"],\"articleSection\":[\"Lettere al direttore\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/genitori-separati-in-caso-di-contrasto-sulla-religione-dei-figli-e-il-giudice-a-decidere\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/genitori-separati-in-caso-di-contrasto-sulla-religione-dei-figli-e-il-giudice-a-decidere\\\/\",\"name\":\"Genitori separati. In caso di contrasto sulla religione dei figli \u00e8 il giudice a decidere - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/genitori-separati-in-caso-di-contrasto-sulla-religione-dei-figli-e-il-giudice-a-decidere\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/genitori-separati-in-caso-di-contrasto-sulla-religione-dei-figli-e-il-giudice-a-decidere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/08\\\/religione.jpg\",\"datePublished\":\"2020-08-17T15:02:05+00:00\",\"dateModified\":\"2020-08-17T15:02:55+00:00\",\"description\":\"Genitori separati. In caso di contrasto tra ex coniugi sull'educazione religiosa da impartire ai figli chi decide? Lo staff di Ai.Bi. risponde\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/genitori-separati-in-caso-di-contrasto-sulla-religione-dei-figli-e-il-giudice-a-decidere\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/genitori-separati-in-caso-di-contrasto-sulla-religione-dei-figli-e-il-giudice-a-decidere\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/genitori-separati-in-caso-di-contrasto-sulla-religione-dei-figli-e-il-giudice-a-decidere\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/08\\\/religione.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/08\\\/religione.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/genitori-separati-in-caso-di-contrasto-sulla-religione-dei-figli-e-il-giudice-a-decidere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lettere al direttore\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/lettere-al-direttore\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Genitori separati. In caso di contrasto sulla religione dei figli \u00e8 il giudice a decidere\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\",\"name\":\"mc.sabatini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/marias\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Genitori separati. In caso di contrasto sulla religione dei figli \u00e8 il giudice a decidere - Ai.Bi. Amici dei Bambini","description":"Genitori separati. In caso di contrasto tra ex coniugi sull'educazione religiosa da impartire ai figli chi decide? Lo staff di Ai.Bi. risponde","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/genitori-separati-in-caso-di-contrasto-sulla-religione-dei-figli-e-il-giudice-a-decidere\/","og_locale":"it_IT","og_type":"article","og_title":"Genitori separati. In caso di contrasto sulla religione dei figli \u00e8 il giudice a decidere","og_description":"Genitori separati. In caso di contrasto tra ex coniugi sull'educazione religiosa da impartire ai figli chi decide? Lo staff di Ai.Bi. risponde","og_url":"https:\/\/www.aibi.it\/ita\/genitori-separati-in-caso-di-contrasto-sulla-religione-dei-figli-e-il-giudice-a-decidere\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2020-08-17T15:02:05+00:00","article_modified_time":"2020-08-17T15:02:55+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2020\/08\/religione.jpg","type":"image\/jpeg"}],"author":"mc.sabatini","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.aibi.it\/ita\/images\/2020\/08\/religione.jpg","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"mc.sabatini","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/genitori-separati-in-caso-di-contrasto-sulla-religione-dei-figli-e-il-giudice-a-decidere\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/genitori-separati-in-caso-di-contrasto-sulla-religione-dei-figli-e-il-giudice-a-decidere\/"},"author":{"name":"mc.sabatini","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938"},"headline":"Genitori separati. In caso di contrasto sulla religione dei figli \u00e8 il giudice a decidere","datePublished":"2020-08-17T15:02:05+00:00","dateModified":"2020-08-17T15:02:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/genitori-separati-in-caso-di-contrasto-sulla-religione-dei-figli-e-il-giudice-a-decidere\/"},"wordCount":440,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/genitori-separati-in-caso-di-contrasto-sulla-religione-dei-figli-e-il-giudice-a-decidere\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2020\/08\/religione.jpg","keywords":["genitori separati"],"articleSection":["Lettere al direttore"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/genitori-separati-in-caso-di-contrasto-sulla-religione-dei-figli-e-il-giudice-a-decidere\/","url":"https:\/\/www.aibi.it\/ita\/genitori-separati-in-caso-di-contrasto-sulla-religione-dei-figli-e-il-giudice-a-decidere\/","name":"Genitori separati. In caso di contrasto sulla religione dei figli \u00e8 il giudice a decidere - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/genitori-separati-in-caso-di-contrasto-sulla-religione-dei-figli-e-il-giudice-a-decidere\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/genitori-separati-in-caso-di-contrasto-sulla-religione-dei-figli-e-il-giudice-a-decidere\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2020\/08\/religione.jpg","datePublished":"2020-08-17T15:02:05+00:00","dateModified":"2020-08-17T15:02:55+00:00","description":"Genitori separati. In caso di contrasto tra ex coniugi sull'educazione religiosa da impartire ai figli chi decide? Lo staff di Ai.Bi. risponde","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/genitori-separati-in-caso-di-contrasto-sulla-religione-dei-figli-e-il-giudice-a-decidere\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/genitori-separati-in-caso-di-contrasto-sulla-religione-dei-figli-e-il-giudice-a-decidere\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/genitori-separati-in-caso-di-contrasto-sulla-religione-dei-figli-e-il-giudice-a-decidere\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2020\/08\/religione.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2020\/08\/religione.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/genitori-separati-in-caso-di-contrasto-sulla-religione-dei-figli-e-il-giudice-a-decidere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Lettere al direttore","item":"https:\/\/www.aibi.it\/ita\/category\/lettere-al-direttore\/"},{"@type":"ListItem","position":3,"name":"Genitori separati. In caso di contrasto sulla religione dei figli \u00e8 il giudice a decidere"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938","name":"mc.sabatini","url":"https:\/\/www.aibi.it\/ita\/author\/marias\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 10:58:20","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/178470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/97"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=178470"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/178470\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/178472"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=178470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=178470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=178470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}