﻿


{"id":178845,"date":"2020-08-28T12:27:50","date_gmt":"2020-08-28T10:27:50","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=178845"},"modified":"2020-08-28T12:27:50","modified_gmt":"2020-08-28T10:27:50","slug":"che-aiuti-riceve-il-bambino-che-sostengo-a-distanza","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/che-aiuti-riceve-il-bambino-che-sostengo-a-distanza\/","title":{"rendered":"Che aiuti riceve il bambino che sostengo a distanza?"},"content":{"rendered":"<blockquote><p>Buongiorno,<\/p>\n<p>vi scrivo perch\u00e9 vorrei sapere quali benefici riceve un bambino sostenuto a distanza. Pi\u00f9 volte io e la mia famiglia abbiamo pensato di sostenere un bambino meno fortunato adottandolo a distanza ma i dubbi su cosa ricevono concretamente questi bambini aiutati a distanza permangono.<\/p>\n<p>Grazie per le delucidazioni, cordiali saluti<\/p>\n<p>Luigi<\/p><\/blockquote>\n<p>Gentile Luigi,<\/p>\n<p>grazie per averci scritto e dato l\u2019occasione con la sua domanda di raccontare l\u2019importanza dell\u2019adozione a distanza e la possibilit\u00e0 grazie a questa accoglienza del cuore di garantire un futuro ai bambini e adolescenti abbandonati o in grave difficolt\u00e0 familiare.<\/p>\n<p>Grazie all\u2019<strong>Adozione a Distanza<\/strong> promuoviamo il diritto alla famiglia del bambino sostenuto e ci adoperiamo per garantire migliori condizioni di vita, l\u2019accesso all\u2019istruzione, alle cure mediche, ad un\u2019alimentazione adeguata alla sua et\u00e0 e la partecipazione ad attivit\u00e0 volte a sviluppare la propria personalit\u00e0 in modo sano e a superare l\u2019abbandono.<\/p>\n<p>Ciascun bambino adottato a distanza viene seguito secondo un Piano di vita personalizzato che tiene conto della sua storia, del suo vissuto, della situazione familiare, sociale e legale, del suo sviluppo psicomotorio e delle sue condizioni di salute.<\/p>\n<p>Questo significa supportare gli operatori dei centri di accoglienza sostenuti da Amici dei Bambini nella realizzazione di indagini socio familiari che permettano, ove possibile, di rintracciare e sostenere la famiglia d\u2019origine per un graduale reinserimento o favorire l\u2019accoglienza in famiglia adottiva; coprire il costo delle tasse scolastiche, delle uniformi e del materiale scolastico; garantire visite mediche periodiche e cure specialistiche (quando necessario); migliorare le condizioni igienico sanitarie degli istituti e organizzare attivit\u00e0 e laboratori di sensibilizzazione e informazione sulla prevenzione delle malattie; garantire un\u2019adeguata alimentazione per sconfiggere la malnutrizione, garantire il diritto all\u2019identit\u00e0 e a un nome, quando necessario. Sono milioni, infatti, i bambini abbandonati che non hanno un\u2019identit\u00e0 e non sono registrati e per questo ancora pi\u00f9 vulnerabili.<\/p>\n<p>Inoltre, grazie all\u2019adozione a distanza il bambino sostenuto partecipa alle attivit\u00e0 ludico-ricreative e sportive organizzate dagli operatori e volontari del centro, per offrire loro attenzione, gioco e un luogo sicuro dove crescere in sicurezza e recuperare un po\u2019 dell\u2019infanzia perduta.<\/p>\n<p>Gli adolescenti e i giovani in uscita dagli istituti grazie all\u2019adozione a distanza possono partecipare a programmi di formazione professionale ed essere seguiti nella ricerca di un alloggio e di un lavoro per una graduale conquista dell\u2019autonomia perch\u00e9 non si ritrovino, dopo una vita in istituto, catapultati nella societ\u00e0 soli e senza riferimenti.<\/p>\n<p>Nella speranza di aver risposto alla sua domanda e di aver sciolto ogni suo dubbio ci auguriamo che voglia presto attivare un\u2019adozione a distanza. Per ulteriori informazioni pu\u00f2 scrivere direttamente alla mail <a href=\"mailto:sad@aibi.it\">sad@aibi.it.<\/a><\/p>\n<p>Un caro saluto,<\/p>\n<p><strong>Staff Sostegno a Distanza &#8211; Ai.Bi. \u2013 Amici dei Bambini<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Buongiorno, vi scrivo perch&eacute; vorrei sapere quali benefici riceve un bambino sostenuto a distanza. Pi&ugrave; volte io e la mia famiglia abbiamo pensato di sostenere un bambino meno fortunato adottandolo a distanza ma i dubbi su cosa ricevono concretamente questi bambini aiutati a distanza permangono. Grazie per le delucidazioni, cordiali [&hellip;]<\/p>\n","protected":false},"author":91,"featured_media":151566,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[50],"tags":[454,318,300],"class_list":["post-178845","post","type-post","status-publish","format-standard","has-post-thumbnail","category-lettere-al-direttore","tag-adozione-a-distanza","tag-lettere-al-direttore","tag-sostegno-a-distanza"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Bambino che sostengo a distanza: che aiuti riceve?<\/title>\n<meta name=\"description\" content=\"Bambino che sostengo a distanza: che aiuti riceve? Il bambino che sostengo a distanza: come lo aiuto con il mio supporto?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/che-aiuti-riceve-il-bambino-che-sostengo-a-distanza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Che aiuti riceve il bambino che sostengo a distanza?\" \/>\n<meta property=\"og:description\" content=\"Buongiorno,vi scrivo perch\u00e9 vorrei sapere quali benefici riceve un bambino sostenuto a distanza.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/che-aiuti-riceve-il-bambino-che-sostengo-a-distanza\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-28T10:27:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/Jose-appello-bolivia_fb-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cristianoP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Che aiuti riceve il bambino che sostengo a distanza?\" \/>\n<meta name=\"twitter:description\" content=\"Buongiorno,vi scrivo perch\u00e9 vorrei sapere quali benefici riceve un bambino sostenuto a distanza.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/Jose-appello-bolivia_fb-2.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"cristianoP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/che-aiuti-riceve-il-bambino-che-sostengo-a-distanza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/che-aiuti-riceve-il-bambino-che-sostengo-a-distanza\\\/\"},\"author\":{\"name\":\"cristianoP\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/b9065848ca5b5cf9a80fad6f849d2c17\"},\"headline\":\"Che aiuti riceve il bambino che sostengo a distanza?\",\"datePublished\":\"2020-08-28T10:27:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/che-aiuti-riceve-il-bambino-che-sostengo-a-distanza\\\/\"},\"wordCount\":469,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/che-aiuti-riceve-il-bambino-che-sostengo-a-distanza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Jose-appello-bolivia_fb-2.jpg\",\"keywords\":[\"adozione a distanza\",\"Lettere al Direttore\",\"sostegno a distanza\"],\"articleSection\":[\"Lettere al direttore\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/che-aiuti-riceve-il-bambino-che-sostengo-a-distanza\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/che-aiuti-riceve-il-bambino-che-sostengo-a-distanza\\\/\",\"name\":\"Bambino che sostengo a distanza: che aiuti riceve?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/che-aiuti-riceve-il-bambino-che-sostengo-a-distanza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/che-aiuti-riceve-il-bambino-che-sostengo-a-distanza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Jose-appello-bolivia_fb-2.jpg\",\"datePublished\":\"2020-08-28T10:27:50+00:00\",\"description\":\"Bambino che sostengo a distanza: che aiuti riceve? Il bambino che sostengo a distanza: come lo aiuto con il mio supporto?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/che-aiuti-riceve-il-bambino-che-sostengo-a-distanza\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/che-aiuti-riceve-il-bambino-che-sostengo-a-distanza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/che-aiuti-riceve-il-bambino-che-sostengo-a-distanza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Jose-appello-bolivia_fb-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Jose-appello-bolivia_fb-2.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/che-aiuti-riceve-il-bambino-che-sostengo-a-distanza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lettere al direttore\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/lettere-al-direttore\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Che aiuti riceve il bambino che sostengo a distanza?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/b9065848ca5b5cf9a80fad6f849d2c17\",\"name\":\"cristianoP\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cristianop\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bambino che sostengo a distanza: che aiuti riceve?","description":"Bambino che sostengo a distanza: che aiuti riceve? Il bambino che sostengo a distanza: come lo aiuto con il mio supporto?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/che-aiuti-riceve-il-bambino-che-sostengo-a-distanza\/","og_locale":"it_IT","og_type":"article","og_title":"Che aiuti riceve il bambino che sostengo a distanza?","og_description":"Buongiorno,vi scrivo perch\u00e9 vorrei sapere quali benefici riceve un bambino sostenuto a distanza.","og_url":"https:\/\/www.aibi.it\/ita\/che-aiuti-riceve-il-bambino-che-sostengo-a-distanza\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2020-08-28T10:27:50+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/Jose-appello-bolivia_fb-2.jpg","type":"image\/jpeg"}],"author":"cristianoP","twitter_card":"summary_large_image","twitter_title":"Che aiuti riceve il bambino che sostengo a distanza?","twitter_description":"Buongiorno,vi scrivo perch\u00e9 vorrei sapere quali benefici riceve un bambino sostenuto a distanza.","twitter_image":"https:\/\/www.aibi.it\/ita\/images\/Jose-appello-bolivia_fb-2.jpg","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"cristianoP","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/che-aiuti-riceve-il-bambino-che-sostengo-a-distanza\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/che-aiuti-riceve-il-bambino-che-sostengo-a-distanza\/"},"author":{"name":"cristianoP","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/b9065848ca5b5cf9a80fad6f849d2c17"},"headline":"Che aiuti riceve il bambino che sostengo a distanza?","datePublished":"2020-08-28T10:27:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/che-aiuti-riceve-il-bambino-che-sostengo-a-distanza\/"},"wordCount":469,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/che-aiuti-riceve-il-bambino-che-sostengo-a-distanza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Jose-appello-bolivia_fb-2.jpg","keywords":["adozione a distanza","Lettere al Direttore","sostegno a distanza"],"articleSection":["Lettere al direttore"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/che-aiuti-riceve-il-bambino-che-sostengo-a-distanza\/","url":"https:\/\/www.aibi.it\/ita\/che-aiuti-riceve-il-bambino-che-sostengo-a-distanza\/","name":"Bambino che sostengo a distanza: che aiuti riceve?","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/che-aiuti-riceve-il-bambino-che-sostengo-a-distanza\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/che-aiuti-riceve-il-bambino-che-sostengo-a-distanza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Jose-appello-bolivia_fb-2.jpg","datePublished":"2020-08-28T10:27:50+00:00","description":"Bambino che sostengo a distanza: che aiuti riceve? Il bambino che sostengo a distanza: come lo aiuto con il mio supporto?","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/che-aiuti-riceve-il-bambino-che-sostengo-a-distanza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/che-aiuti-riceve-il-bambino-che-sostengo-a-distanza\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/che-aiuti-riceve-il-bambino-che-sostengo-a-distanza\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/Jose-appello-bolivia_fb-2.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/Jose-appello-bolivia_fb-2.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/che-aiuti-riceve-il-bambino-che-sostengo-a-distanza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Lettere al direttore","item":"https:\/\/www.aibi.it\/ita\/category\/lettere-al-direttore\/"},{"@type":"ListItem","position":3,"name":"Che aiuti riceve il bambino che sostengo a distanza?"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/b9065848ca5b5cf9a80fad6f849d2c17","name":"cristianoP","url":"https:\/\/www.aibi.it\/ita\/author\/cristianop\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 17:10:50","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/178845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/91"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=178845"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/178845\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/151566"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=178845"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=178845"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=178845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}