﻿


{"id":17906,"date":"2010-12-09T17:29:28","date_gmt":"2010-12-09T16:29:28","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=17906"},"modified":"2010-12-09T17:29:28","modified_gmt":"2010-12-09T16:29:28","slug":"kosovo-i-minori-con-bisogni-speciali-e-la-loro-accoglienza","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/kosovo-i-minori-con-bisogni-speciali-e-la-loro-accoglienza\/","title":{"rendered":"Kosovo: i minori con bisogni speciali e la loro accoglienza"},"content":{"rendered":"<p>I bambini abbandonati sistemati nella Associazione locale &#8220;Casa Api&#8221; sono bambini con bisogni speciali. Questi bambini, devono essere sistemati presso strutture ad hoc, famiglie affidatarie debitamente formate o famiglie adottive disponibili alla loro accoglienza, perch\u00e9 dal Ministero del Lavoro e del Benessere sociale, in particolare dal Dipartimento del Benessere Sociale, abbiamo ricevuto la conferma che alla fine di quest\u2019anno non continueranno con il loro supporto alla filiale di \u201cCasa api\u201d. Il Ministero \u00e8 sempre stato favorevole a forme di accoglienza altrnative all&#8217;istituto privato o pubblico, dato che secondo loro la forma migliore della protezione dei bambini abbandonati \u00e8 la famiglia.<\/p>\n<p>I risultati del lavoro sull\u2019affido famigliare di Amici dei bambini in Kosovo, il nostro supporto con la \u00e8quipe professionale e l\u2019esperienza portata dall\u2019Italia su diversi tipi di formazione e sulla riabilitazione dei bambini in affido ha dato a loro pi\u00f9\u00a0motivazione e competenza \u00a0per continuare con questa strategia senza sosta o mezze misure. Amici dei Bambini Kosovo, ha preparato una lista delle famiglie accoglienti che sono in grado di accogliere in affido bambini con i bisogni speciali e visto che saranno sistemati in affido beneficieranno dei servizi del Pan di Zucchero e della \u00e8quipe multidisciplinare su segnalazione dei servizi sociali che hanno in carico i minori.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I bambini abbandonati sistemati nella Associazione locale &ldquo;Casa Api&rdquo; sono bambini con bisogni speciali. Questi bambini, devono essere sistemati presso strutture ad hoc, famiglie affidatarie debitamente formate o famiglie adottive disponibili alla loro accoglienza, perch&eacute; dal Ministero del Lavoro e del Benessere sociale, in particolare dal Dipartimento del Benessere Sociale, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-17906","post","type-post","status-publish","format-standard","category-cooperazione-internazionale"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Kosovo: i minori con bisogni speciali e la loro accoglienza - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/kosovo-i-minori-con-bisogni-speciali-e-la-loro-accoglienza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kosovo: i minori con bisogni speciali e la loro accoglienza\" \/>\n<meta property=\"og:description\" content=\"I bambini abbandonati sistemati nella Associazione locale &ldquo;Casa Api&rdquo; sono bambini con bisogni speciali. Questi bambini, devono essere sistemati presso strutture ad hoc, famiglie affidatarie debitamente formate o famiglie adottive disponibili alla loro accoglienza, perch&eacute; dal Ministero del Lavoro e del Benessere sociale, in particolare dal Dipartimento del Benessere Sociale, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/kosovo-i-minori-con-bisogni-speciali-e-la-loro-accoglienza\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2010-12-09T16:29:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/aibi_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kosovo-i-minori-con-bisogni-speciali-e-la-loro-accoglienza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kosovo-i-minori-con-bisogni-speciali-e-la-loro-accoglienza\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Kosovo: i minori con bisogni speciali e la loro accoglienza\",\"datePublished\":\"2010-12-09T16:29:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kosovo-i-minori-con-bisogni-speciali-e-la-loro-accoglienza\\\/\"},\"wordCount\":219,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"articleSection\":[\"Cooperazione Internazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kosovo-i-minori-con-bisogni-speciali-e-la-loro-accoglienza\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kosovo-i-minori-con-bisogni-speciali-e-la-loro-accoglienza\\\/\",\"name\":\"Kosovo: i minori con bisogni speciali e la loro accoglienza - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"datePublished\":\"2010-12-09T16:29:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kosovo-i-minori-con-bisogni-speciali-e-la-loro-accoglienza\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kosovo-i-minori-con-bisogni-speciali-e-la-loro-accoglienza\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kosovo-i-minori-con-bisogni-speciali-e-la-loro-accoglienza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cooperazione Internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/cooperazione-internazionale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Kosovo: i minori con bisogni speciali e la loro accoglienza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Kosovo: i minori con bisogni speciali e la loro accoglienza - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/kosovo-i-minori-con-bisogni-speciali-e-la-loro-accoglienza\/","og_locale":"it_IT","og_type":"article","og_title":"Kosovo: i minori con bisogni speciali e la loro accoglienza","og_description":"I bambini abbandonati sistemati nella Associazione locale &ldquo;Casa Api&rdquo; sono bambini con bisogni speciali. Questi bambini, devono essere sistemati presso strutture ad hoc, famiglie affidatarie debitamente formate o famiglie adottive disponibili alla loro accoglienza, perch&eacute; dal Ministero del Lavoro e del Benessere sociale, in particolare dal Dipartimento del Benessere Sociale, [&hellip;]","og_url":"https:\/\/www.aibi.it\/ita\/kosovo-i-minori-con-bisogni-speciali-e-la-loro-accoglienza\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2010-12-09T16:29:28+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/aibi_fb.jpg","type":"image\/jpeg"}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/kosovo-i-minori-con-bisogni-speciali-e-la-loro-accoglienza\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/kosovo-i-minori-con-bisogni-speciali-e-la-loro-accoglienza\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Kosovo: i minori con bisogni speciali e la loro accoglienza","datePublished":"2010-12-09T16:29:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/kosovo-i-minori-con-bisogni-speciali-e-la-loro-accoglienza\/"},"wordCount":219,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"articleSection":["Cooperazione Internazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/kosovo-i-minori-con-bisogni-speciali-e-la-loro-accoglienza\/","url":"https:\/\/www.aibi.it\/ita\/kosovo-i-minori-con-bisogni-speciali-e-la-loro-accoglienza\/","name":"Kosovo: i minori con bisogni speciali e la loro accoglienza - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"datePublished":"2010-12-09T16:29:28+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/kosovo-i-minori-con-bisogni-speciali-e-la-loro-accoglienza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/kosovo-i-minori-con-bisogni-speciali-e-la-loro-accoglienza\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/kosovo-i-minori-con-bisogni-speciali-e-la-loro-accoglienza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Cooperazione Internazionale","item":"https:\/\/www.aibi.it\/ita\/category\/cooperazione-internazionale\/"},{"@type":"ListItem","position":3,"name":"Kosovo: i minori con bisogni speciali e la loro accoglienza"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 00:14:38","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/17906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=17906"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/17906\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=17906"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=17906"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=17906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}