﻿{"id":179133,"date":"2020-09-08T08:00:30","date_gmt":"2020-09-08T06:00:30","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=179133"},"modified":"2020-09-08T09:03:59","modified_gmt":"2020-09-08T07:03:59","slug":"adozioni-e-dottrina-sociale-della-chiesa-cattolica-quale-rapporto-le-unisce","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozioni-e-dottrina-sociale-della-chiesa-cattolica-quale-rapporto-le-unisce\/","title":{"rendered":"Adozioni e Dottrina sociale della Chiesa cattolica: quale rapporto le unisce?"},"content":{"rendered":"<h2>Se ne parla oggi pomeriggio alle 17.30 su Radio Mater. Sar\u00e0 ospite il presidente di Ai.Bi. Marco Griffini<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-179134 alignleft\" src=\"https:\/\/www.aibi.it\/ita\/images\/2020\/09\/PHOTO-2020-09-07-15-17-23-571x300.jpg\" alt=\"\" width=\"571\" height=\"300\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2020\/09\/PHOTO-2020-09-07-15-17-23-571x300.jpg 571w, https:\/\/www.aibi.it\/ita\/images\/2020\/09\/PHOTO-2020-09-07-15-17-23-150x79.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/2020\/09\/PHOTO-2020-09-07-15-17-23-768x403.jpg 768w, https:\/\/www.aibi.it\/ita\/images\/2020\/09\/PHOTO-2020-09-07-15-17-23.jpg 1200w\" sizes=\"auto, (max-width: 571px) 100vw, 571px\" \/>Quale rapporto intercorre tra la <strong>Dottrina sociale della Chiesa cattolica<\/strong> e le <strong>adozioni<\/strong>? Se ne parler\u00e0 questo pomeriggio, marted\u00ec 8 settembre 2020, alle ore 17.30, durante la trasmissione di <strong>Radio Mater<\/strong><br \/>\n<strong><em>\u201cTemi di Dottrina sociale della Chiesa\u201d<\/em><\/strong>, a cura di <strong>Giuseppe Brienza<\/strong>. Ospite della puntata sar\u00e0 infatti il <strong>presidente di Ai.Bi. &#8211; Amici dei Bambini, Marco Griffini.<\/strong><\/p>\n<p>In Italia l\u2019adozione, specie l&#8217;Adozione Internazionale, \u00e8 stata sempre il fiore all\u2019occhiello dell\u2019accoglienza familiare. Quanti sanno per esempio che l\u2019Italia \u00e8 seconda solo agli Stati Uniti, nel mondo intero, per numero di Adozioni Internazionali effettuate? Eppure, per vari motivi che saranno eviscerati nel corso della trasmissione, si \u00e8 passati dalle oltre 4mila adozioni annuali del 2010 alle meno di mille del 2019 rischiando di scendere nel 2020, se cos\u00ec continueranno le cose, sotto quota 500: infatti, complice il Covid e secondo gli ultimi dati resi noti dalla Commissione Adozioni Internazionali, relativi al primo semestre 2020, le autorizzazioni di ingresso rilasciate nel medesimo periodo (ovvero le adozioni internazionali \u201cfinalizzate\u201d) sono state 220 corrispondenti a 274 minori. Il decremento rispetto al primo semestre del 2019 solo in parte \u00e8 dovuto all&#8217;emergenza sanitaria in corso, che ha comportato un rallentamento delle procedure di adozione da parte di molti Paesi di provenienza.<\/p>\n<h3>Adozioni e Dottrina sociale della Chiesa cattolica: i principi in materia di responsabilit\u00e0 genitoriale e accoglienza famigliare<\/h3>\n<p>Ma, per l&#8217;appunto, anche se in molti lo ignorano, l&#8217;adozione presenta una profonda connessione spirituale con i principi che la Dottrina sociale della Chiesa propone in materia di responsabilit\u00e0 genitoriale e accoglienza famigliare. Anzi, agli sposi che non possono avere figli il Catechismo della Chiesa Cattolica raccomanda espressamente la possibilit\u00e0 di adottare o accogliere in affidamento dei bambini. Si tratta di un tema che non tutti conoscono e che, grazie a questa trasmissione, si avr\u00e0 l&#8217;occasione di discutere<\/p>\n<p>Sar\u00e0 possibile intervenire in diretta per porre domande al presidente Griffini.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se ne parla oggi pomeriggio alle 17.30 su Radio Mater. Sar&agrave; ospite il presidente di Ai.Bi. Marco Griffini Quale rapporto intercorre tra la Dottrina sociale della Chiesa cattolica e le adozioni? Se ne parler&agrave; questo pomeriggio, marted&igrave; 8 settembre 2020, alle ore 17.30, durante la trasmissione di Radio Mater &ldquo;Temi [&hellip;]<\/p>\n","protected":false},"author":91,"featured_media":179134,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[347,280],"class_list":["post-179133","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews","tag-adozione-internazionale","tag-radio-mater"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozioni e Dottrina sociale della Chiesa cattolica: quale rapporto?<\/title>\n<meta name=\"description\" content=\"Adozioni e Dottrina sociale della Chiesa cattolica: quale rapporto? Adozioni, cosa le lega alla Dottrina sociale della Chiesa cattolica?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozioni-e-dottrina-sociale-della-chiesa-cattolica-quale-rapporto-le-unisce\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozioni e Dottrina sociale della Chiesa cattolica: quale rapporto le unisce?\" \/>\n<meta property=\"og:description\" content=\"Se ne parla oggi pomeriggio alle 17.30 su Radio Mater. Sar\u00e0 ospite il presidente di Ai.Bi. Marco Griffini\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozioni-e-dottrina-sociale-della-chiesa-cattolica-quale-rapporto-le-unisce\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-08T06:00:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-08T07:03:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/09\/PHOTO-2020-09-07-15-17-23.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cristianoP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Adozioni e Dottrina sociale della Chiesa cattolica: quale rapporto le unisce?\" \/>\n<meta name=\"twitter:description\" content=\"Se ne parla oggi pomeriggio alle 17.30 su Radio Mater. Sar\u00e0 ospite il presidente di Ai.Bi. Marco Griffini\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/09\/PHOTO-2020-09-07-15-17-23.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"cristianoP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-e-dottrina-sociale-della-chiesa-cattolica-quale-rapporto-le-unisce\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-e-dottrina-sociale-della-chiesa-cattolica-quale-rapporto-le-unisce\\\/\"},\"author\":{\"name\":\"cristianoP\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/b9065848ca5b5cf9a80fad6f849d2c17\"},\"headline\":\"Adozioni e Dottrina sociale della Chiesa cattolica: quale rapporto le unisce?\",\"datePublished\":\"2020-09-08T06:00:30+00:00\",\"dateModified\":\"2020-09-08T07:03:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-e-dottrina-sociale-della-chiesa-cattolica-quale-rapporto-le-unisce\\\/\"},\"wordCount\":335,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-e-dottrina-sociale-della-chiesa-cattolica-quale-rapporto-le-unisce\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/09\\\/PHOTO-2020-09-07-15-17-23.jpg\",\"keywords\":[\"Adozione Internazionale\",\"Radio Mater\"],\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-e-dottrina-sociale-della-chiesa-cattolica-quale-rapporto-le-unisce\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-e-dottrina-sociale-della-chiesa-cattolica-quale-rapporto-le-unisce\\\/\",\"name\":\"Adozioni e Dottrina sociale della Chiesa cattolica: quale rapporto?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-e-dottrina-sociale-della-chiesa-cattolica-quale-rapporto-le-unisce\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-e-dottrina-sociale-della-chiesa-cattolica-quale-rapporto-le-unisce\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/09\\\/PHOTO-2020-09-07-15-17-23.jpg\",\"datePublished\":\"2020-09-08T06:00:30+00:00\",\"dateModified\":\"2020-09-08T07:03:59+00:00\",\"description\":\"Adozioni e Dottrina sociale della Chiesa cattolica: quale rapporto? Adozioni, cosa le lega alla Dottrina sociale della Chiesa cattolica?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-e-dottrina-sociale-della-chiesa-cattolica-quale-rapporto-le-unisce\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-e-dottrina-sociale-della-chiesa-cattolica-quale-rapporto-le-unisce\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-e-dottrina-sociale-della-chiesa-cattolica-quale-rapporto-le-unisce\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/09\\\/PHOTO-2020-09-07-15-17-23.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/09\\\/PHOTO-2020-09-07-15-17-23.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-e-dottrina-sociale-della-chiesa-cattolica-quale-rapporto-le-unisce\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozioni e Dottrina sociale della Chiesa cattolica: quale rapporto le unisce?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/b9065848ca5b5cf9a80fad6f849d2c17\",\"name\":\"cristianoP\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cristianop\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozioni e Dottrina sociale della Chiesa cattolica: quale rapporto?","description":"Adozioni e Dottrina sociale della Chiesa cattolica: quale rapporto? Adozioni, cosa le lega alla Dottrina sociale della Chiesa cattolica?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozioni-e-dottrina-sociale-della-chiesa-cattolica-quale-rapporto-le-unisce\/","og_locale":"it_IT","og_type":"article","og_title":"Adozioni e Dottrina sociale della Chiesa cattolica: quale rapporto le unisce?","og_description":"Se ne parla oggi pomeriggio alle 17.30 su Radio Mater. Sar\u00e0 ospite il presidente di Ai.Bi. Marco Griffini","og_url":"https:\/\/www.aibi.it\/ita\/adozioni-e-dottrina-sociale-della-chiesa-cattolica-quale-rapporto-le-unisce\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2020-09-08T06:00:30+00:00","article_modified_time":"2020-09-08T07:03:59+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2020\/09\/PHOTO-2020-09-07-15-17-23.jpg","type":"image\/jpeg"}],"author":"cristianoP","twitter_card":"summary_large_image","twitter_title":"Adozioni e Dottrina sociale della Chiesa cattolica: quale rapporto le unisce?","twitter_description":"Se ne parla oggi pomeriggio alle 17.30 su Radio Mater. Sar\u00e0 ospite il presidente di Ai.Bi. Marco Griffini","twitter_image":"https:\/\/www.aibi.it\/ita\/images\/2020\/09\/PHOTO-2020-09-07-15-17-23.jpg","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"cristianoP","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozioni-e-dottrina-sociale-della-chiesa-cattolica-quale-rapporto-le-unisce\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-e-dottrina-sociale-della-chiesa-cattolica-quale-rapporto-le-unisce\/"},"author":{"name":"cristianoP","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/b9065848ca5b5cf9a80fad6f849d2c17"},"headline":"Adozioni e Dottrina sociale della Chiesa cattolica: quale rapporto le unisce?","datePublished":"2020-09-08T06:00:30+00:00","dateModified":"2020-09-08T07:03:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-e-dottrina-sociale-della-chiesa-cattolica-quale-rapporto-le-unisce\/"},"wordCount":335,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-e-dottrina-sociale-della-chiesa-cattolica-quale-rapporto-le-unisce\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2020\/09\/PHOTO-2020-09-07-15-17-23.jpg","keywords":["Adozione Internazionale","Radio Mater"],"articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozioni-e-dottrina-sociale-della-chiesa-cattolica-quale-rapporto-le-unisce\/","url":"https:\/\/www.aibi.it\/ita\/adozioni-e-dottrina-sociale-della-chiesa-cattolica-quale-rapporto-le-unisce\/","name":"Adozioni e Dottrina sociale della Chiesa cattolica: quale rapporto?","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-e-dottrina-sociale-della-chiesa-cattolica-quale-rapporto-le-unisce\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-e-dottrina-sociale-della-chiesa-cattolica-quale-rapporto-le-unisce\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2020\/09\/PHOTO-2020-09-07-15-17-23.jpg","datePublished":"2020-09-08T06:00:30+00:00","dateModified":"2020-09-08T07:03:59+00:00","description":"Adozioni e Dottrina sociale della Chiesa cattolica: quale rapporto? Adozioni, cosa le lega alla Dottrina sociale della Chiesa cattolica?","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-e-dottrina-sociale-della-chiesa-cattolica-quale-rapporto-le-unisce\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozioni-e-dottrina-sociale-della-chiesa-cattolica-quale-rapporto-le-unisce\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozioni-e-dottrina-sociale-della-chiesa-cattolica-quale-rapporto-le-unisce\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2020\/09\/PHOTO-2020-09-07-15-17-23.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2020\/09\/PHOTO-2020-09-07-15-17-23.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozioni-e-dottrina-sociale-della-chiesa-cattolica-quale-rapporto-le-unisce\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Adozioni e Dottrina sociale della Chiesa cattolica: quale rapporto le unisce?"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/b9065848ca5b5cf9a80fad6f849d2c17","name":"cristianoP","url":"https:\/\/www.aibi.it\/ita\/author\/cristianop\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 12:32:07","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/179133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/91"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=179133"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/179133\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/179134"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=179133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=179133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=179133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}