﻿{"id":179580,"date":"2020-09-18T15:00:47","date_gmt":"2020-09-18T13:00:47","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=179580"},"modified":"2022-07-25T17:35:14","modified_gmt":"2022-07-25T15:35:14","slug":"cina-un-aiuto-concreto-per-i-piccoli-angeli-della-casa-di-accoglienza-vittorino-colombo","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/cina-un-aiuto-concreto-per-i-piccoli-angeli-della-casa-di-accoglienza-vittorino-colombo\/","title":{"rendered":"Cina. Un aiuto concreto per i piccoli angeli della casa di accoglienza Vittorino Colombo"},"content":{"rendered":"<h2><b>In Cina, esiste una casa dove, grazie ad Ai.Bi. e al Sostegno a Distanza, i bimbi pi\u00f9 fragili, soli ed affetti da disabilit\u00e0, sono accolti, amati e curati, in attesa di trovare al pi\u00f9 presto una mamma e un pap\u00e0.<\/b><\/h2>\n<p>La Cina, con una popolazione di 1,4 miliardi di persone, \u00e8 il Paese pi\u00f9 popolato al mondo, oltre ad essere la seconda potenza economia globale.<\/p>\n<p>La rapida crescita del Paese, ha comportato per\u00f2 anche il sopraggiungere di molte problematiche, tra le quali <strong>l\u2019aumento della diseguaglianza sociale.<\/strong><\/p>\n<p>A farne le spese, come spesso accade, sono sempre le fasce pi\u00f9 deboli della popolazione, come i bambini. Sono infatti ben <strong>70 milioni i piccoli che vivono in aree estremamente povere del Paese<\/strong> e si stima che ogni anno vengano abbandonati in Cina oltre 100.000 bimbi.<\/p>\n<h3><strong>Ai.Bi. sempre al fianco dei bimbi pi\u00f9 fragili grazie al Sostegno a Distanza.<\/strong><\/h3>\n<p><strong>Ai.Bi. \u00e8 presente in Cina da pi\u00f9 di 10 anni, fin dal 2008.<\/strong><\/p>\n<p>La sua attivit\u00e0 di <a href=\"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/attivazione-adozione-a-distanza\/?scelta=25&amp;progetto=Cina\">Sostegno a Distanza<\/a> \u00e8 rivolta principalmente a promuovere il \u201cdiritto alla famiglia\u201d dei bimbi pi\u00f9 fragili, quelli soli e affetti da disabilit\u00e0, ospiti della <strong>Casa di Accoglienza \u201cVittorino Colombo\u201d<\/strong>, struttura specializzata nell\u2019accogliere, in un clima di serenit\u00e0 familiare, i bimbi abbandonati con problemi di salute.<\/p>\n<p>Grazie alle amorevoli cure di 4 baby sitter, 2 educatori e un\u2019infermiera specializzata, la casa <strong>pu\u00f2 ospitare contemporaneamente, fino a 8 bambini con diverse patologie.<\/strong><\/p>\n<p>Ai.Bi. \u00e8 ogni giorno al fianco dei piccoli angeli ospiti della casa di accoglienza Vittorino Colombo.<\/p>\n<p>Grazie al prezioso aiuto del <strong>Sostegno a Distanza<\/strong>, Ai. Bi. pu\u00f2 garantire ad ogni bambino accolto visite specialiste, diagnosi mediche esaustive, piani terapeutici e percorsi riabilitativi per aiutarli ad acquisire maggior autonomia e a svolgere, come ogni altro bambino della loro et\u00e0, attivit\u00e0 quotidiane semplici come mangiare, vestirsi, lavarsi, giocare e frequentare la scuola.<\/p>\n<p><strong>Aiuta Ai.Bi. in questo importante compito.<\/strong><\/p>\n<p>Grazie al <a href=\"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/attivazione-adozione-a-distanza\/?scelta=25&amp;progetto=Cina\">Sostegno a Distanza<\/a> alla <strong>casa di accoglienza Vittorino Colombo puoi farlo<\/strong>. Con 25 euro, meno di un caff\u00e8 al giorno puoi donare ai piccoli ospiti della struttura, tutte le cure di cui hanno bisogno, in attesa di incontrare una mamma ed un pap\u00e0 che li amino per tutta la vita.<\/p>\n\n<!-- Buttons X - Start -->\n<style type=\"text\/css\">\/*168342-start*\/\n#btnsx-168342{margin-top:0px;margin-bottom:20px;margin-left:0px;margin-right:0px;padding-top:20px;padding-bottom:20px;padding-left:40px;padding-right:40px;}\n#btnsx-168342 .btnsx-text-primary{font-size:30px;line-height:30px;font-family:Montserrat;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-168342:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-168342 .btnsx-text-secondary{}\n#btnsx-168342 .btnsx-icon{}\n#btnsx-168342 .btnsx-icon-img{}\n#btnsx-168342{background-color:#ef7b0b!important;}\n#btnsx-168342:before{background-color:#eab20b!important;}\n#btnsx-168342:hover{background-color:#eab20b!important;}\n#btnsx-168342{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-168342:hover{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-168342-dropdown .menu-item a{}\n#btnsx-168342-dropdown{border-top-width:px;border-bottom-width:px;border-left-width:px;border-right-width:px;}\n#btnsx-168342-dropdown:before{border-width:8px;margin-left:-8px;border-bottom-color:}\n#btnsx-168342-dropdown:after{}\n#btnsx-168342-dropdown{}\n@media screen and (max-width: 768px) {\n#btnsx-168342 {display:inline-block;}\n#btnsx-168342 .btnsx-text-primary {}\n#btnsx-168342 .btnsx-text-secondary {}\n#btnsx-168342 .btnsx-icon {}\n#btnsx-168342 .btnsx-divider {}\n}@media screen and (max-width: 480px) {\n#btnsx-168342 {display:inline-block;}\n#btnsx-168342 .btnsx-text-primary {}\n#btnsx-168342 .btnsx-text-secondary {}\n#btnsx-168342 .btnsx-icon {}\n#btnsx-168342 .btnsx-divider {}\n}\/*168342-end*\/\n<\/style><div id=\"btnsx-168342-wrap\" class=\"btnsx-wrap-center\" align=\"center\"><div id=\"btnsx-168342-container\" class=\"btnsx-btn-container\">\n<a href=\"https:\/\/www.aibi.it\/ita\/adotta-a-distanza-25\/\" id=\"btnsx-168342\" target=\"_blank\" class=\"btnsx-btn  btnsx-btn-embossed\"  data-font-primary=\"Montserrat\" data-animation-type=\"\">\n\t<span class=\"btnsx-text-primary \">Scopri di pi\u00f9<\/span><\/a>\n<\/div><\/div>\n<!-- Buttons X - End -->\n\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In Cina, esiste una casa dove, grazie ad Ai.Bi. e al Sostegno a Distanza, i bimbi pi&ugrave; fragili, soli ed affetti da disabilit&agrave;, sono accolti, amati e curati, in attesa di trovare al pi&ugrave; presto una mamma e un pap&agrave;. La Cina, con una popolazione di 1,4 miliardi di persone, [&hellip;]<\/p>\n","protected":false},"author":97,"featured_media":179586,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[209],"tags":[649],"class_list":["post-179580","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-a-distanza","tag-vittorino-colombo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cina. Un aiuto concreto per i piccoli angeli della casa di accoglienza Vittorino Colombo - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"In Cina, grazie ad Ai.Bi. e al Sostegno a Distanza, i bimbi pi\u00f9 fragili, sono accolti e curati, in attesa di trovare una mamma e un pap\u00e0.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/cina-un-aiuto-concreto-per-i-piccoli-angeli-della-casa-di-accoglienza-vittorino-colombo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cina. Un aiuto concreto per i piccoli angeli della casa di accoglienza Vittorino Colombo\" \/>\n<meta property=\"og:description\" content=\"In Cina, esiste una casa dove, grazie ad Ai.Bi. e al Sostegno a Distanza, i bimbi pi\u00f9 fragili, soli ed affetti da disabilit\u00e0, sono accolti, amati e curati, in attesa di trovare al pi\u00f9 presto una mamma e un pap\u00e0.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/cina-un-aiuto-concreto-per-i-piccoli-angeli-della-casa-di-accoglienza-vittorino-colombo\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-18T13:00:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-25T15:35:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/09\/Cina-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mc.sabatini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/09\/Cina-1.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mc.sabatini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-un-aiuto-concreto-per-i-piccoli-angeli-della-casa-di-accoglienza-vittorino-colombo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-un-aiuto-concreto-per-i-piccoli-angeli-della-casa-di-accoglienza-vittorino-colombo\\\/\"},\"author\":{\"name\":\"mc.sabatini\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\"},\"headline\":\"Cina. Un aiuto concreto per i piccoli angeli della casa di accoglienza Vittorino Colombo\",\"datePublished\":\"2020-09-18T13:00:47+00:00\",\"dateModified\":\"2022-07-25T15:35:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-un-aiuto-concreto-per-i-piccoli-angeli-della-casa-di-accoglienza-vittorino-colombo\\\/\"},\"wordCount\":386,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-un-aiuto-concreto-per-i-piccoli-angeli-della-casa-di-accoglienza-vittorino-colombo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/09\\\/Cina-1.jpg\",\"keywords\":[\"Vittorino Colombo\"],\"articleSection\":[\"Adozione a Distanza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-un-aiuto-concreto-per-i-piccoli-angeli-della-casa-di-accoglienza-vittorino-colombo\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-un-aiuto-concreto-per-i-piccoli-angeli-della-casa-di-accoglienza-vittorino-colombo\\\/\",\"name\":\"Cina. Un aiuto concreto per i piccoli angeli della casa di accoglienza Vittorino Colombo - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-un-aiuto-concreto-per-i-piccoli-angeli-della-casa-di-accoglienza-vittorino-colombo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-un-aiuto-concreto-per-i-piccoli-angeli-della-casa-di-accoglienza-vittorino-colombo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/09\\\/Cina-1.jpg\",\"datePublished\":\"2020-09-18T13:00:47+00:00\",\"dateModified\":\"2022-07-25T15:35:14+00:00\",\"description\":\"In Cina, grazie ad Ai.Bi. e al Sostegno a Distanza, i bimbi pi\u00f9 fragili, sono accolti e curati, in attesa di trovare una mamma e un pap\u00e0.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-un-aiuto-concreto-per-i-piccoli-angeli-della-casa-di-accoglienza-vittorino-colombo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-un-aiuto-concreto-per-i-piccoli-angeli-della-casa-di-accoglienza-vittorino-colombo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-un-aiuto-concreto-per-i-piccoli-angeli-della-casa-di-accoglienza-vittorino-colombo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/09\\\/Cina-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/09\\\/Cina-1.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-un-aiuto-concreto-per-i-piccoli-angeli-della-casa-di-accoglienza-vittorino-colombo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione a Distanza\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-a-distanza\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cina. Un aiuto concreto per i piccoli angeli della casa di accoglienza Vittorino Colombo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\",\"name\":\"mc.sabatini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/marias\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cina. Un aiuto concreto per i piccoli angeli della casa di accoglienza Vittorino Colombo - Ai.Bi. Amici dei Bambini","description":"In Cina, grazie ad Ai.Bi. e al Sostegno a Distanza, i bimbi pi\u00f9 fragili, sono accolti e curati, in attesa di trovare una mamma e un pap\u00e0.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/cina-un-aiuto-concreto-per-i-piccoli-angeli-della-casa-di-accoglienza-vittorino-colombo\/","og_locale":"it_IT","og_type":"article","og_title":"Cina. Un aiuto concreto per i piccoli angeli della casa di accoglienza Vittorino Colombo","og_description":"In Cina, esiste una casa dove, grazie ad Ai.Bi. e al Sostegno a Distanza, i bimbi pi\u00f9 fragili, soli ed affetti da disabilit\u00e0, sono accolti, amati e curati, in attesa di trovare al pi\u00f9 presto una mamma e un pap\u00e0.","og_url":"https:\/\/www.aibi.it\/ita\/cina-un-aiuto-concreto-per-i-piccoli-angeli-della-casa-di-accoglienza-vittorino-colombo\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2020-09-18T13:00:47+00:00","article_modified_time":"2022-07-25T15:35:14+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2020\/09\/Cina-1.jpg","type":"image\/jpeg"}],"author":"mc.sabatini","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.aibi.it\/ita\/images\/2020\/09\/Cina-1.jpg","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"mc.sabatini","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/cina-un-aiuto-concreto-per-i-piccoli-angeli-della-casa-di-accoglienza-vittorino-colombo\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/cina-un-aiuto-concreto-per-i-piccoli-angeli-della-casa-di-accoglienza-vittorino-colombo\/"},"author":{"name":"mc.sabatini","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938"},"headline":"Cina. Un aiuto concreto per i piccoli angeli della casa di accoglienza Vittorino Colombo","datePublished":"2020-09-18T13:00:47+00:00","dateModified":"2022-07-25T15:35:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/cina-un-aiuto-concreto-per-i-piccoli-angeli-della-casa-di-accoglienza-vittorino-colombo\/"},"wordCount":386,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/cina-un-aiuto-concreto-per-i-piccoli-angeli-della-casa-di-accoglienza-vittorino-colombo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2020\/09\/Cina-1.jpg","keywords":["Vittorino Colombo"],"articleSection":["Adozione a Distanza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/cina-un-aiuto-concreto-per-i-piccoli-angeli-della-casa-di-accoglienza-vittorino-colombo\/","url":"https:\/\/www.aibi.it\/ita\/cina-un-aiuto-concreto-per-i-piccoli-angeli-della-casa-di-accoglienza-vittorino-colombo\/","name":"Cina. Un aiuto concreto per i piccoli angeli della casa di accoglienza Vittorino Colombo - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/cina-un-aiuto-concreto-per-i-piccoli-angeli-della-casa-di-accoglienza-vittorino-colombo\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/cina-un-aiuto-concreto-per-i-piccoli-angeli-della-casa-di-accoglienza-vittorino-colombo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2020\/09\/Cina-1.jpg","datePublished":"2020-09-18T13:00:47+00:00","dateModified":"2022-07-25T15:35:14+00:00","description":"In Cina, grazie ad Ai.Bi. e al Sostegno a Distanza, i bimbi pi\u00f9 fragili, sono accolti e curati, in attesa di trovare una mamma e un pap\u00e0.","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/cina-un-aiuto-concreto-per-i-piccoli-angeli-della-casa-di-accoglienza-vittorino-colombo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/cina-un-aiuto-concreto-per-i-piccoli-angeli-della-casa-di-accoglienza-vittorino-colombo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/cina-un-aiuto-concreto-per-i-piccoli-angeli-della-casa-di-accoglienza-vittorino-colombo\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2020\/09\/Cina-1.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2020\/09\/Cina-1.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/cina-un-aiuto-concreto-per-i-piccoli-angeli-della-casa-di-accoglienza-vittorino-colombo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione a Distanza","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-a-distanza\/"},{"@type":"ListItem","position":3,"name":"Cina. Un aiuto concreto per i piccoli angeli della casa di accoglienza Vittorino Colombo"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938","name":"mc.sabatini","url":"https:\/\/www.aibi.it\/ita\/author\/marias\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 10:52:55","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/179580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/97"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=179580"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/179580\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/179586"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=179580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=179580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=179580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}