﻿{"id":180123,"date":"2020-10-05T16:18:07","date_gmt":"2020-10-05T14:18:07","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=180123"},"modified":"2022-07-25T17:28:04","modified_gmt":"2022-07-25T15:28:04","slug":"bolivia-e-se-la-salute-non-e-un-diritto-garantitoci-sono-degli-angeli-custodi","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/bolivia-e-se-la-salute-non-e-un-diritto-garantitoci-sono-degli-angeli-custodi\/","title":{"rendered":"Bolivia. E se la salute non \u00e8 un diritto garantito\u2026 ci sono degli angeli custodi!"},"content":{"rendered":"<h2>Grazie al <a href=\"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/attivazione-adozione-a-distanza\/\">Sostegno a Distanza<\/a>, Maria e Alvaro, piccoli ospiti del Jos\u00e9 Soria, non devono pi\u00f9 aspettare per crescere in salute<\/h2>\n<p>Il <strong>Sostegno a Distanza<\/strong> di Amici dei Bambini \u00e8 una\u00a0<strong>partecipazione diretta<\/strong>\u00a0alle attivit\u00e0 progettuali rivolte ai minori in difficolt\u00e0 familiare,\u00a0<strong>ospiti di una comunit\u00e0 di accoglienza<\/strong>. Il sostegno contribuisce a migliorare le loro condizioni di vita, assicurando alimentazione adeguata, visite mediche specialistiche, attivit\u00e0 socio\u2013educative, corsi di formazione professionale, percorsi d\u2019inserimento lavorativo per gli adolescenti e tutto ci\u00f2 che si rende necessario per far s\u00ec che i minori ospiti delle comunit\u00e0 sostenute da Ai.Bi. possano crescere, per quanto possibile, serenamente, come se fossero i \u201cnostri\u201d figli. Il Sostegno a Distanza richiede un impegno mensile di\u00a0<strong>25 euro<\/strong>\u00a0ed \u00e8 finalizzato ai progetti in corso in uno dei Paesi esteri in cui Ai.Bi. opera.<\/p>\n<p>Costruito per gli orfani della guerra del Chaco della citt\u00e0 di La Paz, in Bolivia, il <strong>centro di accoglienza Jos\u00e9 Soria\u00a0<\/strong>accoglie fino a 60 bambini e bambine tra i 6 e i 12 anni, vittime di abuso, maltrattamenti o abbandono. Ai.Bi. affianca il centro nella realizzazione di\u00a0<strong>Progetti di Vita Individuali<\/strong>\u00a0volti al ricongiungimento familiare o all\u2019accoglienza in una nuova famiglia, garantendo a ciascun bambino un sostegno psicologico, scolastico, medico e educativo personalizzato.\u00a0<strong>Grazie al\u00a0Sostegno a Distanza<\/strong>, gli operatori di Ai.Bi. Bolivia supportano lo staff\u00a0 dell\u2019istituto nella realizzazione di indagini volte al reinserimento famigliare, e nelle procedure di rilascio del certificato di nascita.<\/p>\n<p>Mai come negli ultimi mesi, dovremmo soffermarci a pensare quanto dei semplici gesti, che prima della pandemia ci sembrano ovvi e facili da compiere, in realt\u00e0 non lo sono sempre e dappertutto. In <strong>Bolivia,<\/strong> ad esempio, lo scenario si presenta molto pi\u00f9 complicato che da questa parte del mondo e il caos generato dal Covid ha peggiorato una situazione gi\u00e0 piuttosto precaria. Se trasliamo quanto ci siamo appena detti in un Centro di Accoglienza dove nulla \u00e8 ovvio e facile per i minori ospiti abbandonati dalle loro famiglie, possiamo facilmente intuire come possa essere molto complicato, alle volte impossibile, reperire anche solo le medicine che \u00a0aiutano i bambini a crescere meglio.<\/p>\n<p><strong>Questa \u00e8 la storia di Maria e Alvaro<\/strong>, accolti al Jos\u00e9 Soria, che, per uno sviluppo neurologico sano, hanno bisogno di assumere giornalmente delle medicine. <strong>Grazie ai sostenitori a distanza di Amici dei Bambini<\/strong>, ai piccoli ospiti del Centro di Accoglienza viene riconosciuto e garantito il diritto fondamentale alla salute, proprio come ognuno di noi farebbe per il proprio figlio.<\/p>\n<p>In Bolivia, aiuta anche tu a garantire a ciascun bambino abbandonato i suoi dritti fondamentali. Attiva un <a href=\"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/attivazione-adozione-a-distanza\/\">Sostegno a Distanza<\/a>.<\/p>\n\n<!-- Buttons X - Start -->\n<style type=\"text\/css\">\/*168342-start*\/\n#btnsx-168342{margin-top:0px;margin-bottom:20px;margin-left:0px;margin-right:0px;padding-top:20px;padding-bottom:20px;padding-left:40px;padding-right:40px;}\n#btnsx-168342 .btnsx-text-primary{font-size:30px;line-height:30px;font-family:Montserrat;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-168342:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-168342 .btnsx-text-secondary{}\n#btnsx-168342 .btnsx-icon{}\n#btnsx-168342 .btnsx-icon-img{}\n#btnsx-168342{background-color:#ef7b0b!important;}\n#btnsx-168342:before{background-color:#eab20b!important;}\n#btnsx-168342:hover{background-color:#eab20b!important;}\n#btnsx-168342{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-168342:hover{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-168342-dropdown .menu-item a{}\n#btnsx-168342-dropdown{border-top-width:px;border-bottom-width:px;border-left-width:px;border-right-width:px;}\n#btnsx-168342-dropdown:before{border-width:8px;margin-left:-8px;border-bottom-color:}\n#btnsx-168342-dropdown:after{}\n#btnsx-168342-dropdown{}\n@media screen and (max-width: 768px) {\n#btnsx-168342 {display:inline-block;}\n#btnsx-168342 .btnsx-text-primary {}\n#btnsx-168342 .btnsx-text-secondary {}\n#btnsx-168342 .btnsx-icon {}\n#btnsx-168342 .btnsx-divider {}\n}@media screen and (max-width: 480px) {\n#btnsx-168342 {display:inline-block;}\n#btnsx-168342 .btnsx-text-primary {}\n#btnsx-168342 .btnsx-text-secondary {}\n#btnsx-168342 .btnsx-icon {}\n#btnsx-168342 .btnsx-divider {}\n}\/*168342-end*\/\n<\/style><div id=\"btnsx-168342-wrap\" class=\"btnsx-wrap-center\" align=\"center\"><div id=\"btnsx-168342-container\" class=\"btnsx-btn-container\">\n<a href=\"https:\/\/www.aibi.it\/ita\/adotta-a-distanza-25\/\" id=\"btnsx-168342\" target=\"_blank\" class=\"btnsx-btn  btnsx-btn-embossed\"  data-font-primary=\"Montserrat\" data-animation-type=\"\">\n\t<span class=\"btnsx-text-primary \">Scopri di pi\u00f9<\/span><\/a>\n<\/div><\/div>\n<!-- Buttons X - End -->\n\n","protected":false},"excerpt":{"rendered":"<p>Grazie al Sostegno a Distanza, Maria e Alvaro, piccoli ospiti del Jos&eacute; Soria, non devono pi&ugrave; aspettare per crescere in salute Il Sostegno a Distanza di Amici dei Bambini &egrave; una&nbsp;partecipazione diretta&nbsp;alle attivit&agrave; progettuali rivolte ai minori in difficolt&agrave; familiare,&nbsp;ospiti di una comunit&agrave; di accoglienza. Il sostegno contribuisce a migliorare [&hellip;]<\/p>\n","protected":false},"author":113,"featured_media":180118,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[209],"tags":[480,647,300],"class_list":["post-180123","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-a-distanza","tag-bolivia","tag-jose-soria","tag-sostegno-a-distanza"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Bolivia. E se la salute non \u00e8 un diritto garantito\u2026 ci sono degli angeli custodi! - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/bolivia-e-se-la-salute-non-e-un-diritto-garantitoci-sono-degli-angeli-custodi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bolivia. E se la salute non \u00e8 un diritto garantito\u2026 ci sono degli angeli custodi!\" \/>\n<meta property=\"og:description\" content=\"Grazie al Sostegno a Distanza, Maria e Alvaro, piccoli ospiti del Jos&eacute; Soria, non devono pi&ugrave; aspettare per crescere in salute Il Sostegno a Distanza di Amici dei Bambini &egrave; una&nbsp;partecipazione diretta&nbsp;alle attivit&agrave; progettuali rivolte ai minori in difficolt&agrave; familiare,&nbsp;ospiti di una comunit&agrave; di accoglienza. Il sostegno contribuisce a migliorare [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/bolivia-e-se-la-salute-non-e-un-diritto-garantitoci-sono-degli-angeli-custodi\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-05T14:18:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-25T15:28:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/10\/storia-bolivia-alimentare_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"carlottaZ\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/10\/storia-bolivia-alimentare_fb.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"carlottaZ\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-e-se-la-salute-non-e-un-diritto-garantitoci-sono-degli-angeli-custodi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-e-se-la-salute-non-e-un-diritto-garantitoci-sono-degli-angeli-custodi\\\/\"},\"author\":{\"name\":\"carlottaZ\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/95193f4e7a1f2190922687ebf84f96c9\"},\"headline\":\"Bolivia. E se la salute non \u00e8 un diritto garantito\u2026 ci sono degli angeli custodi!\",\"datePublished\":\"2020-10-05T14:18:07+00:00\",\"dateModified\":\"2022-07-25T15:28:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-e-se-la-salute-non-e-un-diritto-garantitoci-sono-degli-angeli-custodi\\\/\"},\"wordCount\":460,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-e-se-la-salute-non-e-un-diritto-garantitoci-sono-degli-angeli-custodi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/10\\\/storia-bolivia-alimentare_fb.jpg\",\"keywords\":[\"Bolivia\",\"Jos\u00e8 Soria\",\"sostegno a distanza\"],\"articleSection\":[\"Adozione a Distanza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-e-se-la-salute-non-e-un-diritto-garantitoci-sono-degli-angeli-custodi\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-e-se-la-salute-non-e-un-diritto-garantitoci-sono-degli-angeli-custodi\\\/\",\"name\":\"Bolivia. E se la salute non \u00e8 un diritto garantito\u2026 ci sono degli angeli custodi! - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-e-se-la-salute-non-e-un-diritto-garantitoci-sono-degli-angeli-custodi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-e-se-la-salute-non-e-un-diritto-garantitoci-sono-degli-angeli-custodi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/10\\\/storia-bolivia-alimentare_fb.jpg\",\"datePublished\":\"2020-10-05T14:18:07+00:00\",\"dateModified\":\"2022-07-25T15:28:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-e-se-la-salute-non-e-un-diritto-garantitoci-sono-degli-angeli-custodi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-e-se-la-salute-non-e-un-diritto-garantitoci-sono-degli-angeli-custodi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-e-se-la-salute-non-e-un-diritto-garantitoci-sono-degli-angeli-custodi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/10\\\/storia-bolivia-alimentare_fb.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/10\\\/storia-bolivia-alimentare_fb.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-e-se-la-salute-non-e-un-diritto-garantitoci-sono-degli-angeli-custodi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione a Distanza\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-a-distanza\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bolivia. E se la salute non \u00e8 un diritto garantito\u2026 ci sono degli angeli custodi!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/95193f4e7a1f2190922687ebf84f96c9\",\"name\":\"carlottaZ\",\"sameAs\":[\"cellos\"],\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/carlottaz\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bolivia. E se la salute non \u00e8 un diritto garantito\u2026 ci sono degli angeli custodi! - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/bolivia-e-se-la-salute-non-e-un-diritto-garantitoci-sono-degli-angeli-custodi\/","og_locale":"it_IT","og_type":"article","og_title":"Bolivia. E se la salute non \u00e8 un diritto garantito\u2026 ci sono degli angeli custodi!","og_description":"Grazie al Sostegno a Distanza, Maria e Alvaro, piccoli ospiti del Jos&eacute; Soria, non devono pi&ugrave; aspettare per crescere in salute Il Sostegno a Distanza di Amici dei Bambini &egrave; una&nbsp;partecipazione diretta&nbsp;alle attivit&agrave; progettuali rivolte ai minori in difficolt&agrave; familiare,&nbsp;ospiti di una comunit&agrave; di accoglienza. Il sostegno contribuisce a migliorare [&hellip;]","og_url":"https:\/\/www.aibi.it\/ita\/bolivia-e-se-la-salute-non-e-un-diritto-garantitoci-sono-degli-angeli-custodi\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2020-10-05T14:18:07+00:00","article_modified_time":"2022-07-25T15:28:04+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2020\/10\/storia-bolivia-alimentare_fb.jpg","type":"image\/jpeg"}],"author":"carlottaZ","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.aibi.it\/ita\/images\/2020\/10\/storia-bolivia-alimentare_fb.jpg","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"carlottaZ","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/bolivia-e-se-la-salute-non-e-un-diritto-garantitoci-sono-degli-angeli-custodi\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-e-se-la-salute-non-e-un-diritto-garantitoci-sono-degli-angeli-custodi\/"},"author":{"name":"carlottaZ","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/95193f4e7a1f2190922687ebf84f96c9"},"headline":"Bolivia. E se la salute non \u00e8 un diritto garantito\u2026 ci sono degli angeli custodi!","datePublished":"2020-10-05T14:18:07+00:00","dateModified":"2022-07-25T15:28:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-e-se-la-salute-non-e-un-diritto-garantitoci-sono-degli-angeli-custodi\/"},"wordCount":460,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-e-se-la-salute-non-e-un-diritto-garantitoci-sono-degli-angeli-custodi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2020\/10\/storia-bolivia-alimentare_fb.jpg","keywords":["Bolivia","Jos\u00e8 Soria","sostegno a distanza"],"articleSection":["Adozione a Distanza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/bolivia-e-se-la-salute-non-e-un-diritto-garantitoci-sono-degli-angeli-custodi\/","url":"https:\/\/www.aibi.it\/ita\/bolivia-e-se-la-salute-non-e-un-diritto-garantitoci-sono-degli-angeli-custodi\/","name":"Bolivia. E se la salute non \u00e8 un diritto garantito\u2026 ci sono degli angeli custodi! - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-e-se-la-salute-non-e-un-diritto-garantitoci-sono-degli-angeli-custodi\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-e-se-la-salute-non-e-un-diritto-garantitoci-sono-degli-angeli-custodi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2020\/10\/storia-bolivia-alimentare_fb.jpg","datePublished":"2020-10-05T14:18:07+00:00","dateModified":"2022-07-25T15:28:04+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-e-se-la-salute-non-e-un-diritto-garantitoci-sono-degli-angeli-custodi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/bolivia-e-se-la-salute-non-e-un-diritto-garantitoci-sono-degli-angeli-custodi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/bolivia-e-se-la-salute-non-e-un-diritto-garantitoci-sono-degli-angeli-custodi\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2020\/10\/storia-bolivia-alimentare_fb.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2020\/10\/storia-bolivia-alimentare_fb.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/bolivia-e-se-la-salute-non-e-un-diritto-garantitoci-sono-degli-angeli-custodi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione a Distanza","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-a-distanza\/"},{"@type":"ListItem","position":3,"name":"Bolivia. E se la salute non \u00e8 un diritto garantito\u2026 ci sono degli angeli custodi!"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/95193f4e7a1f2190922687ebf84f96c9","name":"carlottaZ","sameAs":["cellos"],"url":"https:\/\/www.aibi.it\/ita\/author\/carlottaz\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 10:33:10","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/180123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/113"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=180123"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/180123\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/180118"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=180123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=180123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=180123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}