﻿{"id":180657,"date":"2020-10-23T12:53:19","date_gmt":"2020-10-23T10:53:19","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=180657"},"modified":"2020-10-23T15:33:45","modified_gmt":"2020-10-23T13:33:45","slug":"coronavirus-ed-esplosione-di-contagi-dito-puntato-sulla-riapertura-delle-scuole","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/coronavirus-ed-esplosione-di-contagi-dito-puntato-sulla-riapertura-delle-scuole\/","title":{"rendered":"Coronavirus ed esplosione di contagi: dito puntato sulla riapertura delle scuole"},"content":{"rendered":"<h2>Presidi e sindacati protestano contro l&#8217;ordinanza del governatore lombardo Fontana. Ma i numeri sono difficilmente contestabili<\/h2>\n<p>A causa del Coronavirus dopo la <strong>Campania<\/strong>, anche la <strong>Lombardia<\/strong> si appresta a una chiusura delle scuole. Da luned\u00ec gli istituti superiori torneranno infatti alle lezioni a distanza. Anche la <strong>Puglia<\/strong> ha approntato un simile provvedimento che, da luned\u00ec, riguarder\u00e0 le classi dalla terza superiore in su per tre settimane. Purtroppo, piaccia o meno, i numeri stanno infatti dicendo che l&#8217;esplosione dei contagi da Coronavirus si sia manifestata a due settimane dalla riapertura dei plessi scolastici e il dato sta facendo riflettere le giunte regionali. Ma <em>&#8220;la maggior parte degli istituti per ripartire dopo mesi di lockdown ha puntato (anche) ad alleggerire le presenze<\/em>&#8220;, come spiega il <strong><em>Corriere della Sera<\/em><\/strong> e quindi la transizione verso la didattica a distanza era iniziata gi\u00e0 da settembre.<\/p>\n<h3>Coronavirus, contagi e scuole: la triste e dura realt\u00e0<\/h3>\n<p>Tale situazione, e in particolare la decisione di <strong>Regione Lombardia<\/strong> e del suo <strong>governatore, Attilio Fontana<\/strong>, non \u00e8 tuttavia stata digerita dal presidente dell&#8217;<strong>associazione nazionale dei presidi, Antonello Giannelli<\/strong>, che ha messo in dubbio la leggitimit\u00e0 costituzionale dell&#8217;ordinanza, citando l&#8217;articolo 7 della Costituzione che dice che &#8220;<em>l&#8217;organizzazione delle attivit\u00e0 scolastiche non pu\u00f2 essere imposta alle scuole&#8221;.<\/em> Anche i sindacati hanno espresso perplessit\u00e0. &#8220;<em>Lasciare a casa i ragazzi \u00e8 un errore<\/em> &#8211; dice <strong>Tobia Settori, della CGIL regionale<\/strong> &#8211;<em> I contagi non avvengono l\u00ec, le aule sono sicure e la didattica era gi\u00e0 mista nel 90% degli istituti. L&#8217;ordinanza si riferisce poi a tutte le classi, anche agli studenti delle prime appena inseriti e a quelli che dovranno sostenere l&#8217;esame di maturit\u00e0&#8221;.<\/em><\/p>\n<p>Resta per\u00f2 il fatto che, sebbene i presidi puntino il dito sulle attivit\u00e0 extra-scolastiche, tale posizione risulta difficile da sostenere: gli studenti, quando le scuole erano chiuse per le vacanze estive, sono sempre andati in giro e hanno anzi avuto a disposizione molto pi\u00f9 tempo per la socialit\u00e0 rispetto a quanto \u00e8 accaduto dalla riapertura delle scuole. Eppure non vi era alcuna esplosione di contagi.<\/p>\n<p><strong>Forse \u00e8 duro ammettere che la scuola abbia avuto un ruolo nella risalita dei numeri, ma, a ben considerare, sembra essere la triste realt\u00e0.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Presidi e sindacati protestano contro l&rsquo;ordinanza del governatore lombardo Fontana. Ma i numeri sono difficilmente contestabili A causa del Coronavirus dopo la Campania, anche la Lombardia si appresta a una chiusura delle scuole. Da luned&igrave; gli istituti superiori torneranno infatti alle lezioni a distanza. Anche la Puglia ha approntato un [&hellip;]<\/p>\n","protected":false},"author":91,"featured_media":180572,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[292,716,545],"class_list":["post-180657","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews","tag-governo","tag-regione-lombardia","tag-scuola"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Coronavirus e contagi: si punta il dito sulle scuole. La triste realt\u00e0<\/title>\n<meta name=\"description\" content=\"Coronavirus e contagi: si punta il dito sulle scuole. La triste realt\u00e0. Coronavirus, contagi e scuole: una relazione confermata?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/coronavirus-ed-esplosione-di-contagi-dito-puntato-sulla-riapertura-delle-scuole\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coronavirus ed esplosione di contagi: dito puntato sulla riapertura delle scuole\" \/>\n<meta property=\"og:description\" content=\"Presidi e sindacati protestano contro l&#039;ordinanza del governatore lombardo Fontana. Ma i numeri sono difficilmente contestabili\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/coronavirus-ed-esplosione-di-contagi-dito-puntato-sulla-riapertura-delle-scuole\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-23T10:53:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-23T13:33:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/10\/ragazzi_COVID.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cristianoP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Coronavirus ed esplosione di contagi: dito puntato sulla riapertura delle scuole\" \/>\n<meta name=\"twitter:description\" content=\"Presidi e sindacati protestano contro l&#039;ordinanza del governatore lombardo Fontana. Ma i numeri sono difficilmente contestabili\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/10\/ragazzi_COVID.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"cristianoP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/coronavirus-ed-esplosione-di-contagi-dito-puntato-sulla-riapertura-delle-scuole\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/coronavirus-ed-esplosione-di-contagi-dito-puntato-sulla-riapertura-delle-scuole\\\/\"},\"author\":{\"name\":\"cristianoP\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/b9065848ca5b5cf9a80fad6f849d2c17\"},\"headline\":\"Coronavirus ed esplosione di contagi: dito puntato sulla riapertura delle scuole\",\"datePublished\":\"2020-10-23T10:53:19+00:00\",\"dateModified\":\"2020-10-23T13:33:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/coronavirus-ed-esplosione-di-contagi-dito-puntato-sulla-riapertura-delle-scuole\\\/\"},\"wordCount\":372,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/coronavirus-ed-esplosione-di-contagi-dito-puntato-sulla-riapertura-delle-scuole\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/10\\\/ragazzi_COVID.jpg\",\"keywords\":[\"Governo\",\"Regione Lombardia\",\"scuola\"],\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/coronavirus-ed-esplosione-di-contagi-dito-puntato-sulla-riapertura-delle-scuole\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/coronavirus-ed-esplosione-di-contagi-dito-puntato-sulla-riapertura-delle-scuole\\\/\",\"name\":\"Coronavirus e contagi: si punta il dito sulle scuole. La triste realt\u00e0\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/coronavirus-ed-esplosione-di-contagi-dito-puntato-sulla-riapertura-delle-scuole\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/coronavirus-ed-esplosione-di-contagi-dito-puntato-sulla-riapertura-delle-scuole\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/10\\\/ragazzi_COVID.jpg\",\"datePublished\":\"2020-10-23T10:53:19+00:00\",\"dateModified\":\"2020-10-23T13:33:45+00:00\",\"description\":\"Coronavirus e contagi: si punta il dito sulle scuole. La triste realt\u00e0. Coronavirus, contagi e scuole: una relazione confermata?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/coronavirus-ed-esplosione-di-contagi-dito-puntato-sulla-riapertura-delle-scuole\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/coronavirus-ed-esplosione-di-contagi-dito-puntato-sulla-riapertura-delle-scuole\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/coronavirus-ed-esplosione-di-contagi-dito-puntato-sulla-riapertura-delle-scuole\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/10\\\/ragazzi_COVID.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/10\\\/ragazzi_COVID.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/coronavirus-ed-esplosione-di-contagi-dito-puntato-sulla-riapertura-delle-scuole\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Coronavirus ed esplosione di contagi: dito puntato sulla riapertura delle scuole\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/b9065848ca5b5cf9a80fad6f849d2c17\",\"name\":\"cristianoP\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cristianop\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Coronavirus e contagi: si punta il dito sulle scuole. La triste realt\u00e0","description":"Coronavirus e contagi: si punta il dito sulle scuole. La triste realt\u00e0. Coronavirus, contagi e scuole: una relazione confermata?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/coronavirus-ed-esplosione-di-contagi-dito-puntato-sulla-riapertura-delle-scuole\/","og_locale":"it_IT","og_type":"article","og_title":"Coronavirus ed esplosione di contagi: dito puntato sulla riapertura delle scuole","og_description":"Presidi e sindacati protestano contro l'ordinanza del governatore lombardo Fontana. Ma i numeri sono difficilmente contestabili","og_url":"https:\/\/www.aibi.it\/ita\/coronavirus-ed-esplosione-di-contagi-dito-puntato-sulla-riapertura-delle-scuole\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2020-10-23T10:53:19+00:00","article_modified_time":"2020-10-23T13:33:45+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2020\/10\/ragazzi_COVID.jpg","type":"image\/jpeg"}],"author":"cristianoP","twitter_card":"summary_large_image","twitter_title":"Coronavirus ed esplosione di contagi: dito puntato sulla riapertura delle scuole","twitter_description":"Presidi e sindacati protestano contro l'ordinanza del governatore lombardo Fontana. Ma i numeri sono difficilmente contestabili","twitter_image":"https:\/\/www.aibi.it\/ita\/images\/2020\/10\/ragazzi_COVID.jpg","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"cristianoP","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/coronavirus-ed-esplosione-di-contagi-dito-puntato-sulla-riapertura-delle-scuole\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/coronavirus-ed-esplosione-di-contagi-dito-puntato-sulla-riapertura-delle-scuole\/"},"author":{"name":"cristianoP","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/b9065848ca5b5cf9a80fad6f849d2c17"},"headline":"Coronavirus ed esplosione di contagi: dito puntato sulla riapertura delle scuole","datePublished":"2020-10-23T10:53:19+00:00","dateModified":"2020-10-23T13:33:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/coronavirus-ed-esplosione-di-contagi-dito-puntato-sulla-riapertura-delle-scuole\/"},"wordCount":372,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/coronavirus-ed-esplosione-di-contagi-dito-puntato-sulla-riapertura-delle-scuole\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2020\/10\/ragazzi_COVID.jpg","keywords":["Governo","Regione Lombardia","scuola"],"articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/coronavirus-ed-esplosione-di-contagi-dito-puntato-sulla-riapertura-delle-scuole\/","url":"https:\/\/www.aibi.it\/ita\/coronavirus-ed-esplosione-di-contagi-dito-puntato-sulla-riapertura-delle-scuole\/","name":"Coronavirus e contagi: si punta il dito sulle scuole. La triste realt\u00e0","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/coronavirus-ed-esplosione-di-contagi-dito-puntato-sulla-riapertura-delle-scuole\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/coronavirus-ed-esplosione-di-contagi-dito-puntato-sulla-riapertura-delle-scuole\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2020\/10\/ragazzi_COVID.jpg","datePublished":"2020-10-23T10:53:19+00:00","dateModified":"2020-10-23T13:33:45+00:00","description":"Coronavirus e contagi: si punta il dito sulle scuole. La triste realt\u00e0. Coronavirus, contagi e scuole: una relazione confermata?","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/coronavirus-ed-esplosione-di-contagi-dito-puntato-sulla-riapertura-delle-scuole\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/coronavirus-ed-esplosione-di-contagi-dito-puntato-sulla-riapertura-delle-scuole\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/coronavirus-ed-esplosione-di-contagi-dito-puntato-sulla-riapertura-delle-scuole\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2020\/10\/ragazzi_COVID.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2020\/10\/ragazzi_COVID.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/coronavirus-ed-esplosione-di-contagi-dito-puntato-sulla-riapertura-delle-scuole\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Coronavirus ed esplosione di contagi: dito puntato sulla riapertura delle scuole"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/b9065848ca5b5cf9a80fad6f849d2c17","name":"cristianoP","url":"https:\/\/www.aibi.it\/ita\/author\/cristianop\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 04:17:16","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/180657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/91"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=180657"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/180657\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/180572"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=180657"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=180657"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=180657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}