﻿


{"id":180881,"date":"2020-10-29T08:00:10","date_gmt":"2020-10-29T07:00:10","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=180881"},"modified":"2020-10-28T21:02:31","modified_gmt":"2020-10-28T20:02:31","slug":"lockdown-ecco-le-nuove-regole-per-la-didattica-a-distanza-con-il-25-in-meno-di-lezioni-si-ripete-lanno","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/lockdown-ecco-le-nuove-regole-per-la-didattica-a-distanza-con-il-25-in-meno-di-lezioni-si-ripete-lanno\/","title":{"rendered":"Lockdown. Ecco le nuove regole per la didattica a distanza: con il 25% in meno di lezioni si ripete l\u2019anno"},"content":{"rendered":"<h2 style=\"font-weight: 400;\"><strong><b>Puntualit\u00e0, vestiti in ordine, telecamera accesa, lezioni da 50 minuti, assenze da giustificare. Queste le linee di comportamento stabilite dal Ministero dell&#8217;Istruzione.<\/b><\/strong><\/h2>\n<p style=\"font-weight: 400;\">Non ci sono dubbi, l\u2019<strong>emergenza coronavirus<\/strong> ha comportato una modifica radicale del modo di fare scuola. Tra mascherine, distanziamento e regole sanitarie, accanto alle tradizionali lezioni in presenza, la didattica a distanza ha preso sempre pi\u00f9 piede nella vita scolastica di insegnanti ed alunni. Anche l\u2019ultimo dpcm emanato dal governo Conte parla chiaro, sancendo per gli studenti degli istituti superiori una<strong> dad pari almeno al 75% delle attivit\u00e0.<\/strong><\/p>\n<p style=\"font-weight: 400;\">Ma se cos\u00ec deve essere, \u00e8 corretto che per rispetto di insegnanti e compagni, anche per le lezioni da remoto venga stilato un <strong>codice di comportamento<\/strong> che regolamenti la scuola a distanza proprio come quella in presenza.\u00a0Ci ha pensato il Ministero dell\u2019istruzione.<\/p>\n<p style=\"font-weight: 400;\">Basta studenti annoiati in pigiama o impegnati a fare colazione mentre l\u2019insegnante tiene lezione.\u00a0Telecamera accesa ad inquadrare lo studente, <strong>microfono disattivato<\/strong> per non disturbare la classe con rumori di sottofondo e divieto di riprendere o fotografare le immagini sullo schermo senza richiedere il permesso, a tutela della privacy sono d\u2019obbligo.<\/p>\n<p style=\"font-weight: 400;\">La puntualit\u00e0 \u00e8 poi da considerare regola fondamentale in presenza come da remoto. Anche\u00a0\u00a0le assenze \u201con line\u201d saranno infatti conteggiate dagli insegnanti nel calcolo di quelle totali.\u00a0<strong>Con il 25% in meno di lezioni si ripeter\u00e0 l\u2019anno.\u00a0<\/strong>E per venire incontro alle difficolt\u00e0 dei docenti e al maggior pericolo di distrazione degli studenti si ad ore di lezione ridotte che potranno essere anche di 40- 45 minuti.<\/p>\n<p style=\"font-weight: 400;\">Perch\u00e9 come sottolinea <strong>Mario Rusconi,<\/strong> presidente nazionale dei Presidi di Roma e del Lazio, sul quotidiano il Messaggero: \u201c<em>Educazione e rispetto devono essere presenti in classe cos\u00ec come on line\u201d.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Puntualit&agrave;, vestiti in ordine, telecamera accesa, lezioni da 50 minuti, assenze da giustificare. Queste le linee di comportamento stabilite dal Ministero dell&rsquo;Istruzione. Non ci sono dubbi, l&rsquo;emergenza coronavirus ha comportato una modifica radicale del modo di fare scuola. Tra mascherine, distanziamento e regole sanitarie, accanto alle tradizionali lezioni in presenza, [&hellip;]<\/p>\n","protected":false},"author":97,"featured_media":180883,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[545],"class_list":["post-180881","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews","tag-scuola"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Lockdown. Ecco le nuove regole per la didattica a distanza: con il 25% in meno di lezioni si ripete l\u2019anno - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"Didattica a distanza: puntualit\u00e0, vestiti in ordine, telecamera accesa, lezioni da 50 minuti, assenze da giustificare. Ecco le linee del Miur\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/lockdown-ecco-le-nuove-regole-per-la-didattica-a-distanza-con-il-25-in-meno-di-lezioni-si-ripete-lanno\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lockdown. Ecco le nuove regole per la didattica a distanza: con il 25% in meno di lezioni si ripete l\u2019anno\" \/>\n<meta property=\"og:description\" content=\"Puntualit\u00e0, vestiti in ordine, telecamera accesa, lezioni da 50 minuti, assenze da giustificare. Queste le linee di comportamento stabilite dal Ministero dell&#039;Istruzione.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/lockdown-ecco-le-nuove-regole-per-la-didattica-a-distanza-con-il-25-in-meno-di-lezioni-si-ripete-lanno\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-29T07:00:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/10\/didattica-a-distanza.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mc.sabatini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mc.sabatini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/lockdown-ecco-le-nuove-regole-per-la-didattica-a-distanza-con-il-25-in-meno-di-lezioni-si-ripete-lanno\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/lockdown-ecco-le-nuove-regole-per-la-didattica-a-distanza-con-il-25-in-meno-di-lezioni-si-ripete-lanno\\\/\"},\"author\":{\"name\":\"mc.sabatini\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\"},\"headline\":\"Lockdown. Ecco le nuove regole per la didattica a distanza: con il 25% in meno di lezioni si ripete l\u2019anno\",\"datePublished\":\"2020-10-29T07:00:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/lockdown-ecco-le-nuove-regole-per-la-didattica-a-distanza-con-il-25-in-meno-di-lezioni-si-ripete-lanno\\\/\"},\"wordCount\":303,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/lockdown-ecco-le-nuove-regole-per-la-didattica-a-distanza-con-il-25-in-meno-di-lezioni-si-ripete-lanno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/10\\\/didattica-a-distanza.jpg\",\"keywords\":[\"scuola\"],\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/lockdown-ecco-le-nuove-regole-per-la-didattica-a-distanza-con-il-25-in-meno-di-lezioni-si-ripete-lanno\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/lockdown-ecco-le-nuove-regole-per-la-didattica-a-distanza-con-il-25-in-meno-di-lezioni-si-ripete-lanno\\\/\",\"name\":\"Lockdown. Ecco le nuove regole per la didattica a distanza: con il 25% in meno di lezioni si ripete l\u2019anno - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/lockdown-ecco-le-nuove-regole-per-la-didattica-a-distanza-con-il-25-in-meno-di-lezioni-si-ripete-lanno\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/lockdown-ecco-le-nuove-regole-per-la-didattica-a-distanza-con-il-25-in-meno-di-lezioni-si-ripete-lanno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/10\\\/didattica-a-distanza.jpg\",\"datePublished\":\"2020-10-29T07:00:10+00:00\",\"description\":\"Didattica a distanza: puntualit\u00e0, vestiti in ordine, telecamera accesa, lezioni da 50 minuti, assenze da giustificare. Ecco le linee del Miur\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/lockdown-ecco-le-nuove-regole-per-la-didattica-a-distanza-con-il-25-in-meno-di-lezioni-si-ripete-lanno\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/lockdown-ecco-le-nuove-regole-per-la-didattica-a-distanza-con-il-25-in-meno-di-lezioni-si-ripete-lanno\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/lockdown-ecco-le-nuove-regole-per-la-didattica-a-distanza-con-il-25-in-meno-di-lezioni-si-ripete-lanno\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/10\\\/didattica-a-distanza.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/10\\\/didattica-a-distanza.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/lockdown-ecco-le-nuove-regole-per-la-didattica-a-distanza-con-il-25-in-meno-di-lezioni-si-ripete-lanno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lockdown. Ecco le nuove regole per la didattica a distanza: con il 25% in meno di lezioni si ripete l\u2019anno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\",\"name\":\"mc.sabatini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/marias\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Lockdown. Ecco le nuove regole per la didattica a distanza: con il 25% in meno di lezioni si ripete l\u2019anno - Ai.Bi. Amici dei Bambini","description":"Didattica a distanza: puntualit\u00e0, vestiti in ordine, telecamera accesa, lezioni da 50 minuti, assenze da giustificare. Ecco le linee del Miur","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/lockdown-ecco-le-nuove-regole-per-la-didattica-a-distanza-con-il-25-in-meno-di-lezioni-si-ripete-lanno\/","og_locale":"it_IT","og_type":"article","og_title":"Lockdown. Ecco le nuove regole per la didattica a distanza: con il 25% in meno di lezioni si ripete l\u2019anno","og_description":"Puntualit\u00e0, vestiti in ordine, telecamera accesa, lezioni da 50 minuti, assenze da giustificare. Queste le linee di comportamento stabilite dal Ministero dell'Istruzione.","og_url":"https:\/\/www.aibi.it\/ita\/lockdown-ecco-le-nuove-regole-per-la-didattica-a-distanza-con-il-25-in-meno-di-lezioni-si-ripete-lanno\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2020-10-29T07:00:10+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2020\/10\/didattica-a-distanza.jpg","type":"image\/jpeg"}],"author":"mc.sabatini","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"mc.sabatini","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/lockdown-ecco-le-nuove-regole-per-la-didattica-a-distanza-con-il-25-in-meno-di-lezioni-si-ripete-lanno\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/lockdown-ecco-le-nuove-regole-per-la-didattica-a-distanza-con-il-25-in-meno-di-lezioni-si-ripete-lanno\/"},"author":{"name":"mc.sabatini","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938"},"headline":"Lockdown. Ecco le nuove regole per la didattica a distanza: con il 25% in meno di lezioni si ripete l\u2019anno","datePublished":"2020-10-29T07:00:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/lockdown-ecco-le-nuove-regole-per-la-didattica-a-distanza-con-il-25-in-meno-di-lezioni-si-ripete-lanno\/"},"wordCount":303,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/lockdown-ecco-le-nuove-regole-per-la-didattica-a-distanza-con-il-25-in-meno-di-lezioni-si-ripete-lanno\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2020\/10\/didattica-a-distanza.jpg","keywords":["scuola"],"articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/lockdown-ecco-le-nuove-regole-per-la-didattica-a-distanza-con-il-25-in-meno-di-lezioni-si-ripete-lanno\/","url":"https:\/\/www.aibi.it\/ita\/lockdown-ecco-le-nuove-regole-per-la-didattica-a-distanza-con-il-25-in-meno-di-lezioni-si-ripete-lanno\/","name":"Lockdown. Ecco le nuove regole per la didattica a distanza: con il 25% in meno di lezioni si ripete l\u2019anno - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/lockdown-ecco-le-nuove-regole-per-la-didattica-a-distanza-con-il-25-in-meno-di-lezioni-si-ripete-lanno\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/lockdown-ecco-le-nuove-regole-per-la-didattica-a-distanza-con-il-25-in-meno-di-lezioni-si-ripete-lanno\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2020\/10\/didattica-a-distanza.jpg","datePublished":"2020-10-29T07:00:10+00:00","description":"Didattica a distanza: puntualit\u00e0, vestiti in ordine, telecamera accesa, lezioni da 50 minuti, assenze da giustificare. Ecco le linee del Miur","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/lockdown-ecco-le-nuove-regole-per-la-didattica-a-distanza-con-il-25-in-meno-di-lezioni-si-ripete-lanno\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/lockdown-ecco-le-nuove-regole-per-la-didattica-a-distanza-con-il-25-in-meno-di-lezioni-si-ripete-lanno\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/lockdown-ecco-le-nuove-regole-per-la-didattica-a-distanza-con-il-25-in-meno-di-lezioni-si-ripete-lanno\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2020\/10\/didattica-a-distanza.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2020\/10\/didattica-a-distanza.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/lockdown-ecco-le-nuove-regole-per-la-didattica-a-distanza-con-il-25-in-meno-di-lezioni-si-ripete-lanno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Lockdown. Ecco le nuove regole per la didattica a distanza: con il 25% in meno di lezioni si ripete l\u2019anno"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938","name":"mc.sabatini","url":"https:\/\/www.aibi.it\/ita\/author\/marias\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 19:50:18","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/180881","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/97"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=180881"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/180881\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/180883"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=180881"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=180881"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=180881"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}