﻿


{"id":182452,"date":"2020-11-06T12:28:13","date_gmt":"2020-11-06T11:28:13","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=182452"},"modified":"2021-05-04T18:02:44","modified_gmt":"2021-05-04T16:02:44","slug":"adozione-internazionale-piu-forte-del-coronavirus-da-marzo-2020-venti-bambini-adottati-da-ungheria-e-repubblica-ceca","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-piu-forte-del-coronavirus-da-marzo-2020-venti-bambini-adottati-da-ungheria-e-repubblica-ceca\/","title":{"rendered":"Adozione Internazionale pi\u00f9 forte del Coronavirus. Da marzo 2020, venti bambini adottati da Ungheria e Repubblica Ceca"},"content":{"rendered":"<h2>Nonostante l&#8217;emergenza Covid l&#8217;accoglienza, con LIAN, non si \u00e8 fermata<\/h2>\n<p>Nonostante le difficolt\u00e0 del periodo, dettate dall\u2019emergenza <strong>Covid<\/strong>, l\u2019adozione internazionale in <strong>Ungheria<\/strong> e <strong>Repubblica Ceca<\/strong> non si \u00e8 fermata. Da marzo 2020, ovvero dall\u2019inizio delle limitazioni negli spostamenti, sono stati adottati con <strong>Asa Onlus<\/strong> (ente membro di <strong>LIAN &#8211; Life in Adoption Network<\/strong>) ben 20 minori. 20 bambini hanno cos\u00ec trovato una famiglia, tra le braccia di mamme e pap\u00e0 che, nonostante le difficolt\u00e0, non hanno mai smesso di credere che sarebbe andato tutto bene.<\/p>\n<p>Cos\u00ec, facendo le valigie per tornare a casa, una mamma e un pap\u00e0 che hanno ricevuto il regalo pi\u00f9 bello dalla vita, scrivono un pensiero. Un pensiero che emoziona e che ci porta a continuare a sperare che <strong><em>\u201candr\u00e0 tutto bene\u201d.<\/em><\/strong><\/p>\n<p>Ecco di seguito il messaggio della coppia, di ritorno in Italia.<\/p>\n<blockquote><p>&#8220;Buongiorno, mentre ci prepariamo per tornare a casa un grazie dal profondo del nostro cuore per la cura e l\u2019attenzione che tutta l\u2019associazione ci ha riservato fin dal primo giorno in cui abbiamo intrapreso questo percorso. Anche qui non ci hanno fatto mancare nessun tipo di aiuto e sostegno in mezzo a lungaggini burocratiche e Covid. Torniamo a casa con i nostri bimbi che tutti gi\u00e0 non vedono l\u2019ora di conoscere e siamo sicuri che il futuro sar\u00e0 ancora pi\u00f9 bello. Un abbraccio da tutti noi e a presto&#8221;<\/p>\n<p><strong>Una mamma e un pap\u00e0 felici<\/strong><\/p><\/blockquote>\n<p><em>&#8220;Messaggi come questi<\/em> &#8211; afferma il <strong>presidente Asa Onlus, la dottoressa Maria Virgillito<\/strong> &#8211; f<em>anno capire quanto sia importante e fondamentale, per le coppie, avere dei punti di riferimento, soprattutto durante la permanenza all\u2019Estero. In questo delicato momento che stiamo vivendo &#8211; conclude il presidente Asa &#8211; gli faremo sentire ancor di pi\u00f9 la nostra vicinanza e il nostro sostegno\u201d.<\/em><\/p>\n<p>Oltre ad <strong>Asa Onlus<\/strong>, fanno parte di LIAN: <strong>Ai.Bi., Ariete Onlus, CIFA<\/strong> e <strong>Fondazione Patrizia Nidoli<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nonostante l&rsquo;emergenza Covid l&rsquo;accoglienza, con LIAN, non si &egrave; fermata Nonostante le difficolt&agrave; del periodo, dettate dall&rsquo;emergenza Covid, l&rsquo;adozione internazionale in Ungheria e Repubblica Ceca non si &egrave; fermata. Da marzo 2020, ovvero dall&rsquo;inizio delle limitazioni negli spostamenti, sono stati adottati con Asa Onlus (ente membro di LIAN &ndash; Life [&hellip;]<\/p>\n","protected":false},"author":91,"featured_media":182453,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[172,711],"tags":[347,710,727,358],"class_list":["post-182452","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-internazionale","category-lian","tag-adozione-internazionale","tag-lian","tag-repubblica-ceca","tag-ungheria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozione Internazionale in Ungheria e Repubblica Ceca: si va avanti<\/title>\n<meta name=\"description\" content=\"Adozione Internazionale in Ungheria e Repubblica Ceca: si va avanti nonostante il Covid. Adozione Internazionale in Ungheria: i dati 2020.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-piu-forte-del-coronavirus-da-marzo-2020-venti-bambini-adottati-da-ungheria-e-repubblica-ceca\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozione Internazionale pi\u00f9 forte del Coronavirus. Da marzo 2020 ,venti bambini adottati da Ungheria e Repubblica Ceca\" \/>\n<meta property=\"og:description\" content=\"Nonostante l&#039;emergenza Covid l&#039;accoglienza, con LIAN, non si \u00e8 fermata\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-piu-forte-del-coronavirus-da-marzo-2020-venti-bambini-adottati-da-ungheria-e-repubblica-ceca\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-06T11:28:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-04T16:02:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/11\/bambole.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cristianoP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Adozione Internazionale pi\u00f9 forte del Coronavirus. Da marzo 2020 ,venti bambini adottati da Ungheria e Repubblica Ceca\" \/>\n<meta name=\"twitter:description\" content=\"Nonostante l&#039;emergenza Covid l&#039;accoglienza, con LIAN, non si \u00e8 fermata\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/11\/bambole.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"cristianoP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-piu-forte-del-coronavirus-da-marzo-2020-venti-bambini-adottati-da-ungheria-e-repubblica-ceca\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-piu-forte-del-coronavirus-da-marzo-2020-venti-bambini-adottati-da-ungheria-e-repubblica-ceca\\\/\"},\"author\":{\"name\":\"cristianoP\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/b9065848ca5b5cf9a80fad6f849d2c17\"},\"headline\":\"Adozione Internazionale pi\u00f9 forte del Coronavirus. Da marzo 2020, venti bambini adottati da Ungheria e Repubblica Ceca\",\"datePublished\":\"2020-11-06T11:28:13+00:00\",\"dateModified\":\"2021-05-04T16:02:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-piu-forte-del-coronavirus-da-marzo-2020-venti-bambini-adottati-da-ungheria-e-repubblica-ceca\\\/\"},\"wordCount\":329,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-piu-forte-del-coronavirus-da-marzo-2020-venti-bambini-adottati-da-ungheria-e-repubblica-ceca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/11\\\/bambole.jpg\",\"keywords\":[\"Adozione Internazionale\",\"LIAN\",\"Repubblica Ceca\",\"Ungheria\"],\"articleSection\":[\"Adozione Internazionale\",\"Life in Adoption Network\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-piu-forte-del-coronavirus-da-marzo-2020-venti-bambini-adottati-da-ungheria-e-repubblica-ceca\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-piu-forte-del-coronavirus-da-marzo-2020-venti-bambini-adottati-da-ungheria-e-repubblica-ceca\\\/\",\"name\":\"Adozione Internazionale in Ungheria e Repubblica Ceca: si va avanti\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-piu-forte-del-coronavirus-da-marzo-2020-venti-bambini-adottati-da-ungheria-e-repubblica-ceca\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-piu-forte-del-coronavirus-da-marzo-2020-venti-bambini-adottati-da-ungheria-e-repubblica-ceca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/11\\\/bambole.jpg\",\"datePublished\":\"2020-11-06T11:28:13+00:00\",\"dateModified\":\"2021-05-04T16:02:44+00:00\",\"description\":\"Adozione Internazionale in Ungheria e Repubblica Ceca: si va avanti nonostante il Covid. Adozione Internazionale in Ungheria: i dati 2020.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-piu-forte-del-coronavirus-da-marzo-2020-venti-bambini-adottati-da-ungheria-e-repubblica-ceca\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-piu-forte-del-coronavirus-da-marzo-2020-venti-bambini-adottati-da-ungheria-e-repubblica-ceca\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-piu-forte-del-coronavirus-da-marzo-2020-venti-bambini-adottati-da-ungheria-e-repubblica-ceca\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/11\\\/bambole.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/11\\\/bambole.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-piu-forte-del-coronavirus-da-marzo-2020-venti-bambini-adottati-da-ungheria-e-repubblica-ceca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione Internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-internazionale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozione Internazionale pi\u00f9 forte del Coronavirus. Da marzo 2020, venti bambini adottati da Ungheria e Repubblica Ceca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/b9065848ca5b5cf9a80fad6f849d2c17\",\"name\":\"cristianoP\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cristianop\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozione Internazionale in Ungheria e Repubblica Ceca: si va avanti","description":"Adozione Internazionale in Ungheria e Repubblica Ceca: si va avanti nonostante il Covid. Adozione Internazionale in Ungheria: i dati 2020.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-piu-forte-del-coronavirus-da-marzo-2020-venti-bambini-adottati-da-ungheria-e-repubblica-ceca\/","og_locale":"it_IT","og_type":"article","og_title":"Adozione Internazionale pi\u00f9 forte del Coronavirus. Da marzo 2020 ,venti bambini adottati da Ungheria e Repubblica Ceca","og_description":"Nonostante l'emergenza Covid l'accoglienza, con LIAN, non si \u00e8 fermata","og_url":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-piu-forte-del-coronavirus-da-marzo-2020-venti-bambini-adottati-da-ungheria-e-repubblica-ceca\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2020-11-06T11:28:13+00:00","article_modified_time":"2021-05-04T16:02:44+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2020\/11\/bambole.jpg","type":"image\/jpeg"}],"author":"cristianoP","twitter_card":"summary_large_image","twitter_title":"Adozione Internazionale pi\u00f9 forte del Coronavirus. Da marzo 2020 ,venti bambini adottati da Ungheria e Repubblica Ceca","twitter_description":"Nonostante l'emergenza Covid l'accoglienza, con LIAN, non si \u00e8 fermata","twitter_image":"https:\/\/www.aibi.it\/ita\/images\/2020\/11\/bambole.jpg","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"cristianoP","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-piu-forte-del-coronavirus-da-marzo-2020-venti-bambini-adottati-da-ungheria-e-repubblica-ceca\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-piu-forte-del-coronavirus-da-marzo-2020-venti-bambini-adottati-da-ungheria-e-repubblica-ceca\/"},"author":{"name":"cristianoP","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/b9065848ca5b5cf9a80fad6f849d2c17"},"headline":"Adozione Internazionale pi\u00f9 forte del Coronavirus. Da marzo 2020, venti bambini adottati da Ungheria e Repubblica Ceca","datePublished":"2020-11-06T11:28:13+00:00","dateModified":"2021-05-04T16:02:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-piu-forte-del-coronavirus-da-marzo-2020-venti-bambini-adottati-da-ungheria-e-repubblica-ceca\/"},"wordCount":329,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-piu-forte-del-coronavirus-da-marzo-2020-venti-bambini-adottati-da-ungheria-e-repubblica-ceca\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2020\/11\/bambole.jpg","keywords":["Adozione Internazionale","LIAN","Repubblica Ceca","Ungheria"],"articleSection":["Adozione Internazionale","Life in Adoption Network"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-piu-forte-del-coronavirus-da-marzo-2020-venti-bambini-adottati-da-ungheria-e-repubblica-ceca\/","url":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-piu-forte-del-coronavirus-da-marzo-2020-venti-bambini-adottati-da-ungheria-e-repubblica-ceca\/","name":"Adozione Internazionale in Ungheria e Repubblica Ceca: si va avanti","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-piu-forte-del-coronavirus-da-marzo-2020-venti-bambini-adottati-da-ungheria-e-repubblica-ceca\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-piu-forte-del-coronavirus-da-marzo-2020-venti-bambini-adottati-da-ungheria-e-repubblica-ceca\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2020\/11\/bambole.jpg","datePublished":"2020-11-06T11:28:13+00:00","dateModified":"2021-05-04T16:02:44+00:00","description":"Adozione Internazionale in Ungheria e Repubblica Ceca: si va avanti nonostante il Covid. Adozione Internazionale in Ungheria: i dati 2020.","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-piu-forte-del-coronavirus-da-marzo-2020-venti-bambini-adottati-da-ungheria-e-repubblica-ceca\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozione-internazionale-piu-forte-del-coronavirus-da-marzo-2020-venti-bambini-adottati-da-ungheria-e-repubblica-ceca\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-piu-forte-del-coronavirus-da-marzo-2020-venti-bambini-adottati-da-ungheria-e-repubblica-ceca\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2020\/11\/bambole.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2020\/11\/bambole.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-piu-forte-del-coronavirus-da-marzo-2020-venti-bambini-adottati-da-ungheria-e-repubblica-ceca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione Internazionale","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-internazionale\/"},{"@type":"ListItem","position":3,"name":"Adozione Internazionale pi\u00f9 forte del Coronavirus. Da marzo 2020, venti bambini adottati da Ungheria e Repubblica Ceca"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/b9065848ca5b5cf9a80fad6f849d2c17","name":"cristianoP","url":"https:\/\/www.aibi.it\/ita\/author\/cristianop\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 00:40:30","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/182452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/91"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=182452"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/182452\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/182453"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=182452"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=182452"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=182452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}