﻿


{"id":183026,"date":"2020-11-25T06:30:34","date_gmt":"2020-11-25T05:30:34","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=183026"},"modified":"2020-11-25T16:26:00","modified_gmt":"2020-11-25T15:26:00","slug":"adozione-mamma-ma-io-in-realta-da-chi-sono-nato","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozione-mamma-ma-io-in-realta-da-chi-sono-nato\/","title":{"rendered":"Adozione. Mamma, ma io in realt\u00e0 da chi sono nato?"},"content":{"rendered":"<h2><b>\u201cPerch\u00e9 mi hanno abbandonato?\u201d \u201cChi sono i miei genitori naturali?\u201d domande fisiologiche nell\u2019esperienza adottiva, non dobbiamo esserne spaventati, anzi! Queste domande nascondono il desiderio di colmare un vuoto e di costruire la propria identit\u00e0.<\/b><\/h2>\n<p style=\"font-weight: 400;\">Esiste un\u00a0<strong>bisogno<\/strong>\u00a0molto intimo\u00a0<strong>di conoscere la propria storia<\/strong>, che normalmente vediamo nei bambini quando costantemente e ripetutamente chiedono ai genitori di raccontare loro quando sono nati, come erano da piccoli, come sono stati accolti, cosa facevano ecc..<\/p>\n<p style=\"font-weight: 400;\">Il bisogno di scoprire la propria origine risponde in realt\u00e0 ad un pi\u00f9 latente\u00a0<strong>bisogno di appartenenza e di identit\u00e0<\/strong>.<\/p>\n<p style=\"font-weight: 400;\">\u201c<em>Perch\u00e9 mi hanno abbandonato?<\/em>\u201d \u201c<em>Quali sono le mie origini?<\/em>\u201d \u201c<em>Chi sono i miei genitori naturali<\/em>?\u201d sono domande fisiologiche nell\u2019esperienza adottiva; non dobbiamo esserne spaventati, anzi! Queste domande nascondono il desiderio di colmare un vuoto e di costruire la propria identit\u00e0.<\/p>\n<h3 style=\"font-weight: 400;\"><strong>Fare i conti con il proprio passato\u2026<\/strong><\/h3>\n<p style=\"font-weight: 400;\">Ma\u00a0<strong>non sempre i bambini esprimono il loro dolore<\/strong>\u00a0e la loro frustrazione, perch\u00e9 hanno timore di turbare i genitori adottivi o perch\u00e9 sono convinti che a questi non piaccia sentir parlare della loro storia e della loro sofferenza interna. I bambini, quindi,\u00a0<strong>nel primo periodo post adottivo<\/strong>, sentono spesso il bisogno di rimuovere il passato e di sentirsi parte del nucleo adottivo. Questo bisogno si manifesta nel silenzio e spesso nell\u2019apparente \u201cdimenticanza\u201d delle origini.<\/p>\n<p style=\"font-weight: 400;\">Fare i conti con il proprio passato, trovandosi ora in una situazione di agio, amore, attenzione e gioia pu\u00f2 essere insopportabile quando il passato \u00e8 fatto di difficolt\u00e0, rischio, privazioni, negligenza, menefreghismo. Allora inizialmente la soluzione \u00e8 spesso\u00a0<strong>\u201cdimenticare\u201d<\/strong>\u00a0quanto vissuto prima dell\u2019adozione; alle domande anche dirette rispondono spesso con un \u201c<em>boh<\/em>\u201d, \u201c<em>non mi va<\/em>\u201d, \u201c<em>non lo so<\/em>\u201d.<\/p>\n<h3 style=\"font-weight: 400;\"><strong>Gli adolescenti rispondono al disagio del presente cercando risposte nel passato<\/strong><\/h3>\n<p style=\"font-weight: 400;\">In realt\u00e0\u00a0<strong>il passato<\/strong>\u00a0che mettono nel cassetto\u00a0<strong>\u00e8 sempre l\u00ec<\/strong>,\u00a0<em>in guardia<\/em>, in attesa di un momento in cui essere pi\u00f9 pronti a farne i conti, a tirare fuori quello che avevano nascosto.<\/p>\n<p style=\"font-weight: 400;\"><strong>Il confronto<\/strong>\u00a0con\u00a0\u00a0la propria storia, il ritorno alle origini, si presenta, di solito,\u00a0<strong>in adolescenza.<\/strong><\/p>\n<p style=\"font-weight: 400;\">Gli adolescenti rispondono al disagio del presente, tipico dell\u2019et\u00e0, cercando riposte nel passato. Quando il passato \u00e8 sconosciuto o confuso o fonte di dolore, ti senti espropriato di una parte della tua esistenza, provando anche una profonda rabbia e sofferenza.<\/p>\n<p style=\"font-weight: 400;\"><strong>Ricercare e collocare le proprie radici<\/strong>\u00a0in un posto e in un tempo<strong>, \u00e8 necessario<\/strong>\u00a0alla persona per costruire un sicuro senso di se, per colmare quel vuoto che l\u2019abbandono ha prodotto.<\/p>\n<h3 style=\"font-weight: 400;\"><strong>Il ruolo dei genitori adottivi in questo cammino<\/strong><\/h3>\n<p style=\"font-weight: 400;\">In questo cammino tortuoso, ma anche meraviglioso, i genitori adottivi hanno un ruolo\u00a0<strong>fondamentale.<\/strong><\/p>\n<p style=\"font-weight: 400;\">Per prima \u00e8 la legge stessa che parla: l\u2019articolo 28 della legge 184\/1983 e la legge de 2001 impongono ai genitori adottivi di\u00a0<strong>informare il figlio adottato sulle proprie origini.<\/strong>\u00a0\u00c8 \u00a0fondamentale spiegare al bambino il suo status di figlio adottivo e la sua storia (per quanto se ne conosce)\u00a0<strong>fin da subito<\/strong>\u00a0e, con parole adeguate allo stadio di sviluppo.<\/p>\n<p style=\"font-weight: 400;\">Ma la famiglia adottiva deve nel profondo\u00a0<strong>accogliere il passato del figlio<\/strong>, anche il pi\u00f9 difficile e \u201cminaccioso\u201d. Deve essere in grado di accettare le relazioni significative che hanno caratterizzato parte dell\u2019esistenza dei figli, capaci per\u00f2 di riposizionare le relazioni familiari in un ordine che vede loro stessi all\u2019apice.\u00a0<strong>Sicuri di essere madre e padre<\/strong>, si pu\u00f2 rispondere a tutte le domande con serenit\u00e0 e donando serenit\u00e0 a questi figli che da anni la cercano.<\/p>\n<p style=\"font-weight: 400;\"><strong>Non siete soli in questo percorso<\/strong>! Genitori e figli possono disporre di un sistema di supporto esterno composto da tanti professionisti pronti ad accompagnare la famiglia nella costruzione di una casa fatta di mattoni solidi e indistruttibili.<\/p>\n<p style=\"font-weight: 400;\"><strong>Cristina Legnani<\/strong><\/p>\n<p style=\"font-weight: 400;\">Desk Adozione internazionale Ai.Bi.<\/p>\n<p style=\"font-weight: 400;\">\n","protected":false},"excerpt":{"rendered":"<p>&ldquo;Perch&eacute; mi hanno abbandonato?&rdquo; &ldquo;Chi sono i miei genitori naturali?&rdquo; domande fisiologiche nell&rsquo;esperienza adottiva, non dobbiamo esserne spaventati, anzi! Queste domande nascondono il desiderio di colmare un vuoto e di costruire la propria identit&agrave;. Esiste un&nbsp;bisogno&nbsp;molto intimo&nbsp;di conoscere la propria storia, che normalmente vediamo nei bambini quando costantemente e ripetutamente [&hellip;]<\/p>\n","protected":false},"author":97,"featured_media":183027,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[172],"tags":[279],"class_list":["post-183026","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-internazionale","tag-adozione"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozione. Mamma, ma io in realt\u00e0 da chi sono nato? - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"Adozione. \u201cPerch\u00e9 mi hanno abbandonato?\u201d \u201cChi sono i miei genitori naturali?\u201d domande fisiologiche nell\u2019esperienza adottiva, non dobbiamo esserne spaventati, anzi!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozione-mamma-ma-io-in-realta-da-chi-sono-nato\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozione. Mamma, ma io in realt\u00e0 da chi sono nato?\" \/>\n<meta property=\"og:description\" content=\"\u201cPerch\u00e9 mi hanno abbandonato?\u201d \u201cChi sono i miei genitori naturali?\u201d domande fisiologiche nell\u2019esperienza adottiva, non dobbiamo esserne spaventati, anzi! Queste domande nascondono il desiderio di colmare un vuoto e di costruire la propria identit\u00e0.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozione-mamma-ma-io-in-realta-da-chi-sono-nato\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-25T05:30:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-25T15:26:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/11\/adozione-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mc.sabatini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mc.sabatini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-mamma-ma-io-in-realta-da-chi-sono-nato\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-mamma-ma-io-in-realta-da-chi-sono-nato\\\/\"},\"author\":{\"name\":\"mc.sabatini\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\"},\"headline\":\"Adozione. Mamma, ma io in realt\u00e0 da chi sono nato?\",\"datePublished\":\"2020-11-25T05:30:34+00:00\",\"dateModified\":\"2020-11-25T15:26:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-mamma-ma-io-in-realta-da-chi-sono-nato\\\/\"},\"wordCount\":617,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-mamma-ma-io-in-realta-da-chi-sono-nato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/11\\\/adozione-4.jpg\",\"keywords\":[\"adozione\"],\"articleSection\":[\"Adozione Internazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-mamma-ma-io-in-realta-da-chi-sono-nato\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-mamma-ma-io-in-realta-da-chi-sono-nato\\\/\",\"name\":\"Adozione. Mamma, ma io in realt\u00e0 da chi sono nato? - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-mamma-ma-io-in-realta-da-chi-sono-nato\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-mamma-ma-io-in-realta-da-chi-sono-nato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/11\\\/adozione-4.jpg\",\"datePublished\":\"2020-11-25T05:30:34+00:00\",\"dateModified\":\"2020-11-25T15:26:00+00:00\",\"description\":\"Adozione. \u201cPerch\u00e9 mi hanno abbandonato?\u201d \u201cChi sono i miei genitori naturali?\u201d domande fisiologiche nell\u2019esperienza adottiva, non dobbiamo esserne spaventati, anzi!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-mamma-ma-io-in-realta-da-chi-sono-nato\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-mamma-ma-io-in-realta-da-chi-sono-nato\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-mamma-ma-io-in-realta-da-chi-sono-nato\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/11\\\/adozione-4.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/11\\\/adozione-4.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-mamma-ma-io-in-realta-da-chi-sono-nato\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione Internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-internazionale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozione. Mamma, ma io in realt\u00e0 da chi sono nato?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\",\"name\":\"mc.sabatini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/marias\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozione. Mamma, ma io in realt\u00e0 da chi sono nato? - Ai.Bi. Amici dei Bambini","description":"Adozione. \u201cPerch\u00e9 mi hanno abbandonato?\u201d \u201cChi sono i miei genitori naturali?\u201d domande fisiologiche nell\u2019esperienza adottiva, non dobbiamo esserne spaventati, anzi!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozione-mamma-ma-io-in-realta-da-chi-sono-nato\/","og_locale":"it_IT","og_type":"article","og_title":"Adozione. Mamma, ma io in realt\u00e0 da chi sono nato?","og_description":"\u201cPerch\u00e9 mi hanno abbandonato?\u201d \u201cChi sono i miei genitori naturali?\u201d domande fisiologiche nell\u2019esperienza adottiva, non dobbiamo esserne spaventati, anzi! Queste domande nascondono il desiderio di colmare un vuoto e di costruire la propria identit\u00e0.","og_url":"https:\/\/www.aibi.it\/ita\/adozione-mamma-ma-io-in-realta-da-chi-sono-nato\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2020-11-25T05:30:34+00:00","article_modified_time":"2020-11-25T15:26:00+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2020\/11\/adozione-4.jpg","type":"image\/jpeg"}],"author":"mc.sabatini","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"mc.sabatini","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozione-mamma-ma-io-in-realta-da-chi-sono-nato\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-mamma-ma-io-in-realta-da-chi-sono-nato\/"},"author":{"name":"mc.sabatini","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938"},"headline":"Adozione. Mamma, ma io in realt\u00e0 da chi sono nato?","datePublished":"2020-11-25T05:30:34+00:00","dateModified":"2020-11-25T15:26:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-mamma-ma-io-in-realta-da-chi-sono-nato\/"},"wordCount":617,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-mamma-ma-io-in-realta-da-chi-sono-nato\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2020\/11\/adozione-4.jpg","keywords":["adozione"],"articleSection":["Adozione Internazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozione-mamma-ma-io-in-realta-da-chi-sono-nato\/","url":"https:\/\/www.aibi.it\/ita\/adozione-mamma-ma-io-in-realta-da-chi-sono-nato\/","name":"Adozione. Mamma, ma io in realt\u00e0 da chi sono nato? - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-mamma-ma-io-in-realta-da-chi-sono-nato\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-mamma-ma-io-in-realta-da-chi-sono-nato\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2020\/11\/adozione-4.jpg","datePublished":"2020-11-25T05:30:34+00:00","dateModified":"2020-11-25T15:26:00+00:00","description":"Adozione. \u201cPerch\u00e9 mi hanno abbandonato?\u201d \u201cChi sono i miei genitori naturali?\u201d domande fisiologiche nell\u2019esperienza adottiva, non dobbiamo esserne spaventati, anzi!","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-mamma-ma-io-in-realta-da-chi-sono-nato\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozione-mamma-ma-io-in-realta-da-chi-sono-nato\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozione-mamma-ma-io-in-realta-da-chi-sono-nato\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2020\/11\/adozione-4.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2020\/11\/adozione-4.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozione-mamma-ma-io-in-realta-da-chi-sono-nato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione Internazionale","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-internazionale\/"},{"@type":"ListItem","position":3,"name":"Adozione. Mamma, ma io in realt\u00e0 da chi sono nato?"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938","name":"mc.sabatini","url":"https:\/\/www.aibi.it\/ita\/author\/marias\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 00:18:11","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/183026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/97"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=183026"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/183026\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/183027"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=183026"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=183026"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=183026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}