﻿


{"id":183880,"date":"2020-12-28T13:35:26","date_gmt":"2020-12-28T12:35:26","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=183880"},"modified":"2020-12-28T13:40:54","modified_gmt":"2020-12-28T12:40:54","slug":"quante-possibilita-ci-sono-di-essere-chiamati-nellarco-dei-tre-anni-per-ladozione-nazionale","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/quante-possibilita-ci-sono-di-essere-chiamati-nellarco-dei-tre-anni-per-ladozione-nazionale\/","title":{"rendered":"Quante possibilit\u00e0 ci sono di essere chiamati nell\u2019arco dei tre anni per l\u2019adozione nazionale?"},"content":{"rendered":"<blockquote>\n<p style=\"font-weight: 400; text-align: left;\">Buongiorno Ai.Bi.<br \/>\nSiamo una coppia che ha presentato la disponibilit\u00e0 per l\u2019adozione nazionale sia presso il nostro Tribunale per i Minorenni di residenza che in altri 5 Tribunali.<br \/>\nCi chiedevamo se avete idea sulle reali possibilit\u00e0 di essere chiamati nel primo triennio dal deposito della domanda. Sentiamo pareri molto discordanti tra le varie coppie con le quali siamo in contatto.<br \/>\nGrazie<br \/>\nLuciana e Gilberto<\/p>\n<\/blockquote>\n<p style=\"font-weight: 400; text-align: left;\"><span style=\"font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, Oxygen-Sans, Ubuntu, Cantarell, 'Helvetica Neue', sans-serif; font-size: 16px;\">Cari Luciana e Gilberto,<\/span><\/p>\n<p style=\"font-weight: 400; text-align: left;\">in qualit\u00e0 di Enti Autorizzati per l\u2019adozione internazionale\u00a0<strong>non siamo in possesso di dati precisi rispetto alla vostra domanda.<br \/>\n<\/strong>Quello che certamente possiamo dirvi \u00e8 che nel passato la differenza tra il numero di adozioni realizzate annualmente tra procedimenti di internazionale e nazionale era molto significativa.<\/p>\n<p style=\"font-weight: 400;\">\u00a0Si realizzavano circa\u00a0<strong>4.000 adozioni internazionali<\/strong>\u00a0a fronte di circa 1.000 nazionali. Ora la situazione \u00e8 molto cambiata e dallo scorso anno per l\u2019adozione internazionale\u00a0<strong>si fatica ad arrivare a 1.000 minori<\/strong>.<\/p>\n<p style=\"font-weight: 400;\">Quest\u2019anno la situazione sar\u00e0, a causa della pandemia, ancora peggiore, mentre nel corso del tempo il numero di minori adottati in nazionale \u00e8 rimasto pressoch\u00e9 stabile attestandosi sempre\u00a0<strong>sul migliaio all\u2019anno<\/strong>.<\/p>\n<p style=\"font-weight: 400;\">Dirvi se questi bambini sono stati adottati da coppie che avevano depositato la loro disponibilit\u00e0 entro un triennio non \u00e8 un dato che riusciamo a rilevare. Quello che sappiamo \u00e8 che numerose coppie dopo i primi tre anni rinnovano la disponibilit\u00e0 per i successivi tre, come consentito dalla normativa.<\/p>\n<p>I nostri migliori auguri per arrivare a coronare il vostro sogno.<\/p>\n<p style=\"font-weight: 400;\"><strong>Cinzia Bernicchi<\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong>Formazione adozione internazionale Ai.Bi.\u00a0<\/strong><\/p>\n<p style=\"font-weight: 400;\">\n","protected":false},"excerpt":{"rendered":"<p>Buongiorno Ai.Bi. Siamo una coppia che ha presentato la disponibilit&agrave; per l&rsquo;adozione nazionale sia presso il nostro Tribunale per i Minorenni di residenza che in altri 5 Tribunali. Ci chiedevamo se avete idea sulle reali possibilit&agrave; di essere chiamati nel primo triennio dal deposito della domanda. Sentiamo pareri molto discordanti [&hellip;]<\/p>\n","protected":false},"author":97,"featured_media":183883,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[50],"tags":[279,318],"class_list":["post-183880","post","type-post","status-publish","format-standard","has-post-thumbnail","category-lettere-al-direttore","tag-adozione","tag-lettere-al-direttore"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Quante possibilit\u00e0 ci sono di essere chiamati nell\u2019arco dei tre anni per l\u2019adozione nazionale? - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"Luciana e Gilberto hanno presentato domanda di disponibilit\u00e0 in Tribunale per l&#039;adozione nazionale e vorrebbero sapere quante sono le possibilit\u00e0 di essere chiamati nei primi tre anni... Ai.Bi. risponde\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/quante-possibilita-ci-sono-di-essere-chiamati-nellarco-dei-tre-anni-per-ladozione-nazionale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quante possibilit\u00e0 ci sono di essere chiamati nell\u2019arco dei tre anni per l\u2019adozione nazionale?\" \/>\n<meta property=\"og:description\" content=\"Luciana e Gilberto hanno presentato domanda di disponibilit\u00e0 in Tribunale per l&#039;adozione nazionale e vorrebbero sapere quante sono le possibilit\u00e0 di essere chiamati nei primi tre anni... Ai.Bi. risponde\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/quante-possibilita-ci-sono-di-essere-chiamati-nellarco-dei-tre-anni-per-ladozione-nazionale\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-28T12:35:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-28T12:40:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/12\/adozione.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"mc.sabatini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mc.sabatini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/quante-possibilita-ci-sono-di-essere-chiamati-nellarco-dei-tre-anni-per-ladozione-nazionale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/quante-possibilita-ci-sono-di-essere-chiamati-nellarco-dei-tre-anni-per-ladozione-nazionale\\\/\"},\"author\":{\"name\":\"mc.sabatini\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\"},\"headline\":\"Quante possibilit\u00e0 ci sono di essere chiamati nell\u2019arco dei tre anni per l\u2019adozione nazionale?\",\"datePublished\":\"2020-12-28T12:35:26+00:00\",\"dateModified\":\"2020-12-28T12:40:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/quante-possibilita-ci-sono-di-essere-chiamati-nellarco-dei-tre-anni-per-ladozione-nazionale\\\/\"},\"wordCount\":257,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/quante-possibilita-ci-sono-di-essere-chiamati-nellarco-dei-tre-anni-per-ladozione-nazionale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/12\\\/adozione.png\",\"keywords\":[\"adozione\",\"Lettere al Direttore\"],\"articleSection\":[\"Lettere al direttore\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/quante-possibilita-ci-sono-di-essere-chiamati-nellarco-dei-tre-anni-per-ladozione-nazionale\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/quante-possibilita-ci-sono-di-essere-chiamati-nellarco-dei-tre-anni-per-ladozione-nazionale\\\/\",\"name\":\"Quante possibilit\u00e0 ci sono di essere chiamati nell\u2019arco dei tre anni per l\u2019adozione nazionale? - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/quante-possibilita-ci-sono-di-essere-chiamati-nellarco-dei-tre-anni-per-ladozione-nazionale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/quante-possibilita-ci-sono-di-essere-chiamati-nellarco-dei-tre-anni-per-ladozione-nazionale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/12\\\/adozione.png\",\"datePublished\":\"2020-12-28T12:35:26+00:00\",\"dateModified\":\"2020-12-28T12:40:54+00:00\",\"description\":\"Luciana e Gilberto hanno presentato domanda di disponibilit\u00e0 in Tribunale per l'adozione nazionale e vorrebbero sapere quante sono le possibilit\u00e0 di essere chiamati nei primi tre anni... Ai.Bi. risponde\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/quante-possibilita-ci-sono-di-essere-chiamati-nellarco-dei-tre-anni-per-ladozione-nazionale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/quante-possibilita-ci-sono-di-essere-chiamati-nellarco-dei-tre-anni-per-ladozione-nazionale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/quante-possibilita-ci-sono-di-essere-chiamati-nellarco-dei-tre-anni-per-ladozione-nazionale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/12\\\/adozione.png\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/12\\\/adozione.png\",\"width\":1200,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/quante-possibilita-ci-sono-di-essere-chiamati-nellarco-dei-tre-anni-per-ladozione-nazionale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lettere al direttore\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/lettere-al-direttore\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Quante possibilit\u00e0 ci sono di essere chiamati nell\u2019arco dei tre anni per l\u2019adozione nazionale?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\",\"name\":\"mc.sabatini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/marias\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Quante possibilit\u00e0 ci sono di essere chiamati nell\u2019arco dei tre anni per l\u2019adozione nazionale? - Ai.Bi. Amici dei Bambini","description":"Luciana e Gilberto hanno presentato domanda di disponibilit\u00e0 in Tribunale per l'adozione nazionale e vorrebbero sapere quante sono le possibilit\u00e0 di essere chiamati nei primi tre anni... Ai.Bi. risponde","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/quante-possibilita-ci-sono-di-essere-chiamati-nellarco-dei-tre-anni-per-ladozione-nazionale\/","og_locale":"it_IT","og_type":"article","og_title":"Quante possibilit\u00e0 ci sono di essere chiamati nell\u2019arco dei tre anni per l\u2019adozione nazionale?","og_description":"Luciana e Gilberto hanno presentato domanda di disponibilit\u00e0 in Tribunale per l'adozione nazionale e vorrebbero sapere quante sono le possibilit\u00e0 di essere chiamati nei primi tre anni... Ai.Bi. risponde","og_url":"https:\/\/www.aibi.it\/ita\/quante-possibilita-ci-sono-di-essere-chiamati-nellarco-dei-tre-anni-per-ladozione-nazionale\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2020-12-28T12:35:26+00:00","article_modified_time":"2020-12-28T12:40:54+00:00","og_image":[{"width":1200,"height":600,"url":"https:\/\/www.aibi.it\/ita\/images\/2020\/12\/adozione.png","type":"image\/png"}],"author":"mc.sabatini","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"mc.sabatini","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/quante-possibilita-ci-sono-di-essere-chiamati-nellarco-dei-tre-anni-per-ladozione-nazionale\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/quante-possibilita-ci-sono-di-essere-chiamati-nellarco-dei-tre-anni-per-ladozione-nazionale\/"},"author":{"name":"mc.sabatini","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938"},"headline":"Quante possibilit\u00e0 ci sono di essere chiamati nell\u2019arco dei tre anni per l\u2019adozione nazionale?","datePublished":"2020-12-28T12:35:26+00:00","dateModified":"2020-12-28T12:40:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/quante-possibilita-ci-sono-di-essere-chiamati-nellarco-dei-tre-anni-per-ladozione-nazionale\/"},"wordCount":257,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/quante-possibilita-ci-sono-di-essere-chiamati-nellarco-dei-tre-anni-per-ladozione-nazionale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2020\/12\/adozione.png","keywords":["adozione","Lettere al Direttore"],"articleSection":["Lettere al direttore"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/quante-possibilita-ci-sono-di-essere-chiamati-nellarco-dei-tre-anni-per-ladozione-nazionale\/","url":"https:\/\/www.aibi.it\/ita\/quante-possibilita-ci-sono-di-essere-chiamati-nellarco-dei-tre-anni-per-ladozione-nazionale\/","name":"Quante possibilit\u00e0 ci sono di essere chiamati nell\u2019arco dei tre anni per l\u2019adozione nazionale? - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/quante-possibilita-ci-sono-di-essere-chiamati-nellarco-dei-tre-anni-per-ladozione-nazionale\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/quante-possibilita-ci-sono-di-essere-chiamati-nellarco-dei-tre-anni-per-ladozione-nazionale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2020\/12\/adozione.png","datePublished":"2020-12-28T12:35:26+00:00","dateModified":"2020-12-28T12:40:54+00:00","description":"Luciana e Gilberto hanno presentato domanda di disponibilit\u00e0 in Tribunale per l'adozione nazionale e vorrebbero sapere quante sono le possibilit\u00e0 di essere chiamati nei primi tre anni... Ai.Bi. risponde","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/quante-possibilita-ci-sono-di-essere-chiamati-nellarco-dei-tre-anni-per-ladozione-nazionale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/quante-possibilita-ci-sono-di-essere-chiamati-nellarco-dei-tre-anni-per-ladozione-nazionale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/quante-possibilita-ci-sono-di-essere-chiamati-nellarco-dei-tre-anni-per-ladozione-nazionale\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2020\/12\/adozione.png","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2020\/12\/adozione.png","width":1200,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/quante-possibilita-ci-sono-di-essere-chiamati-nellarco-dei-tre-anni-per-ladozione-nazionale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Lettere al direttore","item":"https:\/\/www.aibi.it\/ita\/category\/lettere-al-direttore\/"},{"@type":"ListItem","position":3,"name":"Quante possibilit\u00e0 ci sono di essere chiamati nell\u2019arco dei tre anni per l\u2019adozione nazionale?"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938","name":"mc.sabatini","url":"https:\/\/www.aibi.it\/ita\/author\/marias\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 00:15:55","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/183880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/97"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=183880"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/183880\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/183883"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=183880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=183880"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=183880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}