﻿{"id":184017,"date":"2021-01-03T07:30:15","date_gmt":"2021-01-03T06:30:15","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=184017"},"modified":"2021-01-01T12:15:21","modified_gmt":"2021-01-01T11:15:21","slug":"seconda-adozione-in-russia-su-una-cosa-ivan-e-stato-sicuro-fin-dallinizio-voleva-tornare-nel-suo-paese-di-origine","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/seconda-adozione-in-russia-su-una-cosa-ivan-e-stato-sicuro-fin-dallinizio-voleva-tornare-nel-suo-paese-di-origine\/","title":{"rendered":"Seconda adozione in Russia: &#8220;Su una cosa Ivan \u00e8 stato sicuro fin dall\u2019inizio: voleva tornare nel suo Paese di origine&#8221;"},"content":{"rendered":"<h2 style=\"font-weight: 400;\"><strong>&#8220;Se siamo arrivati alla seconda adozione, \u00e8 solo merito di nostro figlio Ivan! Per quanto noi fossimo gi\u00e0 di questa idea, \u00e8 stato suo il desiderio profondo di avere un fratello o una sorella\u201d.<\/strong><\/h2>\n<p style=\"font-weight: 400;\">Antonella e Marco,\u00a0<a href=\"https:\/\/www.aibi.it\/ita\/adozione-russia-quando-venite-a-prendermi\/\">la cui storia \u00e8 stata gi\u00e0 raccontata nella primavera del 2019,<\/a>\u00a0sono\u00a0oggi\u00a0felicissimi di come Ivan si sia inserito bene a scuola e\u00a0in\u00a0famiglia, di come stia assaporando la vita dopo un passato difficile, trascorso\u00a0in\u00a0buona parte\u00a0in\u00a0un istituto della Federazione Russa.<\/p>\n<p style=\"font-weight: 400;\"><em>\u00a0<\/em><em>\u201cIn\u00a0realt\u00e0 Ivan si sarebbe gi\u00e0 espresso\u2026.vorrebbe una fratellina!<\/em>\u00a0&#8211; dice la mamma, che ricorda il momento\u00a0in\u00a0cui suo figlio rivel\u00f2, con spontaneit\u00e0, il suo desiderio &#8211;\u00a0<em>In<\/em><em>\u00a0fondo sappiamo che sar\u00e0 felice\u00a0in\u00a0ogni modo, da fratello maggiore. Ancor pi\u00f9 felice perch\u00e9 torneremmo\u00a0in\u00a0Federazione Russa\u201d.<\/em><\/p>\n<p style=\"font-weight: 400;\">In\u00a0mesi cos\u00ec difficili\u00a0in\u00a0cui la pandemia sta complicando le procedure e scoraggiando gli animi,\u00a0<strong>la decisione di Antonella e Marco alimenta invece la speranza<\/strong>\u00a0di tanti minori ancora costretti a crescere senza una famiglia. E cos\u00ec il loro amore di famiglia \u00e8 destinato, si spera a breve, a moltiplicarsi.<\/p>\n<h3 style=\"font-weight: 400;\"><strong>Mettere in atto l\u2019iter adottivo di una seconda adozione significa ripartire da zero<\/strong><\/h3>\n<p style=\"font-weight: 400;\"><em>\u00a0<\/em><em>\u201cDopo la nostra decisione, a fine estate dell\u2019anno scorso<\/em>\u00a0&#8211; racconta Marco\u00a0<em>&#8211; abbiamo ricominciato l\u2019iter per arrivare all\u2019idoneit\u00e0. A causa del coronavirus molto \u00e8 stato realizzato online, anche gli incontri con i Servizi, ma sotto un certo aspetto\u2026.<strong>abbiamo impiegato bene il tempo<\/strong>\u201d.<\/em><\/p>\n<p style=\"font-weight: 400;\">Tempo di cui anche Ivan si sta rendendo conto. Questa volta anche lui \u00e8 da questa parte della \u2018barricata\u2019: non \u00e8 pi\u00f9 il figlio\u00a0in\u00a0attesa, ma \u00e8 parte essenziale della famiglia che si prepara all\u2019incontro con un prossimo figlio o una prossima figlia.<\/p>\n<p style=\"font-weight: 400;\"><em>\u201cIl parere di Ivan, le sue emozioni, sono state al centro di diversi incontri con i Servizi. E Ivan \u00e8 stato davvero incredibile<\/em>\u00a0&#8211; raccontano i genitori ancora commossi &#8211;\u00a0<em>Su una cosa \u00e8 stato sicuro fin dall\u2019inizio: voleva tornare nel suo Paese di origine, la Federazione Russa\u201d.<\/em><\/p>\n<p style=\"font-weight: 400;\">E cos\u00ec una volta conferito l\u2019incarico ad Ai.Bi, \u00e8 iniziata\u00a0<strong>la\u00a0seconda\u00a0fase dell\u2019attesa:<\/strong>\u00a0quella\u00a0in\u00a0cui si preparano e inviano documenti, ma soprattutto quella\u00a0in\u00a0cui si fa spazio, emotivo e fisico alla persona che arriver\u00e0.<\/p>\n<p style=\"font-weight: 400;\">\u201c<em>Ivan si sta rendendo conto di cosa comporti l\u2019adozione, anche\u00a0in\u00a0termini pratici<\/em>\u00a0&#8211; dice Antonella &#8211;\u00a0<em>con la Federazione Russa la mole di documenti \u00e8 notevole. Ha gi\u00e0 capito quanto una coppia di genitori davvero desideri un figlio e cosa sia disposta a fare per averlo\u201d.<\/em><\/p>\n<p style=\"font-weight: 400;\">E cos\u00ec, come qualsiasi bambino,\u00a0a tratti comprende a tratti riempie i genitori di domande e richieste, incapace di tollerare l\u2019attesa. \u201c<em>Cos\u00ec ormai ci scherziamo tutti assieme. Speriamo di poter viaggiare presto\u201d<\/em><\/p>\n<p style=\"font-weight: 400;\"><em>\u00a0<\/em><strong><em>\u201cLa dimensione del figlio unico non \u00e8 la nostra\u201d<\/em><\/strong><strong>\u00a0dicono Antonella e Marco che, entrambi, arrivano da famiglie numerose<\/strong>: a casa di mamma vi sono 9 tra fratelli e sorelle, 5 da parte di pap\u00e0.<\/p>\n<p style=\"font-weight: 400;\"><strong>Quindi sorge spontanea la domanda: si fermeranno alla\u00a0seconda\u00a0adozione?<\/strong>\u00a0un mare di auguri a questa famiglia ricca di fecondit\u00e0!<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\"><strong>\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&ldquo;Se siamo arrivati alla seconda adozione, &egrave; solo merito di nostro figlio Ivan! Per quanto noi fossimo gi&agrave; di questa idea, &egrave; stato suo il desiderio profondo di avere un fratello o una sorella&rdquo;. Antonella e Marco,&nbsp;la cui storia &egrave; stata gi&agrave; raccontata nella primavera del 2019,&nbsp;sono&nbsp;oggi&nbsp;felicissimi di come Ivan [&hellip;]<\/p>\n","protected":false},"author":97,"featured_media":180068,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[172],"tags":[279,549],"class_list":["post-184017","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-internazionale","tag-adozione","tag-russia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Seconda adozione in Russia: &quot;Su una cosa Ivan \u00e8 stato sicuro fin dall\u2019inizio: voleva tornare nel suo Paese di origine&quot; - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"Adozione: &quot;Se siamo arrivati alla seconda adozione, \u00e8 solo merito di nostro figlio Ivan! Per quanto noi fossimo gi\u00e0 di questa idea, \u00e8 stato suo il desiderio profondo di avere un fratello o una sorella\u201d.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/seconda-adozione-in-russia-su-una-cosa-ivan-e-stato-sicuro-fin-dallinizio-voleva-tornare-nel-suo-paese-di-origine\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Seconda adozione in Russia: &quot;Su una cosa Ivan \u00e8 stato sicuro fin dall\u2019inizio: voleva tornare nel suo Paese di origine&quot;\" \/>\n<meta property=\"og:description\" content=\"&quot;Se siamo arrivati alla seconda adozione, \u00e8 solo merito di nostro figlio Ivan! Per quanto noi fossimo gi\u00e0 di questa idea, \u00e8 stato suo il desiderio profondo di avere un fratello o una sorella\u201d.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/seconda-adozione-in-russia-su-una-cosa-ivan-e-stato-sicuro-fin-dallinizio-voleva-tornare-nel-suo-paese-di-origine\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-03T06:30:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/10\/Russia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mc.sabatini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mc.sabatini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/seconda-adozione-in-russia-su-una-cosa-ivan-e-stato-sicuro-fin-dallinizio-voleva-tornare-nel-suo-paese-di-origine\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/seconda-adozione-in-russia-su-una-cosa-ivan-e-stato-sicuro-fin-dallinizio-voleva-tornare-nel-suo-paese-di-origine\\\/\"},\"author\":{\"name\":\"mc.sabatini\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\"},\"headline\":\"Seconda adozione in Russia: &#8220;Su una cosa Ivan \u00e8 stato sicuro fin dall\u2019inizio: voleva tornare nel suo Paese di origine&#8221;\",\"datePublished\":\"2021-01-03T06:30:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/seconda-adozione-in-russia-su-una-cosa-ivan-e-stato-sicuro-fin-dallinizio-voleva-tornare-nel-suo-paese-di-origine\\\/\"},\"wordCount\":518,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/seconda-adozione-in-russia-su-una-cosa-ivan-e-stato-sicuro-fin-dallinizio-voleva-tornare-nel-suo-paese-di-origine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/10\\\/Russia.jpg\",\"keywords\":[\"adozione\",\"Russia\"],\"articleSection\":[\"Adozione Internazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/seconda-adozione-in-russia-su-una-cosa-ivan-e-stato-sicuro-fin-dallinizio-voleva-tornare-nel-suo-paese-di-origine\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/seconda-adozione-in-russia-su-una-cosa-ivan-e-stato-sicuro-fin-dallinizio-voleva-tornare-nel-suo-paese-di-origine\\\/\",\"name\":\"Seconda adozione in Russia: \\\"Su una cosa Ivan \u00e8 stato sicuro fin dall\u2019inizio: voleva tornare nel suo Paese di origine\\\" - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/seconda-adozione-in-russia-su-una-cosa-ivan-e-stato-sicuro-fin-dallinizio-voleva-tornare-nel-suo-paese-di-origine\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/seconda-adozione-in-russia-su-una-cosa-ivan-e-stato-sicuro-fin-dallinizio-voleva-tornare-nel-suo-paese-di-origine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/10\\\/Russia.jpg\",\"datePublished\":\"2021-01-03T06:30:15+00:00\",\"description\":\"Adozione: \\\"Se siamo arrivati alla seconda adozione, \u00e8 solo merito di nostro figlio Ivan! Per quanto noi fossimo gi\u00e0 di questa idea, \u00e8 stato suo il desiderio profondo di avere un fratello o una sorella\u201d.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/seconda-adozione-in-russia-su-una-cosa-ivan-e-stato-sicuro-fin-dallinizio-voleva-tornare-nel-suo-paese-di-origine\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/seconda-adozione-in-russia-su-una-cosa-ivan-e-stato-sicuro-fin-dallinizio-voleva-tornare-nel-suo-paese-di-origine\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/seconda-adozione-in-russia-su-una-cosa-ivan-e-stato-sicuro-fin-dallinizio-voleva-tornare-nel-suo-paese-di-origine\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/10\\\/Russia.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/10\\\/Russia.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/seconda-adozione-in-russia-su-una-cosa-ivan-e-stato-sicuro-fin-dallinizio-voleva-tornare-nel-suo-paese-di-origine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione Internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-internazionale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Seconda adozione in Russia: &#8220;Su una cosa Ivan \u00e8 stato sicuro fin dall\u2019inizio: voleva tornare nel suo Paese di origine&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\",\"name\":\"mc.sabatini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/marias\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Seconda adozione in Russia: \"Su una cosa Ivan \u00e8 stato sicuro fin dall\u2019inizio: voleva tornare nel suo Paese di origine\" - Ai.Bi. Amici dei Bambini","description":"Adozione: \"Se siamo arrivati alla seconda adozione, \u00e8 solo merito di nostro figlio Ivan! Per quanto noi fossimo gi\u00e0 di questa idea, \u00e8 stato suo il desiderio profondo di avere un fratello o una sorella\u201d.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/seconda-adozione-in-russia-su-una-cosa-ivan-e-stato-sicuro-fin-dallinizio-voleva-tornare-nel-suo-paese-di-origine\/","og_locale":"it_IT","og_type":"article","og_title":"Seconda adozione in Russia: \"Su una cosa Ivan \u00e8 stato sicuro fin dall\u2019inizio: voleva tornare nel suo Paese di origine\"","og_description":"\"Se siamo arrivati alla seconda adozione, \u00e8 solo merito di nostro figlio Ivan! Per quanto noi fossimo gi\u00e0 di questa idea, \u00e8 stato suo il desiderio profondo di avere un fratello o una sorella\u201d.","og_url":"https:\/\/www.aibi.it\/ita\/seconda-adozione-in-russia-su-una-cosa-ivan-e-stato-sicuro-fin-dallinizio-voleva-tornare-nel-suo-paese-di-origine\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2021-01-03T06:30:15+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2020\/10\/Russia.jpg","type":"image\/jpeg"}],"author":"mc.sabatini","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"mc.sabatini","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/seconda-adozione-in-russia-su-una-cosa-ivan-e-stato-sicuro-fin-dallinizio-voleva-tornare-nel-suo-paese-di-origine\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/seconda-adozione-in-russia-su-una-cosa-ivan-e-stato-sicuro-fin-dallinizio-voleva-tornare-nel-suo-paese-di-origine\/"},"author":{"name":"mc.sabatini","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938"},"headline":"Seconda adozione in Russia: &#8220;Su una cosa Ivan \u00e8 stato sicuro fin dall\u2019inizio: voleva tornare nel suo Paese di origine&#8221;","datePublished":"2021-01-03T06:30:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/seconda-adozione-in-russia-su-una-cosa-ivan-e-stato-sicuro-fin-dallinizio-voleva-tornare-nel-suo-paese-di-origine\/"},"wordCount":518,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/seconda-adozione-in-russia-su-una-cosa-ivan-e-stato-sicuro-fin-dallinizio-voleva-tornare-nel-suo-paese-di-origine\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2020\/10\/Russia.jpg","keywords":["adozione","Russia"],"articleSection":["Adozione Internazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/seconda-adozione-in-russia-su-una-cosa-ivan-e-stato-sicuro-fin-dallinizio-voleva-tornare-nel-suo-paese-di-origine\/","url":"https:\/\/www.aibi.it\/ita\/seconda-adozione-in-russia-su-una-cosa-ivan-e-stato-sicuro-fin-dallinizio-voleva-tornare-nel-suo-paese-di-origine\/","name":"Seconda adozione in Russia: \"Su una cosa Ivan \u00e8 stato sicuro fin dall\u2019inizio: voleva tornare nel suo Paese di origine\" - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/seconda-adozione-in-russia-su-una-cosa-ivan-e-stato-sicuro-fin-dallinizio-voleva-tornare-nel-suo-paese-di-origine\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/seconda-adozione-in-russia-su-una-cosa-ivan-e-stato-sicuro-fin-dallinizio-voleva-tornare-nel-suo-paese-di-origine\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2020\/10\/Russia.jpg","datePublished":"2021-01-03T06:30:15+00:00","description":"Adozione: \"Se siamo arrivati alla seconda adozione, \u00e8 solo merito di nostro figlio Ivan! Per quanto noi fossimo gi\u00e0 di questa idea, \u00e8 stato suo il desiderio profondo di avere un fratello o una sorella\u201d.","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/seconda-adozione-in-russia-su-una-cosa-ivan-e-stato-sicuro-fin-dallinizio-voleva-tornare-nel-suo-paese-di-origine\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/seconda-adozione-in-russia-su-una-cosa-ivan-e-stato-sicuro-fin-dallinizio-voleva-tornare-nel-suo-paese-di-origine\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/seconda-adozione-in-russia-su-una-cosa-ivan-e-stato-sicuro-fin-dallinizio-voleva-tornare-nel-suo-paese-di-origine\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2020\/10\/Russia.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2020\/10\/Russia.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/seconda-adozione-in-russia-su-una-cosa-ivan-e-stato-sicuro-fin-dallinizio-voleva-tornare-nel-suo-paese-di-origine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione Internazionale","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-internazionale\/"},{"@type":"ListItem","position":3,"name":"Seconda adozione in Russia: &#8220;Su una cosa Ivan \u00e8 stato sicuro fin dall\u2019inizio: voleva tornare nel suo Paese di origine&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938","name":"mc.sabatini","url":"https:\/\/www.aibi.it\/ita\/author\/marias\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 08:05:37","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/184017","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/97"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=184017"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/184017\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/180068"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=184017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=184017"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=184017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}