﻿{"id":184156,"date":"2021-01-09T07:30:22","date_gmt":"2021-01-09T06:30:22","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=184156"},"modified":"2022-07-25T16:23:22","modified_gmt":"2022-07-25T14:23:22","slug":"kenya-il-meraviglioso-compleanno-di-gebron-festeggiato-con-i-suoi-compagni-di-classe","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/kenya-il-meraviglioso-compleanno-di-gebron-festeggiato-con-i-suoi-compagni-di-classe\/","title":{"rendered":"Kenya. Il meraviglioso compleanno di Gebron festeggiato con i suoi compagni di classe!"},"content":{"rendered":"<h2 style=\"font-weight: 400;\"><strong>Grazie al programma di Adozione a Distanza, Gebron ha avuto la fortuna di trovare dei sostenitori che gli permettono di frequentare la scuola senza pensieri, \u00a0di avere un\u2019alimentazione sana e ogni tanto qualche regalino come durante la festa del suo decimo compleanno\u2026<\/strong><\/h2>\n<p style=\"font-weight: 400;\"><strong>\u00a0<\/strong>Qualche giorno fa alla scuola\u00a0<strong>Sancare<\/strong>, partner di Ai.Bi. per i progetti di Adozione e di\u00a0Sostegno a Distanza\u00a0a favore dei bambini dell\u2019insediamento informale di\u00a0<strong>Mathare<\/strong>, \u00e8 stato festeggiato il\u00a0<strong>decimo compleanno di Gebron<\/strong>, uno dei suoi piccoli alunni.<\/p>\n<p style=\"font-weight: 400;\">\u00c8 stato un giorno davvero speciale! Gebron ha potuto celebrare il suo compleanno assieme alla mamma, ai suoi amici e ai suoi compagni di classe, grazie al prezioso\u00a0<strong>sostegno dei suoi\u00a0<a href=\"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/\">\u201cangeli a distanza\u201d<\/a><\/strong>\u00a0che hanno voluto regalare al bimbo<strong>\u00a0una buonissima torta<\/strong>,\u00a0<strong>vestiti<\/strong>,\u00a0<strong>scarpe nuove<\/strong>\u00a0e\u00a0<strong>un pacco di alimenti da condividere con la mamma e la nonna.<\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong>\u00a0<\/strong>La mamma di Gebron a causa di un problema alla gamba non pu\u00f2 pi\u00f9 camminare senza stampelle e di conseguenza fa molta fatica a lavorare abbastanza per occuparsi di tutte le spese sue e del figlio, per questo vivono con la nonna materna aiutandosi a vicenda.<\/p>\n<h3 style=\"font-weight: 400;\"><strong>\u00a0<\/strong><strong>Le gioie dell\u2019Adozione a Distanza: l\u2019Accoglienza del cuore\u00a0<\/strong><\/h3>\n<p style=\"font-weight: 400;\">Grazie al programma di\u00a0<strong>Adozione a Distanza,<\/strong>\u00a0Gebron ha avuto la fortuna di trovare dei sostenitori che gli permettono di\u00a0<strong>frequentare la scuola\u00a0<\/strong>senza pensieri, alleggerendo cos\u00ec il carico della mamma e della nonna, di avere\u00a0<strong>un\u2019alimentazione sana<\/strong>\u00a0e ogni tanto qualche regalino come durante la festa del suo decimo compleanno.<\/p>\n<p style=\"font-weight: 400;\">Gebron \u00e8 un bambino davvero fortunato ma sono tanti i minori fragili o soli in\u00a0<strong>Kenya<\/strong>\u00a0ad aver bisogno di un padrino o di una madrina che a distanza veglino sulla loro crescita e sulla loro istruzione.<\/p>\n<p style=\"font-weight: 400;\">Chiss\u00e0 quanti piccoli amici di Gebron gustando la sua buonissima torta di compleanno e ammirando gli abiti nuovi ricevuti in dono, hanno desiderato di poter avere un giorno anche loro\u00a0<strong>un amico lontano a cui affidarsi<\/strong>\u00a0e a cui scrivere, sapendo di essere amati e considerati.<\/p>\n<p style=\"font-weight: 400;\">Gebron era il bambino pi\u00f9 felice del mondo!\u00a0<strong>Era\u00a0la\u00a0prima\u00a0volta\u00a0che per il suo compleanno aveva una\u00a0torta\u00a0tutta sua!<\/strong><\/p>\n<p style=\"font-weight: 400;\">Perch\u00e9 non donare questo sogno anche a tanti altri bimbi che come Gebron hanno bisogno del nostro sostegno per vedere garantite migliori condizioni di vita?<\/p>\n<p style=\"font-weight: 400;\">Grazie\u00a0<strong>all\u2019Adozione a Distanza<\/strong>\u00a0puoi farlo.\u00a0<a href=\"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/\">Visita la nostra pagina<\/a>. Regala ai bambini meno fortunati il diritto ad un\u2019infanzia serena e scopri l\u2019 Accoglienza del cuore.<\/p>\n\n<!-- Buttons X - Start -->\n<style type=\"text\/css\">\/*168342-start*\/\n#btnsx-168342{margin-top:0px;margin-bottom:20px;margin-left:0px;margin-right:0px;padding-top:20px;padding-bottom:20px;padding-left:40px;padding-right:40px;}\n#btnsx-168342 .btnsx-text-primary{font-size:30px;line-height:30px;font-family:Montserrat;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-168342:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-168342 .btnsx-text-secondary{}\n#btnsx-168342 .btnsx-icon{}\n#btnsx-168342 .btnsx-icon-img{}\n#btnsx-168342{background-color:#ef7b0b!important;}\n#btnsx-168342:before{background-color:#eab20b!important;}\n#btnsx-168342:hover{background-color:#eab20b!important;}\n#btnsx-168342{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-168342:hover{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-168342-dropdown .menu-item a{}\n#btnsx-168342-dropdown{border-top-width:px;border-bottom-width:px;border-left-width:px;border-right-width:px;}\n#btnsx-168342-dropdown:before{border-width:8px;margin-left:-8px;border-bottom-color:}\n#btnsx-168342-dropdown:after{}\n#btnsx-168342-dropdown{}\n@media screen and (max-width: 768px) {\n#btnsx-168342 {display:inline-block;}\n#btnsx-168342 .btnsx-text-primary {}\n#btnsx-168342 .btnsx-text-secondary {}\n#btnsx-168342 .btnsx-icon {}\n#btnsx-168342 .btnsx-divider {}\n}@media screen and (max-width: 480px) {\n#btnsx-168342 {display:inline-block;}\n#btnsx-168342 .btnsx-text-primary {}\n#btnsx-168342 .btnsx-text-secondary {}\n#btnsx-168342 .btnsx-icon {}\n#btnsx-168342 .btnsx-divider {}\n}\/*168342-end*\/\n<\/style><div id=\"btnsx-168342-wrap\" class=\"btnsx-wrap-center\" align=\"center\"><div id=\"btnsx-168342-container\" class=\"btnsx-btn-container\">\n<a href=\"https:\/\/www.aibi.it\/ita\/adotta-a-distanza-25\/\" id=\"btnsx-168342\" target=\"_blank\" class=\"btnsx-btn  btnsx-btn-embossed\"  data-font-primary=\"Montserrat\" data-animation-type=\"\">\n\t<span class=\"btnsx-text-primary \">Scopri di pi\u00f9<\/span><\/a>\n<\/div><\/div>\n<!-- Buttons X - End -->\n\n<p style=\"font-weight: 400;\">\n","protected":false},"excerpt":{"rendered":"<p>Grazie al programma di Adozione a Distanza, Gebron ha avuto la fortuna di trovare dei sostenitori che gli permettono di frequentare la scuola senza pensieri, &nbsp;di avere un&rsquo;alimentazione sana e ogni tanto qualche regalino come durante la festa del suo decimo compleanno&hellip; &nbsp;Qualche giorno fa alla scuola&nbsp;Sancare, partner di Ai.Bi. [&hellip;]<\/p>\n","protected":false},"author":97,"featured_media":184159,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[209],"tags":[306],"class_list":["post-184156","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-a-distanza","tag-kenya"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Kenya. Il meraviglioso compleanno di Gebron festeggiato con i suoi compagni di classe! - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"Kenya: grazie al programma di Adozione a Distanza, Gebron ha avuto la fortuna di trovare dei sostenitori che gli permettono di frequentare la scuola senza pensieri, \u00a0di avere un\u2019alimentazione sana e ogni tanto qualche regalino come durante la festa del suo decimo compleanno\u2026\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/kenya-il-meraviglioso-compleanno-di-gebron-festeggiato-con-i-suoi-compagni-di-classe\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kenya. Il meraviglioso compleanno di Gebron festeggiato con i suoi compagni di classe!\" \/>\n<meta property=\"og:description\" content=\"Grazie al programma di Adozione a Distanza, Gebron ha avuto la fortuna di trovare dei sostenitori che gli permettono di frequentare la scuola senza pensieri, \u00a0di avere un\u2019alimentazione sana e ogni tanto qualche regalino come durante la festa del suo decimo compleanno\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/kenya-il-meraviglioso-compleanno-di-gebron-festeggiato-con-i-suoi-compagni-di-classe\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-09T06:30:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-25T14:23:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2021\/01\/Kenya.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mc.sabatini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mc.sabatini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-il-meraviglioso-compleanno-di-gebron-festeggiato-con-i-suoi-compagni-di-classe\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-il-meraviglioso-compleanno-di-gebron-festeggiato-con-i-suoi-compagni-di-classe\\\/\"},\"author\":{\"name\":\"mc.sabatini\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\"},\"headline\":\"Kenya. Il meraviglioso compleanno di Gebron festeggiato con i suoi compagni di classe!\",\"datePublished\":\"2021-01-09T06:30:22+00:00\",\"dateModified\":\"2022-07-25T14:23:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-il-meraviglioso-compleanno-di-gebron-festeggiato-con-i-suoi-compagni-di-classe\\\/\"},\"wordCount\":436,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-il-meraviglioso-compleanno-di-gebron-festeggiato-con-i-suoi-compagni-di-classe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/01\\\/Kenya.jpg\",\"keywords\":[\"Kenya\"],\"articleSection\":[\"Adozione a Distanza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-il-meraviglioso-compleanno-di-gebron-festeggiato-con-i-suoi-compagni-di-classe\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-il-meraviglioso-compleanno-di-gebron-festeggiato-con-i-suoi-compagni-di-classe\\\/\",\"name\":\"Kenya. Il meraviglioso compleanno di Gebron festeggiato con i suoi compagni di classe! - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-il-meraviglioso-compleanno-di-gebron-festeggiato-con-i-suoi-compagni-di-classe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-il-meraviglioso-compleanno-di-gebron-festeggiato-con-i-suoi-compagni-di-classe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/01\\\/Kenya.jpg\",\"datePublished\":\"2021-01-09T06:30:22+00:00\",\"dateModified\":\"2022-07-25T14:23:22+00:00\",\"description\":\"Kenya: grazie al programma di Adozione a Distanza, Gebron ha avuto la fortuna di trovare dei sostenitori che gli permettono di frequentare la scuola senza pensieri, \u00a0di avere un\u2019alimentazione sana e ogni tanto qualche regalino come durante la festa del suo decimo compleanno\u2026\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-il-meraviglioso-compleanno-di-gebron-festeggiato-con-i-suoi-compagni-di-classe\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-il-meraviglioso-compleanno-di-gebron-festeggiato-con-i-suoi-compagni-di-classe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-il-meraviglioso-compleanno-di-gebron-festeggiato-con-i-suoi-compagni-di-classe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/01\\\/Kenya.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/01\\\/Kenya.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-il-meraviglioso-compleanno-di-gebron-festeggiato-con-i-suoi-compagni-di-classe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione a Distanza\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-a-distanza\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Kenya. Il meraviglioso compleanno di Gebron festeggiato con i suoi compagni di classe!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\",\"name\":\"mc.sabatini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/marias\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Kenya. Il meraviglioso compleanno di Gebron festeggiato con i suoi compagni di classe! - Ai.Bi. Amici dei Bambini","description":"Kenya: grazie al programma di Adozione a Distanza, Gebron ha avuto la fortuna di trovare dei sostenitori che gli permettono di frequentare la scuola senza pensieri, \u00a0di avere un\u2019alimentazione sana e ogni tanto qualche regalino come durante la festa del suo decimo compleanno\u2026","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/kenya-il-meraviglioso-compleanno-di-gebron-festeggiato-con-i-suoi-compagni-di-classe\/","og_locale":"it_IT","og_type":"article","og_title":"Kenya. Il meraviglioso compleanno di Gebron festeggiato con i suoi compagni di classe!","og_description":"Grazie al programma di Adozione a Distanza, Gebron ha avuto la fortuna di trovare dei sostenitori che gli permettono di frequentare la scuola senza pensieri, \u00a0di avere un\u2019alimentazione sana e ogni tanto qualche regalino come durante la festa del suo decimo compleanno\u2026","og_url":"https:\/\/www.aibi.it\/ita\/kenya-il-meraviglioso-compleanno-di-gebron-festeggiato-con-i-suoi-compagni-di-classe\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2021-01-09T06:30:22+00:00","article_modified_time":"2022-07-25T14:23:22+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2021\/01\/Kenya.jpg","type":"image\/jpeg"}],"author":"mc.sabatini","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"mc.sabatini","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/kenya-il-meraviglioso-compleanno-di-gebron-festeggiato-con-i-suoi-compagni-di-classe\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-il-meraviglioso-compleanno-di-gebron-festeggiato-con-i-suoi-compagni-di-classe\/"},"author":{"name":"mc.sabatini","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938"},"headline":"Kenya. Il meraviglioso compleanno di Gebron festeggiato con i suoi compagni di classe!","datePublished":"2021-01-09T06:30:22+00:00","dateModified":"2022-07-25T14:23:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-il-meraviglioso-compleanno-di-gebron-festeggiato-con-i-suoi-compagni-di-classe\/"},"wordCount":436,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-il-meraviglioso-compleanno-di-gebron-festeggiato-con-i-suoi-compagni-di-classe\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/01\/Kenya.jpg","keywords":["Kenya"],"articleSection":["Adozione a Distanza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/kenya-il-meraviglioso-compleanno-di-gebron-festeggiato-con-i-suoi-compagni-di-classe\/","url":"https:\/\/www.aibi.it\/ita\/kenya-il-meraviglioso-compleanno-di-gebron-festeggiato-con-i-suoi-compagni-di-classe\/","name":"Kenya. Il meraviglioso compleanno di Gebron festeggiato con i suoi compagni di classe! - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-il-meraviglioso-compleanno-di-gebron-festeggiato-con-i-suoi-compagni-di-classe\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-il-meraviglioso-compleanno-di-gebron-festeggiato-con-i-suoi-compagni-di-classe\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/01\/Kenya.jpg","datePublished":"2021-01-09T06:30:22+00:00","dateModified":"2022-07-25T14:23:22+00:00","description":"Kenya: grazie al programma di Adozione a Distanza, Gebron ha avuto la fortuna di trovare dei sostenitori che gli permettono di frequentare la scuola senza pensieri, \u00a0di avere un\u2019alimentazione sana e ogni tanto qualche regalino come durante la festa del suo decimo compleanno\u2026","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-il-meraviglioso-compleanno-di-gebron-festeggiato-con-i-suoi-compagni-di-classe\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/kenya-il-meraviglioso-compleanno-di-gebron-festeggiato-con-i-suoi-compagni-di-classe\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/kenya-il-meraviglioso-compleanno-di-gebron-festeggiato-con-i-suoi-compagni-di-classe\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2021\/01\/Kenya.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/01\/Kenya.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/kenya-il-meraviglioso-compleanno-di-gebron-festeggiato-con-i-suoi-compagni-di-classe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione a Distanza","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-a-distanza\/"},{"@type":"ListItem","position":3,"name":"Kenya. Il meraviglioso compleanno di Gebron festeggiato con i suoi compagni di classe!"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938","name":"mc.sabatini","url":"https:\/\/www.aibi.it\/ita\/author\/marias\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 03:03:11","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/184156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/97"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=184156"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/184156\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/184159"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=184156"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=184156"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=184156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}