﻿


{"id":184454,"date":"2021-01-19T19:09:56","date_gmt":"2021-01-19T18:09:56","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=184454"},"modified":"2021-02-01T17:48:10","modified_gmt":"2021-02-01T16:48:10","slug":"vorrei-donare-un-lascito-un-bambino-abbandonato-cosa-devo-scrivere-nel-mio-testamento","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/vorrei-donare-un-lascito-un-bambino-abbandonato-cosa-devo-scrivere-nel-mio-testamento\/","title":{"rendered":"Vorrei donare un lascito ad un bambino abbandonato. Cosa devo scrivere nel mio testamento?"},"content":{"rendered":"<blockquote>\n<p style=\"text-align: left;\">Buongiorno,<br class=\"\" \/>mi chiamo Laura e sono una professionista che si avvicina a maturare sufficienti anni di contributi per dire addio al lavoro. Essendo single, vorrei esprimere un desiderio che mi sta a cuore da diverso tempo e pensare a compiere un gesto di solidariet\u00e0 per sostenere la vostra missione contro l\u2019abbandono. Vorrei lasciare parte della mia eredit\u00e0 a un bambino abbandonato. Come posso fare per includerlo nei miei lasciti testamentari? Cosa devo comunicare al notaio per procedere?<br class=\"\" \/>Grazie<br class=\"\" \/>Laura<\/p>\n<\/blockquote>\n<p>Gentilissima Laura,<br class=\"\" \/><br class=\"\" \/>rispondiamo con piacere alla sua email anche se occorrerebbe capire come primo punto se Lei <strong>ha in mente uno specifico bambino abbandonato,<\/strong> ad esempio perch\u00e9 gi\u00e0 sostiene l&#8217;associazione con un SAD oppure perch\u00e9 ha conosciuto un preciso bambino, <strong>oppure se la Sua idea \u00e8 quella di contribuire in generale alla missione di Ai.Bi.<\/strong><br class=\"\" \/><br class=\"\" \/><\/p>\n<p>Nel primo caso, se intende inserire un minorenne come beneficiario del suo testamento, occorre sapere che tra il momento in cui si fa testamento e il momento in cui poi questo spiegher\u00e0 efficacia passeranno molti anni, come speriamo, e quindi il minore potrebbe a quel tempo essere adulto e in tal caso <strong>decider\u00e0 se accettare o meno il lascito e cosa farne.<\/strong> Se invece al tempo dell&#8217;apertura del testamento il beneficiario sar\u00e0 ancora minorenne, allora \u00e8 utile sapere che in assenza di genitori, il bambino o ragazzo avr\u00e0 comunque delle figure che saranno deputate ad esercitare i suoi diritti e quindi ad <strong>occuparsi al suo posto delle procedure per l&#8217;accettazione dell&#8217;eredit\u00e0<\/strong> e la sua corretta gestione fino alla maggiore et\u00e0.<\/p>\n<h3>Accettazione con beneficio di inventario<\/h3>\n<p>Pi\u00f9 precisamente, non potendo il minore agire direttamente, dovr\u00e0 necessariamente <strong>accettare l\u2019eredit\u00e0 con beneficio di inventario in nome e per conto del minore<\/strong>, <strong>un tutore<\/strong>\u00a0(che potr\u00e0 essere o un genitore o una persona nominata dal Tribunale per i Minorenni competente) che accetter\u00e0 al posto suo. Se lo desidera nel testamento stesso si pu\u00f2 anche designare un tutore per questi adempimenti.<br class=\"\" \/><br class=\"\" \/>In ogni caso i beni appartenenti al minore anche se amministrati dal tutore, potranno essere utilizzati a qualsiasi titolo solo con l\u2019autorizzazione del giudice tutelare.<br class=\"\" \/><br class=\"\" \/>Per quanto riguarda l\u2019attivit\u00e0 di <strong>protezione dell&#8217;infanzia<\/strong> che Ai.Bi. svolge per i bambini abbandonati, si tratta per lo pi\u00f9 di minori stranieri normalmente presenti all\u2019estero, per cui la procedura sopra indicata potrebbe diventare particolarmente complicata e non necessariamente utile all&#8217;idea generale di contribuire nel migliori modo all&#8217;utilizzo del denaro per questi scopi. Sempre per il tempo che trascorre tra il fare testamento e la sua apertura, infatti, le situazioni possono mutare e non possiamo essere in grado di sapere se in quel futuro momento esisteranno gli stessi progetti, i bambini in carico in determinate strutture potranno essere rientrati in famiglia o accolti da altra famiglia, non raggiungibili dall&#8217;Associazione e cos\u00ec via.<br class=\"\" \/><br class=\"\" \/><\/p>\n<h3><strong>Lasciti testamentari: parte dell\u2019eredit\u00e0 a un minore abbandonato? Una soluzione pi\u00f9 semplice<\/strong><br class=\"\" \/><br class=\"\" \/><\/h3>\n<p>La soluzione preferibile, in questo caso in cui non avesse in mente uno specifico bambino di sua conoscenza ma avesse <strong>il desiderio di aiutare un bambino in difficolt\u00e0 non identificato<\/strong>, \u00e8 quella di <strong>devolvere per testamento i propri beni direttamente all\u2019Associazione<\/strong> evitando la richiesta di essere utilizzati a vantaggio di un minore specificamente indicato direttamente da lei. Anche l&#8217;indicazione di un preciso progetto a tutela dell\u2019abbandono esistente <span id=\"OBJ_PREFIX_DWT4117_com_zimbra_date\" class=\"Object\" role=\"link\"><span id=\"OBJ_PREFIX_DWT4145_com_zimbra_date\" class=\"Object\" role=\"link\">oggi<\/span><\/span> potrebbe essere controproducente in caso ad essa fosse vincolato il lascito, proprio perch\u00e9 anche per i progetti non si pu\u00f2 essere certi\u00a0<span id=\"OBJ_PREFIX_DWT4118_com_zimbra_date\" class=\"Object\" role=\"link\"><span id=\"OBJ_PREFIX_DWT4146_com_zimbra_date\" class=\"Object\" role=\"link\">oggi<\/span><\/span>\u00a0di quali saranno realizzati e saranno pi\u00f9 urgenti in futuro.<br class=\"\" \/><br class=\"\" \/><\/p>\n<h3><strong>E&#8217; quindi preferibile evitare i lasciti con precisi destinatari tramite l&#8217;Associazione<\/strong><\/h3>\n<p>oppure lasciti condizionati, perch\u00e9 l\u2019Associazione per statuto sostiene comunit\u00e0 e non singole persone e, inoltre, i progetti che vengono realizzati hanno una durata stabilita e sono legati alla presenza e operativit\u00e0 dell\u2019Ente in un dato momento storico: i<strong>n altre parole, non \u00e8 detto che al momento dell\u2019apertura della successione i progetti indicati nel testamento siano ancora in corso<\/strong> n\u00e9 che \u2013 se si tratta di progetti all\u2019estero \u2013 l\u2019Ente operi ancora in quel preciso Paese straniero, visto che questo aspetto \u00e8 legato ad autorizzazioni delle pubbliche autorit\u00e0.<br class=\"\" \/><br class=\"\" \/>Purtroppo, nel caso in cui un progetto non sia identificabile o il bambino indicato come beneficiario attraverso l\u2019associazione non sia pi\u00f9 reperibile all\u2019apertura del testamento, il lascito ad una Associazione condizionato con un utilizzo troppo stringente <strong>potrebbe determinare l\u2019inefficacia della disposizione<\/strong> <strong>testamentaria in favore della stessa Associazione<\/strong>. Diversa e senz\u2019altro preferibile \u00e8 l\u2019ipotesi in cui il lascito all\u2019Associazione di Sua fiducia non sia sottoposto a vincoli, e in quel caso sarebbe senz\u2019altro valido e utilizzato dall\u2019Associazione per gli scopi indicati nello Statuto, a beneficio di progetti e attivit\u00e0 che in quel momento l\u2019Associazione star\u00e0 realizzando.<br class=\"\" \/><br class=\"\" \/>Riteniamo per tutti questi motivi come preferibile la soluzione di indicare al notaio che il lascito abbia ad oggetto una quota del patrimonio di sicura disponibilit\u00e0 senza intaccare porzioni spettanti per legge ad altri e comunicare i riferimenti dell&#8217;Associazione di cui si ha fiducia senza vincolare l&#8217;eredit\u00e0 o il lascito a specifici adempimenti.<br class=\"\" \/><br class=\"\" \/>Sperando di averle fornito delle indicazioni utili, la ringraziamo e per essersi rivolta a noi e porgiamo<br class=\"\" \/><br class=\"\" \/>Cordiali saluti<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Buongiorno,mi chiamo Laura e sono una professionista che si avvicina a maturare sufficienti anni di contributi per dire addio al lavoro. Essendo single, vorrei esprimere un desiderio che mi sta a cuore da diverso tempo e pensare a compiere un gesto di solidariet&agrave; per sostenere la vostra missione contro l&rsquo;abbandono. [&hellip;]<\/p>\n","protected":false},"author":97,"featured_media":184456,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[731,50],"tags":[318],"class_list":["post-184454","post","type-post","status-publish","format-standard","has-post-thumbnail","category-lasciti-testamentari","category-lettere-al-direttore","tag-lettere-al-direttore"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Vorrei donare un lascito ad un bambino abbandonato. Cosa devo scrivere nel mio testamento? - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"Lascito testamentario: Laura vorrebbe lasciare parte della sua eredit\u00e0 a un bambino abbandonato. E chiede ad Ai.Bi. come poter fare\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/vorrei-donare-un-lascito-un-bambino-abbandonato-cosa-devo-scrivere-nel-mio-testamento\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vorrei donare un lascito ad un bambino abbandonato. Cosa devo scrivere nel mio testamento?\" \/>\n<meta property=\"og:description\" content=\"Lascito testamentario: Laura vorrebbe lasciare parte della sua eredit\u00e0 a un bambino abbandonato. E chiede ad Ai.Bi. come poter fare\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/vorrei-donare-un-lascito-un-bambino-abbandonato-cosa-devo-scrivere-nel-mio-testamento\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-19T18:09:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-01T16:48:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2021\/01\/bambino.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mc.sabatini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mc.sabatini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/vorrei-donare-un-lascito-un-bambino-abbandonato-cosa-devo-scrivere-nel-mio-testamento\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/vorrei-donare-un-lascito-un-bambino-abbandonato-cosa-devo-scrivere-nel-mio-testamento\\\/\"},\"author\":{\"name\":\"mc.sabatini\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\"},\"headline\":\"Vorrei donare un lascito ad un bambino abbandonato. Cosa devo scrivere nel mio testamento?\",\"datePublished\":\"2021-01-19T18:09:56+00:00\",\"dateModified\":\"2021-02-01T16:48:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/vorrei-donare-un-lascito-un-bambino-abbandonato-cosa-devo-scrivere-nel-mio-testamento\\\/\"},\"wordCount\":875,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/vorrei-donare-un-lascito-un-bambino-abbandonato-cosa-devo-scrivere-nel-mio-testamento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/01\\\/bambino.jpg\",\"keywords\":[\"Lettere al Direttore\"],\"articleSection\":[\"Lasciti Testamentari\",\"Lettere al direttore\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/vorrei-donare-un-lascito-un-bambino-abbandonato-cosa-devo-scrivere-nel-mio-testamento\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/vorrei-donare-un-lascito-un-bambino-abbandonato-cosa-devo-scrivere-nel-mio-testamento\\\/\",\"name\":\"Vorrei donare un lascito ad un bambino abbandonato. Cosa devo scrivere nel mio testamento? - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/vorrei-donare-un-lascito-un-bambino-abbandonato-cosa-devo-scrivere-nel-mio-testamento\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/vorrei-donare-un-lascito-un-bambino-abbandonato-cosa-devo-scrivere-nel-mio-testamento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/01\\\/bambino.jpg\",\"datePublished\":\"2021-01-19T18:09:56+00:00\",\"dateModified\":\"2021-02-01T16:48:10+00:00\",\"description\":\"Lascito testamentario: Laura vorrebbe lasciare parte della sua eredit\u00e0 a un bambino abbandonato. E chiede ad Ai.Bi. come poter fare\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/vorrei-donare-un-lascito-un-bambino-abbandonato-cosa-devo-scrivere-nel-mio-testamento\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/vorrei-donare-un-lascito-un-bambino-abbandonato-cosa-devo-scrivere-nel-mio-testamento\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/vorrei-donare-un-lascito-un-bambino-abbandonato-cosa-devo-scrivere-nel-mio-testamento\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/01\\\/bambino.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/01\\\/bambino.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/vorrei-donare-un-lascito-un-bambino-abbandonato-cosa-devo-scrivere-nel-mio-testamento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lasciti Testamentari\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/lasciti-testamentari\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Vorrei donare un lascito ad un bambino abbandonato. Cosa devo scrivere nel mio testamento?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\",\"name\":\"mc.sabatini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/marias\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Vorrei donare un lascito ad un bambino abbandonato. Cosa devo scrivere nel mio testamento? - Ai.Bi. Amici dei Bambini","description":"Lascito testamentario: Laura vorrebbe lasciare parte della sua eredit\u00e0 a un bambino abbandonato. E chiede ad Ai.Bi. come poter fare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/vorrei-donare-un-lascito-un-bambino-abbandonato-cosa-devo-scrivere-nel-mio-testamento\/","og_locale":"it_IT","og_type":"article","og_title":"Vorrei donare un lascito ad un bambino abbandonato. Cosa devo scrivere nel mio testamento?","og_description":"Lascito testamentario: Laura vorrebbe lasciare parte della sua eredit\u00e0 a un bambino abbandonato. E chiede ad Ai.Bi. come poter fare","og_url":"https:\/\/www.aibi.it\/ita\/vorrei-donare-un-lascito-un-bambino-abbandonato-cosa-devo-scrivere-nel-mio-testamento\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2021-01-19T18:09:56+00:00","article_modified_time":"2021-02-01T16:48:10+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2021\/01\/bambino.jpg","type":"image\/jpeg"}],"author":"mc.sabatini","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"mc.sabatini","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/vorrei-donare-un-lascito-un-bambino-abbandonato-cosa-devo-scrivere-nel-mio-testamento\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/vorrei-donare-un-lascito-un-bambino-abbandonato-cosa-devo-scrivere-nel-mio-testamento\/"},"author":{"name":"mc.sabatini","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938"},"headline":"Vorrei donare un lascito ad un bambino abbandonato. Cosa devo scrivere nel mio testamento?","datePublished":"2021-01-19T18:09:56+00:00","dateModified":"2021-02-01T16:48:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/vorrei-donare-un-lascito-un-bambino-abbandonato-cosa-devo-scrivere-nel-mio-testamento\/"},"wordCount":875,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/vorrei-donare-un-lascito-un-bambino-abbandonato-cosa-devo-scrivere-nel-mio-testamento\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/01\/bambino.jpg","keywords":["Lettere al Direttore"],"articleSection":["Lasciti Testamentari","Lettere al direttore"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/vorrei-donare-un-lascito-un-bambino-abbandonato-cosa-devo-scrivere-nel-mio-testamento\/","url":"https:\/\/www.aibi.it\/ita\/vorrei-donare-un-lascito-un-bambino-abbandonato-cosa-devo-scrivere-nel-mio-testamento\/","name":"Vorrei donare un lascito ad un bambino abbandonato. Cosa devo scrivere nel mio testamento? - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/vorrei-donare-un-lascito-un-bambino-abbandonato-cosa-devo-scrivere-nel-mio-testamento\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/vorrei-donare-un-lascito-un-bambino-abbandonato-cosa-devo-scrivere-nel-mio-testamento\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/01\/bambino.jpg","datePublished":"2021-01-19T18:09:56+00:00","dateModified":"2021-02-01T16:48:10+00:00","description":"Lascito testamentario: Laura vorrebbe lasciare parte della sua eredit\u00e0 a un bambino abbandonato. E chiede ad Ai.Bi. come poter fare","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/vorrei-donare-un-lascito-un-bambino-abbandonato-cosa-devo-scrivere-nel-mio-testamento\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/vorrei-donare-un-lascito-un-bambino-abbandonato-cosa-devo-scrivere-nel-mio-testamento\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/vorrei-donare-un-lascito-un-bambino-abbandonato-cosa-devo-scrivere-nel-mio-testamento\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2021\/01\/bambino.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/01\/bambino.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/vorrei-donare-un-lascito-un-bambino-abbandonato-cosa-devo-scrivere-nel-mio-testamento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Lasciti Testamentari","item":"https:\/\/www.aibi.it\/ita\/category\/lasciti-testamentari\/"},{"@type":"ListItem","position":3,"name":"Vorrei donare un lascito ad un bambino abbandonato. Cosa devo scrivere nel mio testamento?"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938","name":"mc.sabatini","url":"https:\/\/www.aibi.it\/ita\/author\/marias\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 03:27:25","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/184454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/97"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=184454"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/184454\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/184456"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=184454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=184454"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=184454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}