﻿


{"id":184478,"date":"2021-01-20T07:00:16","date_gmt":"2021-01-20T06:00:16","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=184478"},"modified":"2021-01-20T16:39:55","modified_gmt":"2021-01-20T15:39:55","slug":"adozione-internazionale-romania-esaurita-la-lista-di-attesa-delle-coppie-adottive","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-romania-esaurita-la-lista-di-attesa-delle-coppie-adottive\/","title":{"rendered":"Adozione internazionale.\u00a0Romania: esaurita la lista di attesa delle coppie adottive"},"content":{"rendered":"<h2>Solo le coppie rumene o Italo-rumene residenti in Italia possono adottare nel Paese europeo. Tempi di attesa dal deposito del dossier: 7 mesi.<\/h2>\n<p><strong>Cerchiamo coppie per la Romania!<\/strong><\/p>\n<p>Nella lista di attesa della Romania, Paese nel quale, <strong>nel 2020, 7 coppie di Ai.Bi. hanno adottato 8 bambini<\/strong>, attualmente <strong>ci sono solo 2 coppie in attesa di abbinamento<\/strong>: vorremmo pertanto ampliare la disponibilit\u00e0 della nostra lista, anche per corrispondere, nel migliore dei modi, alle richieste che ci perverranno dalle autorit\u00e0 del Paese europeo.<\/p>\n<p>L&#8217;unico requisito per poter adottare in Romania \u00e8 che <strong>almeno uno dei due coniugi sia di nazionalit\u00e0 rumena.<\/strong> La procedura prevede due viaggi della durata di circa di 1 mese ciascuno.<\/p>\n<p>I bambini dati in abbinamento hanno, per legge rumena, dai 3 anni in su: in particolare <strong>l\u2019et\u00e0 media si attesta sui 6 anni.<\/strong> I piccoli appartengono, prevalentemente, all&#8217;etnia rom. Non sono riscontrabili particolari patologie sanitarie nei minori che arrivano da questo Paese.<\/p>\n<p>La Romania si colloca tra i Paesi pi\u00f9 virtuosi in merito ai tempi di attesa: il tempo medio dal deposito del dossier fino alla ricezione dell\u2019abbinamento \u00e8 infatti di <strong>circa 7 mesi.<\/strong><\/p>\n<p>Dalla riapertura delle adozioni nel Paese, in totale sono state <strong>24<\/strong> le coppie che hanno adottato grazie ad Ai.Bi.<\/p>\n<p>Invitiamo tutte le famiglie in cui almeno un coniuge sia di nazionalit\u00e0 rumena, <strong>gi\u00e0 in possesso del decreto di idoneit\u00e0 o in procinto di averlo,<\/strong> a farsi avanti e contattarci chiamando il numero<strong> 02 988221<\/strong> o scrivendo a <strong>adozioni@aibi.it<\/strong> oppure ad iscriversi ad uno dei nostri incontri informativi gratuiti direttamente tramite il nostro sito al seguente link: https:\/\/www.aibi.it\/ita\/attivita\/adozione-internazionale\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Solo le coppie rumene o Italo-rumene residenti in Italia possono adottare nel Paese europeo. Tempi di attesa dal deposito del dossier: 7 mesi. Cerchiamo coppie per la Romania! Nella lista di attesa della Romania, Paese nel quale, nel 2020, 7 coppie di Ai.Bi. hanno adottato 8 bambini, attualmente ci sono [&hellip;]<\/p>\n","protected":false},"author":97,"featured_media":184471,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[172],"tags":[347,586],"class_list":["post-184478","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-internazionale","tag-adozione-internazionale","tag-romania"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozione internazionale.\u00a0Romania: esaurita la lista di attesa delle coppie adottive - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"Adozione Internazionale: solo le coppie rumene o Italo-rumene residenti in Italia possono adottare nel Paese europeo. Tempi di attesa dal deposito del dossier: 7 mesi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-romania-esaurita-la-lista-di-attesa-delle-coppie-adottive\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozione internazionale.\u00a0Romania: esaurita la lista di attesa delle coppie adottive\" \/>\n<meta property=\"og:description\" content=\"Solo le coppie rumene o Italo-rumene residenti in Italia possono adottare nel Paese europeo. Tempi di attesa dal deposito del dossier: 7 mesi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-romania-esaurita-la-lista-di-attesa-delle-coppie-adottive\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-20T06:00:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-20T15:39:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2021\/01\/Adozioni-Romania.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mc.sabatini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mc.sabatini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-romania-esaurita-la-lista-di-attesa-delle-coppie-adottive\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-romania-esaurita-la-lista-di-attesa-delle-coppie-adottive\\\/\"},\"author\":{\"name\":\"mc.sabatini\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\"},\"headline\":\"Adozione internazionale.\u00a0Romania: esaurita la lista di attesa delle coppie adottive\",\"datePublished\":\"2021-01-20T06:00:16+00:00\",\"dateModified\":\"2021-01-20T15:39:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-romania-esaurita-la-lista-di-attesa-delle-coppie-adottive\\\/\"},\"wordCount\":275,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-romania-esaurita-la-lista-di-attesa-delle-coppie-adottive\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/01\\\/Adozioni-Romania.jpg\",\"keywords\":[\"Adozione Internazionale\",\"Romania\"],\"articleSection\":[\"Adozione Internazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-romania-esaurita-la-lista-di-attesa-delle-coppie-adottive\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-romania-esaurita-la-lista-di-attesa-delle-coppie-adottive\\\/\",\"name\":\"Adozione internazionale.\u00a0Romania: esaurita la lista di attesa delle coppie adottive - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-romania-esaurita-la-lista-di-attesa-delle-coppie-adottive\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-romania-esaurita-la-lista-di-attesa-delle-coppie-adottive\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/01\\\/Adozioni-Romania.jpg\",\"datePublished\":\"2021-01-20T06:00:16+00:00\",\"dateModified\":\"2021-01-20T15:39:55+00:00\",\"description\":\"Adozione Internazionale: solo le coppie rumene o Italo-rumene residenti in Italia possono adottare nel Paese europeo. Tempi di attesa dal deposito del dossier: 7 mesi.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-romania-esaurita-la-lista-di-attesa-delle-coppie-adottive\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-romania-esaurita-la-lista-di-attesa-delle-coppie-adottive\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-romania-esaurita-la-lista-di-attesa-delle-coppie-adottive\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/01\\\/Adozioni-Romania.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/01\\\/Adozioni-Romania.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-romania-esaurita-la-lista-di-attesa-delle-coppie-adottive\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione Internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-internazionale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozione internazionale.\u00a0Romania: esaurita la lista di attesa delle coppie adottive\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\",\"name\":\"mc.sabatini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/marias\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozione internazionale.\u00a0Romania: esaurita la lista di attesa delle coppie adottive - Ai.Bi. Amici dei Bambini","description":"Adozione Internazionale: solo le coppie rumene o Italo-rumene residenti in Italia possono adottare nel Paese europeo. Tempi di attesa dal deposito del dossier: 7 mesi.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-romania-esaurita-la-lista-di-attesa-delle-coppie-adottive\/","og_locale":"it_IT","og_type":"article","og_title":"Adozione internazionale.\u00a0Romania: esaurita la lista di attesa delle coppie adottive","og_description":"Solo le coppie rumene o Italo-rumene residenti in Italia possono adottare nel Paese europeo. Tempi di attesa dal deposito del dossier: 7 mesi.","og_url":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-romania-esaurita-la-lista-di-attesa-delle-coppie-adottive\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2021-01-20T06:00:16+00:00","article_modified_time":"2021-01-20T15:39:55+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2021\/01\/Adozioni-Romania.jpg","type":"image\/jpeg"}],"author":"mc.sabatini","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"mc.sabatini","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-romania-esaurita-la-lista-di-attesa-delle-coppie-adottive\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-romania-esaurita-la-lista-di-attesa-delle-coppie-adottive\/"},"author":{"name":"mc.sabatini","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938"},"headline":"Adozione internazionale.\u00a0Romania: esaurita la lista di attesa delle coppie adottive","datePublished":"2021-01-20T06:00:16+00:00","dateModified":"2021-01-20T15:39:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-romania-esaurita-la-lista-di-attesa-delle-coppie-adottive\/"},"wordCount":275,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-romania-esaurita-la-lista-di-attesa-delle-coppie-adottive\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/01\/Adozioni-Romania.jpg","keywords":["Adozione Internazionale","Romania"],"articleSection":["Adozione Internazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-romania-esaurita-la-lista-di-attesa-delle-coppie-adottive\/","url":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-romania-esaurita-la-lista-di-attesa-delle-coppie-adottive\/","name":"Adozione internazionale.\u00a0Romania: esaurita la lista di attesa delle coppie adottive - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-romania-esaurita-la-lista-di-attesa-delle-coppie-adottive\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-romania-esaurita-la-lista-di-attesa-delle-coppie-adottive\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/01\/Adozioni-Romania.jpg","datePublished":"2021-01-20T06:00:16+00:00","dateModified":"2021-01-20T15:39:55+00:00","description":"Adozione Internazionale: solo le coppie rumene o Italo-rumene residenti in Italia possono adottare nel Paese europeo. Tempi di attesa dal deposito del dossier: 7 mesi.","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-romania-esaurita-la-lista-di-attesa-delle-coppie-adottive\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozione-internazionale-romania-esaurita-la-lista-di-attesa-delle-coppie-adottive\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-romania-esaurita-la-lista-di-attesa-delle-coppie-adottive\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2021\/01\/Adozioni-Romania.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/01\/Adozioni-Romania.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-romania-esaurita-la-lista-di-attesa-delle-coppie-adottive\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione Internazionale","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-internazionale\/"},{"@type":"ListItem","position":3,"name":"Adozione internazionale.\u00a0Romania: esaurita la lista di attesa delle coppie adottive"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938","name":"mc.sabatini","url":"https:\/\/www.aibi.it\/ita\/author\/marias\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 00:44:19","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/184478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/97"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=184478"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/184478\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/184471"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=184478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=184478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=184478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}