﻿{"id":185636,"date":"2021-03-01T07:35:54","date_gmt":"2021-03-01T06:35:54","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=185636"},"modified":"2022-07-25T15:51:37","modified_gmt":"2022-07-25T13:51:37","slug":"bolivia-so-che-guariro-quando-trovero-una-nuova-famiglia","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/bolivia-so-che-guariro-quando-trovero-una-nuova-famiglia\/","title":{"rendered":"Bolivia. So che guarir\u00f2 quando trover\u00f2 una nuova famiglia!"},"content":{"rendered":"<h2>Grazie al <a href=\"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/attivazione-adozione-a-distanza\/?scelta=25&amp;progetto=Bolivia\">Sostegno a Distanza<\/a>, i nostri bambini beneficiari dei Centri di Accoglienza Ni\u00f1o Jes\u00fas e Jos\u00e9 Soria, come Sergio, possono ricevere cure sanitarie, specialmente in un periodo come questo in cui gli ospedali sono in grave difficolt\u00e0<\/h2>\n<p>Il <strong>Sostegno a Distanza<\/strong> di Amici dei Bambini \u00e8 una <strong>partecipazione diretta<\/strong> alle attivit\u00e0 progettuali rivolte ai minori in difficolt\u00e0 familiare, <strong>ospiti di una comunit\u00e0 di accoglienza<\/strong>. Il sostegno contribuisce a migliorare le loro condizioni di vita, assicurando alimentazione adeguata, visite mediche specialistiche, attivit\u00e0 socio\u2013educative, corsi di formazione professionale, percorsi d\u2019inserimento lavorativo per gli adolescenti e tutto ci\u00f2 che si rende necessario per far s\u00ec che i minori ospiti delle comunit\u00e0 sostenute da Ai.Bi. possano crescere, per quanto possibile, serenamente, come se fossero i \u201cnostri\u201d figli.<\/p>\n<p><strong>Ai.Bi. \u00e8 presente in Bolivia dal 1997<\/strong> e dal 2003 \u00e8 impegnata con progetti di Adozione e Sostegno a Distanza per migliorare le condizioni di vita dei minori accolti in due istituti di La Paz e garantire i loro diritti, primo tra tutti, quello di vivere e crescere in famiglia.<\/p>\n<p>Uno degli interventi mirati di Amici dei Bambini \u00e8 quello di garantire il diritto alla salute: <strong>Sergio ha 7 anni<\/strong>, \u00e8 un bellissimo bambino arrivato al centro <strong>Jos\u00e9 Soria<\/strong> di La Paz qualche tempo fa, un bambino dolce e tranquillo ma con grandi problemi di malnutrizione che ha causato tante volte complicazioni di salute con ricoveri urgenti in ospedale. Sin da piccolo ha dovuto ricevere cure e sottoporsi a molti test, ma \u00e8 un grande combattente. Ha anche ricevuto cure in un istituto specializzato in malnutrizione, &#8220;Albina de Pati\u00f1o&#8221;, che esegue tutti i trattamenti possibili per riabilitare i bambini.<\/p>\n<p>Sergio adesso \u00e8 in ospedale, \u00e8 un bambino cos\u00ec forte che ha rubato l\u2019attenzione e l&#8217;affetto di tutti, quando i medici e le infermiere entrano nella sua stanza lo chiamano per nome e lui alza le mani per essere sollevato e coccolato. <strong>Ma Sergio non aspetta solo di star meglio, aspetta anche una famiglia che lo abbracci e lo coccoli, una mamma che gli stia accanto per tenergli la mano<\/strong>. Ed \u00e8 questa la speranza e l\u2019augurio che facciamo a questo meraviglioso bambino: che possa un giorno guarire dai suoi problemi di salute e dall\u2019abbandono.<\/p>\n<p>Ma sappiamo tutti che l\u2019amore \u00e8 uno dei farmaci pi\u00f9 potenti per donare a Sergio salute e famiglia. Grazie ai suoi Angeli, i Sostenitori a Distanza, Sergio aspetta serenamente che il suo futuro possa cambiare: che possa finalmente <strong>diventare figlio e star bene in salute<\/strong>.<\/p>\n<p>Tanti bambini come Sergio attendono una famiglia. \u00a0Aiutali anche tu a far s\u00ec che questo avvenga. Attiva un <a href=\"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/attivazione-adozione-a-distanza\/?scelta=25&amp;progetto=Bolivia\">Sostegno a Distanza<\/a> in Bolivia.<\/p>\n\n<!-- Buttons X - Start -->\n<style type=\"text\/css\">\/*168342-start*\/\n#btnsx-168342{margin-top:0px;margin-bottom:20px;margin-left:0px;margin-right:0px;padding-top:20px;padding-bottom:20px;padding-left:40px;padding-right:40px;}\n#btnsx-168342 .btnsx-text-primary{font-size:30px;line-height:30px;font-family:Montserrat;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-168342:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-168342 .btnsx-text-secondary{}\n#btnsx-168342 .btnsx-icon{}\n#btnsx-168342 .btnsx-icon-img{}\n#btnsx-168342{background-color:#ef7b0b!important;}\n#btnsx-168342:before{background-color:#eab20b!important;}\n#btnsx-168342:hover{background-color:#eab20b!important;}\n#btnsx-168342{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-168342:hover{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-168342-dropdown .menu-item a{}\n#btnsx-168342-dropdown{border-top-width:px;border-bottom-width:px;border-left-width:px;border-right-width:px;}\n#btnsx-168342-dropdown:before{border-width:8px;margin-left:-8px;border-bottom-color:}\n#btnsx-168342-dropdown:after{}\n#btnsx-168342-dropdown{}\n@media screen and (max-width: 768px) {\n#btnsx-168342 {display:inline-block;}\n#btnsx-168342 .btnsx-text-primary {}\n#btnsx-168342 .btnsx-text-secondary {}\n#btnsx-168342 .btnsx-icon {}\n#btnsx-168342 .btnsx-divider {}\n}@media screen and (max-width: 480px) {\n#btnsx-168342 {display:inline-block;}\n#btnsx-168342 .btnsx-text-primary {}\n#btnsx-168342 .btnsx-text-secondary {}\n#btnsx-168342 .btnsx-icon {}\n#btnsx-168342 .btnsx-divider {}\n}\/*168342-end*\/\n<\/style><div id=\"btnsx-168342-wrap\" class=\"btnsx-wrap-center\" align=\"center\"><div id=\"btnsx-168342-container\" class=\"btnsx-btn-container\">\n<a href=\"https:\/\/www.aibi.it\/ita\/adotta-a-distanza-25\/\" id=\"btnsx-168342\" target=\"_blank\" class=\"btnsx-btn  btnsx-btn-embossed\"  data-font-primary=\"Montserrat\" data-animation-type=\"\">\n\t<span class=\"btnsx-text-primary \">Scopri di pi\u00f9<\/span><\/a>\n<\/div><\/div>\n<!-- Buttons X - End -->\n\n","protected":false},"excerpt":{"rendered":"<p>Grazie al Sostegno a Distanza, i nostri bambini beneficiari dei Centri di Accoglienza Ni&ntilde;o Jes&uacute;s e Jos&eacute; Soria, come Sergio, possono ricevere cure sanitarie, specialmente in un periodo come questo in cui gli ospedali sono in grave difficolt&agrave; Il Sostegno a Distanza di Amici dei Bambini &egrave; una partecipazione diretta [&hellip;]<\/p>\n","protected":false},"author":113,"featured_media":185635,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[209],"tags":[480,647,646,300],"class_list":["post-185636","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-a-distanza","tag-bolivia","tag-jose-soria","tag-nino-jesus","tag-sostegno-a-distanza"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Bolivia. So che guarir\u00f2 quando trover\u00f2 una nuova famiglia! - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/bolivia-so-che-guariro-quando-trovero-una-nuova-famiglia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bolivia. So che guarir\u00f2 quando trover\u00f2 una nuova famiglia!\" \/>\n<meta property=\"og:description\" content=\"Grazie al Sostegno a Distanza, i nostri bambini beneficiari dei Centri di Accoglienza Ni&ntilde;o Jes&uacute;s e Jos&eacute; Soria, come Sergio, possono ricevere cure sanitarie, specialmente in un periodo come questo in cui gli ospedali sono in grave difficolt&agrave; Il Sostegno a Distanza di Amici dei Bambini &egrave; una partecipazione diretta [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/bolivia-so-che-guariro-quando-trovero-una-nuova-famiglia\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-01T06:35:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-25T13:51:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2021\/03\/hospital-bolivia_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"carlottaZ\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2021\/03\/hospital-bolivia_fb.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"carlottaZ\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-so-che-guariro-quando-trovero-una-nuova-famiglia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-so-che-guariro-quando-trovero-una-nuova-famiglia\\\/\"},\"author\":{\"name\":\"carlottaZ\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/95193f4e7a1f2190922687ebf84f96c9\"},\"headline\":\"Bolivia. So che guarir\u00f2 quando trover\u00f2 una nuova famiglia!\",\"datePublished\":\"2021-03-01T06:35:54+00:00\",\"dateModified\":\"2022-07-25T13:51:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-so-che-guariro-quando-trovero-una-nuova-famiglia\\\/\"},\"wordCount\":460,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-so-che-guariro-quando-trovero-una-nuova-famiglia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/03\\\/hospital-bolivia_fb.jpg\",\"keywords\":[\"Bolivia\",\"Jos\u00e8 Soria\",\"Nino Jesus\",\"sostegno a distanza\"],\"articleSection\":[\"Adozione a Distanza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-so-che-guariro-quando-trovero-una-nuova-famiglia\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-so-che-guariro-quando-trovero-una-nuova-famiglia\\\/\",\"name\":\"Bolivia. So che guarir\u00f2 quando trover\u00f2 una nuova famiglia! - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-so-che-guariro-quando-trovero-una-nuova-famiglia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-so-che-guariro-quando-trovero-una-nuova-famiglia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/03\\\/hospital-bolivia_fb.jpg\",\"datePublished\":\"2021-03-01T06:35:54+00:00\",\"dateModified\":\"2022-07-25T13:51:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-so-che-guariro-quando-trovero-una-nuova-famiglia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-so-che-guariro-quando-trovero-una-nuova-famiglia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-so-che-guariro-quando-trovero-una-nuova-famiglia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/03\\\/hospital-bolivia_fb.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/03\\\/hospital-bolivia_fb.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-so-che-guariro-quando-trovero-una-nuova-famiglia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione a Distanza\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-a-distanza\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bolivia. So che guarir\u00f2 quando trover\u00f2 una nuova famiglia!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/95193f4e7a1f2190922687ebf84f96c9\",\"name\":\"carlottaZ\",\"sameAs\":[\"cellos\"],\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/carlottaz\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bolivia. So che guarir\u00f2 quando trover\u00f2 una nuova famiglia! - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/bolivia-so-che-guariro-quando-trovero-una-nuova-famiglia\/","og_locale":"it_IT","og_type":"article","og_title":"Bolivia. So che guarir\u00f2 quando trover\u00f2 una nuova famiglia!","og_description":"Grazie al Sostegno a Distanza, i nostri bambini beneficiari dei Centri di Accoglienza Ni&ntilde;o Jes&uacute;s e Jos&eacute; Soria, come Sergio, possono ricevere cure sanitarie, specialmente in un periodo come questo in cui gli ospedali sono in grave difficolt&agrave; Il Sostegno a Distanza di Amici dei Bambini &egrave; una partecipazione diretta [&hellip;]","og_url":"https:\/\/www.aibi.it\/ita\/bolivia-so-che-guariro-quando-trovero-una-nuova-famiglia\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2021-03-01T06:35:54+00:00","article_modified_time":"2022-07-25T13:51:37+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2021\/03\/hospital-bolivia_fb.jpg","type":"image\/jpeg"}],"author":"carlottaZ","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.aibi.it\/ita\/images\/2021\/03\/hospital-bolivia_fb.jpg","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"carlottaZ","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/bolivia-so-che-guariro-quando-trovero-una-nuova-famiglia\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-so-che-guariro-quando-trovero-una-nuova-famiglia\/"},"author":{"name":"carlottaZ","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/95193f4e7a1f2190922687ebf84f96c9"},"headline":"Bolivia. So che guarir\u00f2 quando trover\u00f2 una nuova famiglia!","datePublished":"2021-03-01T06:35:54+00:00","dateModified":"2022-07-25T13:51:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-so-che-guariro-quando-trovero-una-nuova-famiglia\/"},"wordCount":460,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-so-che-guariro-quando-trovero-una-nuova-famiglia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/03\/hospital-bolivia_fb.jpg","keywords":["Bolivia","Jos\u00e8 Soria","Nino Jesus","sostegno a distanza"],"articleSection":["Adozione a Distanza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/bolivia-so-che-guariro-quando-trovero-una-nuova-famiglia\/","url":"https:\/\/www.aibi.it\/ita\/bolivia-so-che-guariro-quando-trovero-una-nuova-famiglia\/","name":"Bolivia. So che guarir\u00f2 quando trover\u00f2 una nuova famiglia! - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-so-che-guariro-quando-trovero-una-nuova-famiglia\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-so-che-guariro-quando-trovero-una-nuova-famiglia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/03\/hospital-bolivia_fb.jpg","datePublished":"2021-03-01T06:35:54+00:00","dateModified":"2022-07-25T13:51:37+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-so-che-guariro-quando-trovero-una-nuova-famiglia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/bolivia-so-che-guariro-quando-trovero-una-nuova-famiglia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/bolivia-so-che-guariro-quando-trovero-una-nuova-famiglia\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2021\/03\/hospital-bolivia_fb.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/03\/hospital-bolivia_fb.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/bolivia-so-che-guariro-quando-trovero-una-nuova-famiglia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione a Distanza","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-a-distanza\/"},{"@type":"ListItem","position":3,"name":"Bolivia. So che guarir\u00f2 quando trover\u00f2 una nuova famiglia!"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/95193f4e7a1f2190922687ebf84f96c9","name":"carlottaZ","sameAs":["cellos"],"url":"https:\/\/www.aibi.it\/ita\/author\/carlottaz\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 09:49:14","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/185636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/113"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=185636"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/185636\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/185635"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=185636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=185636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=185636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}