﻿


{"id":186013,"date":"2021-03-14T07:30:45","date_gmt":"2021-03-14T06:30:45","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=186013"},"modified":"2021-03-12T18:48:30","modified_gmt":"2021-03-12T17:48:30","slug":"lecce-adozione-internazionale-accoglienza-e-amore-ecco-di-cosa-hanno-bisogno-i-bambini-abbandonati-qualsiasi-eta-abbiano","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/lecce-adozione-internazionale-accoglienza-e-amore-ecco-di-cosa-hanno-bisogno-i-bambini-abbandonati-qualsiasi-eta-abbiano\/","title":{"rendered":"Lecce. Adozione internazionale. &#8220;Accoglienza e amore: ecco di cosa hanno bisogno i bambini abbandonati, qualsiasi et\u00e0 abbiano&#8221;\u00a0"},"content":{"rendered":"<h2>\u201c<em>La gioia pi\u00f9 grande \u00e8 quando ci dicono mamma, pap\u00e0 voi siete tutto per noi e questo ci appaga di ogni cosa\u201d<\/em>. Intervista a Cristina e Fernando Carallo, coordinatori Punto Ai.Bi. di Lecce.<\/h2>\n<p><strong><span style=\"color: #000000;\">Che cosa vuol dire famiglia?<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\">Famiglia vuol dire accogliere, vuol dire sostenere, condividere, difendere i nostri figli. Sia che siano nati dal nostro grembo, sia che siano <strong>rinati figli nel nostro cuore<\/strong>. Anzi, soprattutto. Perch\u00e9 i bambini abbandonati non hanno mai sperimentato cosa significhi l\u2019amore. Perch\u00e9 un istituto non \u00e8 una famiglia e nulla potr\u00e0 mai sopperire all\u2019abbraccio e alle carezze di una mamma e di un pap\u00e0.<\/span><\/p>\n<p><span style=\"color: #000000;\">La pensano cos\u00ec <strong>Cristina Melissano e Fernando Carallo,<\/strong> famiglia di\u00a0<strong><span id=\"DWT8216\" class=\"ZmSearchResult\">Lecce<\/span><\/strong>\u00a0che ha adottato grazie ad Ai.Bi. due meravigliosi bambini bulgari di 10 e 13 anni,\u00a0<span id=\"OBJ_PREFIX_DWT8217_com_zimbra_date\" class=\"Object\" role=\"link\">oggi<\/span> quasi ventenni e che gi\u00e0 da tempo si fanno testimoni della bellezza dell\u2019<span id=\"DWT8219\" class=\"ZmSearchResult\">adozione<\/span>\u00a0<span id=\"DWT8221\" class=\"ZmSearchResult\">internazionale<\/span>.<\/span><\/p>\n<p><span style=\"color: #000000;\">Il 14 febbraio, giornata dedicata all\u2019amore appunto, sono stati ospiti della trasmissione <strong>\u201cIn Famiglia\u201d, \u00a0in onda sulla TV regionale, Tele Rama.<\/strong><\/span><\/p>\n<h3><span style=\"color: #000000;\">Accoglienza e amore.<\/span><\/h3>\n<p><span style=\"color: #000000;\">Sono queste le parole che hanno accompagnato come un fil rouge l\u2019intervista della famiglia Carallo durante la trasmissione.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u201c<em>Quattro sono le emergenze importanti nel mondo<\/em> \u2013 sottolinea Cristina Melissano &#8211; <em>fame, malattia, guerra e abbandono. Delle prime tre si pu\u00f2 morire \u00e8 evidente. Con l\u2019abbandono non si vede ma si muore dentro. Noi dobbiamo sopperire a tutto questo. Perch\u00e9 come dico sempre ai miei figli, voi non siete nati dal mio grembo, ma siete nati dal mio cuore. <strong>Il grembo pu\u00f2 abortire ma il cuore no. Una volta che vi si entra dentro l\u00ec<\/strong><\/em><strong> si rimane \u2013<\/strong> continua &#8211; <em>Il primo problema \u00e8 saper accogliere, saper amare. Accogliendo con amore possiamo costruire un mondo migliore\u201d.<\/em><\/span><\/p>\n<p><span style=\"color: #000000;\">Tra gli argomenti trattati durante l\u2019intervista anche l\u2019importanza della <strong>scuola<\/strong> e della preparazione degli insegnanti ad accogliere i bambini giunti da contesti differenti. Minori che sono \u201ctrapiantati\u201d in un nuovo Paese, con una nuova lingua e differenti tradizioni e proprio come una pianta, per poter far aderire le proprie radici, \u201cdevono essere curati, sostenuti ed amati\u201d spiegano i coniugi Carallo.<\/span><\/p>\n<h3>Il video dell&#8217;intervista<\/h3>\n<h3><a href=\"https:\/\/youtu.be\/meOACntDgvE\"><strong><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-185851\" src=\"https:\/\/www.aibi.it\/ita\/images\/2021\/03\/famiglia-carollo-aibi_fb-571x300.jpg\" alt=\"\" width=\"571\" height=\"300\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2021\/03\/famiglia-carollo-aibi_fb-571x300.jpg 571w, https:\/\/www.aibi.it\/ita\/images\/2021\/03\/famiglia-carollo-aibi_fb-150x79.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/2021\/03\/famiglia-carollo-aibi_fb-768x403.jpg 768w, https:\/\/www.aibi.it\/ita\/images\/2021\/03\/famiglia-carollo-aibi_fb.jpg 1200w\" sizes=\"auto, (max-width: 571px) 100vw, 571px\" \/><\/span><\/strong><\/a><\/h3>\n<h3><\/h3>\n<h3><strong><span style=\"color: #000000;\">E quando viene chiesto loro com\u2019\u00e8 stata l\u2019esperienza dell\u2019<span id=\"DWT8223\" class=\"ZmSearchResult\">adozione<\/span>, la loro risposta \u00e8 decisa ed unanime: molto positiva!<\/span><\/strong><\/h3>\n<p><span style=\"color: #000000;\">\u201c<em>I miei figli hanno sempre voluto una famiglia. Noi ci siamo dedicati a loro in pieno e loro si sono sempre sentiti amati<\/em> \u2013 commenta Fernando Carallo, bisogna ricordare che &#8211; \u201c<em>sono loro ad avere bisogno di una famiglia<\/em> \u2013 \u00a0gli fa eco la moglie \u2013 <em>dobbiamo accoglierli senza sogni, senza pregiudizi, capire la realt\u00e0 per poterla dare ai nostri figli. Un ragazzo di 13 anni ha gi\u00e0 un suo vissuto. <strong>Siamo noi che dobbiamo immergerci in cosa sono loro, come la mamma accoglie in grembo un figlio<\/strong>. Le difficolt\u00e0 ci sono, ma come ci sono anche con i figli naturali\u2026 La gioia pi\u00f9 grande \u00e8 quando ci dicono mamma, pap\u00e0 voi \u00a0siete tutto per noi e questo ci appaga di ogni cosa\u201d.<\/em><\/span><\/p>\n<h3><span style=\"color: #000000;\">Due forze della natura i coniugi Carallo.<\/span><\/h3>\n<p><span style=\"color: #000000;\">Sono loro le figure di riferimento del <strong>Punto Famiglia Ai.Bi. di\u00a0<span id=\"DWT8225\" class=\"ZmSearchResult\">Lecce<\/span><\/strong>, sportello informativo, completamente gratuito, dedicato alle famiglie salentine che vogliano avvicinarsi al mondo dell\u2019azione, contattabile alla mail\u00a0<strong><span id=\"OBJ_PREFIX_DWT8226_ZmEmailObjectHandler\" class=\"Object\" role=\"link\">carallo.family@libero.it.<\/span><\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\">Sono <strong>referenti per il Gruppo Famiglie del Salento<\/strong>, \u00a0gruppo di ascolto che si riunisce ogni prima\u00a0<span id=\"OBJ_PREFIX_DWT8227_com_zimbra_date\" class=\"Object\" role=\"link\">domenica<\/span>\u00a0del mese nella parrocchia di San Giovanni Battista, seguito dal padre spirituale don Gerardo Ippolito. Un percorso spirituale dell\u2019Associazione La Pietra Scartata che riunisce tutti i genitori adottivi, che condividono i valori cristiani, al quale si pu\u00f2 aderire liberamente e nel quale ci si \u00a0confronta su problemi e difficolt\u00e0 che l\u2019<span id=\"DWT8229\" class=\"ZmSearchResult\">adozione<\/span>\u00a0comporta.<\/span><\/p>\n<p><span style=\"color: #000000;\">Proprio nella giornata di\u00a0<span id=\"OBJ_PREFIX_DWT8230_com_zimbra_date\" class=\"Object\" role=\"link\">domenica<\/span>\u00a07 marzo, si \u00e8 svolto il primo incontro in presenza del GFL \u00a0Barletta, dopo circa un anno di stop, a causa della pandemia. Incontro celebrato con un video collegamento con il gruppo Famiglie del Salento.<\/span><\/p>\n<p><span style=\"color: #000000;\">Ma non basta perch\u00e9 i coniugi Carallo sono anche membri del forum delle famiglie e promotori di incontri dedicati all\u2019accoglienza.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&ldquo;La gioia pi&ugrave; grande &egrave; quando ci dicono mamma, pap&agrave; voi siete tutto per noi e questo ci appaga di ogni cosa&rdquo;. Intervista a Cristina e Fernando Carallo, coordinatori Punto Ai.Bi. di Lecce. Che cosa vuol dire famiglia? Famiglia vuol dire accogliere, vuol dire sostenere, condividere, difendere i nostri figli. [&hellip;]<\/p>\n","protected":false},"author":97,"featured_media":185852,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[172],"tags":[347],"class_list":["post-186013","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-internazionale","tag-adozione-internazionale"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Lecce. Adozione internazionale. &quot;Accoglienza e amore: ecco di cosa hanno bisogno i bambini abbandonati, qualsiasi et\u00e0 abbiano&quot;\u00a0 - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"\u201cLa gioia pi\u00f9 grande \u00e8 quando ci dicono mamma, pap\u00e0 voi siete tutto per noi e questo ci appaga di ogni cosa\u201d. Intervista a Cristina e Fernando Carallo, coordinatori Punto Ai.Bi. di Lecce.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/lecce-adozione-internazionale-accoglienza-e-amore-ecco-di-cosa-hanno-bisogno-i-bambini-abbandonati-qualsiasi-eta-abbiano\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lecce. Adozione internazionale. &quot;Accoglienza e amore: ecco di cosa hanno bisogno i bambini abbandonati, qualsiasi et\u00e0 abbiano&quot;\u00a0\" \/>\n<meta property=\"og:description\" content=\"\u201cLa gioia pi\u00f9 grande \u00e8 quando ci dicono mamma, pap\u00e0 voi siete tutto per noi e questo ci appaga di ogni cosa\u201d. Intervista a Cristina e Fernando Carallo, coordinatori Punto Ai.Bi. di Lecce.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/lecce-adozione-internazionale-accoglienza-e-amore-ecco-di-cosa-hanno-bisogno-i-bambini-abbandonati-qualsiasi-eta-abbiano\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-14T06:30:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2021\/03\/famiglia-carollo-aibi_1_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mc.sabatini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mc.sabatini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/lecce-adozione-internazionale-accoglienza-e-amore-ecco-di-cosa-hanno-bisogno-i-bambini-abbandonati-qualsiasi-eta-abbiano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/lecce-adozione-internazionale-accoglienza-e-amore-ecco-di-cosa-hanno-bisogno-i-bambini-abbandonati-qualsiasi-eta-abbiano\\\/\"},\"author\":{\"name\":\"mc.sabatini\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\"},\"headline\":\"Lecce. Adozione internazionale. &#8220;Accoglienza e amore: ecco di cosa hanno bisogno i bambini abbandonati, qualsiasi et\u00e0 abbiano&#8221;\u00a0\",\"datePublished\":\"2021-03-14T06:30:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/lecce-adozione-internazionale-accoglienza-e-amore-ecco-di-cosa-hanno-bisogno-i-bambini-abbandonati-qualsiasi-eta-abbiano\\\/\"},\"wordCount\":672,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/lecce-adozione-internazionale-accoglienza-e-amore-ecco-di-cosa-hanno-bisogno-i-bambini-abbandonati-qualsiasi-eta-abbiano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/03\\\/famiglia-carollo-aibi_1_fb.jpg\",\"keywords\":[\"Adozione Internazionale\"],\"articleSection\":[\"Adozione Internazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/lecce-adozione-internazionale-accoglienza-e-amore-ecco-di-cosa-hanno-bisogno-i-bambini-abbandonati-qualsiasi-eta-abbiano\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/lecce-adozione-internazionale-accoglienza-e-amore-ecco-di-cosa-hanno-bisogno-i-bambini-abbandonati-qualsiasi-eta-abbiano\\\/\",\"name\":\"Lecce. Adozione internazionale. \\\"Accoglienza e amore: ecco di cosa hanno bisogno i bambini abbandonati, qualsiasi et\u00e0 abbiano\\\"\u00a0 - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/lecce-adozione-internazionale-accoglienza-e-amore-ecco-di-cosa-hanno-bisogno-i-bambini-abbandonati-qualsiasi-eta-abbiano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/lecce-adozione-internazionale-accoglienza-e-amore-ecco-di-cosa-hanno-bisogno-i-bambini-abbandonati-qualsiasi-eta-abbiano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/03\\\/famiglia-carollo-aibi_1_fb.jpg\",\"datePublished\":\"2021-03-14T06:30:45+00:00\",\"description\":\"\u201cLa gioia pi\u00f9 grande \u00e8 quando ci dicono mamma, pap\u00e0 voi siete tutto per noi e questo ci appaga di ogni cosa\u201d. Intervista a Cristina e Fernando Carallo, coordinatori Punto Ai.Bi. di Lecce.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/lecce-adozione-internazionale-accoglienza-e-amore-ecco-di-cosa-hanno-bisogno-i-bambini-abbandonati-qualsiasi-eta-abbiano\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/lecce-adozione-internazionale-accoglienza-e-amore-ecco-di-cosa-hanno-bisogno-i-bambini-abbandonati-qualsiasi-eta-abbiano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/lecce-adozione-internazionale-accoglienza-e-amore-ecco-di-cosa-hanno-bisogno-i-bambini-abbandonati-qualsiasi-eta-abbiano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/03\\\/famiglia-carollo-aibi_1_fb.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/03\\\/famiglia-carollo-aibi_1_fb.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/lecce-adozione-internazionale-accoglienza-e-amore-ecco-di-cosa-hanno-bisogno-i-bambini-abbandonati-qualsiasi-eta-abbiano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione Internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-internazionale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lecce. Adozione internazionale. &#8220;Accoglienza e amore: ecco di cosa hanno bisogno i bambini abbandonati, qualsiasi et\u00e0 abbiano&#8221;\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\",\"name\":\"mc.sabatini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/marias\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Lecce. Adozione internazionale. \"Accoglienza e amore: ecco di cosa hanno bisogno i bambini abbandonati, qualsiasi et\u00e0 abbiano\"\u00a0 - Ai.Bi. Amici dei Bambini","description":"\u201cLa gioia pi\u00f9 grande \u00e8 quando ci dicono mamma, pap\u00e0 voi siete tutto per noi e questo ci appaga di ogni cosa\u201d. Intervista a Cristina e Fernando Carallo, coordinatori Punto Ai.Bi. di Lecce.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/lecce-adozione-internazionale-accoglienza-e-amore-ecco-di-cosa-hanno-bisogno-i-bambini-abbandonati-qualsiasi-eta-abbiano\/","og_locale":"it_IT","og_type":"article","og_title":"Lecce. Adozione internazionale. \"Accoglienza e amore: ecco di cosa hanno bisogno i bambini abbandonati, qualsiasi et\u00e0 abbiano\"\u00a0","og_description":"\u201cLa gioia pi\u00f9 grande \u00e8 quando ci dicono mamma, pap\u00e0 voi siete tutto per noi e questo ci appaga di ogni cosa\u201d. Intervista a Cristina e Fernando Carallo, coordinatori Punto Ai.Bi. di Lecce.","og_url":"https:\/\/www.aibi.it\/ita\/lecce-adozione-internazionale-accoglienza-e-amore-ecco-di-cosa-hanno-bisogno-i-bambini-abbandonati-qualsiasi-eta-abbiano\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2021-03-14T06:30:45+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2021\/03\/famiglia-carollo-aibi_1_fb.jpg","type":"image\/jpeg"}],"author":"mc.sabatini","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"mc.sabatini","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/lecce-adozione-internazionale-accoglienza-e-amore-ecco-di-cosa-hanno-bisogno-i-bambini-abbandonati-qualsiasi-eta-abbiano\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/lecce-adozione-internazionale-accoglienza-e-amore-ecco-di-cosa-hanno-bisogno-i-bambini-abbandonati-qualsiasi-eta-abbiano\/"},"author":{"name":"mc.sabatini","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938"},"headline":"Lecce. Adozione internazionale. &#8220;Accoglienza e amore: ecco di cosa hanno bisogno i bambini abbandonati, qualsiasi et\u00e0 abbiano&#8221;\u00a0","datePublished":"2021-03-14T06:30:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/lecce-adozione-internazionale-accoglienza-e-amore-ecco-di-cosa-hanno-bisogno-i-bambini-abbandonati-qualsiasi-eta-abbiano\/"},"wordCount":672,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/lecce-adozione-internazionale-accoglienza-e-amore-ecco-di-cosa-hanno-bisogno-i-bambini-abbandonati-qualsiasi-eta-abbiano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/03\/famiglia-carollo-aibi_1_fb.jpg","keywords":["Adozione Internazionale"],"articleSection":["Adozione Internazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/lecce-adozione-internazionale-accoglienza-e-amore-ecco-di-cosa-hanno-bisogno-i-bambini-abbandonati-qualsiasi-eta-abbiano\/","url":"https:\/\/www.aibi.it\/ita\/lecce-adozione-internazionale-accoglienza-e-amore-ecco-di-cosa-hanno-bisogno-i-bambini-abbandonati-qualsiasi-eta-abbiano\/","name":"Lecce. Adozione internazionale. \"Accoglienza e amore: ecco di cosa hanno bisogno i bambini abbandonati, qualsiasi et\u00e0 abbiano\"\u00a0 - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/lecce-adozione-internazionale-accoglienza-e-amore-ecco-di-cosa-hanno-bisogno-i-bambini-abbandonati-qualsiasi-eta-abbiano\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/lecce-adozione-internazionale-accoglienza-e-amore-ecco-di-cosa-hanno-bisogno-i-bambini-abbandonati-qualsiasi-eta-abbiano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/03\/famiglia-carollo-aibi_1_fb.jpg","datePublished":"2021-03-14T06:30:45+00:00","description":"\u201cLa gioia pi\u00f9 grande \u00e8 quando ci dicono mamma, pap\u00e0 voi siete tutto per noi e questo ci appaga di ogni cosa\u201d. Intervista a Cristina e Fernando Carallo, coordinatori Punto Ai.Bi. di Lecce.","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/lecce-adozione-internazionale-accoglienza-e-amore-ecco-di-cosa-hanno-bisogno-i-bambini-abbandonati-qualsiasi-eta-abbiano\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/lecce-adozione-internazionale-accoglienza-e-amore-ecco-di-cosa-hanno-bisogno-i-bambini-abbandonati-qualsiasi-eta-abbiano\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/lecce-adozione-internazionale-accoglienza-e-amore-ecco-di-cosa-hanno-bisogno-i-bambini-abbandonati-qualsiasi-eta-abbiano\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2021\/03\/famiglia-carollo-aibi_1_fb.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/03\/famiglia-carollo-aibi_1_fb.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/lecce-adozione-internazionale-accoglienza-e-amore-ecco-di-cosa-hanno-bisogno-i-bambini-abbandonati-qualsiasi-eta-abbiano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione Internazionale","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-internazionale\/"},{"@type":"ListItem","position":3,"name":"Lecce. Adozione internazionale. &#8220;Accoglienza e amore: ecco di cosa hanno bisogno i bambini abbandonati, qualsiasi et\u00e0 abbiano&#8221;\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938","name":"mc.sabatini","url":"https:\/\/www.aibi.it\/ita\/author\/marias\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 00:42:52","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/186013","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/97"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=186013"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/186013\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/185852"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=186013"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=186013"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=186013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}