﻿{"id":18616,"date":"2011-01-11T16:22:20","date_gmt":"2011-01-11T15:22:20","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=18616"},"modified":"2011-01-11T16:23:13","modified_gmt":"2011-01-11T15:23:13","slug":"congo-approvata-nuova-legge-per-la-tutela-dei-minori-appartenenti-a-popolazioni-indigene","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/congo-approvata-nuova-legge-per-la-tutela-dei-minori-appartenenti-a-popolazioni-indigene\/","title":{"rendered":"Congo: approvata nuova legge per la tutela dei minori appartenenti a popolazioni indigene"},"content":{"rendered":"<p><a href=\"https:\/\/www.aibi.it\/ita\/images\/congo_bambini.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-18617\" style=\"margin: 5px;\" title=\"congo_bambini\" src=\"https:\/\/www.aibi.it\/ita\/images\/congo_bambini.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>La Repubblica Democratica del Congo <strong>ha approvato una nuova legge che garantir\u00e0 ai bambini appartenenti a popolazioni indigene il diritto alla sanit\u00e0, istruzione e protezione. <\/strong><br \/>\n<em>&#8220;Questa legge \u00e8 unica nella regione ed \u00e8 un esempio per tutti gli altri paesi che hanno popolazioni indigene simili a quelle del Congo. Questo \u00e8 un grande passo avanti per i bambini del Congo e rappresenta una pietra miliare nella storia congolese&#8221; <\/em>ha dichiarato Marianne Flach, rappresentante nazionale dell&#8217;UNICEF in Congo.<br \/>\nQuesta legge che tutela e promuove i diritti delle popolazioni indigene, \u00e8 stata adottata dal Senato del paese dopo essere stata ratificata dall\u2019Assemblea Nazionale.<br \/>\nIl Congo ha aderito alla Convenzione delle Nazioni Unite sui diritti del fanciullo, che articola una serie di diritti universali per i bambini, <strong>tra cui il diritto a un&#8217;identit\u00e0, un nome ed una nazionalit\u00e0, il diritto all&#8217;istruzione, il diritto ai pi\u00f9 alti standard possibili di salute e la protezione da abusi e sfruttamento.<br \/>\n<\/strong>Una vasta maggioranza dei popoli indigeni del paese vive sotto la soglia di povert\u00e0, <strong>il 50 per cento dei bambini non hanno certificato di nascita<\/strong>, e <strong>un bambino su cinque muore prima di raggiungere i cinque anni<\/strong>, rispetto a uno su otto tra il resto della popolazione.<br \/>\nSecondo dati dell\u2019Unicef la Repubblica Democratica del Congo \u00e8 anche uno dei paesi pi\u00f9 poveri del mondo, nel quale le popolazioni indigene sono <em>&#8220;in equilibrio precario sul gradino pi\u00f9 basso della societ\u00e0, i pi\u00f9 poveri dei poveri\u201d<\/em>.<br \/>\n<strong>Inoltre, il 40 per cento dei bambini appartenenti a popolazioni indigene soffrono di malnutrizione cronica e il 75 per cento dei giovani sono privi di qualsiasi istruzione.<br \/>\n<\/strong><br \/>\nMs. Flach ha sottolineato la necessit\u00e0 di assicurarsi che la legge venga messa in pratica. <em>&#8220;E\u2019 l&#8217;unico modo per garantire che questo diritto diventi una realt\u00e0 a sostegno dei pi\u00f9 vulnerabili in Congo&#8221;.<\/em><em><br \/>\n<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Repubblica Democratica del Congo <strong>ha approvato una nuova legge che garantir\u00e0 ai bambini appartenenti a popolazioni indigene il diritto alla sanit\u00e0, istruzione e protezione.<\/strong> Questo \u00e8 un grande passo avanti per i bambini del Congo e rappresenta una pietra miliare nella storia congolese&#8221; ha dichiarato Marianne Flach, rappresentante nazionale dell&#8217;UNICEF in Congo. <strong><a href=\"https:\/\/www.aibi.it\/ita\/congo-approvata-nuova-legge-per-la-tutela-dei-minori-appartenenti-a-popolazioni-indigene\/\">LEGGI TUTTO&#8230;<\/a><\/strong><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-18616","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Congo: approvata nuova legge per la tutela dei minori appartenenti a popolazioni indigene - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/congo-approvata-nuova-legge-per-la-tutela-dei-minori-appartenenti-a-popolazioni-indigene\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Congo: approvata nuova legge per la tutela dei minori appartenenti a popolazioni indigene\" \/>\n<meta property=\"og:description\" content=\"La Repubblica Democratica del Congo ha approvato una nuova legge che garantir\u00e0 ai bambini appartenenti a popolazioni indigene il diritto alla sanit\u00e0, istruzione e protezione. Questo \u00e8 un grande passo avanti per i bambini del Congo e rappresenta una pietra miliare nella storia congolese&quot; ha dichiarato Marianne Flach, rappresentante nazionale dell&#039;UNICEF in Congo. LEGGI TUTTO...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/congo-approvata-nuova-legge-per-la-tutela-dei-minori-appartenenti-a-popolazioni-indigene\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-01-11T15:22:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2011-01-11T15:23:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/congo_bambini.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-approvata-nuova-legge-per-la-tutela-dei-minori-appartenenti-a-popolazioni-indigene\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-approvata-nuova-legge-per-la-tutela-dei-minori-appartenenti-a-popolazioni-indigene\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Congo: approvata nuova legge per la tutela dei minori appartenenti a popolazioni indigene\",\"datePublished\":\"2011-01-11T15:22:20+00:00\",\"dateModified\":\"2011-01-11T15:23:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-approvata-nuova-legge-per-la-tutela-dei-minori-appartenenti-a-popolazioni-indigene\\\/\"},\"wordCount\":309,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-approvata-nuova-legge-per-la-tutela-dei-minori-appartenenti-a-popolazioni-indigene\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/congo_bambini.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-approvata-nuova-legge-per-la-tutela-dei-minori-appartenenti-a-popolazioni-indigene\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-approvata-nuova-legge-per-la-tutela-dei-minori-appartenenti-a-popolazioni-indigene\\\/\",\"name\":\"Congo: approvata nuova legge per la tutela dei minori appartenenti a popolazioni indigene - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-approvata-nuova-legge-per-la-tutela-dei-minori-appartenenti-a-popolazioni-indigene\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-approvata-nuova-legge-per-la-tutela-dei-minori-appartenenti-a-popolazioni-indigene\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/congo_bambini.jpg\",\"datePublished\":\"2011-01-11T15:22:20+00:00\",\"dateModified\":\"2011-01-11T15:23:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-approvata-nuova-legge-per-la-tutela-dei-minori-appartenenti-a-popolazioni-indigene\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-approvata-nuova-legge-per-la-tutela-dei-minori-appartenenti-a-popolazioni-indigene\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-approvata-nuova-legge-per-la-tutela-dei-minori-appartenenti-a-popolazioni-indigene\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/congo_bambini.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/congo_bambini.jpg\",\"width\":150,\"height\":150},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-approvata-nuova-legge-per-la-tutela-dei-minori-appartenenti-a-popolazioni-indigene\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Congo: approvata nuova legge per la tutela dei minori appartenenti a popolazioni indigene\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Congo: approvata nuova legge per la tutela dei minori appartenenti a popolazioni indigene - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/congo-approvata-nuova-legge-per-la-tutela-dei-minori-appartenenti-a-popolazioni-indigene\/","og_locale":"it_IT","og_type":"article","og_title":"Congo: approvata nuova legge per la tutela dei minori appartenenti a popolazioni indigene","og_description":"La Repubblica Democratica del Congo ha approvato una nuova legge che garantir\u00e0 ai bambini appartenenti a popolazioni indigene il diritto alla sanit\u00e0, istruzione e protezione. Questo \u00e8 un grande passo avanti per i bambini del Congo e rappresenta una pietra miliare nella storia congolese\" ha dichiarato Marianne Flach, rappresentante nazionale dell'UNICEF in Congo. LEGGI TUTTO...","og_url":"https:\/\/www.aibi.it\/ita\/congo-approvata-nuova-legge-per-la-tutela-dei-minori-appartenenti-a-popolazioni-indigene\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2011-01-11T15:22:20+00:00","article_modified_time":"2011-01-11T15:23:13+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/congo_bambini.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/congo-approvata-nuova-legge-per-la-tutela-dei-minori-appartenenti-a-popolazioni-indigene\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/congo-approvata-nuova-legge-per-la-tutela-dei-minori-appartenenti-a-popolazioni-indigene\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Congo: approvata nuova legge per la tutela dei minori appartenenti a popolazioni indigene","datePublished":"2011-01-11T15:22:20+00:00","dateModified":"2011-01-11T15:23:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/congo-approvata-nuova-legge-per-la-tutela-dei-minori-appartenenti-a-popolazioni-indigene\/"},"wordCount":309,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/congo-approvata-nuova-legge-per-la-tutela-dei-minori-appartenenti-a-popolazioni-indigene\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/congo_bambini.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/congo-approvata-nuova-legge-per-la-tutela-dei-minori-appartenenti-a-popolazioni-indigene\/","url":"https:\/\/www.aibi.it\/ita\/congo-approvata-nuova-legge-per-la-tutela-dei-minori-appartenenti-a-popolazioni-indigene\/","name":"Congo: approvata nuova legge per la tutela dei minori appartenenti a popolazioni indigene - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/congo-approvata-nuova-legge-per-la-tutela-dei-minori-appartenenti-a-popolazioni-indigene\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/congo-approvata-nuova-legge-per-la-tutela-dei-minori-appartenenti-a-popolazioni-indigene\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/congo_bambini.jpg","datePublished":"2011-01-11T15:22:20+00:00","dateModified":"2011-01-11T15:23:13+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/congo-approvata-nuova-legge-per-la-tutela-dei-minori-appartenenti-a-popolazioni-indigene\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/congo-approvata-nuova-legge-per-la-tutela-dei-minori-appartenenti-a-popolazioni-indigene\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/congo-approvata-nuova-legge-per-la-tutela-dei-minori-appartenenti-a-popolazioni-indigene\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/congo_bambini.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/congo_bambini.jpg","width":150,"height":150},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/congo-approvata-nuova-legge-per-la-tutela-dei-minori-appartenenti-a-popolazioni-indigene\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Congo: approvata nuova legge per la tutela dei minori appartenenti a popolazioni indigene"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 18:09:22","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/18616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=18616"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/18616\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=18616"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=18616"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=18616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}