﻿{"id":186354,"date":"2021-03-24T10:00:41","date_gmt":"2021-03-24T09:00:41","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=186354"},"modified":"2021-03-24T18:38:03","modified_gmt":"2021-03-24T17:38:03","slug":"milano-appello-per-adozione-nazionale-due-famiglie-cercasi-per-margherita-e-marta","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/milano-appello-per-adozione-nazionale-due-famiglie-cercasi-per-margherita-e-marta\/","title":{"rendered":"Milano. Appello per Adozione nazionale: due famiglie cercasi per Margherita e Marta"},"content":{"rendered":"<h2><strong>Il Tribunale per i Minorenni di Milano cerca due famiglie per due bambine nate nel 2020,dichiarate adottabili ma che hanno trovato difficolt\u00e0 ad essere accolte da coppie che hanno presentato domanda per l\u2019Adozione Nazionale<\/strong><\/h2>\n<p><strong>\u00a0<\/strong>Avere una famiglia \u00e8 un diritto che, nonostante l\u2019UE non lo abbia incluso nella sua recente <u>\u201cstrategia\u201d per i minori<\/u>, dev\u2019essere garantito a ogni bambino. L\u2019abbraccio e la sicurezza di una casa e di genitori che vogliano bene \u00e8 la base imprescindibile che a ogni bambino non dovrebbe mancare.<\/p>\n<p>Specie se questi minori hanno qualche problema di salute che crea maggiori problemi a loro e, nello stesso tempo, rende pi\u00f9 difficile trovare una famiglia disposta ad accoglierli.<\/p>\n<p>Per questo, il <a href=\"https:\/\/www.tribmin.milano.giustizia.it\/it\/Content\/Index\/45153\">Tribunale di Milano<\/a> pubblica sul proprio sito gli appelli dedicati ai bambini in \u201ccondizioni speciali\u201d, affetti da problemi neurologici, psichici, o genetici (i nomi riportati sono di fantasia).<\/p>\n<h3><strong>APPELLO PER MARGHERITA<\/strong><\/h3>\n<p>Margherita \u00e8 una bimba molto piccola, dagli occhi scuri e vispi, nata a Luglio 2020. Dopo il parto ha riportato alcuni problemi di salute la cui evoluzione non \u00e8 ad\u00a0oggi\u00a0prevedibile &#8211; vista anche la sua tenera et\u00e0 &#8211; ma si sa che nella sua crescita Margherita porter\u00e0 con s\u00e9 un ritardo cognitivo e epilessia. Sta crescendo, interagisce e risponde agli stimoli, ama molto essere coccolata ed \u00e8 una bimba sorridente. E\u2019 in attesa di genitori, fratelli e sorelle affettuosi e disponibili ad accoglierla, consapevoli delle sue difficolt\u00e0.<\/p>\n<p><strong>APPELLO PER MARTA<\/strong><\/p>\n<p>Marta \u00e8 una bella bambina, nata a gennaio 2020. A seguito di un parto complicato ha riportato alcuni problemi di salute, la cui evoluzione non \u00e8 ad\u00a0oggi\u00a0prevedibile, vista anche la sua tenera et\u00e0. La bimba sta crescendo, interagisce e risponde agli stimoli, ma dovr\u00e0 proseguire le terapie ed i controlli consigliati e nel corso del suo sviluppo potrebbe manifestare difficolt\u00e0 di salute e cognitive anche importanti. Marta \u00e8 in attesa di una famiglia affettuosa, anche con figli, che sia disponibile ad accoglierla, consapevole del rischio sanitario che potrebbe compromettere la sua crescita.<em><\/p>\n<p><\/em><\/p>\n<p>La famiglie che desiderano rendersi disponibile ad approfondire la situazione di Margherita e Marta, possono rivolgersi al Tribunale per i Minorenni di Milano, inviando una e-mail all\u2019indirizzo\u00a0<a href=\"mailto:cancelleriaadozioni.tribmin.milano@giustizia.it\" target=\"_blank\" rel=\"noopener\">cancelleriaadozioni.tribmin.milano@giustizia.it<\/a>, indicando il nome della minore e riportando i propri dati e soprattutto i recapiti telefonici.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Tribunale per i Minorenni di Milano cerca due famiglie per due bambine nate nel 2020,dichiarate adottabili ma che hanno trovato difficolt&agrave; ad essere accolte da coppie che hanno presentato domanda per l&rsquo;Adozione Nazionale &nbsp;Avere una famiglia &egrave; un diritto che, nonostante l&rsquo;UE non lo abbia incluso nella sua recente [&hellip;]<\/p>\n","protected":false},"author":102,"featured_media":186355,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[652],"tags":[257],"class_list":["post-186354","post","type-post","status-publish","format-standard","has-post-thumbnail","category-affido","tag-appelli-adozione-nazionale-e-affido"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Milano. Appello per Adozione nazionale per Margherita e Marta<\/title>\n<meta name=\"description\" content=\"Il Tribunale per i Minorenni di Milano cerca due famiglie per due bambine nate nel 2020, dichiarate adottabili ma che hanno trovato difficolt\u00e0 ad essere accolte\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/milano-appello-per-adozione-nazionale-due-famiglie-cercasi-per-margherita-e-marta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Milano. Appello per Adozione nazionale: due famiglie cercasi per Margherita e Marta\" \/>\n<meta property=\"og:description\" content=\"Il Tribunale per i Minorenni di Milano cerca due famiglie per due bambine nate nel 2020, dichiarate adottabili ma che hanno trovato difficolt\u00e0 ad essere accolte\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/milano-appello-per-adozione-nazionale-due-famiglie-cercasi-per-margherita-e-marta\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-24T09:00:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-24T17:38:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2021\/03\/appello_adozione.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-appello-per-adozione-nazionale-due-famiglie-cercasi-per-margherita-e-marta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-appello-per-adozione-nazionale-due-famiglie-cercasi-per-margherita-e-marta\\\/\"},\"author\":{\"name\":\"francescoE\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\"},\"headline\":\"Milano. Appello per Adozione nazionale: due famiglie cercasi per Margherita e Marta\",\"datePublished\":\"2021-03-24T09:00:41+00:00\",\"dateModified\":\"2021-03-24T17:38:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-appello-per-adozione-nazionale-due-famiglie-cercasi-per-margherita-e-marta\\\/\"},\"wordCount\":385,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-appello-per-adozione-nazionale-due-famiglie-cercasi-per-margherita-e-marta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/03\\\/appello_adozione.jpg\",\"keywords\":[\"Appelli Adozione Nazionale e Affido\"],\"articleSection\":[\"Affido &amp; Accoglienza Familiare\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-appello-per-adozione-nazionale-due-famiglie-cercasi-per-margherita-e-marta\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-appello-per-adozione-nazionale-due-famiglie-cercasi-per-margherita-e-marta\\\/\",\"name\":\"Milano. Appello per Adozione nazionale per Margherita e Marta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-appello-per-adozione-nazionale-due-famiglie-cercasi-per-margherita-e-marta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-appello-per-adozione-nazionale-due-famiglie-cercasi-per-margherita-e-marta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/03\\\/appello_adozione.jpg\",\"datePublished\":\"2021-03-24T09:00:41+00:00\",\"dateModified\":\"2021-03-24T17:38:03+00:00\",\"description\":\"Il Tribunale per i Minorenni di Milano cerca due famiglie per due bambine nate nel 2020, dichiarate adottabili ma che hanno trovato difficolt\u00e0 ad essere accolte\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-appello-per-adozione-nazionale-due-famiglie-cercasi-per-margherita-e-marta\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-appello-per-adozione-nazionale-due-famiglie-cercasi-per-margherita-e-marta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-appello-per-adozione-nazionale-due-famiglie-cercasi-per-margherita-e-marta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/03\\\/appello_adozione.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/03\\\/appello_adozione.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-appello-per-adozione-nazionale-due-famiglie-cercasi-per-margherita-e-marta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Affido &amp; Accoglienza Familiare\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/affido\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Milano. Appello per Adozione nazionale: due famiglie cercasi per Margherita e Marta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\",\"name\":\"francescoE\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/francescoe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Milano. Appello per Adozione nazionale per Margherita e Marta","description":"Il Tribunale per i Minorenni di Milano cerca due famiglie per due bambine nate nel 2020, dichiarate adottabili ma che hanno trovato difficolt\u00e0 ad essere accolte","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/milano-appello-per-adozione-nazionale-due-famiglie-cercasi-per-margherita-e-marta\/","og_locale":"it_IT","og_type":"article","og_title":"Milano. Appello per Adozione nazionale: due famiglie cercasi per Margherita e Marta","og_description":"Il Tribunale per i Minorenni di Milano cerca due famiglie per due bambine nate nel 2020, dichiarate adottabili ma che hanno trovato difficolt\u00e0 ad essere accolte","og_url":"https:\/\/www.aibi.it\/ita\/milano-appello-per-adozione-nazionale-due-famiglie-cercasi-per-margherita-e-marta\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2021-03-24T09:00:41+00:00","article_modified_time":"2021-03-24T17:38:03+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2021\/03\/appello_adozione.jpg","type":"image\/jpeg"}],"author":"francescoE","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"francescoE","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/milano-appello-per-adozione-nazionale-due-famiglie-cercasi-per-margherita-e-marta\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/milano-appello-per-adozione-nazionale-due-famiglie-cercasi-per-margherita-e-marta\/"},"author":{"name":"francescoE","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5"},"headline":"Milano. Appello per Adozione nazionale: due famiglie cercasi per Margherita e Marta","datePublished":"2021-03-24T09:00:41+00:00","dateModified":"2021-03-24T17:38:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/milano-appello-per-adozione-nazionale-due-famiglie-cercasi-per-margherita-e-marta\/"},"wordCount":385,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/milano-appello-per-adozione-nazionale-due-famiglie-cercasi-per-margherita-e-marta\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/03\/appello_adozione.jpg","keywords":["Appelli Adozione Nazionale e Affido"],"articleSection":["Affido &amp; Accoglienza Familiare"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/milano-appello-per-adozione-nazionale-due-famiglie-cercasi-per-margherita-e-marta\/","url":"https:\/\/www.aibi.it\/ita\/milano-appello-per-adozione-nazionale-due-famiglie-cercasi-per-margherita-e-marta\/","name":"Milano. Appello per Adozione nazionale per Margherita e Marta","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/milano-appello-per-adozione-nazionale-due-famiglie-cercasi-per-margherita-e-marta\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/milano-appello-per-adozione-nazionale-due-famiglie-cercasi-per-margherita-e-marta\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/03\/appello_adozione.jpg","datePublished":"2021-03-24T09:00:41+00:00","dateModified":"2021-03-24T17:38:03+00:00","description":"Il Tribunale per i Minorenni di Milano cerca due famiglie per due bambine nate nel 2020, dichiarate adottabili ma che hanno trovato difficolt\u00e0 ad essere accolte","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/milano-appello-per-adozione-nazionale-due-famiglie-cercasi-per-margherita-e-marta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/milano-appello-per-adozione-nazionale-due-famiglie-cercasi-per-margherita-e-marta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/milano-appello-per-adozione-nazionale-due-famiglie-cercasi-per-margherita-e-marta\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2021\/03\/appello_adozione.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/03\/appello_adozione.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/milano-appello-per-adozione-nazionale-due-famiglie-cercasi-per-margherita-e-marta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Affido &amp; Accoglienza Familiare","item":"https:\/\/www.aibi.it\/ita\/category\/affido\/"},{"@type":"ListItem","position":3,"name":"Milano. Appello per Adozione nazionale: due famiglie cercasi per Margherita e Marta"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5","name":"francescoE","url":"https:\/\/www.aibi.it\/ita\/author\/francescoe\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 02:13:53","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/186354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=186354"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/186354\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/186355"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=186354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=186354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=186354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}