﻿


{"id":186556,"date":"2021-03-31T07:00:31","date_gmt":"2021-03-31T05:00:31","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=186556"},"modified":"2021-03-31T14:00:10","modified_gmt":"2021-03-31T12:00:10","slug":"bolzano-concluso-il-primo-incontro-dedicato-alla-formazione-degli-insegnanti-referenti-per-ladozione","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/bolzano-concluso-il-primo-incontro-dedicato-alla-formazione-degli-insegnanti-referenti-per-ladozione\/","title":{"rendered":"Bolzano. Concluso il primo incontro dedicato alla formazione degli insegnanti referenti per l\u2019adozione"},"content":{"rendered":"<h2 style=\"font-weight: 400;\"><strong>Grande soddisfazione dei 33 insegnanti partecipanti. Tra i relatori coinvolti nelle lezioni anche Michela De Santi, referente di Ai.Bi. Bolzano.<\/strong><\/h2>\n<p style=\"font-weight: 400;\">Si \u00e8 concluso la scorsa settimana,\u00a0<strong>a Bolzano,<\/strong>\u00a0il primo incontro di formazione\u00a0dedicato agli insegnanti referenti per l\u2019adozione,\u00a0organizzato\u00a0<strong>dall\u2019assessorato\u00a0provinciale\u00a0all\u2019Istruzione.<\/strong><\/p>\n<p style=\"font-weight: 400;\">Alle lezioni, realizzate in modalit\u00e0\u00a0<strong>webinar,<\/strong>\u00a0erano presenti tutti i 33 insegnanti referenti per l\u2019adozione dei plessi scolastici in lingua italiana della provincia autonoma.<\/p>\n<p style=\"font-weight: 400;\">Un\u2019 importante momento di formazione, che ha riscosso grande soddisfazione tra i presenti, dedicato alla tematica dell\u2019adozione e all\u2019approfondimento della figura del referente scolastico.<\/p>\n<p style=\"font-weight: 400;\">Tra gli argomenti trattati, ampio spazio \u00e8 stato dato alle problematiche sociali e psicologiche che possono presentare i bambini e alle strategie che gli insegnanti, assieme alla famiglia, possono mettere in pratica.<\/p>\n<p style=\"font-weight: 400;\">Tra i relatori coinvolti nelle lezioni,\u00a0anche\u00a0<strong>Michela De Santi<\/strong>, assistente sociale e referente della sede Ai.Bi. di Bolzano, che l\u201911 marzo, ha relazionato in materia di bi-culturalit\u00e0, in famiglia e nella scuola.<\/p>\n<h3 style=\"font-weight: 400;\"><strong>E proprio la scuola costituisce un luogo di grande importanza nel percorso di inserimento dei bambini e dei ragazzi adottati.<\/strong><\/h3>\n<p style=\"font-weight: 400;\">Proprio per questo motivo, nel\u00a0dicembre 2014, il MIUR ha pubblicato le\u00a0<strong>Linee guida nazionali per favorire il diritto allo studio<\/strong>\u00a0<strong>dei bambini adottati.<\/strong><\/p>\n<p style=\"font-weight: 400;\">In Alto Adige, nel 2017, si \u00e8 cos\u00ec deciso di dare vita ad un gruppo di lavoro, che potesse raccordare al meglio le linee guida provinciali con quelle nazionali. Al tavolo di lavoro, coordinato dall\u2019Ufficio per la Tutela dei minori e l\u2019inclusione sociale, ha preso parte anche\u00a0<strong>Ai.Bi.<\/strong><\/p>\n<p style=\"font-weight: 400;\">\u201c<em><a href=\"http:\/\/www.provincia.bz.it\/formazione-lingue\/scuola-italiana\/servizi-attivita\/alunni-adottati.asp\">Il risultato di questo lavoro<\/a><\/em>&#8211; si legge nelle premesse del documento-\u00a0<em>\u00e8 stato un documento che racchiude informazioni generali sulle specificit\u00e0 delle bambine e dei bambini adottati oltre ad \u00a0una serie di semplici e chiare indicazioni e utili suggerimenti per\u00a0 dirigenti e insegnanti di ogni ordine di scuola a partire dalla scuola dell\u2019infanzia\u201d.<\/em><\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">\n","protected":false},"excerpt":{"rendered":"<p>Grande soddisfazione dei 33 insegnanti partecipanti. Tra i relatori coinvolti nelle lezioni anche Michela De Santi, referente di Ai.Bi. Bolzano. Si &egrave; concluso la scorsa settimana,&nbsp;a Bolzano,&nbsp;il primo incontro di formazione&nbsp;dedicato agli insegnanti referenti per l&rsquo;adozione,&nbsp;organizzato&nbsp;dall&rsquo;assessorato&nbsp;provinciale&nbsp;all&rsquo;Istruzione. Alle lezioni, realizzate in modalit&agrave;&nbsp;webinar,&nbsp;erano presenti tutti i 33 insegnanti referenti per l&rsquo;adozione dei [&hellip;]<\/p>\n","protected":false},"author":97,"featured_media":186557,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[172],"tags":[347,449,436],"class_list":["post-186556","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-internazionale","tag-adozione-internazionale","tag-bolzano","tag-formazione"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Bolzano. Concluso il primo incontro dedicato alla formazione degli insegnanti referenti per l\u2019adozione - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"Grande soddisfazione dei 33 insegnanti partecipanti. Tra i relatori coinvolti nelle lezioni anche Michela De Santi, referente di Ai.Bi. Bolzano.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/bolzano-concluso-il-primo-incontro-dedicato-alla-formazione-degli-insegnanti-referenti-per-ladozione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bolzano. Concluso il primo incontro dedicato alla formazione degli insegnanti referenti per l\u2019adozione\" \/>\n<meta property=\"og:description\" content=\"Grande soddisfazione dei 33 insegnanti partecipanti. Tra i relatori coinvolti nelle lezioni anche Michela De Santi, referente di Ai.Bi. Bolzano.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/bolzano-concluso-il-primo-incontro-dedicato-alla-formazione-degli-insegnanti-referenti-per-ladozione\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-31T05:00:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-31T12:00:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2021\/03\/bolzano-adozione.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mc.sabatini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mc.sabatini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolzano-concluso-il-primo-incontro-dedicato-alla-formazione-degli-insegnanti-referenti-per-ladozione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolzano-concluso-il-primo-incontro-dedicato-alla-formazione-degli-insegnanti-referenti-per-ladozione\\\/\"},\"author\":{\"name\":\"mc.sabatini\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\"},\"headline\":\"Bolzano. Concluso il primo incontro dedicato alla formazione degli insegnanti referenti per l\u2019adozione\",\"datePublished\":\"2021-03-31T05:00:31+00:00\",\"dateModified\":\"2021-03-31T12:00:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolzano-concluso-il-primo-incontro-dedicato-alla-formazione-degli-insegnanti-referenti-per-ladozione\\\/\"},\"wordCount\":320,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolzano-concluso-il-primo-incontro-dedicato-alla-formazione-degli-insegnanti-referenti-per-ladozione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/03\\\/bolzano-adozione.jpg\",\"keywords\":[\"Adozione Internazionale\",\"Bolzano\",\"formazione\"],\"articleSection\":[\"Adozione Internazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolzano-concluso-il-primo-incontro-dedicato-alla-formazione-degli-insegnanti-referenti-per-ladozione\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolzano-concluso-il-primo-incontro-dedicato-alla-formazione-degli-insegnanti-referenti-per-ladozione\\\/\",\"name\":\"Bolzano. Concluso il primo incontro dedicato alla formazione degli insegnanti referenti per l\u2019adozione - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolzano-concluso-il-primo-incontro-dedicato-alla-formazione-degli-insegnanti-referenti-per-ladozione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolzano-concluso-il-primo-incontro-dedicato-alla-formazione-degli-insegnanti-referenti-per-ladozione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/03\\\/bolzano-adozione.jpg\",\"datePublished\":\"2021-03-31T05:00:31+00:00\",\"dateModified\":\"2021-03-31T12:00:10+00:00\",\"description\":\"Grande soddisfazione dei 33 insegnanti partecipanti. Tra i relatori coinvolti nelle lezioni anche Michela De Santi, referente di Ai.Bi. Bolzano.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolzano-concluso-il-primo-incontro-dedicato-alla-formazione-degli-insegnanti-referenti-per-ladozione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolzano-concluso-il-primo-incontro-dedicato-alla-formazione-degli-insegnanti-referenti-per-ladozione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolzano-concluso-il-primo-incontro-dedicato-alla-formazione-degli-insegnanti-referenti-per-ladozione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/03\\\/bolzano-adozione.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/03\\\/bolzano-adozione.jpg\",\"width\":1200,\"height\":630,\"caption\":\"Clever classmates looking attentively at blackboard at lesson\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolzano-concluso-il-primo-incontro-dedicato-alla-formazione-degli-insegnanti-referenti-per-ladozione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione Internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-internazionale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bolzano. Concluso il primo incontro dedicato alla formazione degli insegnanti referenti per l\u2019adozione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\",\"name\":\"mc.sabatini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/marias\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bolzano. Concluso il primo incontro dedicato alla formazione degli insegnanti referenti per l\u2019adozione - Ai.Bi. Amici dei Bambini","description":"Grande soddisfazione dei 33 insegnanti partecipanti. Tra i relatori coinvolti nelle lezioni anche Michela De Santi, referente di Ai.Bi. Bolzano.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/bolzano-concluso-il-primo-incontro-dedicato-alla-formazione-degli-insegnanti-referenti-per-ladozione\/","og_locale":"it_IT","og_type":"article","og_title":"Bolzano. Concluso il primo incontro dedicato alla formazione degli insegnanti referenti per l\u2019adozione","og_description":"Grande soddisfazione dei 33 insegnanti partecipanti. Tra i relatori coinvolti nelle lezioni anche Michela De Santi, referente di Ai.Bi. Bolzano.","og_url":"https:\/\/www.aibi.it\/ita\/bolzano-concluso-il-primo-incontro-dedicato-alla-formazione-degli-insegnanti-referenti-per-ladozione\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2021-03-31T05:00:31+00:00","article_modified_time":"2021-03-31T12:00:10+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2021\/03\/bolzano-adozione.jpg","type":"image\/jpeg"}],"author":"mc.sabatini","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"mc.sabatini","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/bolzano-concluso-il-primo-incontro-dedicato-alla-formazione-degli-insegnanti-referenti-per-ladozione\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/bolzano-concluso-il-primo-incontro-dedicato-alla-formazione-degli-insegnanti-referenti-per-ladozione\/"},"author":{"name":"mc.sabatini","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938"},"headline":"Bolzano. Concluso il primo incontro dedicato alla formazione degli insegnanti referenti per l\u2019adozione","datePublished":"2021-03-31T05:00:31+00:00","dateModified":"2021-03-31T12:00:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bolzano-concluso-il-primo-incontro-dedicato-alla-formazione-degli-insegnanti-referenti-per-ladozione\/"},"wordCount":320,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bolzano-concluso-il-primo-incontro-dedicato-alla-formazione-degli-insegnanti-referenti-per-ladozione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/03\/bolzano-adozione.jpg","keywords":["Adozione Internazionale","Bolzano","formazione"],"articleSection":["Adozione Internazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/bolzano-concluso-il-primo-incontro-dedicato-alla-formazione-degli-insegnanti-referenti-per-ladozione\/","url":"https:\/\/www.aibi.it\/ita\/bolzano-concluso-il-primo-incontro-dedicato-alla-formazione-degli-insegnanti-referenti-per-ladozione\/","name":"Bolzano. Concluso il primo incontro dedicato alla formazione degli insegnanti referenti per l\u2019adozione - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bolzano-concluso-il-primo-incontro-dedicato-alla-formazione-degli-insegnanti-referenti-per-ladozione\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bolzano-concluso-il-primo-incontro-dedicato-alla-formazione-degli-insegnanti-referenti-per-ladozione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/03\/bolzano-adozione.jpg","datePublished":"2021-03-31T05:00:31+00:00","dateModified":"2021-03-31T12:00:10+00:00","description":"Grande soddisfazione dei 33 insegnanti partecipanti. Tra i relatori coinvolti nelle lezioni anche Michela De Santi, referente di Ai.Bi. Bolzano.","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/bolzano-concluso-il-primo-incontro-dedicato-alla-formazione-degli-insegnanti-referenti-per-ladozione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/bolzano-concluso-il-primo-incontro-dedicato-alla-formazione-degli-insegnanti-referenti-per-ladozione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/bolzano-concluso-il-primo-incontro-dedicato-alla-formazione-degli-insegnanti-referenti-per-ladozione\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2021\/03\/bolzano-adozione.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/03\/bolzano-adozione.jpg","width":1200,"height":630,"caption":"Clever classmates looking attentively at blackboard at lesson"},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/bolzano-concluso-il-primo-incontro-dedicato-alla-formazione-degli-insegnanti-referenti-per-ladozione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione Internazionale","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-internazionale\/"},{"@type":"ListItem","position":3,"name":"Bolzano. Concluso il primo incontro dedicato alla formazione degli insegnanti referenti per l\u2019adozione"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938","name":"mc.sabatini","url":"https:\/\/www.aibi.it\/ita\/author\/marias\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 09:27:29","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/186556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/97"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=186556"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/186556\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/186557"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=186556"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=186556"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=186556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}