﻿


{"id":186891,"date":"2021-04-13T07:22:49","date_gmt":"2021-04-13T05:22:49","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=186891"},"modified":"2021-04-13T15:34:04","modified_gmt":"2021-04-13T13:34:04","slug":"campania-scuola-e-comitati-territoriali-dei-genitori-la-rete-di-panthaku","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/campania-scuola-e-comitati-territoriali-dei-genitori-la-rete-di-panthaku\/","title":{"rendered":"Campania. Scuola e Comitati territoriali dei genitori: la rete di Panthak\u00f9"},"content":{"rendered":"<h2 style=\"font-weight: 400;\"><strong>Mercoled\u00ec 14 aprile, alle 18.30, il primo webinar con gli attori di un nuova, ambiziosa attivit\u00e0 di progetto!<\/strong><\/h2>\n<p style=\"font-weight: 400;\">Creare dei comitati territoriali di genitori, partendo da una rappresentanza di quelli degli alunni coinvolti \u00a0in \u201cPanthak\u00f9. Educare dappertutto\u201d, questo \u00e8 il nuovo ambizioso obiettivo del progetto\u00a0Panthak\u00f9, selezionato da \u201cCon i Bambini\u201d nell\u2019ambito del Fondo per il contrasto della povert\u00e0 educativa minorile e che vede Ai.Bi. come capofila.<\/p>\n<p style=\"font-weight: 400;\"><strong>Per farlo \u00e8 necessario l&#8217;impegno di tutti.<\/strong><\/p>\n<p style=\"font-weight: 400;\">Il primo incontro tra i genitori coinvolti si terr\u00e0\u00a0<strong>mercoled\u00ec 14 aprile,<\/strong> dalle ore 18.30 alle 20.00 sulla \u00a0piattaforma Zoom.<\/p>\n<p style=\"font-weight: 400;\">Saranno presenti all\u2019appuntamento la coordinatrice dell\u2019attivit\u00e0 di progetto\u00a0<strong>Gabriella Monetta\u00a0<\/strong>della\u00a0<strong>Fondazione Carisal<\/strong>\u00a0di Salerno, la\u00a0<strong>coordinatrice scientifica<\/strong>\u00a0incaricata dalla stessa Fondazione,\u00a0<strong>Maria Vittoria Lanzara<\/strong>\u00a0e\u00a0<strong>Antonella Spadafora<\/strong>, project manager Panthak\u00f9 e referente\u00a0<strong>Ai.Bi. Campania<\/strong>.<\/p>\n<h3 style=\"font-weight: 400;\"><strong>Genitori: l\u2019importante \u00e8 fare rete<\/strong><\/h3>\n<p style=\"font-weight: 400;\">\u201c<em>Nel primo incontro ci sar\u00e0 una delegazione composta da\u00a0<strong>tre genitori<\/strong>\u00a0per ogni istituto scolastico partner di progetto (Calcedonia e Montalcini di Salerno, Denza di Castellammare di Stabia e Principe di Piemonte di S.Maria Capua Vetere)<\/em>\u00a0\u2013 spiega Gabriella Monetta \u2013\u00a0<em>Con loro ci confronteremo per coinvolgerli in una co-progettazione tesa a una\u00a0<strong>ricerca sui bisogni dei genitori in una situazione pandemica come quella che stiamo vivendo<\/strong>.<\/em>\u00a0<em>Come hanno vissuto il rapporto con i loro figli in questi lunghi mesi? Come \u00e8 eventualmente cambiato? Come hanno percepito il sostegno genitoriale fornito ai loro ragazzi?<\/em>\u00a0<strong><em>Raccoglieremo le loro percezioni rispetto al vissuto<\/em><\/strong><em>\u00a0per renderli protagonisti di questa nuova azione da svolgere di concerto con la scuola e la comunit\u00e0 educante\u201d<\/em>.<\/p>\n<p style=\"font-weight: 400;\">Non solo. A loro toccher\u00e0 anche il compito di\u00a0<strong>allargare la\u00a0<\/strong>\u00a0<strong>rete<\/strong>\u00a0di genitori attraverso i propri contatti sociali, affinch\u00e9 diventi sempre pi\u00f9 solida.\u00a0<strong>I comitati partiranno infatti da quelli delle scuole partner ma saranno aperti a tutti i genitori dei tre territori di progetto.<\/strong><\/p>\n<p style=\"font-weight: 400;\">Nel corso dell\u2019appuntamento di mercoled\u00ec 14 aprile, si getteranno dunque le basi per rendere concreta l\u2019attivit\u00e0 di progetto, che prevedr\u00e0, successivamente, l&#8217;elaborazione di un questionario e un convegno finale sui risultati emersi, da tenersi a settembre. Non mancheranno, nel corso del tempo, testimonial e\u00a0<strong>incontri di approfondimento sulle relazioni familiari<\/strong>\u00a0che Fondazione Carisal e Ai.Bi. porteranno avanti insieme fino a\u00a0giugno 2022.<\/p>\n<p style=\"font-weight: 400;\">Per informazioni \u00e8 possibile scrivere a<strong>\u00a0<\/strong><a href=\"mailto:salerno@aibi.it\"><strong>salerno@aibi.it\u00a0<\/strong><\/a><\/p>\n<p style=\"font-weight: 400;\">\n","protected":false},"excerpt":{"rendered":"<p>Mercoled&igrave; 14 aprile, alle 18.30, il primo webinar con gli attori di un nuova, ambiziosa attivit&agrave; di progetto! Creare dei comitati territoriali di genitori, partendo da una rappresentanza di quelli degli alunni coinvolti &nbsp;in &ldquo;Panthak&ugrave;. Educare dappertutto&rdquo;, questo &egrave; il nuovo ambizioso obiettivo del progetto&nbsp;Panthak&ugrave;, selezionato da &ldquo;Con i Bambini&rdquo; [&hellip;]<\/p>\n","protected":false},"author":97,"featured_media":186892,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[764],"tags":[450],"class_list":["post-186891","post","type-post","status-publish","format-standard","has-post-thumbnail","category-progetti-in-italia","tag-panthaku"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Campania. Scuola e Comitati territoriali dei genitori: la rete di Panthak\u00f9 - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"Mercoled\u00ec 14\u00a0aprile, alle 18.00,\u00a0il primo webinar con gli attori di un nuova, ambiziosa attivit\u00e0 di progetto!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/campania-scuola-e-comitati-territoriali-dei-genitori-la-rete-di-panthaku\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Campania. Scuola e Comitati territoriali dei genitori: la rete di Panthak\u00f9\" \/>\n<meta property=\"og:description\" content=\"Mercoled\u00ec 14\u00a0aprile, alle 18.00,\u00a0il primo webinar con gli attori di un nuova, ambiziosa attivit\u00e0 di progetto!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/campania-scuola-e-comitati-territoriali-dei-genitori-la-rete-di-panthaku\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-13T05:22:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-13T13:34:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2021\/04\/progetto.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mc.sabatini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mc.sabatini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/campania-scuola-e-comitati-territoriali-dei-genitori-la-rete-di-panthaku\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/campania-scuola-e-comitati-territoriali-dei-genitori-la-rete-di-panthaku\\\/\"},\"author\":{\"name\":\"mc.sabatini\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\"},\"headline\":\"Campania. Scuola e Comitati territoriali dei genitori: la rete di Panthak\u00f9\",\"datePublished\":\"2021-04-13T05:22:49+00:00\",\"dateModified\":\"2021-04-13T13:34:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/campania-scuola-e-comitati-territoriali-dei-genitori-la-rete-di-panthaku\\\/\"},\"wordCount\":378,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/campania-scuola-e-comitati-territoriali-dei-genitori-la-rete-di-panthaku\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/04\\\/progetto.jpg\",\"keywords\":[\"Panthaku\"],\"articleSection\":[\"Progetti in Italia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/campania-scuola-e-comitati-territoriali-dei-genitori-la-rete-di-panthaku\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/campania-scuola-e-comitati-territoriali-dei-genitori-la-rete-di-panthaku\\\/\",\"name\":\"Campania. Scuola e Comitati territoriali dei genitori: la rete di Panthak\u00f9 - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/campania-scuola-e-comitati-territoriali-dei-genitori-la-rete-di-panthaku\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/campania-scuola-e-comitati-territoriali-dei-genitori-la-rete-di-panthaku\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/04\\\/progetto.jpg\",\"datePublished\":\"2021-04-13T05:22:49+00:00\",\"dateModified\":\"2021-04-13T13:34:04+00:00\",\"description\":\"Mercoled\u00ec 14\u00a0aprile, alle 18.00,\u00a0il primo webinar con gli attori di un nuova, ambiziosa attivit\u00e0 di progetto!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/campania-scuola-e-comitati-territoriali-dei-genitori-la-rete-di-panthaku\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/campania-scuola-e-comitati-territoriali-dei-genitori-la-rete-di-panthaku\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/campania-scuola-e-comitati-territoriali-dei-genitori-la-rete-di-panthaku\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/04\\\/progetto.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/04\\\/progetto.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/campania-scuola-e-comitati-territoriali-dei-genitori-la-rete-di-panthaku\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Progetti in Italia\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/progetti-in-italia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Campania. Scuola e Comitati territoriali dei genitori: la rete di Panthak\u00f9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\",\"name\":\"mc.sabatini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/marias\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Campania. Scuola e Comitati territoriali dei genitori: la rete di Panthak\u00f9 - Ai.Bi. Amici dei Bambini","description":"Mercoled\u00ec 14\u00a0aprile, alle 18.00,\u00a0il primo webinar con gli attori di un nuova, ambiziosa attivit\u00e0 di progetto!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/campania-scuola-e-comitati-territoriali-dei-genitori-la-rete-di-panthaku\/","og_locale":"it_IT","og_type":"article","og_title":"Campania. Scuola e Comitati territoriali dei genitori: la rete di Panthak\u00f9","og_description":"Mercoled\u00ec 14\u00a0aprile, alle 18.00,\u00a0il primo webinar con gli attori di un nuova, ambiziosa attivit\u00e0 di progetto!","og_url":"https:\/\/www.aibi.it\/ita\/campania-scuola-e-comitati-territoriali-dei-genitori-la-rete-di-panthaku\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2021-04-13T05:22:49+00:00","article_modified_time":"2021-04-13T13:34:04+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2021\/04\/progetto.jpg","type":"image\/jpeg"}],"author":"mc.sabatini","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"mc.sabatini","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/campania-scuola-e-comitati-territoriali-dei-genitori-la-rete-di-panthaku\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/campania-scuola-e-comitati-territoriali-dei-genitori-la-rete-di-panthaku\/"},"author":{"name":"mc.sabatini","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938"},"headline":"Campania. Scuola e Comitati territoriali dei genitori: la rete di Panthak\u00f9","datePublished":"2021-04-13T05:22:49+00:00","dateModified":"2021-04-13T13:34:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/campania-scuola-e-comitati-territoriali-dei-genitori-la-rete-di-panthaku\/"},"wordCount":378,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/campania-scuola-e-comitati-territoriali-dei-genitori-la-rete-di-panthaku\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/04\/progetto.jpg","keywords":["Panthaku"],"articleSection":["Progetti in Italia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/campania-scuola-e-comitati-territoriali-dei-genitori-la-rete-di-panthaku\/","url":"https:\/\/www.aibi.it\/ita\/campania-scuola-e-comitati-territoriali-dei-genitori-la-rete-di-panthaku\/","name":"Campania. Scuola e Comitati territoriali dei genitori: la rete di Panthak\u00f9 - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/campania-scuola-e-comitati-territoriali-dei-genitori-la-rete-di-panthaku\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/campania-scuola-e-comitati-territoriali-dei-genitori-la-rete-di-panthaku\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/04\/progetto.jpg","datePublished":"2021-04-13T05:22:49+00:00","dateModified":"2021-04-13T13:34:04+00:00","description":"Mercoled\u00ec 14\u00a0aprile, alle 18.00,\u00a0il primo webinar con gli attori di un nuova, ambiziosa attivit\u00e0 di progetto!","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/campania-scuola-e-comitati-territoriali-dei-genitori-la-rete-di-panthaku\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/campania-scuola-e-comitati-territoriali-dei-genitori-la-rete-di-panthaku\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/campania-scuola-e-comitati-territoriali-dei-genitori-la-rete-di-panthaku\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2021\/04\/progetto.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/04\/progetto.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/campania-scuola-e-comitati-territoriali-dei-genitori-la-rete-di-panthaku\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Progetti in Italia","item":"https:\/\/www.aibi.it\/ita\/category\/progetti-in-italia\/"},{"@type":"ListItem","position":3,"name":"Campania. Scuola e Comitati territoriali dei genitori: la rete di Panthak\u00f9"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938","name":"mc.sabatini","url":"https:\/\/www.aibi.it\/ita\/author\/marias\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 02:57:06","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/186891","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/97"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=186891"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/186891\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/186892"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=186891"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=186891"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=186891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}