﻿


{"id":187010,"date":"2021-04-16T15:00:09","date_gmt":"2021-04-16T13:00:09","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=187010"},"modified":"2021-04-16T17:50:28","modified_gmt":"2021-04-16T15:50:28","slug":"bolzano-cosa-mi-ha-dato-ai-bi-ho-imparato-il-significato-della-parola-grazie","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/bolzano-cosa-mi-ha-dato-ai-bi-ho-imparato-il-significato-della-parola-grazie\/","title":{"rendered":"Bolzano: cosa mi ha dato Ai.Bi.? Ho imparato il significato della parola &#8220;grazie&#8221;"},"content":{"rendered":"<h2><strong>Una situazione difficile, la perdita del lavoro\u2026 Poi, l\u2019incontro con i volontari di Ai.Bi. e, soprattutto, con i bambini e le donne del progetto Gorio 2. Per ritrovare il senso del servizio e della gratitudine<\/strong><\/h2>\n<p>Il Covid ha inciso sulla vita di tutti in modi tanto diversi quante sono le <strong>diverse esperienze di vita<\/strong>: chi ha perso i propri cari, chi il lavoro, chi ha lottato contro la solitudine\u2026 Pur nelle difficolt\u00e0, per\u00f2, ci sono state anche tante occasioni nelle quali sperimentare la <strong>vicinanza agli altri<\/strong> e sentire, pi\u00f9 di quanto succedeva nella vita \u201cdi prima\u201d, il senso di dedicare un po\u2019 delle proprie energie agli altri.<\/p>\n<h3><strong>L\u2019esperienza gioiosa di donarsi agli altri<\/strong><\/h3>\n<p>\u00c8 stato cos\u00ec, per esempio, per tutti i volontari che hanno <strong>amorevolmente fatto da tutor<\/strong> dei bambini e dei loro genitori che sono ospiti in un campo di accoglienza migranti di Ai.Bi. Una volontaria, in particolare, ha sentito l\u2019esigenza di raccontare le sue emozioni, regalando, cos\u00ec, uno <strong>spaccato di vita<\/strong> che fa molto pensare sia a quello che sta succedendo nelle case delle famiglie \u201cnormali\u201d, stravolte dalle pesanti conseguenze del Covid ma che si sono <strong>riscoperte in un meraviglioso gesto di altruismo<\/strong> <strong>e accoglienza<\/strong> dei bambini, sia a quelle famiglie che vengono da mondi lontani e che, per tanti, sono quasi invisibili.<\/p>\n<h3><strong>La testimonianza di una volontaria<\/strong><\/h3>\n<p>\u201cDopo 38 anni consecutivi, ho perso il mio lavoro. Io di anni ne ha 58 e di colpo mi sono ritrovata in una situazione resa <strong>ancor pi\u00f9 difficile<\/strong> dal Covid, che mi ha fatto perdere le persone care, a volte in modo repentino e inesorabile.<br \/>\nHo avuto paura, perch\u00e9 non voglio, non posso e non devo pensare che la vita mia e di tutti possa finire cos\u00ec, come nell\u2019ultimo anno. Ecco, allora, che proprio in questo frangente drammatico, la famiglia, la salute, la casa, la societ\u00e0\u2026 hanno iniziato a <strong>reclamare una mia attenzione diversa<\/strong>, chiedendomi di cambiare quelli che prima erano i miei sentimenti verso la \u201ccomodit\u00e0 noiosa\u201d della mia calda cucina e <strong>aprirmi<\/strong> di pi\u00f9, guardando oltre il mio naso.<\/p>\n<p>Il caso, o forse la fortuna, oppure, meglio, la vita, hanno risposto a una mia precisa richiesta<strong>: farmi incontrare qualcuno che ha bisogno<\/strong>. Un\u2019organizzazione che veramente mi faccia sentire \u201cpersona\u201d e non un mero numero, accompagnando a conoscere qualcuno che ha bisogno anche di me.<\/p>\n<h3><strong>L\u2019incontro con Ai.Bi. e la gratitudine per poter essere \u201ca servizio\u201d degli altri<\/strong><\/h3>\n<p>Sono uscita in tutto tre volte in questo periodo di lockdown, e in ben due occasioni, in modi disparati, mi sono imbattuta in un semplice indirizzo mail che probabilmente, senza l\u2019apertura dei miei sensi, sarebbe rimasto non letto, nella mia finta fretta di vita.<\/p>\n<p>Invece \u00e8 stato cos\u00ec che <strong>ho incontrato Ai.Bi.,<\/strong> che ho saputo del progetto <strong>Gorio 2<\/strong> e che ho iniziato <strong>a donare un servizio<\/strong> che si tramuta immediatamente in <strong>calore<\/strong>, <strong>speranza<\/strong>, <strong>famiglia<\/strong>, <strong>societ\u00e0<\/strong>, <strong>studio<\/strong>, <strong>lavoro<\/strong>: in una parola, <strong>decoro<\/strong>. Quello che ogni essere umano ha il diritto di avere.<\/p>\n<p>Ho incontrato la <strong>luce negli occhi dei Bambini<\/strong> seguiti dai volontari di Ai.Bi. Gli occhi silenziosi e tenuti, sempre un po\u2019 bassi, di Donne che ancora non sanno di poter avere diritto alla \u2018D\u2019 maiuscola, non solo scritta qui in questa mia.<br \/>\nVoci di uomini che, in uno stentato italiano\/tedesco, riconoscono il loro bagaglio a volte cos\u00ec enorme da far <strong>tanto male<\/strong> anche a me, cos\u00ec apparentemente inutile ma pronta a dire solo una parola: <strong>grazie<\/strong>.<br \/>\nEcco cosa mi sta dando questo progetto. Ecco cosa mi sta dando l\u2019associazione AiBi: ho imparato nuovamente <strong>il significato della parola \u201cservizio\u201d<\/strong> e della parola \u201c<strong>grazie<\/strong>\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una situazione difficile, la perdita del lavoro&hellip; Poi, l&rsquo;incontro con i volontari di Ai.Bi. e, soprattutto, con i bambini e le donne del progetto Gorio 2. Per ritrovare il senso del servizio e della gratitudine Il Covid ha inciso sulla vita di tutti in modi tanto diversi quante sono le [&hellip;]<\/p>\n","protected":false},"author":102,"featured_media":187016,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[764],"tags":[449,766],"class_list":["post-187010","post","type-post","status-publish","format-standard","has-post-thumbnail","category-progetti-in-italia","tag-bolzano","tag-progetti"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cosa mi ha dato Ai.Bi.? Ho imparato il significato della parola grazie<\/title>\n<meta name=\"description\" content=\"Una situazione difficile, la perdita del lavoro\u2026 Poi, l\u2019incontro con i volontari di Ai.Bi. e con i bambini e le donne del progetto Gorio 2\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/bolzano-cosa-mi-ha-dato-ai-bi-ho-imparato-il-significato-della-parola-grazie\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bolzano: cosa mi ha dato Ai.Bi.? Ho imparato il significato della parola &quot;grazie&quot;\" \/>\n<meta property=\"og:description\" content=\"Una situazione difficile, la perdita del lavoro\u2026 Poi, l\u2019incontro con i volontari di Ai.Bi. e con i bambini e le donne del progetto Gorio 2\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/bolzano-cosa-mi-ha-dato-ai-bi-ho-imparato-il-significato-della-parola-grazie\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-16T13:00:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-16T15:50:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2021\/04\/bolzano-gratitudine.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolzano-cosa-mi-ha-dato-ai-bi-ho-imparato-il-significato-della-parola-grazie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolzano-cosa-mi-ha-dato-ai-bi-ho-imparato-il-significato-della-parola-grazie\\\/\"},\"author\":{\"name\":\"francescoE\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\"},\"headline\":\"Bolzano: cosa mi ha dato Ai.Bi.? Ho imparato il significato della parola &#8220;grazie&#8221;\",\"datePublished\":\"2021-04-16T13:00:09+00:00\",\"dateModified\":\"2021-04-16T15:50:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolzano-cosa-mi-ha-dato-ai-bi-ho-imparato-il-significato-della-parola-grazie\\\/\"},\"wordCount\":615,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolzano-cosa-mi-ha-dato-ai-bi-ho-imparato-il-significato-della-parola-grazie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/04\\\/bolzano-gratitudine.jpg\",\"keywords\":[\"Bolzano\",\"progetti\"],\"articleSection\":[\"Progetti in Italia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolzano-cosa-mi-ha-dato-ai-bi-ho-imparato-il-significato-della-parola-grazie\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolzano-cosa-mi-ha-dato-ai-bi-ho-imparato-il-significato-della-parola-grazie\\\/\",\"name\":\"Cosa mi ha dato Ai.Bi.? Ho imparato il significato della parola grazie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolzano-cosa-mi-ha-dato-ai-bi-ho-imparato-il-significato-della-parola-grazie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolzano-cosa-mi-ha-dato-ai-bi-ho-imparato-il-significato-della-parola-grazie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/04\\\/bolzano-gratitudine.jpg\",\"datePublished\":\"2021-04-16T13:00:09+00:00\",\"dateModified\":\"2021-04-16T15:50:28+00:00\",\"description\":\"Una situazione difficile, la perdita del lavoro\u2026 Poi, l\u2019incontro con i volontari di Ai.Bi. e con i bambini e le donne del progetto Gorio 2\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolzano-cosa-mi-ha-dato-ai-bi-ho-imparato-il-significato-della-parola-grazie\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolzano-cosa-mi-ha-dato-ai-bi-ho-imparato-il-significato-della-parola-grazie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolzano-cosa-mi-ha-dato-ai-bi-ho-imparato-il-significato-della-parola-grazie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/04\\\/bolzano-gratitudine.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/04\\\/bolzano-gratitudine.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolzano-cosa-mi-ha-dato-ai-bi-ho-imparato-il-significato-della-parola-grazie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Progetti in Italia\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/progetti-in-italia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bolzano: cosa mi ha dato Ai.Bi.? Ho imparato il significato della parola &#8220;grazie&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\",\"name\":\"francescoE\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/francescoe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cosa mi ha dato Ai.Bi.? Ho imparato il significato della parola grazie","description":"Una situazione difficile, la perdita del lavoro\u2026 Poi, l\u2019incontro con i volontari di Ai.Bi. e con i bambini e le donne del progetto Gorio 2","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/bolzano-cosa-mi-ha-dato-ai-bi-ho-imparato-il-significato-della-parola-grazie\/","og_locale":"it_IT","og_type":"article","og_title":"Bolzano: cosa mi ha dato Ai.Bi.? Ho imparato il significato della parola \"grazie\"","og_description":"Una situazione difficile, la perdita del lavoro\u2026 Poi, l\u2019incontro con i volontari di Ai.Bi. e con i bambini e le donne del progetto Gorio 2","og_url":"https:\/\/www.aibi.it\/ita\/bolzano-cosa-mi-ha-dato-ai-bi-ho-imparato-il-significato-della-parola-grazie\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2021-04-16T13:00:09+00:00","article_modified_time":"2021-04-16T15:50:28+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2021\/04\/bolzano-gratitudine.jpg","type":"image\/jpeg"}],"author":"francescoE","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"francescoE","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/bolzano-cosa-mi-ha-dato-ai-bi-ho-imparato-il-significato-della-parola-grazie\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/bolzano-cosa-mi-ha-dato-ai-bi-ho-imparato-il-significato-della-parola-grazie\/"},"author":{"name":"francescoE","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5"},"headline":"Bolzano: cosa mi ha dato Ai.Bi.? Ho imparato il significato della parola &#8220;grazie&#8221;","datePublished":"2021-04-16T13:00:09+00:00","dateModified":"2021-04-16T15:50:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bolzano-cosa-mi-ha-dato-ai-bi-ho-imparato-il-significato-della-parola-grazie\/"},"wordCount":615,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bolzano-cosa-mi-ha-dato-ai-bi-ho-imparato-il-significato-della-parola-grazie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/04\/bolzano-gratitudine.jpg","keywords":["Bolzano","progetti"],"articleSection":["Progetti in Italia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/bolzano-cosa-mi-ha-dato-ai-bi-ho-imparato-il-significato-della-parola-grazie\/","url":"https:\/\/www.aibi.it\/ita\/bolzano-cosa-mi-ha-dato-ai-bi-ho-imparato-il-significato-della-parola-grazie\/","name":"Cosa mi ha dato Ai.Bi.? Ho imparato il significato della parola grazie","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bolzano-cosa-mi-ha-dato-ai-bi-ho-imparato-il-significato-della-parola-grazie\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bolzano-cosa-mi-ha-dato-ai-bi-ho-imparato-il-significato-della-parola-grazie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/04\/bolzano-gratitudine.jpg","datePublished":"2021-04-16T13:00:09+00:00","dateModified":"2021-04-16T15:50:28+00:00","description":"Una situazione difficile, la perdita del lavoro\u2026 Poi, l\u2019incontro con i volontari di Ai.Bi. e con i bambini e le donne del progetto Gorio 2","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/bolzano-cosa-mi-ha-dato-ai-bi-ho-imparato-il-significato-della-parola-grazie\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/bolzano-cosa-mi-ha-dato-ai-bi-ho-imparato-il-significato-della-parola-grazie\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/bolzano-cosa-mi-ha-dato-ai-bi-ho-imparato-il-significato-della-parola-grazie\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2021\/04\/bolzano-gratitudine.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/04\/bolzano-gratitudine.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/bolzano-cosa-mi-ha-dato-ai-bi-ho-imparato-il-significato-della-parola-grazie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Progetti in Italia","item":"https:\/\/www.aibi.it\/ita\/category\/progetti-in-italia\/"},{"@type":"ListItem","position":3,"name":"Bolzano: cosa mi ha dato Ai.Bi.? Ho imparato il significato della parola &#8220;grazie&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5","name":"francescoE","url":"https:\/\/www.aibi.it\/ita\/author\/francescoe\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 04:47:52","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/187010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=187010"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/187010\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/187016"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=187010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=187010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=187010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}