﻿{"id":187099,"date":"2021-04-20T07:25:26","date_gmt":"2021-04-20T05:25:26","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=187099"},"modified":"2022-07-25T15:04:38","modified_gmt":"2022-07-25T13:04:38","slug":"bolivia-masiel-e-il-gattino-choco-un-urlo-al-bisogno-di-famiglia","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/bolivia-masiel-e-il-gattino-choco-un-urlo-al-bisogno-di-famiglia\/","title":{"rendered":"Bolivia. Masiel e il gattino Choco, un urlo al bisogno di famiglia"},"content":{"rendered":"<h2>Masiel e gli altri bambini accolti al Jos\u00e9 Soria stanno ricostruendo la loro storia grazie anche al proprio album fotografico, voluto e valorizzato dallo staff del Centro. Tutto ci\u00f2 \u00e8 possibile grazie al <a href=\"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/attivazione-adozione-a-distanza\/?scelta=25&amp;progetto=Bolivia\">Sostegno a Distanza<\/a><\/h2>\n<p>La\u00a0<strong>Bolivia<\/strong>\u00a0\u00e8 il Paese pi\u00f9 povero dell\u2019America Latina e con la maggior disuguaglianza sociale in termini di accesso alle risorse, salute, sviluppo economico, istruzione e aspettativa di vita.\u00a0Uno Stato \u201cgiovane\u201d con oltre 4 milioni di bambini e adolescenti sotto i 15 anni di et\u00e0 di cui, per\u00f2, la met\u00e0 vive in condizioni di estrema povert\u00e0 e quasi 9 mila sono collocati in 196 istituti per l\u2019infanzia nel Paese.<\/p>\n<p><strong>Ai.Bi. \u00e8 presente in Bolivia dal 1997\u00a0<\/strong>e dal 2003 \u00e8 impegnata con progetti di\u00a0Adozione e Sostegno a Distanza\u00a0per migliorare le condizioni di vita dei minori accolti in due istituti di La Paz e garantire i loro diritti, primo tra tutti, quello di vivere e crescere in famiglia. Il centro di accoglienza <strong>Jos\u00e9 Soria<\/strong> fu costruito per gli orfani della guerra del Chaco della citt\u00e0 di La Paz, oggi accoglie fino a 60 bambini e bambine tra i 6 e i 12 anni, vittime di abuso, maltrattamenti o abbandono. Ai.Bi. affianca il centro nella realizzazione di\u00a0<strong>Progetti di Vita Individuali\u00a0<\/strong>volti al ricongiungimento familiare o all\u2019accoglienza in una nuova famiglia, garantendo a ciascun bambino un sostegno psicologico, scolastico, medico e educativo personalizzato.\u00a0<strong>Grazie al\u00a0Sostegno a Distanza<\/strong>, gli operatori di Ai.Bi. Bolivia supportano lo staff\u00a0 dell\u2019istituto nella realizzazione di indagini volte al reinserimento famigliare, e nelle procedure di rilascio del certificato di nascita.<\/p>\n<p><strong>Masiel \u00e8 una bambina di 10 anni<\/strong>, vive al Jos\u00e9 Soria dove \u00e8 stata trasferita un anno fa circa in quanto il\u00a0Centro di Accoglienza dove risiedeva \u00e9 stato chiuso per problemi economici. Inizialmente Masiel ha avuto difficolt\u00e0 ad adattarsi ai suoi nuovi compagni e, per distrarsi e sentirsi utile, ha trascorso del tempo prendendosi cura del gattino del Centro chiamato <strong>Choco<\/strong>. Si \u00e8 molto affezionata a lui, tanto da farne un bel disegno e regalarlo all\u2019assistente sociale del Centro la quale ha apprezzato il gesto e dato valore a questa bellissima amicizia tra Masiel e Choco. L\u2019operatrice ha poi scattato una foto al disegno e l\u2019ha inserita nell\u2019album della piccola. <strong>Grazie al Sostegno a Distanza<\/strong>, infatti, viene data molto importanza a quest\u2019ultimo in quanto testimonianza e racconto della storia di vita dei minori accolti nel Centro di Accoglienza, bambini che altrimenti non avrebbero radici e ricordi a cui aggrapparsi per guardare al futuro con fiducia.<\/p>\n<p>Diventa anche tu un <a href=\"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/attivazione-adozione-a-distanza\/?scelta=25&amp;progetto=Bolivia\">sostenitore<\/a> del centro di accoglienza Jos\u00e9 Soria, potrai seguire e accompagnare ogni giorno la vita, i progressi e le difficolt\u00e0 dei 60 bambini abbandonati accolti, e soprattutto la loro gioia quando incontreranno la loro nuova famiglia adottiva. Ogni mese riceverai un report che ti permetter\u00e0 di essere aggiornato costantemente. Per te un caff\u00e8 in meno al giorno, per i &#8221; 60 altri tuoi figli\u201d la speranza per una vita in famiglia.<\/p>\n\n<!-- Buttons X - Start -->\n<style type=\"text\/css\">\/*168342-start*\/\n#btnsx-168342{margin-top:0px;margin-bottom:20px;margin-left:0px;margin-right:0px;padding-top:20px;padding-bottom:20px;padding-left:40px;padding-right:40px;}\n#btnsx-168342 .btnsx-text-primary{font-size:30px;line-height:30px;font-family:Montserrat;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-168342:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-168342 .btnsx-text-secondary{}\n#btnsx-168342 .btnsx-icon{}\n#btnsx-168342 .btnsx-icon-img{}\n#btnsx-168342{background-color:#ef7b0b!important;}\n#btnsx-168342:before{background-color:#eab20b!important;}\n#btnsx-168342:hover{background-color:#eab20b!important;}\n#btnsx-168342{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-168342:hover{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-168342-dropdown .menu-item a{}\n#btnsx-168342-dropdown{border-top-width:px;border-bottom-width:px;border-left-width:px;border-right-width:px;}\n#btnsx-168342-dropdown:before{border-width:8px;margin-left:-8px;border-bottom-color:}\n#btnsx-168342-dropdown:after{}\n#btnsx-168342-dropdown{}\n@media screen and (max-width: 768px) {\n#btnsx-168342 {display:inline-block;}\n#btnsx-168342 .btnsx-text-primary {}\n#btnsx-168342 .btnsx-text-secondary {}\n#btnsx-168342 .btnsx-icon {}\n#btnsx-168342 .btnsx-divider {}\n}@media screen and (max-width: 480px) {\n#btnsx-168342 {display:inline-block;}\n#btnsx-168342 .btnsx-text-primary {}\n#btnsx-168342 .btnsx-text-secondary {}\n#btnsx-168342 .btnsx-icon {}\n#btnsx-168342 .btnsx-divider {}\n}\/*168342-end*\/\n<\/style><div id=\"btnsx-168342-wrap\" class=\"btnsx-wrap-center\" align=\"center\"><div id=\"btnsx-168342-container\" class=\"btnsx-btn-container\">\n<a href=\"https:\/\/www.aibi.it\/ita\/adotta-a-distanza-25\/\" id=\"btnsx-168342\" target=\"_blank\" class=\"btnsx-btn  btnsx-btn-embossed\"  data-font-primary=\"Montserrat\" data-animation-type=\"\">\n\t<span class=\"btnsx-text-primary \">Scopri di pi\u00f9<\/span><\/a>\n<\/div><\/div>\n<!-- Buttons X - End -->\n\n","protected":false},"excerpt":{"rendered":"<p>Masiel e gli altri bambini accolti al Jos&eacute; Soria stanno ricostruendo la loro storia grazie anche al proprio album fotografico, voluto e valorizzato dallo staff del Centro. Tutto ci&ograve; &egrave; possibile grazie al Sostegno a Distanza La&nbsp;Bolivia&nbsp;&egrave; il Paese pi&ugrave; povero dell&rsquo;America Latina e con la maggior disuguaglianza sociale in [&hellip;]<\/p>\n","protected":false},"author":113,"featured_media":187093,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[209],"tags":[480,647,300],"class_list":["post-187099","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-a-distanza","tag-bolivia","tag-jose-soria","tag-sostegno-a-distanza"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Bolivia. Masiel e il gattino Choco, un urlo al bisogno di famiglia - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/bolivia-masiel-e-il-gattino-choco-un-urlo-al-bisogno-di-famiglia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bolivia. Masiel e il gattino Choco, un urlo al bisogno di famiglia\" \/>\n<meta property=\"og:description\" content=\"Masiel e gli altri bambini accolti al Jos&eacute; Soria stanno ricostruendo la loro storia grazie anche al proprio album fotografico, voluto e valorizzato dallo staff del Centro. Tutto ci&ograve; &egrave; possibile grazie al Sostegno a Distanza La&nbsp;Bolivia&nbsp;&egrave; il Paese pi&ugrave; povero dell&rsquo;America Latina e con la maggior disuguaglianza sociale in [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/bolivia-masiel-e-il-gattino-choco-un-urlo-al-bisogno-di-famiglia\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-20T05:25:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-25T13:04:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2021\/04\/masiello-e-il-gattino-Choco_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"carlottaZ\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2021\/04\/masiello-e-il-gattino-Choco_fb.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"carlottaZ\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-masiel-e-il-gattino-choco-un-urlo-al-bisogno-di-famiglia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-masiel-e-il-gattino-choco-un-urlo-al-bisogno-di-famiglia\\\/\"},\"author\":{\"name\":\"carlottaZ\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/95193f4e7a1f2190922687ebf84f96c9\"},\"headline\":\"Bolivia. Masiel e il gattino Choco, un urlo al bisogno di famiglia\",\"datePublished\":\"2021-04-20T05:25:26+00:00\",\"dateModified\":\"2022-07-25T13:04:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-masiel-e-il-gattino-choco-un-urlo-al-bisogno-di-famiglia\\\/\"},\"wordCount\":511,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-masiel-e-il-gattino-choco-un-urlo-al-bisogno-di-famiglia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/04\\\/masiello-e-il-gattino-Choco_fb.jpg\",\"keywords\":[\"Bolivia\",\"Jos\u00e8 Soria\",\"sostegno a distanza\"],\"articleSection\":[\"Adozione a Distanza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-masiel-e-il-gattino-choco-un-urlo-al-bisogno-di-famiglia\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-masiel-e-il-gattino-choco-un-urlo-al-bisogno-di-famiglia\\\/\",\"name\":\"Bolivia. Masiel e il gattino Choco, un urlo al bisogno di famiglia - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-masiel-e-il-gattino-choco-un-urlo-al-bisogno-di-famiglia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-masiel-e-il-gattino-choco-un-urlo-al-bisogno-di-famiglia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/04\\\/masiello-e-il-gattino-Choco_fb.jpg\",\"datePublished\":\"2021-04-20T05:25:26+00:00\",\"dateModified\":\"2022-07-25T13:04:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-masiel-e-il-gattino-choco-un-urlo-al-bisogno-di-famiglia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-masiel-e-il-gattino-choco-un-urlo-al-bisogno-di-famiglia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-masiel-e-il-gattino-choco-un-urlo-al-bisogno-di-famiglia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/04\\\/masiello-e-il-gattino-Choco_fb.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/04\\\/masiello-e-il-gattino-Choco_fb.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-masiel-e-il-gattino-choco-un-urlo-al-bisogno-di-famiglia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione a Distanza\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-a-distanza\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bolivia. Masiel e il gattino Choco, un urlo al bisogno di famiglia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/95193f4e7a1f2190922687ebf84f96c9\",\"name\":\"carlottaZ\",\"sameAs\":[\"cellos\"],\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/carlottaz\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bolivia. Masiel e il gattino Choco, un urlo al bisogno di famiglia - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/bolivia-masiel-e-il-gattino-choco-un-urlo-al-bisogno-di-famiglia\/","og_locale":"it_IT","og_type":"article","og_title":"Bolivia. Masiel e il gattino Choco, un urlo al bisogno di famiglia","og_description":"Masiel e gli altri bambini accolti al Jos&eacute; Soria stanno ricostruendo la loro storia grazie anche al proprio album fotografico, voluto e valorizzato dallo staff del Centro. Tutto ci&ograve; &egrave; possibile grazie al Sostegno a Distanza La&nbsp;Bolivia&nbsp;&egrave; il Paese pi&ugrave; povero dell&rsquo;America Latina e con la maggior disuguaglianza sociale in [&hellip;]","og_url":"https:\/\/www.aibi.it\/ita\/bolivia-masiel-e-il-gattino-choco-un-urlo-al-bisogno-di-famiglia\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2021-04-20T05:25:26+00:00","article_modified_time":"2022-07-25T13:04:38+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2021\/04\/masiello-e-il-gattino-Choco_fb.jpg","type":"image\/jpeg"}],"author":"carlottaZ","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.aibi.it\/ita\/images\/2021\/04\/masiello-e-il-gattino-Choco_fb.jpg","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"carlottaZ","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/bolivia-masiel-e-il-gattino-choco-un-urlo-al-bisogno-di-famiglia\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-masiel-e-il-gattino-choco-un-urlo-al-bisogno-di-famiglia\/"},"author":{"name":"carlottaZ","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/95193f4e7a1f2190922687ebf84f96c9"},"headline":"Bolivia. Masiel e il gattino Choco, un urlo al bisogno di famiglia","datePublished":"2021-04-20T05:25:26+00:00","dateModified":"2022-07-25T13:04:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-masiel-e-il-gattino-choco-un-urlo-al-bisogno-di-famiglia\/"},"wordCount":511,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-masiel-e-il-gattino-choco-un-urlo-al-bisogno-di-famiglia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/04\/masiello-e-il-gattino-Choco_fb.jpg","keywords":["Bolivia","Jos\u00e8 Soria","sostegno a distanza"],"articleSection":["Adozione a Distanza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/bolivia-masiel-e-il-gattino-choco-un-urlo-al-bisogno-di-famiglia\/","url":"https:\/\/www.aibi.it\/ita\/bolivia-masiel-e-il-gattino-choco-un-urlo-al-bisogno-di-famiglia\/","name":"Bolivia. Masiel e il gattino Choco, un urlo al bisogno di famiglia - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-masiel-e-il-gattino-choco-un-urlo-al-bisogno-di-famiglia\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-masiel-e-il-gattino-choco-un-urlo-al-bisogno-di-famiglia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/04\/masiello-e-il-gattino-Choco_fb.jpg","datePublished":"2021-04-20T05:25:26+00:00","dateModified":"2022-07-25T13:04:38+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-masiel-e-il-gattino-choco-un-urlo-al-bisogno-di-famiglia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/bolivia-masiel-e-il-gattino-choco-un-urlo-al-bisogno-di-famiglia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/bolivia-masiel-e-il-gattino-choco-un-urlo-al-bisogno-di-famiglia\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2021\/04\/masiello-e-il-gattino-Choco_fb.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/04\/masiello-e-il-gattino-Choco_fb.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/bolivia-masiel-e-il-gattino-choco-un-urlo-al-bisogno-di-famiglia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione a Distanza","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-a-distanza\/"},{"@type":"ListItem","position":3,"name":"Bolivia. Masiel e il gattino Choco, un urlo al bisogno di famiglia"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/95193f4e7a1f2190922687ebf84f96c9","name":"carlottaZ","sameAs":["cellos"],"url":"https:\/\/www.aibi.it\/ita\/author\/carlottaz\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 09:49:30","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/187099","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/113"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=187099"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/187099\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/187093"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=187099"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=187099"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=187099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}