﻿


{"id":187429,"date":"2021-04-27T15:56:19","date_gmt":"2021-04-27T13:56:19","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=187429"},"modified":"2021-04-27T15:56:19","modified_gmt":"2021-04-27T13:56:19","slug":"sostegno-a-distanza-visita-centro-accoglienza-tempo-a-disposizione","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/sostegno-a-distanza-visita-centro-accoglienza-tempo-a-disposizione\/","title":{"rendered":"Sostegno a Distanza: se volessi fare visita al centro di accoglienza che seguo, quanto tempo a disposizione ho per stare con i bambini?"},"content":{"rendered":"<blockquote>\n<p style=\"font-weight: 400;\">Cari amici di Ai.Bi.,<br \/>\nvi scrivo perch\u00e9 sto per attivare un Sostegno a Distanza centro e ho scelto il Volodarka in Ucraina. Devo essere sincera, l\u2019ho scelto anche in base alla distanza dall\u2019Italia perch\u00e9 mi piacerebbe tantissimo, appena sar\u00e0 possibile, andare a fare visita al centro per poter guardare negli occhi i piccoli ospiti.<br \/>\nVolevo, per\u00f2, sapere come funziona? Ho letto che bisogna organizzare il tutto con un po\u2019 di tempo di preavviso, ma vorrei sapere se fosse possibile trascorrere pi\u00f9 di un giorno con loro all\u2019interno del centro, cos\u00ec da sperimentare la quotidianit\u00e0 insieme a loro?<\/p>\n<p style=\"font-weight: 400;\">Grazie.<br \/>\nMonica<\/p>\n<\/blockquote>\n<p style=\"font-weight: 400;\">Cara Monica,<br \/>\ngrazie per averci scritto e per la sua volont\u00e0 di attivare un\u00a0<strong>Sostegno a Distanza<\/strong>\u00a0<strong>centro<\/strong>.<br \/>\nRafforzando una sua affermazione riportata all\u2019interno della domanda, le diciamo che \u00e8 davvero difficile spiegare a parole quello che \u00e8\u00a0<strong>visibile solo con i propri occhi<\/strong>. Siamo proprio noi che consigliamo a tutti quelli che ce lo chiedono di fare questa esperienza particolare di visitare il centro che si sono impegnati a sostenere.<br \/>\n\u00c8 un viaggio per immergersi in una realt\u00e0 che non si conosce mai fino in fondo: tutti i nostri sostenitori che sono riusciti a vivere questo momento della vita tornano a casa non solo contenti, ma anche e soprattutto pi\u00f9 \u201cricchi\u201d, con una valigia piena di\u00a0<strong>sorrisi<\/strong>,\u00a0<strong>volti<\/strong>,\u00a0<strong>pensieri<\/strong>\u00a0che li accompagneranno, poi, per tantissimo tempo.<\/p>\n<p style=\"font-weight: 400;\">Con una\u00a0<strong>visita centro accoglienza<\/strong>\u00a0si pu\u00f2 toccare con mano le realt\u00e0 e i bambini che si sostengono; capire meglio quello che Amici dei Bambini, grazie a voi e al vostro aiuto, riesce a fare, e vedere e comprendere cos\u2019\u00e8 un istituto e cosa significa vivere l\u00ec ogni giorno.<\/p>\n<p style=\"font-weight: 400;\">Ritornando alla sua domanda, le rispondiamo che molto dipende dalla volont\u00e0 del direttore del Centro e dall\u2019organizzazione delle giornate. Di certo, noi porteremo avanti il suo desiderio di voler trascorrere almeno un paio di giorni, nelle ore diurne ovviamente, con i bambini del centro Volodarka e, se il direttore ce lo conceder\u00e0, potr\u00e0 farlo. Sicuramente, comunque, le\u00a0<strong>garantiamo che potr\u00e0 far visita al centro<\/strong>\u00a0almeno un giorno.<br \/>\nInsieme al nostro\u00a0<strong>volontario espatriato<\/strong>, presente in loco, organizzeremo al meglio la sua visita e potremo farle vivere un\u2019esperienza che lascer\u00e0 il segno e sar\u00e0 importante per lei ma anche per tutti i nostri bambini.<\/p>\n<p style=\"font-weight: 400;\">Si ricordi che attivando un\u00a0<a href=\"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/?scelta=25&amp;progetto=Ucraina\"><u>Sostegno a Distanza<\/u><\/a>\u00a0centro potr\u00e0 davvero aiutare i piccoli ospiti di\u00a0<strong>Volodarka<\/strong>\u00a0a crescere serenamente in attesa di una famiglia che possa accoglierli. Potr\u00e0 seguire e accompagnare ogni giorno la loro vita, i loro progressi e le difficolt\u00e0: grazie a\u00a0<strong>report mensili<\/strong>, infatti, sar\u00e0 costantemente aggiornata sui progressi raggiunti e le difficolt\u00e0 affrontate.<\/p>\n<p style=\"font-weight: 400;\">L\u2019impegno, come lei ben sapr\u00e0, \u00e8 di 25 euro al mese: per noi, il valore di un caff\u00e8 al giorno; per loro, la speranza di una vita in famiglia.<\/p>\n<p style=\"font-weight: 400;\">Grazie e a presto<br \/>\nStaff Sostegno a Distanza<\/p>\n[btnsx_dual id=&#8221;162084&#8243; button_second_link_type=&#8221;url&#8221; button_second_link=&#8221;https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/?scelta=25&amp;progetto=Ucraina&#8221;]\n","protected":false},"excerpt":{"rendered":"<p>Cari amici di Ai.Bi., vi scrivo perch&eacute; sto per attivare un Sostegno a Distanza centro e ho scelto il Volodarka in Ucraina. Devo essere sincera, l&rsquo;ho scelto anche in base alla distanza dall&rsquo;Italia perch&eacute; mi piacerebbe tantissimo, appena sar&agrave; possibile, andare a fare visita al centro per poter guardare negli [&hellip;]<\/p>\n","protected":false},"author":102,"featured_media":187433,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[50],"tags":[300,423],"class_list":["post-187429","post","type-post","status-publish","format-standard","has-post-thumbnail","category-lettere-al-direttore","tag-sostegno-a-distanza","tag-ucraina"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Se vogli far visita al centro accoglienza che seguo, quanto tempo ho?<\/title>\n<meta name=\"description\" content=\"Chi sottoscrive un Sosteno a distanza centro pu\u00f2 richiedere di fare visita al centro accoglienza per passare del tempo con i bambini che sostiene\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/sostegno-a-distanza-visita-centro-accoglienza-tempo-a-disposizione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sostegno a Distanza: se volessi fare visita al centro di accoglienza che seguo, quanto tempo a disposizione ho per stare con i bambini?\" \/>\n<meta property=\"og:description\" content=\"Chi sottoscrive un Sosteno a distanza centro pu\u00f2 richiedere di fare visita al centro accoglienza per passare del tempo con i bambini che sostiene\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/sostegno-a-distanza-visita-centro-accoglienza-tempo-a-disposizione\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-27T13:56:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2021\/04\/LAD-centro-accoglienza.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/sostegno-a-distanza-visita-centro-accoglienza-tempo-a-disposizione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/sostegno-a-distanza-visita-centro-accoglienza-tempo-a-disposizione\\\/\"},\"author\":{\"name\":\"francescoE\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\"},\"headline\":\"Sostegno a Distanza: se volessi fare visita al centro di accoglienza che seguo, quanto tempo a disposizione ho per stare con i bambini?\",\"datePublished\":\"2021-04-27T13:56:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/sostegno-a-distanza-visita-centro-accoglienza-tempo-a-disposizione\\\/\"},\"wordCount\":519,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/sostegno-a-distanza-visita-centro-accoglienza-tempo-a-disposizione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/04\\\/LAD-centro-accoglienza.jpg\",\"keywords\":[\"sostegno a distanza\",\"Ucraina\"],\"articleSection\":[\"Lettere al direttore\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/sostegno-a-distanza-visita-centro-accoglienza-tempo-a-disposizione\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/sostegno-a-distanza-visita-centro-accoglienza-tempo-a-disposizione\\\/\",\"name\":\"Se vogli far visita al centro accoglienza che seguo, quanto tempo ho?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/sostegno-a-distanza-visita-centro-accoglienza-tempo-a-disposizione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/sostegno-a-distanza-visita-centro-accoglienza-tempo-a-disposizione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/04\\\/LAD-centro-accoglienza.jpg\",\"datePublished\":\"2021-04-27T13:56:19+00:00\",\"description\":\"Chi sottoscrive un Sosteno a distanza centro pu\u00f2 richiedere di fare visita al centro accoglienza per passare del tempo con i bambini che sostiene\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/sostegno-a-distanza-visita-centro-accoglienza-tempo-a-disposizione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/sostegno-a-distanza-visita-centro-accoglienza-tempo-a-disposizione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/sostegno-a-distanza-visita-centro-accoglienza-tempo-a-disposizione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/04\\\/LAD-centro-accoglienza.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/04\\\/LAD-centro-accoglienza.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/sostegno-a-distanza-visita-centro-accoglienza-tempo-a-disposizione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lettere al direttore\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/lettere-al-direttore\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sostegno a Distanza: se volessi fare visita al centro di accoglienza che seguo, quanto tempo a disposizione ho per stare con i bambini?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\",\"name\":\"francescoE\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/francescoe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Se vogli far visita al centro accoglienza che seguo, quanto tempo ho?","description":"Chi sottoscrive un Sosteno a distanza centro pu\u00f2 richiedere di fare visita al centro accoglienza per passare del tempo con i bambini che sostiene","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/sostegno-a-distanza-visita-centro-accoglienza-tempo-a-disposizione\/","og_locale":"it_IT","og_type":"article","og_title":"Sostegno a Distanza: se volessi fare visita al centro di accoglienza che seguo, quanto tempo a disposizione ho per stare con i bambini?","og_description":"Chi sottoscrive un Sosteno a distanza centro pu\u00f2 richiedere di fare visita al centro accoglienza per passare del tempo con i bambini che sostiene","og_url":"https:\/\/www.aibi.it\/ita\/sostegno-a-distanza-visita-centro-accoglienza-tempo-a-disposizione\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2021-04-27T13:56:19+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2021\/04\/LAD-centro-accoglienza.jpg","type":"image\/jpeg"}],"author":"francescoE","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"francescoE","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/sostegno-a-distanza-visita-centro-accoglienza-tempo-a-disposizione\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/sostegno-a-distanza-visita-centro-accoglienza-tempo-a-disposizione\/"},"author":{"name":"francescoE","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5"},"headline":"Sostegno a Distanza: se volessi fare visita al centro di accoglienza che seguo, quanto tempo a disposizione ho per stare con i bambini?","datePublished":"2021-04-27T13:56:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/sostegno-a-distanza-visita-centro-accoglienza-tempo-a-disposizione\/"},"wordCount":519,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/sostegno-a-distanza-visita-centro-accoglienza-tempo-a-disposizione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/04\/LAD-centro-accoglienza.jpg","keywords":["sostegno a distanza","Ucraina"],"articleSection":["Lettere al direttore"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/sostegno-a-distanza-visita-centro-accoglienza-tempo-a-disposizione\/","url":"https:\/\/www.aibi.it\/ita\/sostegno-a-distanza-visita-centro-accoglienza-tempo-a-disposizione\/","name":"Se vogli far visita al centro accoglienza che seguo, quanto tempo ho?","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/sostegno-a-distanza-visita-centro-accoglienza-tempo-a-disposizione\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/sostegno-a-distanza-visita-centro-accoglienza-tempo-a-disposizione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/04\/LAD-centro-accoglienza.jpg","datePublished":"2021-04-27T13:56:19+00:00","description":"Chi sottoscrive un Sosteno a distanza centro pu\u00f2 richiedere di fare visita al centro accoglienza per passare del tempo con i bambini che sostiene","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/sostegno-a-distanza-visita-centro-accoglienza-tempo-a-disposizione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/sostegno-a-distanza-visita-centro-accoglienza-tempo-a-disposizione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/sostegno-a-distanza-visita-centro-accoglienza-tempo-a-disposizione\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2021\/04\/LAD-centro-accoglienza.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/04\/LAD-centro-accoglienza.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/sostegno-a-distanza-visita-centro-accoglienza-tempo-a-disposizione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Lettere al direttore","item":"https:\/\/www.aibi.it\/ita\/category\/lettere-al-direttore\/"},{"@type":"ListItem","position":3,"name":"Sostegno a Distanza: se volessi fare visita al centro di accoglienza che seguo, quanto tempo a disposizione ho per stare con i bambini?"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5","name":"francescoE","url":"https:\/\/www.aibi.it\/ita\/author\/francescoe\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 17:09:31","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/187429","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=187429"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/187429\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/187433"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=187429"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=187429"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=187429"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}