﻿{"id":187679,"date":"2021-05-04T08:00:26","date_gmt":"2021-05-04T06:00:26","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=187679"},"modified":"2021-05-03T18:52:05","modified_gmt":"2021-05-03T16:52:05","slug":"papa-francesco-14-maggio-aprira-stati-generali-della-natalita","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/papa-francesco-14-maggio-aprira-stati-generali-della-natalita\/","title":{"rendered":"Papa Francesco il 14 maggio aprir\u00e0 gli Stati generali della Natalit\u00e0"},"content":{"rendered":"<h2><strong>Si aprir\u00e0 con un intervento di Papa Francesco l\u2019evento degli Stati generali della Natalit\u00e0 fortemente voluto dal Forum delle Associazioni Familiari per riflettere sul problema della natalit\u00e0 e la difesa della famiglia in Italia e nel mondo<\/strong><\/h2>\n<p>Il prossimo venerd\u00ec 14 maggio avranno inizio i primi <strong>Stati generali della Natalit\u00e0<\/strong>, un\u2019iniziativa fortemente voluta dal <strong>Forum delle Associazioni Familiari<\/strong> per riportare in cima all\u2019agenda politica il tema della <strong>natalit\u00e0<\/strong> che, come <a href=\"https:\/\/www.aibi.it\/ita\/allarme-nascite-e-sparita-la-citta-di-firenze\/\">gi\u00e0 ampiamente sottolineato<\/a>, ha fatto segnare nel 2020 un saldo negativo, in Italia, di 383.922 tra nuovi nati e decessi.<\/p>\n<h3><strong>Gli Stati Generali della Natalit\u00e0 per parlare dell\u2019allarme nascite<\/strong><\/h3>\n<p>A sottolineare la grande importanza e attualit\u00e0 di questo tema \u00e8 stato reso noto dal direttore della Sala Stampa della Santa Sede Matteo Bruni, che ad aprire l\u2019appuntamento presso il Foyer dell\u2019Auditorium della Conciliazione a Roma sar\u00e0 <strong>Papa Francesco<\/strong>.<br \/>\nNon poteva esserci segnale pi\u00f9 ufficiale e <strong>straordinario<\/strong> per ribadire quanto il tema della <strong>famiglia<\/strong> e della <strong>natalit\u00e0<\/strong> sia fondamentale per il futuro del nostro Paese e del mondo, e quanto sia apprezzata l\u2019iniziativa lanciata dal presidente nazionale del Forum delle associazioni familiari, <strong>Gigi De Palo<\/strong>, per \u2013 come riporta Agenzia SIR &#8211; \u201cMettere attorno a un tavolo le istituzioni, le imprese, i media e il mondo della cultura per approfondire <strong>la sfida dell\u2019inverno<\/strong> demografico e sollecitare una nuova narrazione sul tema della natalit\u00e0\u201d.<\/p>\n<h3><strong>Dalle imprese allo sport, tante le personalit\u00e0 che interverranno agli <\/strong><strong>Stati Generali della Natalit\u00e0<\/strong><\/h3>\n<p>Terminato il suo intervento, il Santo Padre far\u00e0 ritorno in Vaticano, mentre gli Stati Generali proseguiranno con i saluti istituzionali di <strong>Elena Bonetti<\/strong>, Ministro alla Famiglia; <strong>Patrizio Bianchi<\/strong>, Ministro all\u2019Istruzione e <strong>Nicola Zingaretti<\/strong>, Presidente Regione Lazio.<br \/>\nA seguire la prima relazione sar\u00e0 affidata a <strong>Gian Carlo Blangiardo<\/strong>, Presidente Di Istat, che presenter\u00e0 gli ultimi dati relativi alla natalit\u00e0 in Italia e gli scenari per il prossimo futuro.<\/p>\n<p>L\u2019evento proseguir\u00e0 poi fino alle 13,30 con diversi tavoli tematici. Per quello dedicato alle <strong>imprese<\/strong> saranno presenti Matteo Del Fante, A.D. Poste Italiane; Elisabetta Ripa, A.D. Open Fiber; Marcello Foa, Presidente Rai; Carlo Tamburi; Direttore Enel Italia; Chiara Bidoli, Direttrice Area Infanzia RCS Media Group.<\/p>\n<p>Il tavolo \u201c<strong>Nuove nascite, un buon investimento<\/strong>\u201d vedr\u00e0, invece, gli interventi di Marco Sesana, Country Manager e Ceo di Generali Italia e GBL; Sara Doris, Presidente Esecutivo Fond. Mediolanum Onlus; Sergio Gatti, Direttore Generale Federcasse e il giornalista Aldo Cazzullo.<\/p>\n<p>Infine, il tavolo dedicato al mondo dei <strong>media<\/strong> e della <strong>comunicazione<\/strong>, <strong>sport<\/strong> e <strong>spettacolo<\/strong>, potr\u00e0 contare sugli interventi dell\u2019attaccante della Lazio e della Nazionale Ciro Immobile, insieme alla moglie Jessica; di Luca e Paola Bernabei, A.D. Lux Vide; dell\u2019attrice Anna Foglietta; del Direttore di Avvenire Marco Tarquinio e della giornalista Annalisa Cuzzocrea.<\/p>\n<p>Tutte le informazioni sul <a href=\"https:\/\/www.statigeneralidellanatalita.it\/\" target=\"_blank\" rel=\"noopener\">sito ufficiale<\/a> degli Stati Generali della Natalit\u00e0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si aprir&agrave; con un intervento di Papa Francesco l&rsquo;evento degli Stati generali della Natalit&agrave; fortemente voluto dal Forum delle Associazioni Familiari per riflettere sul problema della natalit&agrave; e la difesa della famiglia in Italia e nel mondo Il prossimo venerd&igrave; 14 maggio avranno inizio i primi Stati generali della Natalit&agrave;, [&hellip;]<\/p>\n","protected":false},"author":102,"featured_media":187680,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[299,297,695],"class_list":["post-187679","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews","tag-denatalita","tag-famiglia","tag-forum-delle-associazioni-familiari"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Il Papa aprir\u00e0 gli Stati generali della Natalit\u00e0, 14 maggio<\/title>\n<meta name=\"description\" content=\"Sar\u00e0 Papa Francesco ad aprire gli Stati generali della Natalit\u00e0 voluti dal Forum delle Associazioni Familiari per riflettere sul problema delle nascite\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/papa-francesco-14-maggio-aprira-stati-generali-della-natalita\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Papa Francesco il 14 maggio aprir\u00e0 gli Stati generali della Natalit\u00e0\" \/>\n<meta property=\"og:description\" content=\"Sar\u00e0 Papa Francesco ad aprire gli Stati generali della Natalit\u00e0 voluti dal Forum delle Associazioni Familiari per riflettere sul problema delle nascite\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/papa-francesco-14-maggio-aprira-stati-generali-della-natalita\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-04T06:00:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2021\/05\/stati-generali-natalita.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/papa-francesco-14-maggio-aprira-stati-generali-della-natalita\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/papa-francesco-14-maggio-aprira-stati-generali-della-natalita\\\/\"},\"author\":{\"name\":\"francescoE\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\"},\"headline\":\"Papa Francesco il 14 maggio aprir\u00e0 gli Stati generali della Natalit\u00e0\",\"datePublished\":\"2021-05-04T06:00:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/papa-francesco-14-maggio-aprira-stati-generali-della-natalita\\\/\"},\"wordCount\":470,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/papa-francesco-14-maggio-aprira-stati-generali-della-natalita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/05\\\/stati-generali-natalita.jpg\",\"keywords\":[\"denatalit\u00e0\",\"famiglia\",\"Forum delle Associazioni Familiari\"],\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/papa-francesco-14-maggio-aprira-stati-generali-della-natalita\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/papa-francesco-14-maggio-aprira-stati-generali-della-natalita\\\/\",\"name\":\"Il Papa aprir\u00e0 gli Stati generali della Natalit\u00e0, 14 maggio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/papa-francesco-14-maggio-aprira-stati-generali-della-natalita\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/papa-francesco-14-maggio-aprira-stati-generali-della-natalita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/05\\\/stati-generali-natalita.jpg\",\"datePublished\":\"2021-05-04T06:00:26+00:00\",\"description\":\"Sar\u00e0 Papa Francesco ad aprire gli Stati generali della Natalit\u00e0 voluti dal Forum delle Associazioni Familiari per riflettere sul problema delle nascite\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/papa-francesco-14-maggio-aprira-stati-generali-della-natalita\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/papa-francesco-14-maggio-aprira-stati-generali-della-natalita\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/papa-francesco-14-maggio-aprira-stati-generali-della-natalita\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/05\\\/stati-generali-natalita.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/05\\\/stati-generali-natalita.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/papa-francesco-14-maggio-aprira-stati-generali-della-natalita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Papa Francesco il 14 maggio aprir\u00e0 gli Stati generali della Natalit\u00e0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\",\"name\":\"francescoE\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/francescoe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Il Papa aprir\u00e0 gli Stati generali della Natalit\u00e0, 14 maggio","description":"Sar\u00e0 Papa Francesco ad aprire gli Stati generali della Natalit\u00e0 voluti dal Forum delle Associazioni Familiari per riflettere sul problema delle nascite","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/papa-francesco-14-maggio-aprira-stati-generali-della-natalita\/","og_locale":"it_IT","og_type":"article","og_title":"Papa Francesco il 14 maggio aprir\u00e0 gli Stati generali della Natalit\u00e0","og_description":"Sar\u00e0 Papa Francesco ad aprire gli Stati generali della Natalit\u00e0 voluti dal Forum delle Associazioni Familiari per riflettere sul problema delle nascite","og_url":"https:\/\/www.aibi.it\/ita\/papa-francesco-14-maggio-aprira-stati-generali-della-natalita\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2021-05-04T06:00:26+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2021\/05\/stati-generali-natalita.jpg","type":"image\/jpeg"}],"author":"francescoE","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"francescoE","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/papa-francesco-14-maggio-aprira-stati-generali-della-natalita\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/papa-francesco-14-maggio-aprira-stati-generali-della-natalita\/"},"author":{"name":"francescoE","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5"},"headline":"Papa Francesco il 14 maggio aprir\u00e0 gli Stati generali della Natalit\u00e0","datePublished":"2021-05-04T06:00:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/papa-francesco-14-maggio-aprira-stati-generali-della-natalita\/"},"wordCount":470,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/papa-francesco-14-maggio-aprira-stati-generali-della-natalita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/05\/stati-generali-natalita.jpg","keywords":["denatalit\u00e0","famiglia","Forum delle Associazioni Familiari"],"articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/papa-francesco-14-maggio-aprira-stati-generali-della-natalita\/","url":"https:\/\/www.aibi.it\/ita\/papa-francesco-14-maggio-aprira-stati-generali-della-natalita\/","name":"Il Papa aprir\u00e0 gli Stati generali della Natalit\u00e0, 14 maggio","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/papa-francesco-14-maggio-aprira-stati-generali-della-natalita\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/papa-francesco-14-maggio-aprira-stati-generali-della-natalita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/05\/stati-generali-natalita.jpg","datePublished":"2021-05-04T06:00:26+00:00","description":"Sar\u00e0 Papa Francesco ad aprire gli Stati generali della Natalit\u00e0 voluti dal Forum delle Associazioni Familiari per riflettere sul problema delle nascite","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/papa-francesco-14-maggio-aprira-stati-generali-della-natalita\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/papa-francesco-14-maggio-aprira-stati-generali-della-natalita\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/papa-francesco-14-maggio-aprira-stati-generali-della-natalita\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2021\/05\/stati-generali-natalita.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/05\/stati-generali-natalita.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/papa-francesco-14-maggio-aprira-stati-generali-della-natalita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Papa Francesco il 14 maggio aprir\u00e0 gli Stati generali della Natalit\u00e0"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5","name":"francescoE","url":"https:\/\/www.aibi.it\/ita\/author\/francescoe\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 06:08:02","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/187679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=187679"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/187679\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/187680"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=187679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=187679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=187679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}