﻿


{"id":187728,"date":"2021-05-04T11:30:26","date_gmt":"2021-05-04T09:30:26","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=187728"},"modified":"2021-05-04T16:28:15","modified_gmt":"2021-05-04T14:28:15","slug":"festa-della-mamma-2021-sono-ancora-in-tempo-per-richiedere-i-regali-solidali-di-ai-bi-mamma-per-la-vita","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/festa-della-mamma-2021-sono-ancora-in-tempo-per-richiedere-i-regali-solidali-di-ai-bi-mamma-per-la-vita\/","title":{"rendered":"Festa della mamma 2021. Sono ancora in tempo per richiedere i regali solidali di Ai.Bi. &#8220;Mamma Per la Vita&#8221;?"},"content":{"rendered":"<p>Buongiorno,<br \/>\nvi seguo da tempo e sono rimasta positivamente colpita dalla vostra iniziativa \u201cMamma per la vita\u201d. Con l\u2019avvicinarsi della festa della mamma mai come in questo periodo il mio pensiero va subito a mia sorella Carlotta, diventata mamma da pochi mesi, e alla mia mamma che mi ha accompagnata in ogni passo della mia vita con pazienza e amore, contribuendo a rendermi la persona che sono oggi.<br \/>\nPurtroppo, la lontananza forzata non mi ha permesso di essere loro vicina come avrei voluto. So che apprezzerebbero ricevere un messaggio di augurio cos\u00ec speciale e sapere di aver dato, insieme, un aiuto ad altre mamme.Sono ancora in tempo per fare l\u2019ordine?<\/p>\n<p>Grazie per quanto fate<br \/>\nMarta<\/p>\n<p>&nbsp;<\/p>\n<p>Cara Marta,<br \/>\n\u00e8 sempre un piacere per noi sapere che i nostri sostenitori ci seguono e apprezzano le nostre iniziative. L\u2019iniziativa \u201c<a href=\"https:\/\/www.fondazioneaibi.it\/regali-solidali\/29-festa-della-mamma\">Mamma per la Vita<\/a>\u201d durer\u00e0 per tutto il mese di maggio per sostenere la nostra campagna <strong><em>\u201cFame di Mamma\u201d:<\/em><\/strong> <a href=\"https:\/\/www.fondazioneaibi.it\/regali-solidali\/tutti-i-prodotti\/132-120-t-shirt-festa-della-mamma.html#\/2-dimensione-m\/8-colore-bianco\">una t-shirt<\/a>, <a href=\"https:\/\/www.fondazioneaibi.it\/regali-solidali\/tutti-i-prodotti\/134-tazza-festa-della-mamma.html\">una tazza<\/a>, una <a href=\"https:\/\/www.fondazioneaibi.it\/regali-solidali\/tutti-i-prodotti\/133-shopper-personalizzate-cuore.html\">shopping bag<\/a> tutte illustrate ad hoc per dire che \u201c<strong><em>la mamma \u00e8 per la vita<\/em><\/strong>\u201d. Che sia di pancia o di cuore, che ti abbia partorito, accolto da un Paese lontano o solo per il tempo limitato di un affido&#8230; la mamma sar\u00e0 per sempre mamma.<\/p>\n\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*187669-start*\/\n#btnsx-187669{margin-top:0px;margin-bottom:0px;margin-left:0px;margin-right:0px;padding-top:10px;padding-bottom:10px;padding-left:40px;padding-right:40px;}\n#btnsx-187669 .btnsx-text-primary{text-transform:uppercase;font-size:21px;line-height:21px;font-style:normal;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-187669{background-color:#02c2f3!important;}\n#btnsx-187669:hover{background-color:#65d6f2!important;}\n#btnsx-187669{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-left-radius:0px;border-bottom-right-radius:0px;}\n#btnsx-187669:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-left-radius:0px;border-bottom-right-radius:0px;}\n#btnsx-187669{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-187669:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*187669-end*\/\n<\/style><div id=\"btnsx-187669-wrap\" class=\"btnsx-wrap-center\" align=\"center\">\n<a href=\"https:\/\/www.fondazioneaibi.it\/regali-solidali\/29-festa-della-mamma\" id=\"btnsx-187669\" target=\"_blank\" class=\"btnsx-btn btnsx-btn-block\" >\n\t<span class=\"btnsx-text-primary \">Acquista Ora<\/span><\/a>\n<\/div>\n<!-- Buttons X - End -->\n\n<p>Fame di mamma sostiene i Centri Servizi alla Famiglia \u201c<strong>Pan di Zucchero<\/strong>\u201d attivi sul territorio italiano e ben <strong>15 comunit\u00e0 d\u2019accoglienza<\/strong>: comunit\u00e0 e appartamenti di semi e alta autonomia per mamme in situazione di fragilit\u00e0 insieme ai loro figli, case di accoglienza per adolescenti e minori stranieri non accompagnati e la Family House, a sudest della citt\u00e0 di Milano, un\u2019eccellenza nel campo dell\u2019accoglienza.<\/p>\n<p><strong>La t-shirt, disponibile nelle taglie S\/M\/L\/XL, la tazza e la shopping bag della linea regali solidali di Amici dei Bambini<\/strong> sono acquistabili sul sito della <a href=\"https:\/\/www.fondazioneaibi.it\/regali-solidali\/29-festa-della-mamma\">Fondazione Ai.Bi.<\/a> per tutto il mese di maggio. Non si preoccupi, sua mamma e sua sorella potranno ricevere i suoi auguri \u201cMamma per la Vita\u201d e apprezzare la bont\u00e0 e l\u2019utilit\u00e0 di questa sua scelta solidale.<br \/>\nGrazie a quanti come lei sceglieranno i nostri regali solidali \u201c<strong><em>Mamma per la Vita\u201d<\/em><\/strong>\u00a0, ci impegniamo a raccogliere fondi per garantire l\u2019acquisto di un pulmino per la Family House e per proseguire al meglio nell\u2019opera di protezione e cura delle mamme accolte insieme ai loro bambini.<\/p>\n<p>Buona festa della mamma,<br \/>\nStaff Ai.Bi.<\/p>\n\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*187669-start*\/\n#btnsx-187669{margin-top:0px;margin-bottom:0px;margin-left:0px;margin-right:0px;padding-top:10px;padding-bottom:10px;padding-left:40px;padding-right:40px;}\n#btnsx-187669 .btnsx-text-primary{text-transform:uppercase;font-size:21px;line-height:21px;font-style:normal;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-187669{background-color:#02c2f3!important;}\n#btnsx-187669:hover{background-color:#65d6f2!important;}\n#btnsx-187669{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-left-radius:0px;border-bottom-right-radius:0px;}\n#btnsx-187669:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-left-radius:0px;border-bottom-right-radius:0px;}\n#btnsx-187669{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-187669:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*187669-end*\/\n<\/style><div id=\"btnsx-187669-wrap\" class=\"btnsx-wrap-center\" align=\"center\">\n<a href=\"https:\/\/www.fondazioneaibi.it\/regali-solidali\/29-festa-della-mamma\" id=\"btnsx-187669\" target=\"_blank\" class=\"btnsx-btn btnsx-btn-block\" >\n\t<span class=\"btnsx-text-primary \">Acquista Ora<\/span><\/a>\n<\/div>\n<!-- Buttons X - End -->\n\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Buongiorno, vi seguo da tempo e sono rimasta positivamente colpita dalla vostra iniziativa &ldquo;Mamma per la vita&rdquo;. Con l&rsquo;avvicinarsi della festa della mamma mai come in questo periodo il mio pensiero va subito a mia sorella Carlotta, diventata mamma da pochi mesi, e alla mia mamma che mi ha accompagnata [&hellip;]<\/p>\n","protected":false},"author":102,"featured_media":187734,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[50],"tags":[608,276],"class_list":["post-187728","post","type-post","status-publish","format-standard","has-post-thumbnail","category-lettere-al-direttore","tag-fame-di-mamma","tag-mamma"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Festa della mamma 2021. I regali solidali di Ai.Bi. &quot;Mamma Per la Vita&quot;?<\/title>\n<meta name=\"description\" content=\"Con la t-shirt, la tazza e la shopping bag &quot;Mamma per la vita&quot;, sostieni i progetti di Ai.Bi. per la Family House che accoglie mamme e bambini in difficolt\u00e0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/festa-della-mamma-2021-sono-ancora-in-tempo-per-richiedere-i-regali-solidali-di-ai-bi-mamma-per-la-vita\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Festa della mamma 2021. Sono ancora in tempo per richiedere i regali solidali di Ai.Bi. &quot;Mamma Per la Vita&quot;?\" \/>\n<meta property=\"og:description\" content=\"Con la t-shirt, la tazza e la shopping bag &quot;Mamma per la vita&quot;, sostieni i progetti di Ai.Bi. per la Family House che accoglie mamme e bambini in difficolt\u00e0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/festa-della-mamma-2021-sono-ancora-in-tempo-per-richiedere-i-regali-solidali-di-ai-bi-mamma-per-la-vita\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-04T09:30:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-04T14:28:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2021\/05\/prodotti-festa-della-mamma_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/festa-della-mamma-2021-sono-ancora-in-tempo-per-richiedere-i-regali-solidali-di-ai-bi-mamma-per-la-vita\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/festa-della-mamma-2021-sono-ancora-in-tempo-per-richiedere-i-regali-solidali-di-ai-bi-mamma-per-la-vita\\\/\"},\"author\":{\"name\":\"francescoE\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\"},\"headline\":\"Festa della mamma 2021. Sono ancora in tempo per richiedere i regali solidali di Ai.Bi. &#8220;Mamma Per la Vita&#8221;?\",\"datePublished\":\"2021-05-04T09:30:26+00:00\",\"dateModified\":\"2021-05-04T14:28:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/festa-della-mamma-2021-sono-ancora-in-tempo-per-richiedere-i-regali-solidali-di-ai-bi-mamma-per-la-vita\\\/\"},\"wordCount\":419,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/festa-della-mamma-2021-sono-ancora-in-tempo-per-richiedere-i-regali-solidali-di-ai-bi-mamma-per-la-vita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/05\\\/prodotti-festa-della-mamma_fb.jpg\",\"keywords\":[\"Fame di mamma\",\"mamma\"],\"articleSection\":[\"Lettere al direttore\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/festa-della-mamma-2021-sono-ancora-in-tempo-per-richiedere-i-regali-solidali-di-ai-bi-mamma-per-la-vita\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/festa-della-mamma-2021-sono-ancora-in-tempo-per-richiedere-i-regali-solidali-di-ai-bi-mamma-per-la-vita\\\/\",\"name\":\"Festa della mamma 2021. I regali solidali di Ai.Bi. \\\"Mamma Per la Vita\\\"?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/festa-della-mamma-2021-sono-ancora-in-tempo-per-richiedere-i-regali-solidali-di-ai-bi-mamma-per-la-vita\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/festa-della-mamma-2021-sono-ancora-in-tempo-per-richiedere-i-regali-solidali-di-ai-bi-mamma-per-la-vita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/05\\\/prodotti-festa-della-mamma_fb.jpg\",\"datePublished\":\"2021-05-04T09:30:26+00:00\",\"dateModified\":\"2021-05-04T14:28:15+00:00\",\"description\":\"Con la t-shirt, la tazza e la shopping bag \\\"Mamma per la vita\\\", sostieni i progetti di Ai.Bi. per la Family House che accoglie mamme e bambini in difficolt\u00e0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/festa-della-mamma-2021-sono-ancora-in-tempo-per-richiedere-i-regali-solidali-di-ai-bi-mamma-per-la-vita\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/festa-della-mamma-2021-sono-ancora-in-tempo-per-richiedere-i-regali-solidali-di-ai-bi-mamma-per-la-vita\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/festa-della-mamma-2021-sono-ancora-in-tempo-per-richiedere-i-regali-solidali-di-ai-bi-mamma-per-la-vita\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/05\\\/prodotti-festa-della-mamma_fb.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/05\\\/prodotti-festa-della-mamma_fb.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/festa-della-mamma-2021-sono-ancora-in-tempo-per-richiedere-i-regali-solidali-di-ai-bi-mamma-per-la-vita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lettere al direttore\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/lettere-al-direttore\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Festa della mamma 2021. Sono ancora in tempo per richiedere i regali solidali di Ai.Bi. &#8220;Mamma Per la Vita&#8221;?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\",\"name\":\"francescoE\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/francescoe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Festa della mamma 2021. I regali solidali di Ai.Bi. \"Mamma Per la Vita\"?","description":"Con la t-shirt, la tazza e la shopping bag \"Mamma per la vita\", sostieni i progetti di Ai.Bi. per la Family House che accoglie mamme e bambini in difficolt\u00e0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/festa-della-mamma-2021-sono-ancora-in-tempo-per-richiedere-i-regali-solidali-di-ai-bi-mamma-per-la-vita\/","og_locale":"it_IT","og_type":"article","og_title":"Festa della mamma 2021. Sono ancora in tempo per richiedere i regali solidali di Ai.Bi. \"Mamma Per la Vita\"?","og_description":"Con la t-shirt, la tazza e la shopping bag \"Mamma per la vita\", sostieni i progetti di Ai.Bi. per la Family House che accoglie mamme e bambini in difficolt\u00e0","og_url":"https:\/\/www.aibi.it\/ita\/festa-della-mamma-2021-sono-ancora-in-tempo-per-richiedere-i-regali-solidali-di-ai-bi-mamma-per-la-vita\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2021-05-04T09:30:26+00:00","article_modified_time":"2021-05-04T14:28:15+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2021\/05\/prodotti-festa-della-mamma_fb.jpg","type":"image\/jpeg"}],"author":"francescoE","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"francescoE","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/festa-della-mamma-2021-sono-ancora-in-tempo-per-richiedere-i-regali-solidali-di-ai-bi-mamma-per-la-vita\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/festa-della-mamma-2021-sono-ancora-in-tempo-per-richiedere-i-regali-solidali-di-ai-bi-mamma-per-la-vita\/"},"author":{"name":"francescoE","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5"},"headline":"Festa della mamma 2021. Sono ancora in tempo per richiedere i regali solidali di Ai.Bi. &#8220;Mamma Per la Vita&#8221;?","datePublished":"2021-05-04T09:30:26+00:00","dateModified":"2021-05-04T14:28:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/festa-della-mamma-2021-sono-ancora-in-tempo-per-richiedere-i-regali-solidali-di-ai-bi-mamma-per-la-vita\/"},"wordCount":419,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/festa-della-mamma-2021-sono-ancora-in-tempo-per-richiedere-i-regali-solidali-di-ai-bi-mamma-per-la-vita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/05\/prodotti-festa-della-mamma_fb.jpg","keywords":["Fame di mamma","mamma"],"articleSection":["Lettere al direttore"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/festa-della-mamma-2021-sono-ancora-in-tempo-per-richiedere-i-regali-solidali-di-ai-bi-mamma-per-la-vita\/","url":"https:\/\/www.aibi.it\/ita\/festa-della-mamma-2021-sono-ancora-in-tempo-per-richiedere-i-regali-solidali-di-ai-bi-mamma-per-la-vita\/","name":"Festa della mamma 2021. I regali solidali di Ai.Bi. \"Mamma Per la Vita\"?","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/festa-della-mamma-2021-sono-ancora-in-tempo-per-richiedere-i-regali-solidali-di-ai-bi-mamma-per-la-vita\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/festa-della-mamma-2021-sono-ancora-in-tempo-per-richiedere-i-regali-solidali-di-ai-bi-mamma-per-la-vita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/05\/prodotti-festa-della-mamma_fb.jpg","datePublished":"2021-05-04T09:30:26+00:00","dateModified":"2021-05-04T14:28:15+00:00","description":"Con la t-shirt, la tazza e la shopping bag \"Mamma per la vita\", sostieni i progetti di Ai.Bi. per la Family House che accoglie mamme e bambini in difficolt\u00e0","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/festa-della-mamma-2021-sono-ancora-in-tempo-per-richiedere-i-regali-solidali-di-ai-bi-mamma-per-la-vita\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/festa-della-mamma-2021-sono-ancora-in-tempo-per-richiedere-i-regali-solidali-di-ai-bi-mamma-per-la-vita\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/festa-della-mamma-2021-sono-ancora-in-tempo-per-richiedere-i-regali-solidali-di-ai-bi-mamma-per-la-vita\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2021\/05\/prodotti-festa-della-mamma_fb.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/05\/prodotti-festa-della-mamma_fb.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/festa-della-mamma-2021-sono-ancora-in-tempo-per-richiedere-i-regali-solidali-di-ai-bi-mamma-per-la-vita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Lettere al direttore","item":"https:\/\/www.aibi.it\/ita\/category\/lettere-al-direttore\/"},{"@type":"ListItem","position":3,"name":"Festa della mamma 2021. Sono ancora in tempo per richiedere i regali solidali di Ai.Bi. &#8220;Mamma Per la Vita&#8221;?"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5","name":"francescoE","url":"https:\/\/www.aibi.it\/ita\/author\/francescoe\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 09:39:15","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/187728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=187728"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/187728\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/187734"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=187728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=187728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=187728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}