﻿


{"id":188814,"date":"2021-06-09T12:24:43","date_gmt":"2021-06-09T10:24:43","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=188814"},"modified":"2022-07-25T14:42:09","modified_gmt":"2022-07-25T12:42:09","slug":"bolivia-un-sogno-che-si-avvera-finalmente-abbraccio-la-mia-famiglia","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/bolivia-un-sogno-che-si-avvera-finalmente-abbraccio-la-mia-famiglia\/","title":{"rendered":"Bolivia. Un sogno che si avvera: finalmente abbraccio la mia famiglia!"},"content":{"rendered":"<h2>Ogni bambino ha diritto a vivere in famiglia e ogni bambino che scopre la sua \u00e8 il compimento della mission di Amici dei Bambini, grazie anche all\u2019aiuto dei <a href=\"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/attivazione-adozione-a-distanza\/?scelta=25&amp;progetto=Bolivia\">sostenitori a distanza<\/a><\/h2>\n<p><strong>Ogni bambino ha diritto a vivere in famiglia<\/strong>. \u00c8 questa la mission di Amici dei Bambini che, dal 1986, \u00e8 in prima linea affinch\u00e9 questo diritto venga garantito ad ogni minore, in tutto il mondo.<\/p>\n<p>Anche <strong>in Bolivia, dove Ai.Bi. \u00e8 presente dal 1997<\/strong>, il nostro impegno per migliorare le condizioni di vita dei minori accolti in due istituti di La Paz e garantire i loro diritti, primo tra tutti, quello di vivere e crescere in famiglia, \u00e8 costante, anche <strong>grazie ai sostenitori a distanza<\/strong>.<\/p>\n<p>Questo \u00e8 quanto accade, ad esempio, al centro di accoglienza <strong>Ni\u00f1o Jes\u00fas<\/strong> di La Paz che accoglie fino a 70 bambini, da 0 a 6 anni, in situazioni di abbandono e negligenza familiare, e giovani mamme sole. <strong>Grazie al\u00a0Sostegno a Distanza<\/strong>, gli operatori di Ai.Bi. Bolivia supportano lo staff dell\u2019istituto\u00a0nella realizzazione di un\u00a0<strong>Progetto di Vita Individuale<\/strong>\u00a0assicurando a ciascun neonato e bambino accolto: cure e sostegno medico e psicologico personalizzato; indagini socio-familiari per il reinserimento in famiglia e il rilascio del certificato di nascita.<\/p>\n<p>Se il minore \u00e8 stato abbandonato senza aver lasciato nessun riferimento della famiglia biologica, l&#8217;indagine sociale \u00e8 un passaggio fondamentale per definire la situazione giuridica del bambino ed \u00e8 importante affinch\u00e9 possa essere integrato nella propria famiglia di origine o, se questa alternativa non fosse possibile, affinch\u00e9 sia dichiarato adottabile.<\/p>\n<p>Il costante lavoro di Amici dei Bambini e dello staff della Casa di Accoglienza sta dando i suoi frutti e i bambini che non possono rientrare nelle loro famiglie di origine, hanno finalmente la possibilit\u00e0 di <strong>rinascere figli grazie al caldo abbraccio delle loro famiglie adottive<\/strong>. Sono bambini che attendono l&#8217;arrivo dei loro genitori, spesso preparati grazie a dei video realizzati da questi ultimi e che permettono, poco a poco, di conoscersi fino all\u2019indimenticabile primo abbraccio. Per la prima volta tutte le attenzioni sono solo per loro con momenti di gioco, di convivenza e di conoscenza reciproca. \u00c8 quest\u2019immagine familiare che ci da la forza per affrontare le mille difficolt\u00e0 che incontriamo nel nostro lavoro.<\/p>\n<p>Diventa anche tu un\u00a0<a href=\"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/attivazione-adozione-a-distanza\/?scelta=25&amp;progetto=Bolivia\">sostenitore<\/a>\u00a0del centro di accoglienza Ni\u00f1o Jes\u00fas, potrai seguire e accompagnare ogni giorno la vita, i progressi e le difficolt\u00e0 dei 70 bambini abbandonati accolti, e soprattutto la loro gioia quando incontreranno la loro nuova famiglia adottiva. Ogni mese riceverai un report che ti permetter\u00e0 di essere aggiornato costantemente. Per te un caff\u00e8 in meno al giorno, per i &#8221; 70 altri tuoi figli\u201d la speranza per una vita in famiglia.<\/p>\n<p>Attiva un <a href=\"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/attivazione-adozione-a-distanza\/?scelta=25&amp;progetto=Bolivia\">Sostegno a Distanza<\/a>, bastano <strong>25 euro<\/strong> al mese.<\/p>\n\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*168342-start*\/\n#btnsx-168342{margin-top:0px;margin-bottom:20px;margin-left:0px;margin-right:0px;padding-top:20px;padding-bottom:20px;padding-left:40px;padding-right:40px;}\n#btnsx-168342 .btnsx-text-primary{font-size:30px;line-height:30px;font-family:Montserrat;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-168342:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-168342{background-color:#ef7b0b!important;}\n#btnsx-168342:hover{background-color:#eab20b!important;}\n#btnsx-168342{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-168342:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*168342-end*\/\n<\/style><div id=\"btnsx-168342-wrap\" class=\"btnsx-wrap-center\" align=\"center\"><div id=\"btnsx-168342-container\" class=\"btnsx-btn-container\">\n<a href=\"https:\/\/www.aibi.it\/ita\/adotta-a-distanza-25\/\" id=\"btnsx-168342\" target=\"_blank\" class=\"btnsx-btn btnsx-btn-embossed\"  data-font-primary=\"Montserrat\">\n\t<span class=\"btnsx-text-primary \">Scopri di pi\u00f9<\/span><\/a>\n<\/div><\/div>\n<!-- Buttons X - End -->\n\n","protected":false},"excerpt":{"rendered":"<p>Ogni bambino ha diritto a vivere in famiglia e ogni bambino che scopre la sua &egrave; il compimento della mission di Amici dei Bambini, grazie anche all&rsquo;aiuto dei sostenitori a distanza Ogni bambino ha diritto a vivere in famiglia. &Egrave; questa la mission di Amici dei Bambini che, dal 1986, [&hellip;]<\/p>\n","protected":false},"author":113,"featured_media":175834,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[209],"tags":[480,646,300],"class_list":["post-188814","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-a-distanza","tag-bolivia","tag-nino-jesus","tag-sostegno-a-distanza"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Bolivia. Un sogno che si avvera: finalmente abbraccio la mia famiglia! - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/bolivia-un-sogno-che-si-avvera-finalmente-abbraccio-la-mia-famiglia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bolivia. Un sogno che si avvera: finalmente abbraccio la mia famiglia!\" \/>\n<meta property=\"og:description\" content=\"Ogni bambino ha diritto a vivere in famiglia e ogni bambino che scopre la sua &egrave; il compimento della mission di Amici dei Bambini, grazie anche all&rsquo;aiuto dei sostenitori a distanza Ogni bambino ha diritto a vivere in famiglia. &Egrave; questa la mission di Amici dei Bambini che, dal 1986, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/bolivia-un-sogno-che-si-avvera-finalmente-abbraccio-la-mia-famiglia\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-09T10:24:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-25T12:42:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/06\/Nino-Jesus-ingresso.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"carlottaZ\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/06\/Nino-Jesus-ingresso.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"carlottaZ\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-un-sogno-che-si-avvera-finalmente-abbraccio-la-mia-famiglia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-un-sogno-che-si-avvera-finalmente-abbraccio-la-mia-famiglia\\\/\"},\"author\":{\"name\":\"carlottaZ\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/95193f4e7a1f2190922687ebf84f96c9\"},\"headline\":\"Bolivia. Un sogno che si avvera: finalmente abbraccio la mia famiglia!\",\"datePublished\":\"2021-06-09T10:24:43+00:00\",\"dateModified\":\"2022-07-25T12:42:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-un-sogno-che-si-avvera-finalmente-abbraccio-la-mia-famiglia\\\/\"},\"wordCount\":473,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-un-sogno-che-si-avvera-finalmente-abbraccio-la-mia-famiglia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/06\\\/Nino-Jesus-ingresso.jpg\",\"keywords\":[\"Bolivia\",\"Nino Jesus\",\"sostegno a distanza\"],\"articleSection\":[\"Adozione a Distanza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-un-sogno-che-si-avvera-finalmente-abbraccio-la-mia-famiglia\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-un-sogno-che-si-avvera-finalmente-abbraccio-la-mia-famiglia\\\/\",\"name\":\"Bolivia. Un sogno che si avvera: finalmente abbraccio la mia famiglia! - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-un-sogno-che-si-avvera-finalmente-abbraccio-la-mia-famiglia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-un-sogno-che-si-avvera-finalmente-abbraccio-la-mia-famiglia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/06\\\/Nino-Jesus-ingresso.jpg\",\"datePublished\":\"2021-06-09T10:24:43+00:00\",\"dateModified\":\"2022-07-25T12:42:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-un-sogno-che-si-avvera-finalmente-abbraccio-la-mia-famiglia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-un-sogno-che-si-avvera-finalmente-abbraccio-la-mia-famiglia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-un-sogno-che-si-avvera-finalmente-abbraccio-la-mia-famiglia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/06\\\/Nino-Jesus-ingresso.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/06\\\/Nino-Jesus-ingresso.jpg\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-un-sogno-che-si-avvera-finalmente-abbraccio-la-mia-famiglia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione a Distanza\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-a-distanza\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bolivia. Un sogno che si avvera: finalmente abbraccio la mia famiglia!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/95193f4e7a1f2190922687ebf84f96c9\",\"name\":\"carlottaZ\",\"sameAs\":[\"cellos\"],\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/carlottaz\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bolivia. Un sogno che si avvera: finalmente abbraccio la mia famiglia! - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/bolivia-un-sogno-che-si-avvera-finalmente-abbraccio-la-mia-famiglia\/","og_locale":"it_IT","og_type":"article","og_title":"Bolivia. Un sogno che si avvera: finalmente abbraccio la mia famiglia!","og_description":"Ogni bambino ha diritto a vivere in famiglia e ogni bambino che scopre la sua &egrave; il compimento della mission di Amici dei Bambini, grazie anche all&rsquo;aiuto dei sostenitori a distanza Ogni bambino ha diritto a vivere in famiglia. &Egrave; questa la mission di Amici dei Bambini che, dal 1986, [&hellip;]","og_url":"https:\/\/www.aibi.it\/ita\/bolivia-un-sogno-che-si-avvera-finalmente-abbraccio-la-mia-famiglia\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2021-06-09T10:24:43+00:00","article_modified_time":"2022-07-25T12:42:09+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.aibi.it\/ita\/images\/2020\/06\/Nino-Jesus-ingresso.jpg","type":"image\/jpeg"}],"author":"carlottaZ","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.aibi.it\/ita\/images\/2020\/06\/Nino-Jesus-ingresso.jpg","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"carlottaZ","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/bolivia-un-sogno-che-si-avvera-finalmente-abbraccio-la-mia-famiglia\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-un-sogno-che-si-avvera-finalmente-abbraccio-la-mia-famiglia\/"},"author":{"name":"carlottaZ","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/95193f4e7a1f2190922687ebf84f96c9"},"headline":"Bolivia. Un sogno che si avvera: finalmente abbraccio la mia famiglia!","datePublished":"2021-06-09T10:24:43+00:00","dateModified":"2022-07-25T12:42:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-un-sogno-che-si-avvera-finalmente-abbraccio-la-mia-famiglia\/"},"wordCount":473,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-un-sogno-che-si-avvera-finalmente-abbraccio-la-mia-famiglia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2020\/06\/Nino-Jesus-ingresso.jpg","keywords":["Bolivia","Nino Jesus","sostegno a distanza"],"articleSection":["Adozione a Distanza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/bolivia-un-sogno-che-si-avvera-finalmente-abbraccio-la-mia-famiglia\/","url":"https:\/\/www.aibi.it\/ita\/bolivia-un-sogno-che-si-avvera-finalmente-abbraccio-la-mia-famiglia\/","name":"Bolivia. Un sogno che si avvera: finalmente abbraccio la mia famiglia! - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-un-sogno-che-si-avvera-finalmente-abbraccio-la-mia-famiglia\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-un-sogno-che-si-avvera-finalmente-abbraccio-la-mia-famiglia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2020\/06\/Nino-Jesus-ingresso.jpg","datePublished":"2021-06-09T10:24:43+00:00","dateModified":"2022-07-25T12:42:09+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-un-sogno-che-si-avvera-finalmente-abbraccio-la-mia-famiglia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/bolivia-un-sogno-che-si-avvera-finalmente-abbraccio-la-mia-famiglia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/bolivia-un-sogno-che-si-avvera-finalmente-abbraccio-la-mia-famiglia\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2020\/06\/Nino-Jesus-ingresso.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2020\/06\/Nino-Jesus-ingresso.jpg","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/bolivia-un-sogno-che-si-avvera-finalmente-abbraccio-la-mia-famiglia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione a Distanza","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-a-distanza\/"},{"@type":"ListItem","position":3,"name":"Bolivia. Un sogno che si avvera: finalmente abbraccio la mia famiglia!"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/95193f4e7a1f2190922687ebf84f96c9","name":"carlottaZ","sameAs":["cellos"],"url":"https:\/\/www.aibi.it\/ita\/author\/carlottaz\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 15:24:24","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/188814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/113"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=188814"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/188814\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/175834"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=188814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=188814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=188814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}