﻿


{"id":188967,"date":"2021-06-14T10:30:00","date_gmt":"2021-06-14T08:30:00","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=188967"},"modified":"2021-06-14T17:13:58","modified_gmt":"2021-06-14T15:13:58","slug":"marocco-lotta-contro-il-lavoro-minorile-lesperienza-de-iltesam","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/marocco-lotta-contro-il-lavoro-minorile-lesperienza-de-iltesam\/","title":{"rendered":"Marocco. Lotta contro il lavoro minorile: l\u2019esperienza de \u201cIltesam\u201d"},"content":{"rendered":"<h2><strong>Iniziativa per la lotta contro il lavoro minorile in Marocco: un progetto pionieristico per sradicare un problema persistente e ridare un\u2019infanzia ai bambini del Paese africano<\/strong><\/h2>\n<p>Molti bambini sono privati della loro infanzia perch\u00e9 costretti a lavorare e a non frequentare la scuola. Questa piaga \u00e8 all&#8217;origine dell&#8217;iniziativa &#8220;ILTESAM&#8221; (Iniziativa per la lotta contro il lavoro minorile in Marocco), una piattaforma lanciata recentemente dalla CGEM per cambiare la situazione e superare un problema che perpetua l&#8217;insicurezza.<\/p>\n<h3><strong>Una piaga ricordata il 12 giugno dalla Giornata Mondiale contro lo sfruttamento del lavoro minorile<\/strong><\/h3>\n<p>Il &#8220;lavoro minorile&#8221; \u00e8 spesso definito come un lavoro che <strong>priva i bambini della loro infanzia<\/strong>, del loro potenziale e della loro dignit\u00e0, danneggia il loro sviluppo fisico e mentale e mette a repentaglio la loro salute e la loro istruzione. Da qui l&#8217;urgente necessit\u00e0 di un&#8217;azione per affrontare alla radice le cause che determinano questa <strong>violazione dei diritti umani<\/strong> che, in Marocco come in altri Paesi, d\u00e0 origine a diversi problemi economici e sociali.<\/p>\n<p>Per cambiare la situazione, tutte le cause devono essere affrontate e tutti gli attori coinvolti devono lavorare insieme. Consapevole di questa sfida e della necessit\u00e0 di permettere ai bambini di costruire il loro futuro con dignit\u00e0, la <strong>Confederazione generale delle imprese marocchine<\/strong> (CGEM) si \u00e8 mobilitata contro il lavoro minorile in Marocco e, in collaborazione con l&#8217;Organizzazione internazionale del lavoro (OIL), ha lanciato &#8220;l&#8217;iniziativa del settore privato marocchino per la lotta contro il lavoro infantile&#8221;. L&#8217;associazione dei datori di lavoro assicura che &#8220;<strong>ILTESAM<\/strong>&#8220;, <strong>l&#8217;equivalente arabo della parola &#8220;impegno&#8221;<\/strong>, \u00e8 un&#8217;iniziativa pionieristica che <strong>rafforzer\u00e0 l&#8217;impegno del settore privato per contribuire all&#8217;eliminazione del lavoro infantile<\/strong> in Marocco, particolarmente nei lavori pericolosi.<\/p>\n<p>Unica nel suo genere, l&#8217;iniziativa &#8220;ILTESAM&#8221; consiste nella <strong>creazione di una piattaforma<\/strong> per sostenere concretamente le imprese marocchine nel successo delle loro azioni contro il lavoro minorile, fornendo loro tutte le <strong>informazioni<\/strong> necessarie, <strong>kit di sensibilizzazione<\/strong> e <strong>formazione<\/strong> online. Questa piattaforma offre anche alle aziende l&#8217;opportunit\u00e0 di contribuire concretamente al raggiungimento dell&#8217;obiettivo 8.7 degli Obiettivi di Sviluppo Sostenibile delle Nazioni Unite, che esorta i paesi ad adottare misure immediate ed efficaci per porre fine al lavoro minorile in tutte le sue forme entro il 2025.<\/p>\n<h3><strong>Numeri in miglioramento: ma la piaga del lavoro minorile rimane un problema mondiale enorme<\/strong><\/h3>\n<p>Per il presidente della commissione sociale della CGEM, <strong>Hicham Zouanat<\/strong>, gli sforzi fatti nella lotta contro il lavoro infantile in Marocco sono notevoli, con una <strong>diminuzione del 92%<\/strong> in due decenni del numero di bambini lavoratori da 517.000 a 42.000. Ha assicurato in una dichiarazione alla MAP che questo tema resta di particolare importanza in un contesto socio-economico segnato dalla crisi sanitaria del Covid-19, perch\u00e9 le crisi e le pandemie sono <strong>amplificatori delle disuguaglianze sociali<\/strong> che mettono ancora il tema sul tavolo.<\/p>\n<p>In questo senso, ha spiegato, il CGEM ha creato questa piattaforma che ha tre obiettivi: sensibilizzare e comunicare sul tema, creare dibattiti, accompagnare le aziende con kit di comunicazione e formazione online per sensibilizzare e responsabilizzare i datori di lavoro e dare loro gli argomenti per sradicare il lavoro minorile non solo nella loro azienda ma soprattutto in tutta la catena del valore.<br \/>\nIn terzo luogo, ha continuato, questa piattaforma vuole essere come un <strong>divulgatore di punti di riferimento<\/strong>, cio\u00e8 raccogliere le pratiche di sradicamento del lavoro infantile in Marocco e all&#8217;estero e condividerle con tutte le imprese del Marocco. Gli obiettivi diretti di questa iniziativa sono, secondo l&#8217;associazione dei datori di lavoro, lavorare per il miglioramento del rispetto da parte delle aziende delle norme nazionali e internazionali nella lotta contro il lavoro minorile, fornire alle aziende un meccanismo per lo scambio di conoscenze sulle strategie di lotta contro il lavoro minorile nelle catene di approvvigionamento e incoraggiare le aziende a sviluppare <strong>approcci pratici e collaborativi<\/strong> per combattere il lavoro minorile.<\/p>\n<p>In Marocco, secondo l&#8217;indagine nazionale sull&#8217;occupazione condotta dall&#8217;Alta Commissione per la Pianificazione (HCP) nel 2018, il numero di bambini lavoratori sotto i 15 anni ammonta a <strong>41.200<\/strong> (90% nelle zone rurali e 10% nelle aree urbane). Secondo lo stesso sondaggio, dei <strong>247.000 bambini dai 7 ai 17 anni<\/strong> che sono economicamente occupati, <strong>162.000 sono impegnati in lavori pericolosi<\/strong>, cio\u00e8 2 bambini lavoratori su 3 sono direttamente esposti a lavori pericolosi. Data l&#8217;attuale situazione dello stato di emergenza a causa del Coronavirus, il rischio potenziale del lavoro minorile diventa pi\u00f9 importante. L&#8217;<strong>abbandono scolastico<\/strong>, che \u00e8 la causa principale del lavoro minorile in Marocco, rischia di aumentare con la chiusura temporanea delle scuole e l&#8217;impoverimento delle famiglie. L&#8217;adesione alla Child Labour Platform permetter\u00e0 all&#8217;azienda, tra le altre cose, di partecipare all&#8217;iniziativa globale e nazionale per eliminare il lavoro minorile entro il 2025, di lavorare con altre aziende per sviluppare modelli innovativi di collaborazione per affrontare il lavoro minorile nelle catene di fornitura attraverso un approccio di lavoro dignitoso, e di accedere a una serie di strumenti pratici come la verifica dell&#8217;et\u00e0, il monitoraggio, cos\u00ec come le attivit\u00e0 di formazione e capacity building. Per i datori di lavoro \u00e8 essenziale riunire e coordinare tutti gli sforzi dei diversi attori in un unico luogo per avere <strong>un&#8217;unica forza d&#8217;urto contro il lavoro minorile<\/strong> e la sfida oggi \u00e8 quella di intensificare la lotta contro il lavoro minorile fino alla sua definitiva eliminazione.<\/p>\n<h3><strong>Giornata Mondiale e Anno Internazionale per l\u2019eliminazione del lavoro minorile<\/strong><\/h3>\n<p>La recente Giornata Mondiale contro il lavoro minorile ha riacceso i riflettori su questa emergenza, con un richiamo fatto anche dal Papa <a href=\"https:\/\/twitter.com\/Pontifex_it\/status\/1403645751171817472\" target=\"_blank\" rel=\"noopener\">attraverso un Tweet<\/a>. Ma non solo: l&#8217;<strong>Organizzazione Internazionale del Lavoro ha dichiarato il 2021 come Anno Internazionale per l&#8217;eliminazione del lavoro minorile<\/strong>. Negli ultimi vent&#8217;anni, quasi <strong>100 milioni di bambini sono stati sottratti al lavoro minorile<\/strong>, portando il numero a 152 milioni nel 2016 dai 246 milioni del 2000, sottolinea l&#8217;ILO, notando che la crisi del COVID-19 ha aumentato il livello di povert\u00e0 di queste popolazioni gi\u00e0 vulnerabili, e potrebbe portare ad un arretramento dei progressi contro il lavoro minorile, cos\u00ec come la chiusura delle scuole ha peggiorato la situazione, con molti milioni di bambini che lavorano per contribuire al reddito familiare.<\/p>\n\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*168342-start*\/\n#btnsx-168342{margin-top:0px;margin-bottom:20px;margin-left:0px;margin-right:0px;padding-top:20px;padding-bottom:20px;padding-left:40px;padding-right:40px;}\n#btnsx-168342 .btnsx-text-primary{font-size:30px;line-height:30px;font-family:Montserrat;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-168342:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-168342{background-color:#ef7b0b!important;}\n#btnsx-168342:hover{background-color:#eab20b!important;}\n#btnsx-168342{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-168342:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*168342-end*\/\n<\/style><div id=\"btnsx-168342-wrap\" class=\"btnsx-wrap-center\" align=\"center\"><div id=\"btnsx-168342-container\" class=\"btnsx-btn-container\">\n<a href=\"https:\/\/dona.aibi.it\/adozione-a-distanza\/\" id=\"btnsx-168342\" target=\"_blank\" class=\"btnsx-btn btnsx-btn-embossed\"  data-font-primary=\"Montserrat\">\n\t<span class=\"btnsx-text-primary \">Adotta a Distanza ORA<\/span><\/a>\n<\/div><\/div>\n<!-- Buttons X - End -->\n\n","protected":false},"excerpt":{"rendered":"<p>Iniziativa per la lotta contro il lavoro minorile in Marocco: un progetto pionieristico per sradicare un problema persistente e ridare un&rsquo;infanzia ai bambini del Paese africano Molti bambini sono privati della loro infanzia perch&eacute; costretti a lavorare e a non frequentare la scuola. Questa piaga &egrave; all&rsquo;origine dell&rsquo;iniziativa &ldquo;ILTESAM&rdquo; (Iniziativa [&hellip;]<\/p>\n","protected":false},"author":102,"featured_media":188968,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[551,378,300],"class_list":["post-188967","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cooperazione-internazionale","tag-cooperazione-internazionale","tag-marocco","tag-sostegno-a-distanza"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Marocco. Lotta al lavoro minorile: l\u2019esperienza de \u201cIltesam\u201d<\/title>\n<meta name=\"description\" content=\"Iniziativa per la lotta contro il lavoro minorile in Marocco: un progetto pionieristico per sradicare un problema persistente e ridare un\u2019infanzia ai bambini\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/marocco-lotta-contro-il-lavoro-minorile-lesperienza-de-iltesam\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marocco. Lotta contro il lavoro minorile: l\u2019esperienza de \u201cIltesam\u201d\" \/>\n<meta property=\"og:description\" content=\"Iniziativa per la lotta contro il lavoro minorile in Marocco: un progetto pionieristico per sradicare un problema persistente e ridare un\u2019infanzia ai bambini\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/marocco-lotta-contro-il-lavoro-minorile-lesperienza-de-iltesam\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-14T08:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-14T15:13:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2021\/06\/marocco-lavoro-minorile.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/marocco-lotta-contro-il-lavoro-minorile-lesperienza-de-iltesam\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/marocco-lotta-contro-il-lavoro-minorile-lesperienza-de-iltesam\\\/\"},\"author\":{\"name\":\"francescoE\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\"},\"headline\":\"Marocco. Lotta contro il lavoro minorile: l\u2019esperienza de \u201cIltesam\u201d\",\"datePublished\":\"2021-06-14T08:30:00+00:00\",\"dateModified\":\"2021-06-14T15:13:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/marocco-lotta-contro-il-lavoro-minorile-lesperienza-de-iltesam\\\/\"},\"wordCount\":1015,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/marocco-lotta-contro-il-lavoro-minorile-lesperienza-de-iltesam\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/06\\\/marocco-lavoro-minorile.jpg\",\"keywords\":[\"cooperazione internazionale\",\"Marocco\",\"sostegno a distanza\"],\"articleSection\":[\"Cooperazione Internazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/marocco-lotta-contro-il-lavoro-minorile-lesperienza-de-iltesam\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/marocco-lotta-contro-il-lavoro-minorile-lesperienza-de-iltesam\\\/\",\"name\":\"Marocco. Lotta al lavoro minorile: l\u2019esperienza de \u201cIltesam\u201d\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/marocco-lotta-contro-il-lavoro-minorile-lesperienza-de-iltesam\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/marocco-lotta-contro-il-lavoro-minorile-lesperienza-de-iltesam\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/06\\\/marocco-lavoro-minorile.jpg\",\"datePublished\":\"2021-06-14T08:30:00+00:00\",\"dateModified\":\"2021-06-14T15:13:58+00:00\",\"description\":\"Iniziativa per la lotta contro il lavoro minorile in Marocco: un progetto pionieristico per sradicare un problema persistente e ridare un\u2019infanzia ai bambini\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/marocco-lotta-contro-il-lavoro-minorile-lesperienza-de-iltesam\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/marocco-lotta-contro-il-lavoro-minorile-lesperienza-de-iltesam\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/marocco-lotta-contro-il-lavoro-minorile-lesperienza-de-iltesam\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/06\\\/marocco-lavoro-minorile.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/06\\\/marocco-lavoro-minorile.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/marocco-lotta-contro-il-lavoro-minorile-lesperienza-de-iltesam\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cooperazione Internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/cooperazione-internazionale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Marocco. Lotta contro il lavoro minorile: l\u2019esperienza de \u201cIltesam\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\",\"name\":\"francescoE\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/francescoe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Marocco. Lotta al lavoro minorile: l\u2019esperienza de \u201cIltesam\u201d","description":"Iniziativa per la lotta contro il lavoro minorile in Marocco: un progetto pionieristico per sradicare un problema persistente e ridare un\u2019infanzia ai bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/marocco-lotta-contro-il-lavoro-minorile-lesperienza-de-iltesam\/","og_locale":"it_IT","og_type":"article","og_title":"Marocco. Lotta contro il lavoro minorile: l\u2019esperienza de \u201cIltesam\u201d","og_description":"Iniziativa per la lotta contro il lavoro minorile in Marocco: un progetto pionieristico per sradicare un problema persistente e ridare un\u2019infanzia ai bambini","og_url":"https:\/\/www.aibi.it\/ita\/marocco-lotta-contro-il-lavoro-minorile-lesperienza-de-iltesam\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2021-06-14T08:30:00+00:00","article_modified_time":"2021-06-14T15:13:58+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2021\/06\/marocco-lavoro-minorile.jpg","type":"image\/jpeg"}],"author":"francescoE","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"francescoE","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/marocco-lotta-contro-il-lavoro-minorile-lesperienza-de-iltesam\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/marocco-lotta-contro-il-lavoro-minorile-lesperienza-de-iltesam\/"},"author":{"name":"francescoE","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5"},"headline":"Marocco. Lotta contro il lavoro minorile: l\u2019esperienza de \u201cIltesam\u201d","datePublished":"2021-06-14T08:30:00+00:00","dateModified":"2021-06-14T15:13:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/marocco-lotta-contro-il-lavoro-minorile-lesperienza-de-iltesam\/"},"wordCount":1015,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/marocco-lotta-contro-il-lavoro-minorile-lesperienza-de-iltesam\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/06\/marocco-lavoro-minorile.jpg","keywords":["cooperazione internazionale","Marocco","sostegno a distanza"],"articleSection":["Cooperazione Internazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/marocco-lotta-contro-il-lavoro-minorile-lesperienza-de-iltesam\/","url":"https:\/\/www.aibi.it\/ita\/marocco-lotta-contro-il-lavoro-minorile-lesperienza-de-iltesam\/","name":"Marocco. Lotta al lavoro minorile: l\u2019esperienza de \u201cIltesam\u201d","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/marocco-lotta-contro-il-lavoro-minorile-lesperienza-de-iltesam\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/marocco-lotta-contro-il-lavoro-minorile-lesperienza-de-iltesam\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/06\/marocco-lavoro-minorile.jpg","datePublished":"2021-06-14T08:30:00+00:00","dateModified":"2021-06-14T15:13:58+00:00","description":"Iniziativa per la lotta contro il lavoro minorile in Marocco: un progetto pionieristico per sradicare un problema persistente e ridare un\u2019infanzia ai bambini","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/marocco-lotta-contro-il-lavoro-minorile-lesperienza-de-iltesam\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/marocco-lotta-contro-il-lavoro-minorile-lesperienza-de-iltesam\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/marocco-lotta-contro-il-lavoro-minorile-lesperienza-de-iltesam\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2021\/06\/marocco-lavoro-minorile.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/06\/marocco-lavoro-minorile.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/marocco-lotta-contro-il-lavoro-minorile-lesperienza-de-iltesam\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Cooperazione Internazionale","item":"https:\/\/www.aibi.it\/ita\/category\/cooperazione-internazionale\/"},{"@type":"ListItem","position":3,"name":"Marocco. Lotta contro il lavoro minorile: l\u2019esperienza de \u201cIltesam\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5","name":"francescoE","url":"https:\/\/www.aibi.it\/ita\/author\/francescoe\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 15:23:15","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/188967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=188967"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/188967\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/188968"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=188967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=188967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=188967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}