﻿


{"id":188984,"date":"2021-06-15T11:15:33","date_gmt":"2021-06-15T09:15:33","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=188984"},"modified":"2021-06-15T16:22:37","modified_gmt":"2021-06-15T14:22:37","slug":"il-bello-che-fa-bene-raddoppia-parte-il-temporary-shop-summer-edition","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/il-bello-che-fa-bene-raddoppia-parte-il-temporary-shop-summer-edition\/","title":{"rendered":"\u201cIl Bello che Fa Bene\u201d raddoppia: parte il temporary shop summer edition"},"content":{"rendered":"<h2><strong>Da marted\u00ec 15 giugno parte la prima <em>summer edition<\/em> del Temporary Shop Solidale di Ai.Bi. Centinaia di prodotti di grandi marche per sostenere i progetti in favore dei bambini abbandonati e di donne e famiglie in difficolt\u00e0<\/strong><\/h2>\n<p><strong>\u00a0<\/strong>Quest\u2019anno l\u2019estate inizia con una sorpresa speciale: la consueta iniziativa \u201cnatalizia\u201d <strong><em>Il Bello che Fa Bene<\/em>, Temporary Shop Solidale<\/strong> a sostegno dei progetti per i bambini abbandonati e le famiglie in difficolt\u00e0 portati avanti da Ai.Bi. \u2013 Amici dei bambini, raddoppia il suo appuntamento e si presenta con una fresca versione \u201cestiva\u201d.<br \/>\n<strong>Dal 15 giugno fino al 30 luglio<\/strong> sul <a href=\"https:\/\/www.aibi.it\/temporary-shop\/\" target=\"_blank\" rel=\"noopener\">sito di Ai.Bi.<\/a> si pu\u00f2 trovare una selezione di prodotti, esclusivamente di grandi marchi, come da tradizione del Temporary Shop \u201cIl Bello che fa Bene\u201d, che hanno aderito all\u2019iniziativa.<\/p>\n<p>Si possono trovare gioielli <strong>Chantecler<\/strong>; farsi coccolare dagli abiti firmati <strong>Anna Viero Cashmere<\/strong> o dai prodotti di bellezza <strong>Baldan<\/strong> e quelli di make up <strong>KIKO<\/strong>; gustarsi un buon vino <strong>Caprai<\/strong>; scegliere un capo firmato <strong>Armani<\/strong> o un raffinato set <strong>Rocco Bormioli<\/strong> per la cucina.<br \/>\nOppure, ancora, trovare le tazzine da caff\u00e8 Art Collection by <strong>Illy Caf\u00e8<\/strong>, il made in Italy di <strong>Ornella Prosperi<\/strong>, le coloratissime borse cruelty-free di <strong>Save My Bag<\/strong>, gli oggetti di design <strong>Alessi<\/strong> e i giochi <strong>Mattel<\/strong> per i pi\u00f9 piccoli.<br \/>\nInoltre, anche in questa <em>summer edition<\/em> del Temporary Shop Solidale restano al fianco di Ai.Bi. grandi marchi come <strong>Dexter Milano<\/strong>, <strong>Antonello Blandi<\/strong> con Sicilia Colorata, l\u2019<strong>Enciclopedia Arte Italiana<\/strong>,<strong> Frette<\/strong>, <strong>Guardini<\/strong>, <strong>Lagostina<\/strong>, <strong>Peg Perego<\/strong>, <strong>Emilio Pucci<\/strong>, <strong>Hogan<\/strong>, <strong>Merola Gloves<\/strong> e <strong>Sunnei<\/strong>.<\/p>\n<h3><strong>Temporary Shop solidale di Ai.Bi.: lo shopping che regala sorrisi!<\/strong><\/h3>\n<p>Al di l\u00e0 della bellezza dei prodotti, ogni donazione fatta \u00e8 soprattutto un sostegno per il futuro dei bambini e degli adolescenti in situazioni di fragilit\u00e0, quest\u2019anno ancor pi\u00f9 colpiti dalle conseguenze dell\u2019emergenza sanitaria Covid19. Tutti i fondi raccolti grazie alla <strong>Summer Edition <\/strong>del<strong> Temporary Shop Solidale <\/strong>saranno infatti destinati alla campagna &#8220;<strong>Continuiamo dai bambini. L&#8217;accoglienza non si ferma<\/strong>\u201d, per rimanere al fianco dei minori e vicini alle famiglie che si sono ritrovate a fronteggiare da sole l\u2019isolamento e i suoi effetti.<\/p>\n<p>Per tutto il periodo dello shop l\u2019assortimento dei prodotti sar\u00e0 continuamente rinnovato: si pu\u00f2 scoprire il tutto alla pagina del sito dedicata al <a href=\"https:\/\/www.aibi.it\/temporary-shop\/\" target=\"_blank\" rel=\"noopener\">Temporary Shop solidale<\/a>.<br \/>\n<strong>Tutte le donazioni al Temporary Shop godono delle agevolazioni fiscali.<\/strong><br \/>\nIl Bello che fa Bene\u2026 in versione estiva!<br \/>\n\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*188985-start*\/\n#btnsx-188985{margin-top:10px;margin-bottom:10px;margin-left:0px;margin-right:0px;padding-top:10px;padding-bottom:10px;padding-left:40px;padding-right:40px;}\n#btnsx-188985 .btnsx-text-primary{font-size:33px;line-height:33px;font-style:normal;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-188985:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-188985{background-color:#ef7d0b!important;}\n#btnsx-188985:hover{background-color:#dd3333!important;}\n#btnsx-188985{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-left-radius:10px;border-bottom-right-radius:10px;}\n#btnsx-188985:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-left-radius:10px;border-bottom-right-radius:10px;}\n#btnsx-188985{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-188985:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*188985-end*\/\n<\/style><div id=\"btnsx-188985-wrap\" class=\"btnsx-wrap-center\" align=\"center\">\n<a href=\"https:\/\/www.aibi.it\/temporary-shop\/?utm_source=post&amp;utm_medium=button&amp;utm_campaign=temporary_summer\" id=\"btnsx-188985\" target=\"_self\" class=\"btnsx-btn\" >\n\t<span class=\"btnsx-text-primary \">Vai allo Shop<\/span><\/a>\n<\/div>\n<!-- Buttons X - End -->\n\n","protected":false},"excerpt":{"rendered":"<p>Da marted&igrave; 15 giugno parte la prima summer edition del Temporary Shop Solidale di Ai.Bi. Centinaia di prodotti di grandi marche per sostenere i progetti in favore dei bambini abbandonati e di donne e famiglie in difficolt&agrave; &nbsp;Quest&rsquo;anno l&rsquo;estate inizia con una sorpresa speciale: la consueta iniziativa &ldquo;natalizia&rdquo; Il Bello [&hellip;]<\/p>\n","protected":false},"author":102,"featured_media":188993,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[764],"tags":[308,766],"class_list":["post-188984","post","type-post","status-publish","format-standard","has-post-thumbnail","category-progetti-in-italia","tag-bello-che-fa-bene","tag-progetti"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Il Bello che Fa Bene: temporary shop solidale di Ai.Bi. summer edition<\/title>\n<meta name=\"description\" content=\"La summer edition del Temporary Shop Solidale di Ai.Bi. Prodotti di grandi marche per sostenere i progetti in favore di bambini e famiglie in difficolt\u00e0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/il-bello-che-fa-bene-raddoppia-parte-il-temporary-shop-summer-edition\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cIl Bello che Fa Bene\u201d raddoppia: parte il temporary shop summer edition\" \/>\n<meta property=\"og:description\" content=\"La summer edition del Temporary Shop Solidale di Ai.Bi. Prodotti di grandi marche per sostenere i progetti in favore di bambini e famiglie in difficolt\u00e0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/il-bello-che-fa-bene-raddoppia-parte-il-temporary-shop-summer-edition\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-15T09:15:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-15T14:22:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2021\/06\/temporary-shop-solidale-summer-edition_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-bello-che-fa-bene-raddoppia-parte-il-temporary-shop-summer-edition\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-bello-che-fa-bene-raddoppia-parte-il-temporary-shop-summer-edition\\\/\"},\"author\":{\"name\":\"francescoE\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\"},\"headline\":\"\u201cIl Bello che Fa Bene\u201d raddoppia: parte il temporary shop summer edition\",\"datePublished\":\"2021-06-15T09:15:33+00:00\",\"dateModified\":\"2021-06-15T14:22:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-bello-che-fa-bene-raddoppia-parte-il-temporary-shop-summer-edition\\\/\"},\"wordCount\":434,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-bello-che-fa-bene-raddoppia-parte-il-temporary-shop-summer-edition\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/06\\\/temporary-shop-solidale-summer-edition_fb.jpg\",\"keywords\":[\"Bello che fa bene\",\"progetti\"],\"articleSection\":[\"Progetti in Italia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-bello-che-fa-bene-raddoppia-parte-il-temporary-shop-summer-edition\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-bello-che-fa-bene-raddoppia-parte-il-temporary-shop-summer-edition\\\/\",\"name\":\"Il Bello che Fa Bene: temporary shop solidale di Ai.Bi. summer edition\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-bello-che-fa-bene-raddoppia-parte-il-temporary-shop-summer-edition\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-bello-che-fa-bene-raddoppia-parte-il-temporary-shop-summer-edition\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/06\\\/temporary-shop-solidale-summer-edition_fb.jpg\",\"datePublished\":\"2021-06-15T09:15:33+00:00\",\"dateModified\":\"2021-06-15T14:22:37+00:00\",\"description\":\"La summer edition del Temporary Shop Solidale di Ai.Bi. Prodotti di grandi marche per sostenere i progetti in favore di bambini e famiglie in difficolt\u00e0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-bello-che-fa-bene-raddoppia-parte-il-temporary-shop-summer-edition\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-bello-che-fa-bene-raddoppia-parte-il-temporary-shop-summer-edition\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-bello-che-fa-bene-raddoppia-parte-il-temporary-shop-summer-edition\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/06\\\/temporary-shop-solidale-summer-edition_fb.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/06\\\/temporary-shop-solidale-summer-edition_fb.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-bello-che-fa-bene-raddoppia-parte-il-temporary-shop-summer-edition\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Progetti in Italia\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/progetti-in-italia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u201cIl Bello che Fa Bene\u201d raddoppia: parte il temporary shop summer edition\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\",\"name\":\"francescoE\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/francescoe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Il Bello che Fa Bene: temporary shop solidale di Ai.Bi. summer edition","description":"La summer edition del Temporary Shop Solidale di Ai.Bi. Prodotti di grandi marche per sostenere i progetti in favore di bambini e famiglie in difficolt\u00e0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/il-bello-che-fa-bene-raddoppia-parte-il-temporary-shop-summer-edition\/","og_locale":"it_IT","og_type":"article","og_title":"\u201cIl Bello che Fa Bene\u201d raddoppia: parte il temporary shop summer edition","og_description":"La summer edition del Temporary Shop Solidale di Ai.Bi. Prodotti di grandi marche per sostenere i progetti in favore di bambini e famiglie in difficolt\u00e0","og_url":"https:\/\/www.aibi.it\/ita\/il-bello-che-fa-bene-raddoppia-parte-il-temporary-shop-summer-edition\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2021-06-15T09:15:33+00:00","article_modified_time":"2021-06-15T14:22:37+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2021\/06\/temporary-shop-solidale-summer-edition_fb.jpg","type":"image\/jpeg"}],"author":"francescoE","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"francescoE","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/il-bello-che-fa-bene-raddoppia-parte-il-temporary-shop-summer-edition\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/il-bello-che-fa-bene-raddoppia-parte-il-temporary-shop-summer-edition\/"},"author":{"name":"francescoE","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5"},"headline":"\u201cIl Bello che Fa Bene\u201d raddoppia: parte il temporary shop summer edition","datePublished":"2021-06-15T09:15:33+00:00","dateModified":"2021-06-15T14:22:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/il-bello-che-fa-bene-raddoppia-parte-il-temporary-shop-summer-edition\/"},"wordCount":434,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/il-bello-che-fa-bene-raddoppia-parte-il-temporary-shop-summer-edition\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/06\/temporary-shop-solidale-summer-edition_fb.jpg","keywords":["Bello che fa bene","progetti"],"articleSection":["Progetti in Italia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/il-bello-che-fa-bene-raddoppia-parte-il-temporary-shop-summer-edition\/","url":"https:\/\/www.aibi.it\/ita\/il-bello-che-fa-bene-raddoppia-parte-il-temporary-shop-summer-edition\/","name":"Il Bello che Fa Bene: temporary shop solidale di Ai.Bi. summer edition","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/il-bello-che-fa-bene-raddoppia-parte-il-temporary-shop-summer-edition\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/il-bello-che-fa-bene-raddoppia-parte-il-temporary-shop-summer-edition\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/06\/temporary-shop-solidale-summer-edition_fb.jpg","datePublished":"2021-06-15T09:15:33+00:00","dateModified":"2021-06-15T14:22:37+00:00","description":"La summer edition del Temporary Shop Solidale di Ai.Bi. Prodotti di grandi marche per sostenere i progetti in favore di bambini e famiglie in difficolt\u00e0","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/il-bello-che-fa-bene-raddoppia-parte-il-temporary-shop-summer-edition\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/il-bello-che-fa-bene-raddoppia-parte-il-temporary-shop-summer-edition\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/il-bello-che-fa-bene-raddoppia-parte-il-temporary-shop-summer-edition\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2021\/06\/temporary-shop-solidale-summer-edition_fb.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/06\/temporary-shop-solidale-summer-edition_fb.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/il-bello-che-fa-bene-raddoppia-parte-il-temporary-shop-summer-edition\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Progetti in Italia","item":"https:\/\/www.aibi.it\/ita\/category\/progetti-in-italia\/"},{"@type":"ListItem","position":3,"name":"\u201cIl Bello che Fa Bene\u201d raddoppia: parte il temporary shop summer edition"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5","name":"francescoE","url":"https:\/\/www.aibi.it\/ita\/author\/francescoe\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 04:49:26","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/188984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=188984"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/188984\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/188993"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=188984"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=188984"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=188984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}