﻿


{"id":190255,"date":"2021-07-14T09:30:15","date_gmt":"2021-07-14T07:30:15","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=190255"},"modified":"2021-07-14T17:08:31","modified_gmt":"2021-07-14T15:08:31","slug":"adozione-che-emozione-riprendono-gli-abbinamenti-e-io-volo-tre-metri-su-nel-cielo","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozione-che-emozione-riprendono-gli-abbinamenti-e-io-volo-tre-metri-su-nel-cielo\/","title":{"rendered":"Adozione. Che emozione! Riprendono gli abbinamenti e io: &#8220;Volo tre metri su nel cielo!&#8221;"},"content":{"rendered":"<h2>La pandemia e le difficolt\u00e0 non hanno fermato i genitori adottivi, che hanno fatto di tutto per raggiungere i \u201cloro\u201d bambini abbandonati. Ora che le restrizioni si allentano, l\u2019Adozione Internazionale riprende ancor pi\u00f9 vigore, per la gioia e l\u2019entusiasmo di tutti<\/h2>\n<p>Dopo lunghi mesi di lockdown, incertezze, voli cancellati e tanta, tanta paziente attesa, finalmente nelle ultime settimane sono <strong>ripresi gli abbinamenti e le partenze<\/strong> legate alle adozioni internazionali.<br \/>\nLa sede Ai.Bi. in Puglia, per esempio, ha vissuto giorni di grande e gioioso fermento, con la partenza di due coppie: la prima con destinazione <strong>Bulgaria<\/strong>, per il primo viaggio che l\u2019ha portata a conoscere una coppia di sorelline; l\u2019altra, a distanza di un solo giorno, verso la <strong>Romania<\/strong>, dove ad attenderla cera un bimbo. Dopo averlo conosciuto ed essere stata per il primo periodo insieme a lui, la coppia \u00e8 rientrata in Italia e, ora, \u00e8 nuovamente volata in Romania, da cui dovrebbe rientrare, insieme a loro figlio, nel mese di agosto.<\/p>\n<h3><strong>L\u2019entusiasmo di accompagnare i genitori all\u2019adozione<\/strong><\/h3>\n<p>Era da tempo che anche gli operatori non provavano queste <strong>bellissime emozioni<\/strong>: comunicare alle coppie il momento in cui potranno realizzare il loro sogno; abbracciare i loro bambini; trasmettergli l\u2019amore che da anni tengono in serbo e che \u00e8 sbocciato non appena hanno visto in un foto quei visi <strong>bisognosi di affetto e protezione<\/strong>!<br \/>\n\u201cOggi \u2013 racconta Floriana, la responsabile della sede Ai.Bi. in Puglia \u2013 \u00e8 una di quelle giornate in cui <strong>ti senti tre metri sopra il cielo<\/strong>, perch\u00e9 sai che per quei bambini e per quelle coppie l\u2019attesa \u00e8 finita! Il cuore pu\u00f2 esplodere di gioia, e tu ringrazi il Signore per aver fatto in modo di incrociare il loro cammino ed essere un piccolo pezzettino di questo bellissimo ingranaggio che \u00e8 l\u2019adozione\u201d!<\/p>\n<h3><strong>La situazione dei Paesi in cui opera Ai.Bi.<\/strong><\/h3>\n<p>Le attivit\u00e0, dunque, fervono: per la <strong>Bolivia<\/strong>, per esempio, oltre alle 4 coppie che hanno concluso la procedura di adozione tra maggio e giugno, c&#8217;\u00e8 ora una nuova coppia abbinata in attesa di partire, verosimilmente all&#8217;inizio di agosto.<br \/>\nPer la <strong>Russia<\/strong>, le coppie abbinate sono 7, di cui 3 in partenza. Come in partenza sono le 2 coppie abbinate per il <strong>Brasile<\/strong>.<\/p>\n<p>Ben 11, invece, le coppie abbinate in <strong>Cina<\/strong>: per loro l\u2019attesa dura ormai da un anno e mezzo e la speranza \u00e8 che finalmente anche in questo caso si sblocchi la situazione per poter andare a recuperare i loro 11 bambini.<\/p>\n<p>Dalla <strong>Colombia<\/strong> sono rientrate 2 coppie nel 2021 con tre bimbe! Pronte a partire ce ne sono altre tre: una di Cagliari, che accoglier\u00e0 ben quattro bimbi; una di Napoli, che accoglier\u00e0 una bimba di 6 anni; una di Barletta, pronta ad andare a prendere le due bimbe di 9 e 7 anni. In pi\u00f9, \u00e8 arrivata una nuova assegnazione: presto un\u2019altra famiglia gioir\u00e0!<\/p>\n<p>Due bimbi piccoli aspettano in <strong>Albania<\/strong>, dove sono pronte ad arrivare due coppie di genitori: una per un bimbo di 18 mesi, l\u2019altra per una bimba di 8.<\/p>\n<p>Per <strong>Haiti<\/strong>, le due coppie abbinate hanno potuto gi\u00e0 fare la conoscenza dei loro bambini grazie alla decisione del Paese, causa Covid, di sostituire il primo dei due viaggi abitualmente previsti con diverse chiamate tramite Skype. Una coppia \u00e8 pronta a partire a breve per andare a prendere il suo bimbo di 6 anni; l\u2019altra invece dovr\u00e0 attendere ancora un pochino per abbracciare la sua bimba di 4 anni e mezzo.<\/p>\n<p>Per il <strong>Cile<\/strong>, infine, si sta aspettando la conferma dall\u2019Autorit\u00e0 Centrale di tre proposte fatte ad altrettante coppie disposte a partire! Incrociamo le dita!<br \/>\nIn totale, sono <strong>29 gli abbinamenti effettuati<\/strong>: tutti, sempre, con l\u2019entusiasmo della \u201cprima volta\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La pandemia e le difficolt&agrave; non hanno fermato i genitori adottivi, che hanno fatto di tutto per raggiungere i &ldquo;loro&rdquo; bambini abbandonati. Ora che le restrizioni si allentano, l&rsquo;Adozione Internazionale riprende ancor pi&ugrave; vigore, per la gioia e l&rsquo;entusiasmo di tutti Dopo lunghi mesi di lockdown, incertezze, voli cancellati e [&hellip;]<\/p>\n","protected":false},"author":102,"featured_media":190260,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[172],"tags":[660,347],"class_list":["post-190255","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-internazionale","tag-abbinamento","tag-adozione-internazionale"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozione. Che emozione! Riprendono gli abbinamenti<\/title>\n<meta name=\"description\" content=\"Dopo la pandemia, con le restrizioni che si allentano, riprendono gli abbinamenti e riparte l\u2019Adozione Internazionale, per la gioia e l\u2019entusiasmo di tutti\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozione-che-emozione-riprendono-gli-abbinamenti-e-io-volo-tre-metri-su-nel-cielo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozione. Che emozione! Riprendono gli abbinamenti e io: &quot;Volo tre metri su nel cielo!&quot;\" \/>\n<meta property=\"og:description\" content=\"Dopo la pandemia, con le restrizioni che si allentano, riprendono gli abbinamenti e riparte l\u2019Adozione Internazionale, per la gioia e l\u2019entusiasmo di tutti\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozione-che-emozione-riprendono-gli-abbinamenti-e-io-volo-tre-metri-su-nel-cielo\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-14T07:30:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-14T15:08:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2021\/07\/volo-tre-metri-su-nel-cielo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-che-emozione-riprendono-gli-abbinamenti-e-io-volo-tre-metri-su-nel-cielo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-che-emozione-riprendono-gli-abbinamenti-e-io-volo-tre-metri-su-nel-cielo\\\/\"},\"author\":{\"name\":\"francescoE\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\"},\"headline\":\"Adozione. Che emozione! Riprendono gli abbinamenti e io: &#8220;Volo tre metri su nel cielo!&#8221;\",\"datePublished\":\"2021-07-14T07:30:15+00:00\",\"dateModified\":\"2021-07-14T15:08:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-che-emozione-riprendono-gli-abbinamenti-e-io-volo-tre-metri-su-nel-cielo\\\/\"},\"wordCount\":612,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-che-emozione-riprendono-gli-abbinamenti-e-io-volo-tre-metri-su-nel-cielo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/07\\\/volo-tre-metri-su-nel-cielo.jpg\",\"keywords\":[\"abbinamento\",\"Adozione Internazionale\"],\"articleSection\":[\"Adozione Internazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-che-emozione-riprendono-gli-abbinamenti-e-io-volo-tre-metri-su-nel-cielo\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-che-emozione-riprendono-gli-abbinamenti-e-io-volo-tre-metri-su-nel-cielo\\\/\",\"name\":\"Adozione. Che emozione! Riprendono gli abbinamenti\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-che-emozione-riprendono-gli-abbinamenti-e-io-volo-tre-metri-su-nel-cielo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-che-emozione-riprendono-gli-abbinamenti-e-io-volo-tre-metri-su-nel-cielo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/07\\\/volo-tre-metri-su-nel-cielo.jpg\",\"datePublished\":\"2021-07-14T07:30:15+00:00\",\"dateModified\":\"2021-07-14T15:08:31+00:00\",\"description\":\"Dopo la pandemia, con le restrizioni che si allentano, riprendono gli abbinamenti e riparte l\u2019Adozione Internazionale, per la gioia e l\u2019entusiasmo di tutti\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-che-emozione-riprendono-gli-abbinamenti-e-io-volo-tre-metri-su-nel-cielo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-che-emozione-riprendono-gli-abbinamenti-e-io-volo-tre-metri-su-nel-cielo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-che-emozione-riprendono-gli-abbinamenti-e-io-volo-tre-metri-su-nel-cielo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/07\\\/volo-tre-metri-su-nel-cielo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/07\\\/volo-tre-metri-su-nel-cielo.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-che-emozione-riprendono-gli-abbinamenti-e-io-volo-tre-metri-su-nel-cielo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione Internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-internazionale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozione. Che emozione! Riprendono gli abbinamenti e io: &#8220;Volo tre metri su nel cielo!&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\",\"name\":\"francescoE\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/francescoe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozione. Che emozione! Riprendono gli abbinamenti","description":"Dopo la pandemia, con le restrizioni che si allentano, riprendono gli abbinamenti e riparte l\u2019Adozione Internazionale, per la gioia e l\u2019entusiasmo di tutti","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozione-che-emozione-riprendono-gli-abbinamenti-e-io-volo-tre-metri-su-nel-cielo\/","og_locale":"it_IT","og_type":"article","og_title":"Adozione. Che emozione! Riprendono gli abbinamenti e io: \"Volo tre metri su nel cielo!\"","og_description":"Dopo la pandemia, con le restrizioni che si allentano, riprendono gli abbinamenti e riparte l\u2019Adozione Internazionale, per la gioia e l\u2019entusiasmo di tutti","og_url":"https:\/\/www.aibi.it\/ita\/adozione-che-emozione-riprendono-gli-abbinamenti-e-io-volo-tre-metri-su-nel-cielo\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2021-07-14T07:30:15+00:00","article_modified_time":"2021-07-14T15:08:31+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2021\/07\/volo-tre-metri-su-nel-cielo.jpg","type":"image\/jpeg"}],"author":"francescoE","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"francescoE","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozione-che-emozione-riprendono-gli-abbinamenti-e-io-volo-tre-metri-su-nel-cielo\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-che-emozione-riprendono-gli-abbinamenti-e-io-volo-tre-metri-su-nel-cielo\/"},"author":{"name":"francescoE","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5"},"headline":"Adozione. Che emozione! Riprendono gli abbinamenti e io: &#8220;Volo tre metri su nel cielo!&#8221;","datePublished":"2021-07-14T07:30:15+00:00","dateModified":"2021-07-14T15:08:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-che-emozione-riprendono-gli-abbinamenti-e-io-volo-tre-metri-su-nel-cielo\/"},"wordCount":612,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-che-emozione-riprendono-gli-abbinamenti-e-io-volo-tre-metri-su-nel-cielo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/07\/volo-tre-metri-su-nel-cielo.jpg","keywords":["abbinamento","Adozione Internazionale"],"articleSection":["Adozione Internazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozione-che-emozione-riprendono-gli-abbinamenti-e-io-volo-tre-metri-su-nel-cielo\/","url":"https:\/\/www.aibi.it\/ita\/adozione-che-emozione-riprendono-gli-abbinamenti-e-io-volo-tre-metri-su-nel-cielo\/","name":"Adozione. Che emozione! Riprendono gli abbinamenti","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-che-emozione-riprendono-gli-abbinamenti-e-io-volo-tre-metri-su-nel-cielo\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-che-emozione-riprendono-gli-abbinamenti-e-io-volo-tre-metri-su-nel-cielo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/07\/volo-tre-metri-su-nel-cielo.jpg","datePublished":"2021-07-14T07:30:15+00:00","dateModified":"2021-07-14T15:08:31+00:00","description":"Dopo la pandemia, con le restrizioni che si allentano, riprendono gli abbinamenti e riparte l\u2019Adozione Internazionale, per la gioia e l\u2019entusiasmo di tutti","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-che-emozione-riprendono-gli-abbinamenti-e-io-volo-tre-metri-su-nel-cielo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozione-che-emozione-riprendono-gli-abbinamenti-e-io-volo-tre-metri-su-nel-cielo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozione-che-emozione-riprendono-gli-abbinamenti-e-io-volo-tre-metri-su-nel-cielo\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2021\/07\/volo-tre-metri-su-nel-cielo.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/07\/volo-tre-metri-su-nel-cielo.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozione-che-emozione-riprendono-gli-abbinamenti-e-io-volo-tre-metri-su-nel-cielo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione Internazionale","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-internazionale\/"},{"@type":"ListItem","position":3,"name":"Adozione. Che emozione! Riprendono gli abbinamenti e io: &#8220;Volo tre metri su nel cielo!&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5","name":"francescoE","url":"https:\/\/www.aibi.it\/ita\/author\/francescoe\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 09:58:35","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/190255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=190255"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/190255\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/190260"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=190255"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=190255"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=190255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}