﻿


{"id":190479,"date":"2021-07-23T08:00:33","date_gmt":"2021-07-23T06:00:33","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=190479"},"modified":"2021-07-23T17:13:40","modified_gmt":"2021-07-23T15:13:40","slug":"al-via-le-olimpiadi-di-tokyo-2020-messaggio-di-speranza-e-integrazione","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/al-via-le-olimpiadi-di-tokyo-2020-messaggio-di-speranza-e-integrazione\/","title":{"rendered":"Al via le Olimpiadi di Tokyo 2020: messaggio di speranza e integrazione"},"content":{"rendered":"<h2><strong><b><span style=\"color: #000000;\">Alle 13 di Venerd\u00ec 23\u00a0<span id=\"OBJ_PREFIX_DWT8582_com_zimbra_date\" class=\"Object\" role=\"link\">luglio\u00a0<\/span>si terr\u00e0 la cerimonia di apertura delle XXXII Olimpiadi di Tokyo 2020.<\/span> <\/b><b>Paola Egonu scelta come portabandiera del vessillo a cinque cerchi: la <\/b><b>prima storia bellissima<\/b> di questi Giochi<\/strong><\/h2>\n<p>Probabilmente sono i <strong>Giochi Olimpici pi\u00f9 attesi di sempre<\/strong>, proprio in senso cronologico, visto che si chiamano \u201cOlimpiadi di Tokyo 2020\u201d e si disputano nel 2021; ma sappiamo tutti com\u2019\u00e8 andata.<br \/>\nPer dirla tutta, in realt\u00e0, bisognerebbe affermare \u201csappiamo come sta ancora andando\u201d, visto che la Pandemia \u00e8 tutt\u2019altro che sconfitta e che gi\u00e0 non pochi atleti hanno dovuto rinunciare a partecipare perch\u00e9 ammalatisi. Ma nonostante le restrizioni, l\u2019assenza di pubblico, una cerimonia di apertura davanti a \u201cpochi intimi\u201d sugli spalti, protocolli estenuanti e l\u2019incognita di cosa succeder\u00e0 durante le tre settimane di competizioni\u2026 <strong>I Giochi Olimpici rimangono i Giochi Olimpici<\/strong>, uno degli ultimi eventi che, nonostante il giro d\u2019affari planetario che muovono, mantiene quel romanticismo e quell\u2019<strong>epica del racconto<\/strong> che smuovono l\u2019animo di atleti e spettatori di tutto il mondo.<\/p>\n<h3><strong>Olimpiadi di Tokyo: ripartiamo da qui<\/strong><\/h3>\n<p>Ecco, dunque, che a poche ore dall\u2019apertura ufficiale dei XXXII Giochi Olimpici (la Cerimonia di inaugurazione si svolger\u00e0 <strong>venerd\u00ec 23 a partire dalle ore 13 italiane<\/strong>), pi\u00f9 delle preoccupazioni, delle polemiche che non mancano mai, delle incognite\u2026 \u00e8 giusto guardare ai Giochi anche come a un <strong>messaggio di speranza<\/strong>. Lo ha detto il giornalista <strong>Italo Cucci<\/strong> intervenendo alla trasmissione di Radio Vaticana <em>Non solo sport<\/em>: \u201cA queste Olimpiadi di Tokyo <strong>nascer\u00e0 quell\u2019ottimismo e la speranza che solo i giovani sanno dare<\/strong>\u201d. Un bel messaggio davvero, che porta un po\u2019 alla memoria, volendo fare un paragone, l\u2019atmosfera che si viveva prima dei giochi di Roma, quando un\u2019Italia con ancora le cicatrici della sconfitta nella Seconda Guerra Mondiale guardava ai Giochi come momento, non solo simbolico, di <strong>rinascita, di benessere e di progresso<\/strong>. Chiss\u00e0, allora, che anche le giornate di Tokyo e l\u2019umanit\u00e0 propria degli eventi agonistici non possano <strong>indicare la strada per uscire definitivamente dalla pandemia<\/strong>.<\/p>\n<h3><strong>La bella storia di integrazione di Paola Egonu alle <\/strong><strong>Olimpiadi di Tokyo<\/strong><\/h3>\n<p>E di storie belle da raccontare ce n\u2019\u00e8 gi\u00e0 una prima ancora di cominciare. Quella della <strong>pallavolista italiana Paola Egonu<\/strong>, scelta dal CIO per essere una degli atleti che porteranno la bandiera con i cinque cerchi, simbolo delle Olimpiadi, nella sfilata di apertura dei Giochi. Una grande emozione per la ragazza classe 1998, nata a Cittadella da genitori nigeriani, che \u00e8 scoppiata a piangere non appena il Presidente del Coni Giovanni Malag\u00f2 le ha comunicato la notizia: \u201cPerch\u00e9 &#8211; sono le sue parole riportate da <em>Il Sole 24 Ore<\/em> &#8211; mi ritrovo a <strong>rappresentare gli atleti di tutto il mondo<\/strong>, ed \u00e8 una grossa responsabilit\u00e0: attraverso me <strong>esprimer\u00f2 e sfiler\u00f2 per ogni atleta di questo pianeta<\/strong>\u201d.<br \/>\nE sfiler\u00e0, anche, ci permettiamo di aggiungere, per tutti quei <strong>bambini<\/strong> che trovano degli ostacoli nel loro percorso di integrazione e per quei genitori che vorrebbero adottare ma sono preoccupati di accogliere bambini di altre nazionalit\u00e0 proprio per via delle difficolt\u00e0 di integrazione. Paola Egonu \u00e8 un esempio splendido in tal senso: la <strong>prima storia bellissima<\/strong> di questa Olimpiade che sta per cominciare.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alle 13 di Venerd&igrave; 23&nbsp;luglio&nbsp;si terr&agrave; la cerimonia di apertura delle XXXII Olimpiadi di Tokyo 2020. Paola Egonu scelta come portabandiera del vessillo a cinque cerchi: la prima storia bellissima di questi Giochi Probabilmente sono i Giochi Olimpici pi&ugrave; attesi di sempre, proprio in senso cronologico, visto che si chiamano [&hellip;]<\/p>\n","protected":false},"author":102,"featured_media":190480,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[818,664,794],"class_list":["post-190479","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews","tag-integrazione","tag-razzismo","tag-sport"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Olimpiadi di Tokyo 2020 messaggio di speranza e integrazione<\/title>\n<meta name=\"description\" content=\"Olimpiadi di Tokyo 2020: tra restrizioni e timori, la speranza \u00e8 che siano un evento da cui ripartire. Cominciando dal messaggio di integrazione di Paola Egonu\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/al-via-le-olimpiadi-di-tokyo-2020-messaggio-di-speranza-e-integrazione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Al via le Olimpiadi di Tokyo 2020: messaggio di speranza e integrazione\" \/>\n<meta property=\"og:description\" content=\"Olimpiadi di Tokyo 2020: tra restrizioni e timori, la speranza \u00e8 che siano un evento da cui ripartire. Cominciando dal messaggio di integrazione di Paola Egonu\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/al-via-le-olimpiadi-di-tokyo-2020-messaggio-di-speranza-e-integrazione\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-23T06:00:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-23T15:13:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2021\/07\/Olimpiadi-Tokyo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/al-via-le-olimpiadi-di-tokyo-2020-messaggio-di-speranza-e-integrazione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/al-via-le-olimpiadi-di-tokyo-2020-messaggio-di-speranza-e-integrazione\\\/\"},\"author\":{\"name\":\"francescoE\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\"},\"headline\":\"Al via le Olimpiadi di Tokyo 2020: messaggio di speranza e integrazione\",\"datePublished\":\"2021-07-23T06:00:33+00:00\",\"dateModified\":\"2021-07-23T15:13:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/al-via-le-olimpiadi-di-tokyo-2020-messaggio-di-speranza-e-integrazione\\\/\"},\"wordCount\":526,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/al-via-le-olimpiadi-di-tokyo-2020-messaggio-di-speranza-e-integrazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/07\\\/Olimpiadi-Tokyo.jpg\",\"keywords\":[\"integrazione\",\"razzismo\",\"sport\"],\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/al-via-le-olimpiadi-di-tokyo-2020-messaggio-di-speranza-e-integrazione\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/al-via-le-olimpiadi-di-tokyo-2020-messaggio-di-speranza-e-integrazione\\\/\",\"name\":\"Olimpiadi di Tokyo 2020 messaggio di speranza e integrazione\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/al-via-le-olimpiadi-di-tokyo-2020-messaggio-di-speranza-e-integrazione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/al-via-le-olimpiadi-di-tokyo-2020-messaggio-di-speranza-e-integrazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/07\\\/Olimpiadi-Tokyo.jpg\",\"datePublished\":\"2021-07-23T06:00:33+00:00\",\"dateModified\":\"2021-07-23T15:13:40+00:00\",\"description\":\"Olimpiadi di Tokyo 2020: tra restrizioni e timori, la speranza \u00e8 che siano un evento da cui ripartire. Cominciando dal messaggio di integrazione di Paola Egonu\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/al-via-le-olimpiadi-di-tokyo-2020-messaggio-di-speranza-e-integrazione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/al-via-le-olimpiadi-di-tokyo-2020-messaggio-di-speranza-e-integrazione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/al-via-le-olimpiadi-di-tokyo-2020-messaggio-di-speranza-e-integrazione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/07\\\/Olimpiadi-Tokyo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/07\\\/Olimpiadi-Tokyo.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/al-via-le-olimpiadi-di-tokyo-2020-messaggio-di-speranza-e-integrazione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Al via le Olimpiadi di Tokyo 2020: messaggio di speranza e integrazione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\",\"name\":\"francescoE\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/francescoe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Olimpiadi di Tokyo 2020 messaggio di speranza e integrazione","description":"Olimpiadi di Tokyo 2020: tra restrizioni e timori, la speranza \u00e8 che siano un evento da cui ripartire. Cominciando dal messaggio di integrazione di Paola Egonu","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/al-via-le-olimpiadi-di-tokyo-2020-messaggio-di-speranza-e-integrazione\/","og_locale":"it_IT","og_type":"article","og_title":"Al via le Olimpiadi di Tokyo 2020: messaggio di speranza e integrazione","og_description":"Olimpiadi di Tokyo 2020: tra restrizioni e timori, la speranza \u00e8 che siano un evento da cui ripartire. Cominciando dal messaggio di integrazione di Paola Egonu","og_url":"https:\/\/www.aibi.it\/ita\/al-via-le-olimpiadi-di-tokyo-2020-messaggio-di-speranza-e-integrazione\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2021-07-23T06:00:33+00:00","article_modified_time":"2021-07-23T15:13:40+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2021\/07\/Olimpiadi-Tokyo.jpg","type":"image\/jpeg"}],"author":"francescoE","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"francescoE","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/al-via-le-olimpiadi-di-tokyo-2020-messaggio-di-speranza-e-integrazione\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/al-via-le-olimpiadi-di-tokyo-2020-messaggio-di-speranza-e-integrazione\/"},"author":{"name":"francescoE","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5"},"headline":"Al via le Olimpiadi di Tokyo 2020: messaggio di speranza e integrazione","datePublished":"2021-07-23T06:00:33+00:00","dateModified":"2021-07-23T15:13:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/al-via-le-olimpiadi-di-tokyo-2020-messaggio-di-speranza-e-integrazione\/"},"wordCount":526,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/al-via-le-olimpiadi-di-tokyo-2020-messaggio-di-speranza-e-integrazione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/07\/Olimpiadi-Tokyo.jpg","keywords":["integrazione","razzismo","sport"],"articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/al-via-le-olimpiadi-di-tokyo-2020-messaggio-di-speranza-e-integrazione\/","url":"https:\/\/www.aibi.it\/ita\/al-via-le-olimpiadi-di-tokyo-2020-messaggio-di-speranza-e-integrazione\/","name":"Olimpiadi di Tokyo 2020 messaggio di speranza e integrazione","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/al-via-le-olimpiadi-di-tokyo-2020-messaggio-di-speranza-e-integrazione\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/al-via-le-olimpiadi-di-tokyo-2020-messaggio-di-speranza-e-integrazione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/07\/Olimpiadi-Tokyo.jpg","datePublished":"2021-07-23T06:00:33+00:00","dateModified":"2021-07-23T15:13:40+00:00","description":"Olimpiadi di Tokyo 2020: tra restrizioni e timori, la speranza \u00e8 che siano un evento da cui ripartire. Cominciando dal messaggio di integrazione di Paola Egonu","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/al-via-le-olimpiadi-di-tokyo-2020-messaggio-di-speranza-e-integrazione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/al-via-le-olimpiadi-di-tokyo-2020-messaggio-di-speranza-e-integrazione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/al-via-le-olimpiadi-di-tokyo-2020-messaggio-di-speranza-e-integrazione\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2021\/07\/Olimpiadi-Tokyo.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/07\/Olimpiadi-Tokyo.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/al-via-le-olimpiadi-di-tokyo-2020-messaggio-di-speranza-e-integrazione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Al via le Olimpiadi di Tokyo 2020: messaggio di speranza e integrazione"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5","name":"francescoE","url":"https:\/\/www.aibi.it\/ita\/author\/francescoe\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 13:58:28","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/190479","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=190479"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/190479\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/190480"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=190479"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=190479"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=190479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}