﻿


{"id":190623,"date":"2021-07-27T07:45:14","date_gmt":"2021-07-27T05:45:14","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=190623"},"modified":"2021-07-27T17:46:46","modified_gmt":"2021-07-27T15:46:46","slug":"adozione-ecco-cosa-mi-ricordo-di-quando-vi-ho-incontrato-per-la-prima-volta","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozione-ecco-cosa-mi-ricordo-di-quando-vi-ho-incontrato-per-la-prima-volta\/","title":{"rendered":"Adozione. Ecco cosa mi ricordo di quando vi ho incontrato per la prima volta"},"content":{"rendered":"<h2 style=\"font-weight: 400;\"><strong>Miller ricordava il pianto, la faccia rossa della mamma e la macchina su cui siamo arrivati, inoltre, ci ha tenuto a precisare che finalmente erano arrivati i suoi veri genitori!<\/strong><\/h2>\n<p style=\"font-weight: 400;\"><strong>\u00a0<\/strong><em>\u201cOgni figlio \u00e8 un dono: come tale va atteso, anzi bisogna imparare ad attenderlo\u201d.<\/em><\/p>\n<p style=\"font-weight: 400;\">Questa \u00e8 la frase di Padre Mario Colombo che accoglie chi entra nella pagina di Ai.Bi. dedicata all\u2019adozione.<\/p>\n<p style=\"font-weight: 400;\">Per diventare genitori adottivi desiderio di accogliere e tanto cuore sono davvero indispensabili ma \u00e8 fondamentale anche\u00a0<strong>conoscenza e preparazione.<\/strong><\/p>\n<p style=\"font-weight: 400;\">Per rispondere all\u2019esigenza delle coppie di essere formate ed informate, Ai.Bi. organizza un corso dal titolo evocativo\u00a0<strong>\u201cL\u2019incontro con mio figlio\u201d,<\/strong>\u00a0con l\u2019obiettivo di preparare nel migliore dei modi i futuri genitori adottivi all\u2019incontro con i loro figli.<\/p>\n<p style=\"font-weight: 400;\">Al corso, che avviene in modalit\u00e0 on line, possono partecipare le coppie in possesso del decreto di idoneit\u00e0 che abbiano gi\u00e0 partecipato al primo incontro informativo sull\u2019adozione.<\/p>\n<h3 style=\"font-weight: 400;\"><strong>Cosa succede ai corsi &#8220;l\u2019incontro con mio figlio?\u201d<\/strong><\/h3>\n<p style=\"font-weight: 400;\"><strong>\u00a0<\/strong>Gli incontri di gruppo sono condotti da\u00a0<strong>psicologhe specializzate<\/strong>\u00a0in adozione internazionale, affiancate da\u00a0<strong>famiglie adottive esperte<\/strong>. Noi di Ai.Bi. infatti, riteniamo che sia davvero importante, per le coppie che stanno muovendo i primi passi sul sentiero dell\u2019adozione poter ascoltare e potersi confrontare con famiglie che questo percorso lo hanno gi\u00e0 concluso. Proprio come Roberta e Massimo.<\/p>\n<p style=\"font-weight: 400;\">Durante una delle loro testimonianze \u00e8 accaduto un evento inaspettato e davvero emozionante: Chengbin e Miller, i loro figli adottivi, che passavano di l\u00ec, hanno deciso di fermarsi per un saluto. A quel punto, una delle coppie presenti, ha posto loro una domanda molto carina. La risposta anche per Roberta e Massimo \u00e8 stata una rivelazione: \u201cNon ce l\u2019avevano mai detto\u201d raccontano\u2026<\/p>\n<p style=\"font-weight: 400;\">D\u2019un tratto sono apparsi i nostri figli, Chengbin e Miller. Le coppie hanno chiesto loro cosa ricordassero del giorno del primo incontro con noi&#8230;<\/p>\n<h3 style=\"font-weight: 400;\"><strong>Le loro risposte sono state una rivelazione anche per noi!\u00a0<\/strong><\/h3>\n<p style=\"font-weight: 400;\"><strong>\u00a0<\/strong>Chengbin ricordava i vestiti che indossavamo ed il pianto della mamma\u2026\u00a0 Miller ricordava il pianto, la faccia rossa della mamma e la macchina su cui siamo arrivati\u2026 inoltre ci ha tenuto a precisare che finalmente erano arrivati i suoi veri genitori.<\/p>\n<p style=\"font-weight: 400;\">Poi\u00a0<strong>la dott.ssa Moretti<\/strong>\u00a0ha chiesto se volessero dare un consiglio alle coppie e Miller ha risposto che per lui la cosa pi\u00f9 importante \u00e8 far capire e sentire ai figli che\u00a0<strong>mamma e pap\u00e0 ci saranno per sempre<\/strong>\u00a0ma ha sottolineato che bisogna farlo capire\u00a0<strong>con i gesti,<\/strong>\u00a0quindi essendo sempre presenti e non a parole, perch\u00e9 le sole parole non danno sicurezza&#8230;ed anche questa risposta \u00e8 stata per noi inaspettata&#8230;<\/p>\n<h3 style=\"font-weight: 400;\"><strong>L\u2019adozione \u00e8 davvero una cosa meravigliosa!<\/strong><\/h3>\n<p style=\"font-weight: 400;\">Per maggiori informazioni sull\u2019adozione o per partecipare ad un primo incontro formativo\u00a0<a href=\"https:\/\/www.aibi.it\/ita\/attivita\/adozione-internazionale\/\">QUI<\/a><\/p>\n<p style=\"font-weight: 400;\">\n","protected":false},"excerpt":{"rendered":"<p>Miller ricordava il pianto, la faccia rossa della mamma e la macchina su cui siamo arrivati, inoltre, ci ha tenuto a precisare che finalmente erano arrivati i suoi veri genitori! &nbsp;&ldquo;Ogni figlio &egrave; un dono: come tale va atteso, anzi bisogna imparare ad attenderlo&rdquo;. Questa &egrave; la frase di Padre [&hellip;]<\/p>\n","protected":false},"author":97,"featured_media":190624,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[172],"tags":[279],"class_list":["post-190623","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-internazionale","tag-adozione"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozione. Ecco cosa mi ricordo di quando vi ho incontrato per la prima volta - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"Adozione. Miller ricordava il pianto, la faccia rossa della mamma e la macchina su cui siamo arrivati, inoltre, ci ha tenuto a precisare che finalmente erano arrivati i suoi veri genitori!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozione-ecco-cosa-mi-ricordo-di-quando-vi-ho-incontrato-per-la-prima-volta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozione. Ecco cosa mi ricordo di quando vi ho incontrato per la prima volta\" \/>\n<meta property=\"og:description\" content=\"Miller ricordava il pianto, la faccia rossa della mamma e la macchina su cui siamo arrivati, inoltre, ci ha tenuto a precisare che finalmente erano arrivati i suoi veri genitori!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozione-ecco-cosa-mi-ricordo-di-quando-vi-ho-incontrato-per-la-prima-volta\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-27T05:45:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-27T15:46:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2021\/07\/adozione-2-6.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mc.sabatini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mc.sabatini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-ecco-cosa-mi-ricordo-di-quando-vi-ho-incontrato-per-la-prima-volta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-ecco-cosa-mi-ricordo-di-quando-vi-ho-incontrato-per-la-prima-volta\\\/\"},\"author\":{\"name\":\"mc.sabatini\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\"},\"headline\":\"Adozione. Ecco cosa mi ricordo di quando vi ho incontrato per la prima volta\",\"datePublished\":\"2021-07-27T05:45:14+00:00\",\"dateModified\":\"2021-07-27T15:46:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-ecco-cosa-mi-ricordo-di-quando-vi-ho-incontrato-per-la-prima-volta\\\/\"},\"wordCount\":463,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-ecco-cosa-mi-ricordo-di-quando-vi-ho-incontrato-per-la-prima-volta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/07\\\/adozione-2-6.jpg\",\"keywords\":[\"adozione\"],\"articleSection\":[\"Adozione Internazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-ecco-cosa-mi-ricordo-di-quando-vi-ho-incontrato-per-la-prima-volta\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-ecco-cosa-mi-ricordo-di-quando-vi-ho-incontrato-per-la-prima-volta\\\/\",\"name\":\"Adozione. Ecco cosa mi ricordo di quando vi ho incontrato per la prima volta - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-ecco-cosa-mi-ricordo-di-quando-vi-ho-incontrato-per-la-prima-volta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-ecco-cosa-mi-ricordo-di-quando-vi-ho-incontrato-per-la-prima-volta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/07\\\/adozione-2-6.jpg\",\"datePublished\":\"2021-07-27T05:45:14+00:00\",\"dateModified\":\"2021-07-27T15:46:46+00:00\",\"description\":\"Adozione. Miller ricordava il pianto, la faccia rossa della mamma e la macchina su cui siamo arrivati, inoltre, ci ha tenuto a precisare che finalmente erano arrivati i suoi veri genitori!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-ecco-cosa-mi-ricordo-di-quando-vi-ho-incontrato-per-la-prima-volta\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-ecco-cosa-mi-ricordo-di-quando-vi-ho-incontrato-per-la-prima-volta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-ecco-cosa-mi-ricordo-di-quando-vi-ho-incontrato-per-la-prima-volta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/07\\\/adozione-2-6.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/07\\\/adozione-2-6.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-ecco-cosa-mi-ricordo-di-quando-vi-ho-incontrato-per-la-prima-volta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione Internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-internazionale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozione. Ecco cosa mi ricordo di quando vi ho incontrato per la prima volta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\",\"name\":\"mc.sabatini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/marias\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozione. Ecco cosa mi ricordo di quando vi ho incontrato per la prima volta - Ai.Bi. Amici dei Bambini","description":"Adozione. Miller ricordava il pianto, la faccia rossa della mamma e la macchina su cui siamo arrivati, inoltre, ci ha tenuto a precisare che finalmente erano arrivati i suoi veri genitori!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozione-ecco-cosa-mi-ricordo-di-quando-vi-ho-incontrato-per-la-prima-volta\/","og_locale":"it_IT","og_type":"article","og_title":"Adozione. Ecco cosa mi ricordo di quando vi ho incontrato per la prima volta","og_description":"Miller ricordava il pianto, la faccia rossa della mamma e la macchina su cui siamo arrivati, inoltre, ci ha tenuto a precisare che finalmente erano arrivati i suoi veri genitori!","og_url":"https:\/\/www.aibi.it\/ita\/adozione-ecco-cosa-mi-ricordo-di-quando-vi-ho-incontrato-per-la-prima-volta\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2021-07-27T05:45:14+00:00","article_modified_time":"2021-07-27T15:46:46+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2021\/07\/adozione-2-6.jpg","type":"image\/jpeg"}],"author":"mc.sabatini","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"mc.sabatini","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozione-ecco-cosa-mi-ricordo-di-quando-vi-ho-incontrato-per-la-prima-volta\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-ecco-cosa-mi-ricordo-di-quando-vi-ho-incontrato-per-la-prima-volta\/"},"author":{"name":"mc.sabatini","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938"},"headline":"Adozione. Ecco cosa mi ricordo di quando vi ho incontrato per la prima volta","datePublished":"2021-07-27T05:45:14+00:00","dateModified":"2021-07-27T15:46:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-ecco-cosa-mi-ricordo-di-quando-vi-ho-incontrato-per-la-prima-volta\/"},"wordCount":463,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-ecco-cosa-mi-ricordo-di-quando-vi-ho-incontrato-per-la-prima-volta\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/07\/adozione-2-6.jpg","keywords":["adozione"],"articleSection":["Adozione Internazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozione-ecco-cosa-mi-ricordo-di-quando-vi-ho-incontrato-per-la-prima-volta\/","url":"https:\/\/www.aibi.it\/ita\/adozione-ecco-cosa-mi-ricordo-di-quando-vi-ho-incontrato-per-la-prima-volta\/","name":"Adozione. Ecco cosa mi ricordo di quando vi ho incontrato per la prima volta - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-ecco-cosa-mi-ricordo-di-quando-vi-ho-incontrato-per-la-prima-volta\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-ecco-cosa-mi-ricordo-di-quando-vi-ho-incontrato-per-la-prima-volta\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/07\/adozione-2-6.jpg","datePublished":"2021-07-27T05:45:14+00:00","dateModified":"2021-07-27T15:46:46+00:00","description":"Adozione. Miller ricordava il pianto, la faccia rossa della mamma e la macchina su cui siamo arrivati, inoltre, ci ha tenuto a precisare che finalmente erano arrivati i suoi veri genitori!","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-ecco-cosa-mi-ricordo-di-quando-vi-ho-incontrato-per-la-prima-volta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozione-ecco-cosa-mi-ricordo-di-quando-vi-ho-incontrato-per-la-prima-volta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozione-ecco-cosa-mi-ricordo-di-quando-vi-ho-incontrato-per-la-prima-volta\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2021\/07\/adozione-2-6.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/07\/adozione-2-6.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozione-ecco-cosa-mi-ricordo-di-quando-vi-ho-incontrato-per-la-prima-volta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione Internazionale","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-internazionale\/"},{"@type":"ListItem","position":3,"name":"Adozione. Ecco cosa mi ricordo di quando vi ho incontrato per la prima volta"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938","name":"mc.sabatini","url":"https:\/\/www.aibi.it\/ita\/author\/marias\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 01:08:21","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/190623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/97"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=190623"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/190623\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/190624"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=190623"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=190623"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=190623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}