﻿


{"id":190802,"date":"2021-08-04T09:00:50","date_gmt":"2021-08-04T07:00:50","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=190802"},"modified":"2022-07-25T12:16:41","modified_gmt":"2022-07-25T10:16:41","slug":"marocco-perche-sostenere-a-distanza-un-careleaver-ahmed-ve-lo-spiega","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/marocco-perche-sostenere-a-distanza-un-careleaver-ahmed-ve-lo-spiega\/","title":{"rendered":"Marocco. Perch\u00e9 sostenere a distanza un careleaver? Ahmed ve lo spiega"},"content":{"rendered":"<h2>I giovani della Maison Akkari si impegnano molto nel loro percorso scolastico per costruire il proprio futuro, supportati dal <a href=\"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/attivazione-adozione-a-distanza\/?scelta=25&amp;progetto=Marocco\">Sostegno a Distanza<\/a><\/h2>\n<p>Per i bambini abbandonati la vita all\u2019interno dei centri di accoglienza non \u00e8 certo semplice e lineare: oltre all\u2019accompagnamento dell\u2019abbandono, il bisogno di soddisfare i bisogni primari come cibarsi, avere accesso all\u2019educazione, alla sanit\u00e0, cosi come il bisogno di un sostegno psicologico o di cimentarsi in attivit\u00e0 ludiche, si aggiunge il grande impegno necessario per la preparazione di un progetto di vita adatto alle proprie esigenze, interessi e propensioni, la crescita all\u2019interno del centro, nonch\u00e9 il completamento del percorso scolastico prima di lasciare l\u2019istituto.<\/p>\n<p><strong>Questa realt\u00e0 Ahmed e i suoi amici la conoscono molto bene sin dall\u2019infanzia<\/strong>.<\/p>\n<p>Nato da genitori sconosciuti, Ahmed \u00e8 un beneficiario della <strong>Maison Akkari<\/strong>, situata nell\u2019omonimo quartiere della capitale marocchina, Rabat. Ci \u00e8 arrivato da piccolino e, <strong>bench\u00e9 non abbia mai provato cosa sia l\u2019amore di una famiglia, il sostegno e l\u2019accompagnamento del personale del Centro e dei sostenitori e la vicinanza con i suoi coetanei gli hanno dato la forza di non abbattersi e di provare a costruirsi un futuro degno dei suoi sforzi<\/strong>.<\/p>\n<p>Da anni Ai.Bi. porta avanti il progetto di <strong>Sostegno a Distanza<\/strong> presso il centro Akkari di Rabat. <strong>Qui vivono sia bambini la cui famiglia riversa in una situazione difficile, sia bambini abbandonati, dai pi\u00f9 piccoli ai pi\u00f9 giovani che si apprestano a prendere il diploma di maturit\u00e0 e lasciare definitivamente il Centro<\/strong>. Grazie al progetto di Sostegno a Distanza, Ai.Bi. continua a garantire la presenza di operatori nel Centro (un\u2019assistente sociale, uno psicologo e un ortofonista) cosi come materiali didattici.<\/p>\n<p>Ahmed \u00e8 uno dei beneficiari di questo progetto; a differenza di altri, durante la permanenza nel centro Akkari, <strong>Ahmed si \u00e8 contraddistinto per la sua grande determinazione per potersi formare e condurre una vita autonoma fuori dall\u2019istituto<\/strong>. Infatti, cosi desideroso di potersi rifare una vita fuori dal Centro, Ahmed ha fatto tesoro di tutto quello che ha potuto imparare durante le lezioni a scuola. Durante il suo percorso scolastico, \u00e8 cresciuta dentro di lui una grande curiosit\u00e0 e un interesse particolare per i computer, al punto che Ahmed ha deciso di imparare a utilizzare i programmi di editing video. Continuando a riportare buoni voti e successivamente a conseguire il diploma di maturit\u00e0, negli anni Ahmed \u00e8 diventato sempre pi\u00f9 bravo nel campo dell\u2019editing, riuscendo a farsi notare da alcuni youtuber che gli hanno chiesto di realizzare alcuni montaggi video.<\/p>\n<p>Accompagnato e spronato dal personale della Maison Akkari, una volta uscito dal centro Ahmed non ha smesso di seguire dei corsi online per specializzarsi e diventare un esperto in questo settore. Oggi, a 21 anni, Ahmed spera ancora di potersi guadagnare da vivere con le conoscenze e competenze acquisite. La strada \u00e8 ancora in salita, ma Ahmed non smette di credere in se stesso e in un futuro migliore. <strong>La sua storia \u00e8 una di quelle che da forza e speranza agli altri bambini e ragazzi che, come lui, non possono crescere con l\u2019amore di una famiglia<\/strong>.<\/p>\n<p>Diventa anche tu un\u00a0<a href=\"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/attivazione-adozione-a-distanza\/?scelta=25&amp;progetto=Marocco\">sostenitore<\/a>\u00a0del centro Akkari, puoi fare la differenza per questi\u00a0<strong>ragazzi che non hanno una rete familiare in grado di sostenerli e proteggerli nel passaggio dall\u2019infanzia all\u2019et\u00e0 adulta<\/strong>.\u00a0 Inoltre potrai seguire e accompagnare ogni giorno la vita, i progressi e le difficolt\u00e0 dei 250 bambini accolti. Grazie a report mensili infatti sarai costantemente aggiornato sui progressi raggiunti e le difficolt\u00e0 affrontate.<\/p>\n<p>Attiva un\u00a0<a href=\"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/attivazione-adozione-a-distanza\/?scelta=25&amp;progetto=Marocco\">Sostegno a Distanza<\/a>, bastano\u00a0<strong>25 euro<\/strong>\u00a0al mese.<\/p>\n\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*168342-start*\/\n#btnsx-168342{margin-top:0px;margin-bottom:20px;margin-left:0px;margin-right:0px;padding-top:20px;padding-bottom:20px;padding-left:40px;padding-right:40px;}\n#btnsx-168342 .btnsx-text-primary{font-size:30px;line-height:30px;font-family:Montserrat;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-168342:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-168342{background-color:#ef7b0b!important;}\n#btnsx-168342:hover{background-color:#eab20b!important;}\n#btnsx-168342{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-168342:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*168342-end*\/\n<\/style><div id=\"btnsx-168342-wrap\" class=\"btnsx-wrap-center\" align=\"center\"><div id=\"btnsx-168342-container\" class=\"btnsx-btn-container\">\n<a href=\"https:\/\/www.aibi.it\/ita\/adotta-a-distanza-25\/\" id=\"btnsx-168342\" target=\"_blank\" class=\"btnsx-btn btnsx-btn-embossed\"  data-font-primary=\"Montserrat\">\n\t<span class=\"btnsx-text-primary \">Scopri di pi\u00f9<\/span><\/a>\n<\/div><\/div>\n<!-- Buttons X - End -->\n\n","protected":false},"excerpt":{"rendered":"<p>I giovani della Maison Akkari si impegnano molto nel loro percorso scolastico per costruire il proprio futuro, supportati dal Sostegno a Distanza Per i bambini abbandonati la vita all&rsquo;interno dei centri di accoglienza non &egrave; certo semplice e lineare: oltre all&rsquo;accompagnamento dell&rsquo;abbandono, il bisogno di soddisfare i bisogni primari come [&hellip;]<\/p>\n","protected":false},"author":113,"featured_media":190588,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[209],"tags":[602,378,300],"class_list":["post-190802","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-a-distanza","tag-akkari","tag-marocco","tag-sostegno-a-distanza"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Marocco. Perch\u00e9 sostenere a distanza un careleaver? Ahmed ve lo spiega - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/marocco-perche-sostenere-a-distanza-un-careleaver-ahmed-ve-lo-spiega\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marocco. Perch\u00e9 sostenere a distanza un careleaver? Ahmed ve lo spiega\" \/>\n<meta property=\"og:description\" content=\"I giovani della Maison Akkari si impegnano molto nel loro percorso scolastico per costruire il proprio futuro, supportati dal Sostegno a Distanza Per i bambini abbandonati la vita all&rsquo;interno dei centri di accoglienza non &egrave; certo semplice e lineare: oltre all&rsquo;accompagnamento dell&rsquo;abbandono, il bisogno di soddisfare i bisogni primari come [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/marocco-perche-sostenere-a-distanza-un-careleaver-ahmed-ve-lo-spiega\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-04T07:00:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-25T10:16:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2021\/07\/sad-AHMED_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"carlottaZ\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2021\/07\/sad-AHMED_fb.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"carlottaZ\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/marocco-perche-sostenere-a-distanza-un-careleaver-ahmed-ve-lo-spiega\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/marocco-perche-sostenere-a-distanza-un-careleaver-ahmed-ve-lo-spiega\\\/\"},\"author\":{\"name\":\"carlottaZ\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/95193f4e7a1f2190922687ebf84f96c9\"},\"headline\":\"Marocco. Perch\u00e9 sostenere a distanza un careleaver? Ahmed ve lo spiega\",\"datePublished\":\"2021-08-04T07:00:50+00:00\",\"dateModified\":\"2022-07-25T10:16:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/marocco-perche-sostenere-a-distanza-un-careleaver-ahmed-ve-lo-spiega\\\/\"},\"wordCount\":615,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/marocco-perche-sostenere-a-distanza-un-careleaver-ahmed-ve-lo-spiega\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/07\\\/sad-AHMED_fb.jpg\",\"keywords\":[\"Akkari\",\"Marocco\",\"sostegno a distanza\"],\"articleSection\":[\"Adozione a Distanza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/marocco-perche-sostenere-a-distanza-un-careleaver-ahmed-ve-lo-spiega\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/marocco-perche-sostenere-a-distanza-un-careleaver-ahmed-ve-lo-spiega\\\/\",\"name\":\"Marocco. Perch\u00e9 sostenere a distanza un careleaver? Ahmed ve lo spiega - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/marocco-perche-sostenere-a-distanza-un-careleaver-ahmed-ve-lo-spiega\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/marocco-perche-sostenere-a-distanza-un-careleaver-ahmed-ve-lo-spiega\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/07\\\/sad-AHMED_fb.jpg\",\"datePublished\":\"2021-08-04T07:00:50+00:00\",\"dateModified\":\"2022-07-25T10:16:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/marocco-perche-sostenere-a-distanza-un-careleaver-ahmed-ve-lo-spiega\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/marocco-perche-sostenere-a-distanza-un-careleaver-ahmed-ve-lo-spiega\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/marocco-perche-sostenere-a-distanza-un-careleaver-ahmed-ve-lo-spiega\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/07\\\/sad-AHMED_fb.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/07\\\/sad-AHMED_fb.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/marocco-perche-sostenere-a-distanza-un-careleaver-ahmed-ve-lo-spiega\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione a Distanza\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-a-distanza\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Marocco. Perch\u00e9 sostenere a distanza un careleaver? Ahmed ve lo spiega\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/95193f4e7a1f2190922687ebf84f96c9\",\"name\":\"carlottaZ\",\"sameAs\":[\"cellos\"],\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/carlottaz\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Marocco. Perch\u00e9 sostenere a distanza un careleaver? Ahmed ve lo spiega - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/marocco-perche-sostenere-a-distanza-un-careleaver-ahmed-ve-lo-spiega\/","og_locale":"it_IT","og_type":"article","og_title":"Marocco. Perch\u00e9 sostenere a distanza un careleaver? Ahmed ve lo spiega","og_description":"I giovani della Maison Akkari si impegnano molto nel loro percorso scolastico per costruire il proprio futuro, supportati dal Sostegno a Distanza Per i bambini abbandonati la vita all&rsquo;interno dei centri di accoglienza non &egrave; certo semplice e lineare: oltre all&rsquo;accompagnamento dell&rsquo;abbandono, il bisogno di soddisfare i bisogni primari come [&hellip;]","og_url":"https:\/\/www.aibi.it\/ita\/marocco-perche-sostenere-a-distanza-un-careleaver-ahmed-ve-lo-spiega\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2021-08-04T07:00:50+00:00","article_modified_time":"2022-07-25T10:16:41+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2021\/07\/sad-AHMED_fb.jpg","type":"image\/jpeg"}],"author":"carlottaZ","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.aibi.it\/ita\/images\/2021\/07\/sad-AHMED_fb.jpg","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"carlottaZ","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/marocco-perche-sostenere-a-distanza-un-careleaver-ahmed-ve-lo-spiega\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/marocco-perche-sostenere-a-distanza-un-careleaver-ahmed-ve-lo-spiega\/"},"author":{"name":"carlottaZ","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/95193f4e7a1f2190922687ebf84f96c9"},"headline":"Marocco. Perch\u00e9 sostenere a distanza un careleaver? Ahmed ve lo spiega","datePublished":"2021-08-04T07:00:50+00:00","dateModified":"2022-07-25T10:16:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/marocco-perche-sostenere-a-distanza-un-careleaver-ahmed-ve-lo-spiega\/"},"wordCount":615,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/marocco-perche-sostenere-a-distanza-un-careleaver-ahmed-ve-lo-spiega\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/07\/sad-AHMED_fb.jpg","keywords":["Akkari","Marocco","sostegno a distanza"],"articleSection":["Adozione a Distanza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/marocco-perche-sostenere-a-distanza-un-careleaver-ahmed-ve-lo-spiega\/","url":"https:\/\/www.aibi.it\/ita\/marocco-perche-sostenere-a-distanza-un-careleaver-ahmed-ve-lo-spiega\/","name":"Marocco. Perch\u00e9 sostenere a distanza un careleaver? Ahmed ve lo spiega - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/marocco-perche-sostenere-a-distanza-un-careleaver-ahmed-ve-lo-spiega\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/marocco-perche-sostenere-a-distanza-un-careleaver-ahmed-ve-lo-spiega\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/07\/sad-AHMED_fb.jpg","datePublished":"2021-08-04T07:00:50+00:00","dateModified":"2022-07-25T10:16:41+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/marocco-perche-sostenere-a-distanza-un-careleaver-ahmed-ve-lo-spiega\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/marocco-perche-sostenere-a-distanza-un-careleaver-ahmed-ve-lo-spiega\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/marocco-perche-sostenere-a-distanza-un-careleaver-ahmed-ve-lo-spiega\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2021\/07\/sad-AHMED_fb.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/07\/sad-AHMED_fb.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/marocco-perche-sostenere-a-distanza-un-careleaver-ahmed-ve-lo-spiega\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione a Distanza","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-a-distanza\/"},{"@type":"ListItem","position":3,"name":"Marocco. Perch\u00e9 sostenere a distanza un careleaver? Ahmed ve lo spiega"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/95193f4e7a1f2190922687ebf84f96c9","name":"carlottaZ","sameAs":["cellos"],"url":"https:\/\/www.aibi.it\/ita\/author\/carlottaz\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 12:39:13","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/190802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/113"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=190802"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/190802\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/190588"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=190802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=190802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=190802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}