﻿


{"id":191159,"date":"2021-08-19T07:46:42","date_gmt":"2021-08-19T05:46:42","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=191159"},"modified":"2021-08-19T15:50:23","modified_gmt":"2021-08-19T13:50:23","slug":"adozione-internazionale-e-importante-che-i-mariti-siano-coinvolti-nella-scelta-di-accogliere-un-bambino-abbandonato","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-e-importante-che-i-mariti-siano-coinvolti-nella-scelta-di-accogliere-un-bambino-abbandonato\/","title":{"rendered":"Adozione internazionale. \u00c8 importante che i mariti siano coinvolti nella scelta di accogliere un bambino abbandonato?"},"content":{"rendered":"<h2 style=\"font-weight: 400;\"><strong>Il futuro padre che si lascia coinvolgere nei differenti passaggi dell\u2019iter adottivo, favorisce la creazione di uno spazio di accoglienza adeguato per il figlio che arriver\u00e0 e una crescita consapevole e armonica delle risorse di coppia<\/strong><\/h2>\n<p style=\"font-weight: 400;\">Spesso, quando si sente parlare di\u00a0<strong>accoglienza<\/strong>, cura, accudimento, viene spontaneo tradurre la sensazione di comfort e di calore, che la pronuncia di questi termini genera con un&#8217;unica parola, che, in un colpo solo, li racchiude tutti:\u00a0<strong>maternit\u00e0.<\/strong><\/p>\n<p style=\"font-weight: 400;\">Per la donna, la \u201cmaternit\u00e0\u201d di pancia o di cuore \u00e8 un fatto istintuale e sovente la voglia di aprire la propria casa e il proprio cuore ad un bambino abbandonato, per donargli\u00a0<strong>la gioia di una famiglia<\/strong>, bussa prima nel cuore della\u00a0<strong>\u201cfutura mamma\u201d,<\/strong>\u00a0ma solo grazie al coinvolgimento del pap\u00e0, alla\u00a0<strong>decisione condivisa<\/strong>\u00a0di affrontare questo percorso, il desiderio diviene reale e si gettano\u00a0<strong>basi solide per il futuro<\/strong>.<\/p>\n<p style=\"font-weight: 400;\">Tutto questo per dire che, la figura del pap\u00e0, che a volte viene lasciata un po\u2019 sullo sfondo, \u00e8 davvero importante nella scelta di accogliere un bambino abbandonato e il suo coinvolgimento, assieme a quello della madre, \u00e8 fondamentale per \u201c<em>la creazione di uno spazio di accoglienza adeguato per il figlio che arriver\u00e0 e una crescita consapevole e armonica delle risorse di coppia\u201d.<\/em><\/p>\n<h3 style=\"font-weight: 400;\"><strong>Vediamo il perch\u00e9 assieme a Francesca Berti, psicologa e psicoterapeuta di Ai.Bi.<\/strong><\/h3>\n<p style=\"font-weight: 400;\"><strong>\u00a0<\/strong><strong>Il ruolo genitoriale del padre<\/strong>\u00a0\u00e8 stato studiato sempre di pi\u00f9 nel corso degli ultimi decenni, complice un grande\u00a0<strong>cambiamento culturale<\/strong>\u00a0in atto rispetto ai ruoli di genere nella societ\u00e0, che ha visto fiorire approfondimenti di ogni tipologia sulle funzioni genitoriali e le \u201cnuove\u201d dinamiche familiari.<\/p>\n<p style=\"font-weight: 400;\">Da sempre, la pi\u00f9 studiata,\u00a0<strong>la funzione materna<\/strong>, al di l\u00e0 di chi la adempie, \u00e8 quella\u00a0<strong>deputata all\u2019accoglienza\u00a0e all\u2019accudimento<\/strong>: \u00e8 quella che nutre, si prende cura, custodisce, protegge, garantendo una \u201cbase sicura\u201d e continuit\u00e0 di risposta ai bisogni sia concreti che psichici del nuovo arrivato.<\/p>\n<p style=\"font-weight: 400;\"><strong>La funzione paterna<\/strong>\u00a0\u00e8 pi\u00f9 legata alla\u00a0<strong>regolazione e alla guida<\/strong>\u00a0nel mondo, all\u2019emancipazione.<\/p>\n<p style=\"font-weight: 400;\">Le regole e i limiti con cui i bambini si trovano a confrontarsi rappresentano per loro la possibilit\u00e0 di\u00a0<strong>orientarsi nel caos del mondo<\/strong>\u00a0e non sentirsi soli nell\u2019affrontarlo. Le regole familiari hanno questa funzione anche quando i figli scelgono di trasgredirle.<\/p>\n<p style=\"font-weight: 400;\">La funzione paterna \u00e8 anche quella di\u00a0<strong>accompagnare il figlio alla scoperta del mondo,<\/strong>\u00a0aiutandolo a crescere, nel distacco dalla dipendenza, e a costruire il proprio s\u00e9 separato e individuale.<\/p>\n<p style=\"font-weight: 400;\">Non necessariamente i codici coincidono con il maschile e il femminile biologico e soprattutto\u00a0<strong>si pu\u00f2 assolvere una determinata funzione anche in parte, coadiuvandosi e integrandosi con l\u2019altro.<\/strong><\/p>\n<p style=\"font-weight: 400;\">Entrambe le funzioni per\u00f2 sono fondamentali per garantire ai figli la soddisfazione dei bisogni di contenimento e al contempo anche i suoi bisogni di autonomia.<\/p>\n<h3 style=\"font-weight: 400;\"><strong>Rispetto al ruolo del padre, viviamo un momento storico e sociale del tutto nuovo e ricco di potenzialit\u00e0 interessanti.<\/strong><\/h3>\n<p style=\"font-weight: 400;\">Fino alla met\u00e0 del secolo scorso il padre era una figura fondamentalmente assente dal percorso di crescita dei figli. Man mano che la societ\u00e0 si trasformava poi,\u00a0<strong>i ruoli di genere sono diventati pi\u00f9 fluidi<\/strong>, anche all\u2019interno della famiglia.<\/p>\n<p style=\"font-weight: 400;\">L\u2019autoritarismo ha perso legittimit\u00e0 e interesse e\u00a0<strong>oggi\u00a0i padri<\/strong>, a differenza di un tempo,\u00a0<strong>sono molto presenti nella vita dei figli,<\/strong>\u00a0talvolta in difficolt\u00e0 nella ricerca di un modo propriamente \u201cpaterno\u201d e personale per aiutarli a crescere.<\/p>\n<p style=\"font-weight: 400;\">Nella genitorialit\u00e0 biologica la mamma sperimenta i segnali del suo corpo che cambia e ha modo cos\u00ec di iniziare a elaborare i tanti sentimenti ambivalenti, tra la gioia e la paura, l\u2019euforia e la preoccupazione, legati all\u2019essere genitori. Inoltre, ha delle mutazioni ormonali fisiologiche che la aiutano a prepararsi ad accogliere.<\/p>\n<h3 style=\"font-weight: 400;\"><strong>Ci sono evidenze scientifiche che mostrano anche nei padri una predisposizione biologica all\u2019accudimento del bambino.<\/strong><\/h3>\n<p style=\"font-weight: 400;\">Se il padre \u00e8 coinvolto si verificano cambiamenti ormonali simili a quelli materni, seppur meno intensi e duraturi. Le ricerche in tale ambito rilevano che la mamma \u00e8 praticamente sempre \u201caccesa\u201d e pronta per accudire il suo piccolo, mentre il padre deve essere attivato; ne deriva che, paradossalmente, il padre pu\u00f2 avere pi\u00f9 bisogno di incontri e corsi di preparazione alla nascita rispetto alla mamma, che pu\u00f2 invece contare anche su un innato intuito.<\/p>\n<h3 style=\"font-weight: 400;\"><strong>Tutto questo ha a che fare anche con la genitorialit\u00e0 adottiva, e forse anche di pi\u00f9.<\/strong><\/h3>\n<p style=\"font-weight: 400;\">Le coppie, nell\u2019adozione, compiono tutti i passaggi in maniera congiunta.\u00a0<strong>Elaborano il loro desiderio insieme all\u2019altro<\/strong>, seguono i vari passaggi sempre in coppia.<\/p>\n<p style=\"font-weight: 400;\">Il futuro padre adottivo, che si lascia coinvolgere nei differenti passaggi dell\u2019iter e della preparazione all\u2019accoglienza di un figlio in stato di abbandono, inizia, insieme alla futura mamma, a \u201cmentalizzare\u201d il bambino, cio\u00e8 a farsene un\u2019idea e a pensarlo, anche se in maniera ideale e fantastica. Questo processo\u00a0<strong>favorisce la creazione di uno spazio di accoglienza adeguato per il figlio<\/strong>\u00a0che arriver\u00e0 e una crescita consapevole e armonica delle risorse di coppia.<\/p>\n<p style=\"font-weight: 400;\">Affinch\u00e9 questo complesso processo creativo possa sviluppare tutto il suo potenziale\u00a0<strong>occorre che entrambe le figure genitoriali siano presenti<\/strong>, fisicamente ed emotivamente, che siano parimenti coinvolte in tutti i passaggi che li porteranno ad accogliere un bambino che andr\u00e0 aiutato non solo a costruire la propria \u201cnuova\u201d storia, ma anche a rielaborare la sua precedente storia, molto spesso ricca di difficolt\u00e0 e dolore.<\/p>\n<p style=\"font-weight: 400;\"><em>\u201cLe case felici sono costruite con mattoni di pazienza\u201d.\u00a0<\/em>(Harold E. Kohn)<\/p>\n<p style=\"font-weight: 400;\"><strong>Francesca Berti<\/strong><\/p>\n<p style=\"font-weight: 400;\">Psicologa e psicoterapeuta di Ai.Bi. \u2013 \u00a0Associazione Amici dei Bambini<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il futuro padre che si lascia coinvolgere nei differenti passaggi dell&rsquo;iter adottivo, favorisce la creazione di uno spazio di accoglienza adeguato per il figlio che arriver&agrave; e una crescita consapevole e armonica delle risorse di coppia Spesso, quando si sente parlare di&nbsp;accoglienza, cura, accudimento, viene spontaneo tradurre la sensazione di [&hellip;]<\/p>\n","protected":false},"author":97,"featured_media":191160,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[172],"tags":[347],"class_list":["post-191159","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-internazionale","tag-adozione-internazionale"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozione internazionale. \u00c8 importante che i mariti siano coinvolti nella scelta di accogliere un bambino abbandonato? - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"Adozione. Il futuro padre che si lascia coinvolgere nei differenti passaggi dell\u2019iter adottivo, favorisce la creazione di uno spazio di accoglienza adeguato per il figlio che arriver\u00e0 e una crescita consapevole e armonica delle risorse di coppia\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-e-importante-che-i-mariti-siano-coinvolti-nella-scelta-di-accogliere-un-bambino-abbandonato\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozione internazionale. \u00c8 importante che i mariti siano coinvolti nella scelta di accogliere un bambino abbandonato?\" \/>\n<meta property=\"og:description\" content=\"Adozione. Il futuro padre che si lascia coinvolgere nei differenti passaggi dell\u2019iter adottivo, favorisce la creazione di uno spazio di accoglienza adeguato per il figlio che arriver\u00e0 e una crescita consapevole e armonica delle risorse di coppia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-e-importante-che-i-mariti-siano-coinvolti-nella-scelta-di-accogliere-un-bambino-abbandonato\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-19T05:46:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-19T13:50:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2021\/08\/adozione-2-6.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mc.sabatini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mc.sabatini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-e-importante-che-i-mariti-siano-coinvolti-nella-scelta-di-accogliere-un-bambino-abbandonato\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-e-importante-che-i-mariti-siano-coinvolti-nella-scelta-di-accogliere-un-bambino-abbandonato\\\/\"},\"author\":{\"name\":\"mc.sabatini\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\"},\"headline\":\"Adozione internazionale. \u00c8 importante che i mariti siano coinvolti nella scelta di accogliere un bambino abbandonato?\",\"datePublished\":\"2021-08-19T05:46:42+00:00\",\"dateModified\":\"2021-08-19T13:50:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-e-importante-che-i-mariti-siano-coinvolti-nella-scelta-di-accogliere-un-bambino-abbandonato\\\/\"},\"wordCount\":909,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-e-importante-che-i-mariti-siano-coinvolti-nella-scelta-di-accogliere-un-bambino-abbandonato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/08\\\/adozione-2-6.jpg\",\"keywords\":[\"Adozione Internazionale\"],\"articleSection\":[\"Adozione Internazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-e-importante-che-i-mariti-siano-coinvolti-nella-scelta-di-accogliere-un-bambino-abbandonato\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-e-importante-che-i-mariti-siano-coinvolti-nella-scelta-di-accogliere-un-bambino-abbandonato\\\/\",\"name\":\"Adozione internazionale. \u00c8 importante che i mariti siano coinvolti nella scelta di accogliere un bambino abbandonato? - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-e-importante-che-i-mariti-siano-coinvolti-nella-scelta-di-accogliere-un-bambino-abbandonato\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-e-importante-che-i-mariti-siano-coinvolti-nella-scelta-di-accogliere-un-bambino-abbandonato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/08\\\/adozione-2-6.jpg\",\"datePublished\":\"2021-08-19T05:46:42+00:00\",\"dateModified\":\"2021-08-19T13:50:23+00:00\",\"description\":\"Adozione. Il futuro padre che si lascia coinvolgere nei differenti passaggi dell\u2019iter adottivo, favorisce la creazione di uno spazio di accoglienza adeguato per il figlio che arriver\u00e0 e una crescita consapevole e armonica delle risorse di coppia\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-e-importante-che-i-mariti-siano-coinvolti-nella-scelta-di-accogliere-un-bambino-abbandonato\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-e-importante-che-i-mariti-siano-coinvolti-nella-scelta-di-accogliere-un-bambino-abbandonato\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-e-importante-che-i-mariti-siano-coinvolti-nella-scelta-di-accogliere-un-bambino-abbandonato\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/08\\\/adozione-2-6.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/08\\\/adozione-2-6.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-e-importante-che-i-mariti-siano-coinvolti-nella-scelta-di-accogliere-un-bambino-abbandonato\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione Internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-internazionale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozione internazionale. \u00c8 importante che i mariti siano coinvolti nella scelta di accogliere un bambino abbandonato?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\",\"name\":\"mc.sabatini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/marias\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozione internazionale. \u00c8 importante che i mariti siano coinvolti nella scelta di accogliere un bambino abbandonato? - Ai.Bi. Amici dei Bambini","description":"Adozione. Il futuro padre che si lascia coinvolgere nei differenti passaggi dell\u2019iter adottivo, favorisce la creazione di uno spazio di accoglienza adeguato per il figlio che arriver\u00e0 e una crescita consapevole e armonica delle risorse di coppia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-e-importante-che-i-mariti-siano-coinvolti-nella-scelta-di-accogliere-un-bambino-abbandonato\/","og_locale":"it_IT","og_type":"article","og_title":"Adozione internazionale. \u00c8 importante che i mariti siano coinvolti nella scelta di accogliere un bambino abbandonato?","og_description":"Adozione. Il futuro padre che si lascia coinvolgere nei differenti passaggi dell\u2019iter adottivo, favorisce la creazione di uno spazio di accoglienza adeguato per il figlio che arriver\u00e0 e una crescita consapevole e armonica delle risorse di coppia","og_url":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-e-importante-che-i-mariti-siano-coinvolti-nella-scelta-di-accogliere-un-bambino-abbandonato\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2021-08-19T05:46:42+00:00","article_modified_time":"2021-08-19T13:50:23+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2021\/08\/adozione-2-6.jpg","type":"image\/jpeg"}],"author":"mc.sabatini","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"mc.sabatini","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-e-importante-che-i-mariti-siano-coinvolti-nella-scelta-di-accogliere-un-bambino-abbandonato\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-e-importante-che-i-mariti-siano-coinvolti-nella-scelta-di-accogliere-un-bambino-abbandonato\/"},"author":{"name":"mc.sabatini","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938"},"headline":"Adozione internazionale. \u00c8 importante che i mariti siano coinvolti nella scelta di accogliere un bambino abbandonato?","datePublished":"2021-08-19T05:46:42+00:00","dateModified":"2021-08-19T13:50:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-e-importante-che-i-mariti-siano-coinvolti-nella-scelta-di-accogliere-un-bambino-abbandonato\/"},"wordCount":909,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-e-importante-che-i-mariti-siano-coinvolti-nella-scelta-di-accogliere-un-bambino-abbandonato\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/08\/adozione-2-6.jpg","keywords":["Adozione Internazionale"],"articleSection":["Adozione Internazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-e-importante-che-i-mariti-siano-coinvolti-nella-scelta-di-accogliere-un-bambino-abbandonato\/","url":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-e-importante-che-i-mariti-siano-coinvolti-nella-scelta-di-accogliere-un-bambino-abbandonato\/","name":"Adozione internazionale. \u00c8 importante che i mariti siano coinvolti nella scelta di accogliere un bambino abbandonato? - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-e-importante-che-i-mariti-siano-coinvolti-nella-scelta-di-accogliere-un-bambino-abbandonato\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-e-importante-che-i-mariti-siano-coinvolti-nella-scelta-di-accogliere-un-bambino-abbandonato\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/08\/adozione-2-6.jpg","datePublished":"2021-08-19T05:46:42+00:00","dateModified":"2021-08-19T13:50:23+00:00","description":"Adozione. Il futuro padre che si lascia coinvolgere nei differenti passaggi dell\u2019iter adottivo, favorisce la creazione di uno spazio di accoglienza adeguato per il figlio che arriver\u00e0 e una crescita consapevole e armonica delle risorse di coppia","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-e-importante-che-i-mariti-siano-coinvolti-nella-scelta-di-accogliere-un-bambino-abbandonato\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozione-internazionale-e-importante-che-i-mariti-siano-coinvolti-nella-scelta-di-accogliere-un-bambino-abbandonato\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-e-importante-che-i-mariti-siano-coinvolti-nella-scelta-di-accogliere-un-bambino-abbandonato\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2021\/08\/adozione-2-6.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/08\/adozione-2-6.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-e-importante-che-i-mariti-siano-coinvolti-nella-scelta-di-accogliere-un-bambino-abbandonato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione Internazionale","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-internazionale\/"},{"@type":"ListItem","position":3,"name":"Adozione internazionale. \u00c8 importante che i mariti siano coinvolti nella scelta di accogliere un bambino abbandonato?"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938","name":"mc.sabatini","url":"https:\/\/www.aibi.it\/ita\/author\/marias\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 01:07:16","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/191159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/97"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=191159"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/191159\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/191160"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=191159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=191159"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=191159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}