﻿{"id":19116,"date":"2011-01-31T16:34:27","date_gmt":"2011-01-31T15:34:27","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=19116"},"modified":"2011-01-31T16:38:33","modified_gmt":"2011-01-31T15:38:33","slug":"moldavia-verso-una-vita-migliore","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/moldavia-verso-una-vita-migliore\/","title":{"rendered":"Moldavia: verso una vita migliore"},"content":{"rendered":"<p><a href=\"https:\/\/www.aibi.it\/ita\/images\/chisinau.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-19117\" style=\"margin: 5px;\" title=\"chisinau\" src=\"https:\/\/www.aibi.it\/ita\/images\/chisinau.jpg\" alt=\"\" width=\"100\" height=\"100\" \/><\/a>La storia di Valeria ci ha impressionati sin dall\u2019inizio, quando siamo andati a conoscere i casi con i quali abbiamo scelto di lavorare a Chisinau in Moldavia. I suoi genitori, purtroppo non stanno pi\u00f9 insieme. Dopo il divorzio, ciascuno\u00a0si \u00e8\u00a0rifatto la propria vita, lasciando il passato alle spalle ed insieme al passato, anche una figlia di 5 anni.<\/p>\n<p>La piccola ha vissuto per un periodo con la nonna che, nonostante i suoi gravi problemi di salute, ha fatto di tutto per offrire il meglio alla nipote. La bimba gode infatti di un\u2019educazione speciale e dimostra delle spiccate qualit\u00e0 di massaia.<strong> \u00c8 stata una delle bambine pi\u00f9 brave dell\u2019istituto. \u00c8 comunicativa, amichevole ed ha una passione per il disegno e per l\u2019arte fotografica.<\/strong> Di questa sua passione, ci ha parlato la bambina stessa, raccontandoci che, quando era piccola, Valeria \u00e8 stata la mascotte di alcune agenzie di pubblicit\u00e0 del paese.<\/p>\n<p>Anche se in istituto a Valeria non mancava niente e nonostante fosse molto amata dai compagni e dagli insegnanti, la bambina sentiva la mancanza di casa e di sua nonna. Anche la nonna \u00e8 molto legata alla nipote, <strong>ma a causa delle scarse condizioni economiche, \u00e8 stata costretta ad istituzionalizzare la bambina.<\/strong><\/p>\n<p>Il Centro Servizi Sociali al Bambino e alla Famiglia \u00e8 una struttura creata da Ai.Bi. e ora divenuta Associazione che offre sostegno e orientamento per quelle famiglie che, nonostante le difficolt\u00e0 che riscontrano, sanno e vogliono rimanere accanto ai propri bambini. Lo \u00e8 anche il caso di questa famiglia e perci\u00f2 abbiamo deciso di starle accanto ed accompagnarla verso una vita migliore.<\/p>\n<p>Durante le visite al domicilio, siamo stati accolti sempre con il massimo di disponibilit\u00e0 ed \u00e8 probabilmente questa bont\u00e0 d\u2019animo che emana la nonna, che ha contribuito ad una buona crescita e all\u2019educazione della nipote.<\/p>\n<p>In seguito al sostegno materiale e psicologico che abbiamo offerto sia alla nonna, che alla bambina, oggi le due sono di nuovo insieme. Valeria torna a casa ogni giorno dopo le lezioni, questo perch\u00e9, da pochi mesi frequenta una scuola della comunit\u00e0. Ha una buona riuscita scolastica e si \u00e8 presto conquistata la simpatia del suo nuovo collettivo scolastico.<\/p>\n<p><strong>Manca ancora un po\u2019 finch\u00e9 questa famiglia raggiunger\u00e0 l\u2019indipendenza economica, ma siamo sicuri che il primo passo \u00e8 stato fatto.<\/strong> La nonna \u00e8 pi\u00f9 autonoma nel gestire le proprie risorse, ma resteremo vicini alla nonna, offrendole tutto l\u2019appoggio necessario in modo che lei possa sostenere la nipote a crescere serena ed a realizzare i suoi sogni.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La storia di Valeria ci ha impressionati sin dall\u2019inizio,\u00a0i suoi genitori purtroppo non stanno pi\u00f9 insieme. Dopo il divorzio, ciascuno\u00a0si \u00e8\u00a0rifatto la propria vita, <strong>lasciando il passato alle spalle ed insieme al passato, anche una figlia di 5 anni.<\/strong> <strong><a href=\"https:\/\/www.aibi.it\/ita\/moldavia-verso-una-vita-migliore\/\">LEGGI TUTTO&#8230;<\/a><\/strong><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-19116","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Moldavia: verso una vita migliore - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/moldavia-verso-una-vita-migliore\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Moldavia: verso una vita migliore\" \/>\n<meta property=\"og:description\" content=\"La storia di Valeria ci ha impressionati sin dall\u2019inizio,\u00a0i suoi genitori purtroppo non stanno pi\u00f9 insieme. Dopo il divorzio, ciascuno\u00a0si \u00e8\u00a0rifatto la propria vita, lasciando il passato alle spalle ed insieme al passato, anche una figlia di 5 anni. LEGGI TUTTO...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/moldavia-verso-una-vita-migliore\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-01-31T15:34:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2011-01-31T15:38:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/chisinau.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldavia-verso-una-vita-migliore\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldavia-verso-una-vita-migliore\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Moldavia: verso una vita migliore\",\"datePublished\":\"2011-01-31T15:34:27+00:00\",\"dateModified\":\"2011-01-31T15:38:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldavia-verso-una-vita-migliore\\\/\"},\"wordCount\":416,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldavia-verso-una-vita-migliore\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/chisinau.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldavia-verso-una-vita-migliore\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldavia-verso-una-vita-migliore\\\/\",\"name\":\"Moldavia: verso una vita migliore - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldavia-verso-una-vita-migliore\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldavia-verso-una-vita-migliore\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/chisinau.jpg\",\"datePublished\":\"2011-01-31T15:34:27+00:00\",\"dateModified\":\"2011-01-31T15:38:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldavia-verso-una-vita-migliore\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldavia-verso-una-vita-migliore\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldavia-verso-una-vita-migliore\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/chisinau.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/chisinau.jpg\",\"width\":100,\"height\":100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldavia-verso-una-vita-migliore\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Moldavia: verso una vita migliore\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Moldavia: verso una vita migliore - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/moldavia-verso-una-vita-migliore\/","og_locale":"it_IT","og_type":"article","og_title":"Moldavia: verso una vita migliore","og_description":"La storia di Valeria ci ha impressionati sin dall\u2019inizio,\u00a0i suoi genitori purtroppo non stanno pi\u00f9 insieme. Dopo il divorzio, ciascuno\u00a0si \u00e8\u00a0rifatto la propria vita, lasciando il passato alle spalle ed insieme al passato, anche una figlia di 5 anni. LEGGI TUTTO...","og_url":"https:\/\/www.aibi.it\/ita\/moldavia-verso-una-vita-migliore\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2011-01-31T15:34:27+00:00","article_modified_time":"2011-01-31T15:38:33+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/chisinau.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/moldavia-verso-una-vita-migliore\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/moldavia-verso-una-vita-migliore\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Moldavia: verso una vita migliore","datePublished":"2011-01-31T15:34:27+00:00","dateModified":"2011-01-31T15:38:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/moldavia-verso-una-vita-migliore\/"},"wordCount":416,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/moldavia-verso-una-vita-migliore\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/chisinau.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/moldavia-verso-una-vita-migliore\/","url":"https:\/\/www.aibi.it\/ita\/moldavia-verso-una-vita-migliore\/","name":"Moldavia: verso una vita migliore - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/moldavia-verso-una-vita-migliore\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/moldavia-verso-una-vita-migliore\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/chisinau.jpg","datePublished":"2011-01-31T15:34:27+00:00","dateModified":"2011-01-31T15:38:33+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/moldavia-verso-una-vita-migliore\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/moldavia-verso-una-vita-migliore\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/moldavia-verso-una-vita-migliore\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/chisinau.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/chisinau.jpg","width":100,"height":100},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/moldavia-verso-una-vita-migliore\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Moldavia: verso una vita migliore"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 18:10:26","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/19116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=19116"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/19116\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=19116"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=19116"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=19116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}