﻿{"id":191240,"date":"2021-08-23T07:40:03","date_gmt":"2021-08-23T05:40:03","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=191240"},"modified":"2021-08-23T14:16:09","modified_gmt":"2021-08-23T12:16:09","slug":"affido-luciana-littizzetto-ho-sempre-avuto-il-tarlo-dellaffido","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/affido-luciana-littizzetto-ho-sempre-avuto-il-tarlo-dellaffido\/","title":{"rendered":"Affido. Luciana Littizzetto: \u201cHo sempre avuto il tarlo dell\u2019affido&#8221;"},"content":{"rendered":"<h2 style=\"font-weight: 400;\"><strong>Littizzetto<em>: \u201cI figli non sono venuti, non era destino [\u2026] il desiderio di maternit\u00e0 non era cos\u00ec pressante. Ero una donna abbastanza serena e contenta, per\u00f2 all\u2019idea di diventare madre non avevo rinunciato&#8221;\u00a0<\/em><\/strong><\/h2>\n<p style=\"font-weight: 400;\"><strong>Luciana Littizzetto,<\/strong> amatissima comica italiana che non ha bisogno di presentazioni, non \u00e8 solo una professionista affermata dal talento ironico e pungente, ma anche una <strong>mamma affidataria<\/strong>\u00a0di due fratelli, ormai grandi:\u00a0<strong>Vanessa e Jordan<\/strong>, ai quali ha aperto le porte della propria casa e del proprio cuore.<\/p>\n<p style=\"font-weight: 400;\">In un\u2019intervista rilasciata al settimanale\u00a0<strong>Oggi<\/strong> e riportata da <strong>Meteo week<\/strong>, la bravissima comica racconta: \u201c<strong><em>I figli non sono venuti, non era destino<\/em><\/strong><em>\u00a0[\u2026] il desiderio di maternit\u00e0 non era cos\u00ec pressante. Ero una donna abbastanza serena e contenta, per\u00f2 all\u2019idea di diventare madre non avevo rinunciato,\u00a0<strong>ho sempre avuto il tarlo dell\u2019affido\u201d.<\/strong><\/em><\/p>\n<p style=\"font-weight: 400;\">In un\u2019intervista di alcuni anni fa di\u00a0<strong>Vanity Fair,\u00a0<\/strong>ripresa dal web magazine\u00a0<strong>Mamma\u00a0oggi<\/strong>, la Littizzetto si definiva \u201c<strong><em>una mamma pi\u00f9 di cuore che di utero<\/em>\u201d,<\/strong>\u00a0con la voglia di prendersi cura di \u201cragazzi pi\u00f9 grandi\u201d.<\/p>\n<p style=\"font-weight: 400;\">Iniziata come una \u201c<em>cosa sociale<\/em>\u201d, ben presto Luciana ha conosciuto il\u00a0<strong>reale significato profondo del suo impegno:<\/strong><\/p>\n<p style=\"font-weight: 400;\">\u201c<em>Non \u00e8 solo una cosa sociale, perch\u00e9 i bambini quando arrivano a casa vogliono la mamma, e piangono, e hanno la febbre. L\u2019inizio \u00e8 stato da panico perch\u00e9 pensavo: devo compensarli di quello che non hanno avuto, devo essere una mamma perfetta [\u2026] Finalmente, un giorno, ho fatto uno switch leggerissimo ma fondamentale. Faccio quello che posso, faccio la mamma come sono io\u201d.<\/em><\/p>\n<p style=\"font-weight: 400;\">Un\u2019esperienza meravigliosa, anche se complessa, che la Littizzetto\u00a0<strong>rifarebbe \u201ctutta la vita\u201d<\/strong>\u00a0e che consiglia, anche se non nasconde: \u201c<em>\u00e8 molto complesso \u2013\u00a0<\/em>si legge su\u00a0<strong>Meteoweek<\/strong><em>&#8211; e devi sapere che soffrirai perch\u00e9\u00a0<strong>alla base di tutto c\u2019\u00e8 un abbandono, una ferita che non si rimargina mai<\/strong>\u00a0e che per quanto amore tu dia, a intervalli regolari torna a galla come una ventata venefica. E devi farci i conti. Mi spiace che le istituzioni non supportino affatto i genitori affidatari: tu sei visto come la soluzione a un problema e basta. Invece avremmo bisogno di essere sostenuti e rispettati\u201d<\/em><em>.<\/em><\/p>\n<p>\u00a0Foto: Chenews.it<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Littizzetto: &ldquo;I figli non sono venuti, non era destino [&hellip;] il desiderio di maternit&agrave; non era cos&igrave; pressante. Ero una donna abbastanza serena e contenta, per&ograve; all&rsquo;idea di diventare madre non avevo rinunciato&rdquo;&nbsp; Luciana Littizzetto, amatissima comica italiana che non ha bisogno di presentazioni, non &egrave; solo una professionista affermata [&hellip;]<\/p>\n","protected":false},"author":97,"featured_media":191241,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[652],"tags":[320],"class_list":["post-191240","post","type-post","status-publish","format-standard","has-post-thumbnail","category-affido","tag-affido"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Affido. Luciana Littizzetto: \u201cHo sempre avuto il tarlo dell\u2019affido&quot; - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"Luciana Littizzetto: \u201cI figli non sono venuti, non era destino [\u2026] il desiderio di maternit\u00e0 non era cos\u00ec pressante. Ero una donna abbastanza serena e contenta, per\u00f2 all\u2019idea di diventare madre non avevo rinunciato&quot;\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/affido-luciana-littizzetto-ho-sempre-avuto-il-tarlo-dellaffido\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Affido. Luciana Littizzetto: \u201cHo sempre avuto il tarlo dell\u2019affido&quot;\" \/>\n<meta property=\"og:description\" content=\"Luciana Littizzetto: \u201cI figli non sono venuti, non era destino [\u2026] il desiderio di maternit\u00e0 non era cos\u00ec pressante. Ero una donna abbastanza serena e contenta, per\u00f2 all\u2019idea di diventare madre non avevo rinunciato&quot;\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/affido-luciana-littizzetto-ho-sempre-avuto-il-tarlo-dellaffido\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-23T05:40:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-23T12:16:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2021\/08\/LITTIZZETTO.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mc.sabatini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mc.sabatini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-luciana-littizzetto-ho-sempre-avuto-il-tarlo-dellaffido\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-luciana-littizzetto-ho-sempre-avuto-il-tarlo-dellaffido\\\/\"},\"author\":{\"name\":\"mc.sabatini\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\"},\"headline\":\"Affido. Luciana Littizzetto: \u201cHo sempre avuto il tarlo dell\u2019affido&#8221;\",\"datePublished\":\"2021-08-23T05:40:03+00:00\",\"dateModified\":\"2021-08-23T12:16:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-luciana-littizzetto-ho-sempre-avuto-il-tarlo-dellaffido\\\/\"},\"wordCount\":363,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-luciana-littizzetto-ho-sempre-avuto-il-tarlo-dellaffido\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/08\\\/LITTIZZETTO.jpg\",\"keywords\":[\"affido\"],\"articleSection\":[\"Affido &amp; Accoglienza Familiare\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-luciana-littizzetto-ho-sempre-avuto-il-tarlo-dellaffido\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-luciana-littizzetto-ho-sempre-avuto-il-tarlo-dellaffido\\\/\",\"name\":\"Affido. Luciana Littizzetto: \u201cHo sempre avuto il tarlo dell\u2019affido\\\" - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-luciana-littizzetto-ho-sempre-avuto-il-tarlo-dellaffido\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-luciana-littizzetto-ho-sempre-avuto-il-tarlo-dellaffido\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/08\\\/LITTIZZETTO.jpg\",\"datePublished\":\"2021-08-23T05:40:03+00:00\",\"dateModified\":\"2021-08-23T12:16:09+00:00\",\"description\":\"Luciana Littizzetto: \u201cI figli non sono venuti, non era destino [\u2026] il desiderio di maternit\u00e0 non era cos\u00ec pressante. Ero una donna abbastanza serena e contenta, per\u00f2 all\u2019idea di diventare madre non avevo rinunciato\\\"\u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-luciana-littizzetto-ho-sempre-avuto-il-tarlo-dellaffido\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-luciana-littizzetto-ho-sempre-avuto-il-tarlo-dellaffido\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-luciana-littizzetto-ho-sempre-avuto-il-tarlo-dellaffido\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/08\\\/LITTIZZETTO.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/08\\\/LITTIZZETTO.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-luciana-littizzetto-ho-sempre-avuto-il-tarlo-dellaffido\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Affido &amp; Accoglienza Familiare\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/affido\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Affido. Luciana Littizzetto: \u201cHo sempre avuto il tarlo dell\u2019affido&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\",\"name\":\"mc.sabatini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/marias\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Affido. Luciana Littizzetto: \u201cHo sempre avuto il tarlo dell\u2019affido\" - Ai.Bi. Amici dei Bambini","description":"Luciana Littizzetto: \u201cI figli non sono venuti, non era destino [\u2026] il desiderio di maternit\u00e0 non era cos\u00ec pressante. Ero una donna abbastanza serena e contenta, per\u00f2 all\u2019idea di diventare madre non avevo rinunciato\"\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/affido-luciana-littizzetto-ho-sempre-avuto-il-tarlo-dellaffido\/","og_locale":"it_IT","og_type":"article","og_title":"Affido. Luciana Littizzetto: \u201cHo sempre avuto il tarlo dell\u2019affido\"","og_description":"Luciana Littizzetto: \u201cI figli non sono venuti, non era destino [\u2026] il desiderio di maternit\u00e0 non era cos\u00ec pressante. Ero una donna abbastanza serena e contenta, per\u00f2 all\u2019idea di diventare madre non avevo rinunciato\"\u00a0","og_url":"https:\/\/www.aibi.it\/ita\/affido-luciana-littizzetto-ho-sempre-avuto-il-tarlo-dellaffido\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2021-08-23T05:40:03+00:00","article_modified_time":"2021-08-23T12:16:09+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2021\/08\/LITTIZZETTO.jpg","type":"image\/jpeg"}],"author":"mc.sabatini","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"mc.sabatini","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/affido-luciana-littizzetto-ho-sempre-avuto-il-tarlo-dellaffido\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/affido-luciana-littizzetto-ho-sempre-avuto-il-tarlo-dellaffido\/"},"author":{"name":"mc.sabatini","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938"},"headline":"Affido. Luciana Littizzetto: \u201cHo sempre avuto il tarlo dell\u2019affido&#8221;","datePublished":"2021-08-23T05:40:03+00:00","dateModified":"2021-08-23T12:16:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/affido-luciana-littizzetto-ho-sempre-avuto-il-tarlo-dellaffido\/"},"wordCount":363,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/affido-luciana-littizzetto-ho-sempre-avuto-il-tarlo-dellaffido\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/08\/LITTIZZETTO.jpg","keywords":["affido"],"articleSection":["Affido &amp; Accoglienza Familiare"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/affido-luciana-littizzetto-ho-sempre-avuto-il-tarlo-dellaffido\/","url":"https:\/\/www.aibi.it\/ita\/affido-luciana-littizzetto-ho-sempre-avuto-il-tarlo-dellaffido\/","name":"Affido. Luciana Littizzetto: \u201cHo sempre avuto il tarlo dell\u2019affido\" - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/affido-luciana-littizzetto-ho-sempre-avuto-il-tarlo-dellaffido\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/affido-luciana-littizzetto-ho-sempre-avuto-il-tarlo-dellaffido\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/08\/LITTIZZETTO.jpg","datePublished":"2021-08-23T05:40:03+00:00","dateModified":"2021-08-23T12:16:09+00:00","description":"Luciana Littizzetto: \u201cI figli non sono venuti, non era destino [\u2026] il desiderio di maternit\u00e0 non era cos\u00ec pressante. Ero una donna abbastanza serena e contenta, per\u00f2 all\u2019idea di diventare madre non avevo rinunciato\"\u00a0","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/affido-luciana-littizzetto-ho-sempre-avuto-il-tarlo-dellaffido\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/affido-luciana-littizzetto-ho-sempre-avuto-il-tarlo-dellaffido\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/affido-luciana-littizzetto-ho-sempre-avuto-il-tarlo-dellaffido\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2021\/08\/LITTIZZETTO.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/08\/LITTIZZETTO.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/affido-luciana-littizzetto-ho-sempre-avuto-il-tarlo-dellaffido\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Affido &amp; Accoglienza Familiare","item":"https:\/\/www.aibi.it\/ita\/category\/affido\/"},{"@type":"ListItem","position":3,"name":"Affido. Luciana Littizzetto: \u201cHo sempre avuto il tarlo dell\u2019affido&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938","name":"mc.sabatini","url":"https:\/\/www.aibi.it\/ita\/author\/marias\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 04:19:33","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/191240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/97"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=191240"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/191240\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/191241"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=191240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=191240"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=191240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}