﻿


{"id":191263,"date":"2021-08-24T08:00:04","date_gmt":"2021-08-24T06:00:04","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=191263"},"modified":"2021-08-31T08:58:19","modified_gmt":"2021-08-31T06:58:19","slug":"su-50-incarichi-adozione-internazionale-primo-semestre-21","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/su-50-incarichi-adozione-internazionale-primo-semestre-21\/","title":{"rendered":"Sorpresa! Le famiglie italiane ritornano a credere nell\u2019adozione internazionale: primo semestre \u201821, incarichi su del 50 %"},"content":{"rendered":"<h2><strong>Nonostante il Covid, le lentezze burocratiche, le carenze di sostegni economici efficaci, la scarsa \u201cpubblicit\u00e0\u201d, gli incarichi agli enti per l&#8217;adozione internazionale sono tornati al livello del 2019<\/strong><\/h2>\n<p><strong>\u00a0<\/strong>Nel 2019 sono stati <strong>675<\/strong>. Nel 2020 si \u00e8 scesi a <strong>445<\/strong>. Oggi, dopo i soli primi sei mesi dell\u2019anno, il numero \u00e8 gi\u00e0 di <strong>337<\/strong>. Stiamo parlando degli <strong>incarichi conferiti agli enti autorizzati<\/strong> per l\u2019adozione internazionale. Gi\u00e0 solo da questo primo raffronto si capisce come l\u2019anno in corso sia <strong>sorprendentemente positivo<\/strong>, con i dati dei primi sei mesi che si attestano sui valori del 2019, anno in cui del Covid non c\u2019era nemmeno l\u2019ombra.<\/p>\n<p><strong>Covid, burocrazia, aiuti economici\u2026 le difficolt\u00e0 dell\u2019Adozione Internazionale<\/strong><\/p>\n<p>Perch\u00e9 proprio il Covid, inutile girarci intorno, \u00e8 il principale responsabile del calo dei conferimenti dello scorso anno, cos\u00ec come ancora oggi rimane il <strong>principale ostacolo<\/strong> alle coppie che decidono comunque di percorrere il cammino dell\u2019adozione internazionale.<br \/>\nNell\u2019ultimo anno e mezzo abbiamo visto bene tutte le difficolt\u00e0 che i genitori, i bambini e, per la loro parte, anche gli enti, hanno dovuto affrontare: <strong>chiusura delle frontiere<\/strong>; impossibilit\u00e0 di <strong>viaggiare<\/strong>; <strong>coppie bloccate<\/strong> nel Paese di arrivo senza riuscire a tornare a casa con il loro figlio per settimane; confusione sui <strong>vaccini<\/strong> da fare\u2026<br \/>\nNon sono mancate le \u201cvie crucis\u201d, raccontate da molte coppie, di incontri con i servizi sociali continuamente rimandati, di call a distanza difficoltose, di informazioni che faticavano ad arrivare.<br \/>\nInsomma: durante il periodo della pendemia l\u2019adozione si \u00e8 trasformata davvero in una corsa a ostacoli sempre pi\u00f9 complicata.<\/p>\n<p>E non che ce ne fosse bisogno, visto che anche prima difficolt\u00e0 e malfunzionamenti, pi\u00f9 volte sottolineati dagli enti nella speranza di un miglioramento, non sono mai mancati. Per esempio le <strong>incombenze burocratiche<\/strong>, che hanno sempre contribuito all\u2019allungamento dei tempi: basti pensare ad alcune Prefetture che per una legalizzazione fanno aspettare oltre due settimane, oppure ad alcune Procure che rilasciano appuntamenti anche a un mese per la legalizzazione delle asseverazioni delle traduzioni dei documenti\u201d.<\/p>\n<p>Ma si possono anche citare i pochi aiuti economici destinati alle coppie adottive: nonostante le dichiarazioni pubbliche di aumenti, in realt\u00e0 <a href=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-perche-il-bonus-da-10-mila-euro-e-di-gran-lunga-migliore-dei-rimborsi-proposti-dalla-ministra-bonetti\/\">sono ben poche le famiglie che riescono a utilizzarli<\/a>. Mentre la proposta di un <strong>bonus unico<\/strong>, fisso, da dare a tutte le coppie che decidono di adottare, formulata da Ai.Bi. e pi\u00f9 volta riproposta all\u2019attenzione delle autorit\u00e0, <strong>rimane inascoltata<\/strong>.<\/p>\n<p><strong>La fiducia delle coppie italiane verso l\u2019adozione internazionale<\/strong><\/p>\n<p>Nonostante tutto questo, e nonostante l\u2019adozione internazionale <strong>non venga mai promossa n\u00e9 citata nemmeno quando si parla di iniziative contro la denatalit\u00e0<\/strong> (clamorosa la lacuna dell\u2019assoluta assenza dell\u2019adozione internazionale \u2013 cui non \u00e8 stata dedicata neppure una citazione &#8211; nei recenti Stati Generali della Natalit\u00e0 promossi dal Forum delle Associazioni Familiari ), i dati dimostrano che <strong>le coppie italiane ritornano<\/strong> a credere (o, forse, in fondo, loro non hanno mai smesso) nell\u2019adozione internazionale. I dati degli enti di <strong>337 incarichi<\/strong> nei primi sei mesi proiettano un totale sull\u2019anno che potrebbe arrivare a quasi <strong>700<\/strong>. Ovvero 58 promesse al mese di salvare un bambino dall\u2019abbandono, riconoscendogli il diritto di essere figlio. 58 promesse al mese di nuove famiglie che nascono o ri-nascono, nonostante gli ostacoli, nonostante le paure, nonostante i punti di domanda sul futuro e le difficolt\u00e0 economiche.<\/p>\n<p>Un segnale che regala <strong>grande speranza<\/strong> e che dovrebbe essere uno sprone per la CAI, le autorit\u00e0 e anche gli enti autorizzati a <strong>moltiplicare gli sforzi<\/strong> e andare incontro a quel desiderio che le coppie italiane non hanno mai abbandonato: costruire una famiglia e dare una nuova casa e una speranza di futuro ai bambini abbandonati di tutto il mondo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nonostante il Covid, le lentezze burocratiche, le carenze di sostegni economici efficaci, la scarsa &ldquo;pubblicit&agrave;&rdquo;, gli incarichi agli enti per l&rsquo;adozione internazionale sono tornati al livello del 2019 &nbsp;Nel 2019 sono stati 675. Nel 2020 si &egrave; scesi a 445. Oggi, dopo i soli primi sei mesi dell&rsquo;anno, il numero [&hellip;]<\/p>\n","protected":false},"author":102,"featured_media":191265,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[172],"tags":[347,433],"class_list":["post-191263","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-internazionale","tag-adozione-internazionale","tag-cai"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Su del 50% gli incarichi per l\u2019adozione internazionale nel primo semestre \u201821<\/title>\n<meta name=\"description\" content=\"Nonostante il Covid, la burocrazia, i pochi sostegni economici, gli incarichi agli enti per l&#039;adozione internazionale sono tornati al livello del 2019\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/su-50-incarichi-adozione-internazionale-primo-semestre-21\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sorpresa! Le famiglie italiane ritornano a credere nell\u2019adozione internazionale: primo semestre \u201821, incarichi su del 50 %\" \/>\n<meta property=\"og:description\" content=\"Nonostante il Covid, la burocrazia, i pochi sostegni economici, gli incarichi agli enti per l&#039;adozione internazionale sono tornati al livello del 2019\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/su-50-incarichi-adozione-internazionale-primo-semestre-21\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-24T06:00:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-31T06:58:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2021\/08\/adozione_incarichi_enti.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/su-50-incarichi-adozione-internazionale-primo-semestre-21\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/su-50-incarichi-adozione-internazionale-primo-semestre-21\\\/\"},\"author\":{\"name\":\"francescoE\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\"},\"headline\":\"Sorpresa! Le famiglie italiane ritornano a credere nell\u2019adozione internazionale: primo semestre \u201821, incarichi su del 50 %\",\"datePublished\":\"2021-08-24T06:00:04+00:00\",\"dateModified\":\"2021-08-31T06:58:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/su-50-incarichi-adozione-internazionale-primo-semestre-21\\\/\"},\"wordCount\":608,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/su-50-incarichi-adozione-internazionale-primo-semestre-21\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/08\\\/adozione_incarichi_enti.jpg\",\"keywords\":[\"Adozione Internazionale\",\"CAI\"],\"articleSection\":[\"Adozione Internazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/su-50-incarichi-adozione-internazionale-primo-semestre-21\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/su-50-incarichi-adozione-internazionale-primo-semestre-21\\\/\",\"name\":\"Su del 50% gli incarichi per l\u2019adozione internazionale nel primo semestre \u201821\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/su-50-incarichi-adozione-internazionale-primo-semestre-21\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/su-50-incarichi-adozione-internazionale-primo-semestre-21\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/08\\\/adozione_incarichi_enti.jpg\",\"datePublished\":\"2021-08-24T06:00:04+00:00\",\"dateModified\":\"2021-08-31T06:58:19+00:00\",\"description\":\"Nonostante il Covid, la burocrazia, i pochi sostegni economici, gli incarichi agli enti per l'adozione internazionale sono tornati al livello del 2019\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/su-50-incarichi-adozione-internazionale-primo-semestre-21\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/su-50-incarichi-adozione-internazionale-primo-semestre-21\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/su-50-incarichi-adozione-internazionale-primo-semestre-21\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/08\\\/adozione_incarichi_enti.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/08\\\/adozione_incarichi_enti.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/su-50-incarichi-adozione-internazionale-primo-semestre-21\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione Internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-internazionale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sorpresa! Le famiglie italiane ritornano a credere nell\u2019adozione internazionale: primo semestre \u201821, incarichi su del 50 %\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\",\"name\":\"francescoE\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/francescoe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Su del 50% gli incarichi per l\u2019adozione internazionale nel primo semestre \u201821","description":"Nonostante il Covid, la burocrazia, i pochi sostegni economici, gli incarichi agli enti per l'adozione internazionale sono tornati al livello del 2019","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/su-50-incarichi-adozione-internazionale-primo-semestre-21\/","og_locale":"it_IT","og_type":"article","og_title":"Sorpresa! Le famiglie italiane ritornano a credere nell\u2019adozione internazionale: primo semestre \u201821, incarichi su del 50 %","og_description":"Nonostante il Covid, la burocrazia, i pochi sostegni economici, gli incarichi agli enti per l'adozione internazionale sono tornati al livello del 2019","og_url":"https:\/\/www.aibi.it\/ita\/su-50-incarichi-adozione-internazionale-primo-semestre-21\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2021-08-24T06:00:04+00:00","article_modified_time":"2021-08-31T06:58:19+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2021\/08\/adozione_incarichi_enti.jpg","type":"image\/jpeg"}],"author":"francescoE","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"francescoE","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/su-50-incarichi-adozione-internazionale-primo-semestre-21\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/su-50-incarichi-adozione-internazionale-primo-semestre-21\/"},"author":{"name":"francescoE","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5"},"headline":"Sorpresa! Le famiglie italiane ritornano a credere nell\u2019adozione internazionale: primo semestre \u201821, incarichi su del 50 %","datePublished":"2021-08-24T06:00:04+00:00","dateModified":"2021-08-31T06:58:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/su-50-incarichi-adozione-internazionale-primo-semestre-21\/"},"wordCount":608,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/su-50-incarichi-adozione-internazionale-primo-semestre-21\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/08\/adozione_incarichi_enti.jpg","keywords":["Adozione Internazionale","CAI"],"articleSection":["Adozione Internazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/su-50-incarichi-adozione-internazionale-primo-semestre-21\/","url":"https:\/\/www.aibi.it\/ita\/su-50-incarichi-adozione-internazionale-primo-semestre-21\/","name":"Su del 50% gli incarichi per l\u2019adozione internazionale nel primo semestre \u201821","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/su-50-incarichi-adozione-internazionale-primo-semestre-21\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/su-50-incarichi-adozione-internazionale-primo-semestre-21\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/08\/adozione_incarichi_enti.jpg","datePublished":"2021-08-24T06:00:04+00:00","dateModified":"2021-08-31T06:58:19+00:00","description":"Nonostante il Covid, la burocrazia, i pochi sostegni economici, gli incarichi agli enti per l'adozione internazionale sono tornati al livello del 2019","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/su-50-incarichi-adozione-internazionale-primo-semestre-21\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/su-50-incarichi-adozione-internazionale-primo-semestre-21\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/su-50-incarichi-adozione-internazionale-primo-semestre-21\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2021\/08\/adozione_incarichi_enti.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/08\/adozione_incarichi_enti.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/su-50-incarichi-adozione-internazionale-primo-semestre-21\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione Internazionale","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-internazionale\/"},{"@type":"ListItem","position":3,"name":"Sorpresa! Le famiglie italiane ritornano a credere nell\u2019adozione internazionale: primo semestre \u201821, incarichi su del 50 %"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5","name":"francescoE","url":"https:\/\/www.aibi.it\/ita\/author\/francescoe\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 00:43:20","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/191263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=191263"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/191263\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/191265"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=191263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=191263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=191263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}