﻿


{"id":191271,"date":"2021-08-24T12:13:57","date_gmt":"2021-08-24T10:13:57","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=191271"},"modified":"2021-08-24T12:13:57","modified_gmt":"2021-08-24T10:13:57","slug":"psicologia-delladozione-perche-aspetti-anni-e-poi-quando-arriva-labbinamento-scatta-la-paura-e-chiedi-di-aspettare","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/psicologia-delladozione-perche-aspetti-anni-e-poi-quando-arriva-labbinamento-scatta-la-paura-e-chiedi-di-aspettare\/","title":{"rendered":"Psicologia dell&#8217;adozione: perch\u00e9 aspetti anni e poi quando arriva l\u2019abbinamento scatta la paura e chiedi di aspettare?"},"content":{"rendered":"<h2><strong>L\u2019abbinamento \u00e8 l\u2019incontro con il figlio reale, che pu\u00f2 essere diverso da quello immaginato: ecco perch\u00e9 occorre essere ben preparati\u00a0<\/strong><\/h2>\n<p>Il colloquio di abbinamento \u0117 sempre intenso, emozionante, e\u00a0<strong>ogni coppia reagisce a suo modo<\/strong>.<\/p>\n<p>Ho visto futuri genitori reagire con evidente felicit\u00e0, entusiasmo e commozione, altri invece restano quasi\u00a0<strong>bloccati, incerti e un po&#8217; smarriti<\/strong>, mi guardano con sguardi interrogativi e che chiedono aiuto.<\/p>\n<p>Credo non sia possibile dare una risposta unica e certa alla domanda come mai queste coppie reagiscano cos\u00ec, sicuramente durante tutto il periodo di attesa, a volte anche molto lungo,\u00a0<strong>il bambino \u00e8 stato desiderato ed immaginato,\u00a0<\/strong>sono state coltivate grandi aspettative, legate ai propri desideri ed ideali.<\/p>\n<h3><strong>L\u2019abbinamento \u00e8 l\u2019incontro con il figlio reale, che pu\u00f2 essere diverso da quello immaginato<\/strong><\/h3>\n<p>Seppur su carta, in quanto durante il colloquio la psicologa insieme ad un tecnico legge la scheda di descrizione del bambino, l\u2019abbinamento \u00e8 l\u2019incontro con il figlio reale e concreto, che spesso pu\u00f2 essere diverso da quello immaginato;\u00a0<strong>la realt\u00e0 non \u00e8 cos\u00ec semplice ed ideale<\/strong>, pu\u00f2 causare titubanze e sentimenti contrastanti. Quel bambino pu\u00f2 sembrare un estraneo, non corrisponde a ci\u00f2 che la coppia si era immaginato e pu\u00f2 scattare la sensazione che non sia possibile inserirlo nel proprio cuore e nella propria vita.<\/p>\n<p>Pu\u00f2 succedere che non si senta quella spinta, quell\u2019entusiasmo che tutti raccontano, e\u00a0<strong>scatta la paura<\/strong>\u00a0e anche\u00a0<strong>la sensazione di essere sbagliati<\/strong>, ingiusti e inadeguati. In questo colloquio si concretizza il fatto che c\u2019\u00e8 veramente un figlio che sta aspettando, e come una volta mi ha detto una coppia, \u201cfinora si \u00e8 solo parlato,\u00a0<strong>ora si comincia a fare e vivere realmente la famiglia\u201d<\/strong>\u00a0e prendere contatto con questa nuova consapevolezza pu\u00f2 far scattare qualche timore.<\/p>\n<h3><strong>Questo \u00e8 il momento in cui si fanno i conti con i propri limiti e a volte con emozioni che non si pensava ci appartenessero.<\/strong><\/h3>\n<p>Pu\u00f2 essere necessario un tempo di elaborazione della perdita di un bambino che era solo nella propria immaginazione ed aspettativa, un sogno che era dentro di s\u00e9, per poter accogliere quel bambino reale che viene raccontato dalla scheda e che \u00e8 presente nella foto mostrata durante l\u2019abbinamento.<\/p>\n<p>Credo sia importante prima di tutto\u00a0<strong>accogliere questa paura e come futuri genitori perdonarsi questa titubanza:<\/strong>\u00a0l\u2019amore e il senso di appartenenza reciproca si creano gradualmente, nella quotidianit\u00e0, giorno dopo giorno, nella condivisione di esperienze ed emozioni. Dentro il proprio cuore c\u2019\u00e8 gi\u00e0 una parte che dice questo \u00e8 mio figlio, mi sta aspettando, e una parte che per\u00f2 lo sente un estraneo: \u00e8 un momento delicato in cui \u00e8 importante riguardare il proprio percorso, le proprie motivazioni, ascoltare entrambe queste parti, per poi lasciare spazio al cuore e all\u2019amore per\u00a0<strong>quel bambino cos\u00ec come \u00e8 lui, unico e speciale.<\/strong><\/p>\n<p>Mi \u00e8 capitato di cogliere pi\u00f9 volte questa titubanza, ma\u00a0<strong>con il supporto della psicologa, e un buon dialogo di coppia,<\/strong>\u00a0i futuri genitori affrontano e risolvono i loro dubbi e si aprono con gioia all\u2019accoglienza del proprio figlio, accettandolo pienamente cos\u00ec com\u2019\u00e8, con i suoi bisogni e le sue risorse.<\/p>\n<p><strong>Anna Maria Elisa\u00a0Rossi\u00a0<\/strong>&#8211; psicologa e psicoterapeuta di Ai.Bi.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<h3><strong>Formazione e sostegno degli esperti: un supporto importante per l\u2019adozione<\/strong><\/h3>\n<p>L\u2019amore e la volont\u00e0 di farsi famiglia e di accompagnare lungo il cammino della vita un figlio, sono la base imprescindibile per poter intraprendere il cammino dell\u2019adozione internazionale, ma\u00a0<strong>da soli non bastano<\/strong>.<\/p>\n<p>\u00c8 importante per i futuri genitori adottivi, essere\u00a0<strong>informati e formati<\/strong>. \u00c8 importante, nei momenti di difficolt\u00e0 che inevitabilmente si incontreranno durante il proprio percorso, sapere di poter contare sull\u2019appoggio e il sostegno di professionisti esperti.<\/p>\n<p><strong>FARIS \u2013 Family Relationship International School<\/strong>, forte di un\u2019esperienza di pi\u00f9 di 30 anni maturata nel campo dell\u2019accoglienza, mette a disposizione\u00a0<strong>la consulenza dei propri esperti<\/strong>\u00a0per poter fornire ai neo genitori strumenti di lettura e di azione, per meglio comprendere i propri sentimenti e gli atteggiamenti dei propri figli.<\/p>\n<p>Per le coppie invece che volessero conoscere di pi\u00f9, sul mondo dell\u2019adozione internazionale, prima di decidere se intraprendere o meno questo percorso meraviglioso, seppure impegnativo, FARIS organizza il\u00a0<strong>2 settembre<\/strong>\u00a0un webinar gratuito, intitolato: \u201c<strong>Primi passi nel mondo dell\u2019adozione internazionale\u201d.<\/strong><\/p>\n<p>Per maggiori informazioni, vi invitiamo a consultare il sito di\u00a0<strong>FARIS \u2013 Family Relationship International School\u00a0<\/strong><a href=\"https:\/\/www.fondazioneaibi.it\/faris\/prodotto\/primi-passi-nel-mondo-delladozione-internazionale-2\/\"><strong>QUI.<\/strong><\/a><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;abbinamento &egrave; l&rsquo;incontro con il figlio reale, che pu&ograve; essere diverso da quello immaginato: ecco perch&eacute; occorre essere ben preparati&nbsp; Il colloquio di abbinamento &#279; sempre intenso, emozionante, e&nbsp;ogni coppia reagisce a suo modo. Ho visto futuri genitori reagire con evidente felicit&agrave;, entusiasmo e commozione, altri invece restano quasi&nbsp;bloccati, incerti [&hellip;]<\/p>\n","protected":false},"author":97,"featured_media":191273,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[777],"tags":[347,776],"class_list":["post-191271","post","type-post","status-publish","format-standard","has-post-thumbnail","category-faris","tag-adozione-internazionale","tag-faris"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Psicologia dell&#039;adozione: perch\u00e9 aspetti anni e poi quando arriva l\u2019abbinamento scatta la paura e chiedi di aspettare? - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"Adozione. L\u2019abbinamento \u00e8 l\u2019incontro con il figlio reale, che pu\u00f2 essere diverso da quello immaginato: ecco perch\u00e9 occorre essere ben preparati\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/psicologia-delladozione-perche-aspetti-anni-e-poi-quando-arriva-labbinamento-scatta-la-paura-e-chiedi-di-aspettare\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Psicologia dell&#039;adozione: perch\u00e9 aspetti anni e poi quando arriva l\u2019abbinamento scatta la paura e chiedi di aspettare?\" \/>\n<meta property=\"og:description\" content=\"Adozione. L\u2019abbinamento \u00e8 l\u2019incontro con il figlio reale, che pu\u00f2 essere diverso da quello immaginato: ecco perch\u00e9 occorre essere ben preparati\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/psicologia-delladozione-perche-aspetti-anni-e-poi-quando-arriva-labbinamento-scatta-la-paura-e-chiedi-di-aspettare\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-24T10:13:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2021\/08\/adozione-2-7.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mc.sabatini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mc.sabatini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/psicologia-delladozione-perche-aspetti-anni-e-poi-quando-arriva-labbinamento-scatta-la-paura-e-chiedi-di-aspettare\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/psicologia-delladozione-perche-aspetti-anni-e-poi-quando-arriva-labbinamento-scatta-la-paura-e-chiedi-di-aspettare\\\/\"},\"author\":{\"name\":\"mc.sabatini\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\"},\"headline\":\"Psicologia dell&#8217;adozione: perch\u00e9 aspetti anni e poi quando arriva l\u2019abbinamento scatta la paura e chiedi di aspettare?\",\"datePublished\":\"2021-08-24T10:13:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/psicologia-delladozione-perche-aspetti-anni-e-poi-quando-arriva-labbinamento-scatta-la-paura-e-chiedi-di-aspettare\\\/\"},\"wordCount\":727,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/psicologia-delladozione-perche-aspetti-anni-e-poi-quando-arriva-labbinamento-scatta-la-paura-e-chiedi-di-aspettare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/08\\\/adozione-2-7.jpg\",\"keywords\":[\"Adozione Internazionale\",\"FARIS\"],\"articleSection\":[\"Faris\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/psicologia-delladozione-perche-aspetti-anni-e-poi-quando-arriva-labbinamento-scatta-la-paura-e-chiedi-di-aspettare\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/psicologia-delladozione-perche-aspetti-anni-e-poi-quando-arriva-labbinamento-scatta-la-paura-e-chiedi-di-aspettare\\\/\",\"name\":\"Psicologia dell'adozione: perch\u00e9 aspetti anni e poi quando arriva l\u2019abbinamento scatta la paura e chiedi di aspettare? - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/psicologia-delladozione-perche-aspetti-anni-e-poi-quando-arriva-labbinamento-scatta-la-paura-e-chiedi-di-aspettare\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/psicologia-delladozione-perche-aspetti-anni-e-poi-quando-arriva-labbinamento-scatta-la-paura-e-chiedi-di-aspettare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/08\\\/adozione-2-7.jpg\",\"datePublished\":\"2021-08-24T10:13:57+00:00\",\"description\":\"Adozione. L\u2019abbinamento \u00e8 l\u2019incontro con il figlio reale, che pu\u00f2 essere diverso da quello immaginato: ecco perch\u00e9 occorre essere ben preparati\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/psicologia-delladozione-perche-aspetti-anni-e-poi-quando-arriva-labbinamento-scatta-la-paura-e-chiedi-di-aspettare\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/psicologia-delladozione-perche-aspetti-anni-e-poi-quando-arriva-labbinamento-scatta-la-paura-e-chiedi-di-aspettare\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/psicologia-delladozione-perche-aspetti-anni-e-poi-quando-arriva-labbinamento-scatta-la-paura-e-chiedi-di-aspettare\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/08\\\/adozione-2-7.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/08\\\/adozione-2-7.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/psicologia-delladozione-perche-aspetti-anni-e-poi-quando-arriva-labbinamento-scatta-la-paura-e-chiedi-di-aspettare\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Faris\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/faris\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Psicologia dell&#8217;adozione: perch\u00e9 aspetti anni e poi quando arriva l\u2019abbinamento scatta la paura e chiedi di aspettare?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\",\"name\":\"mc.sabatini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/marias\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Psicologia dell'adozione: perch\u00e9 aspetti anni e poi quando arriva l\u2019abbinamento scatta la paura e chiedi di aspettare? - Ai.Bi. Amici dei Bambini","description":"Adozione. L\u2019abbinamento \u00e8 l\u2019incontro con il figlio reale, che pu\u00f2 essere diverso da quello immaginato: ecco perch\u00e9 occorre essere ben preparati","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/psicologia-delladozione-perche-aspetti-anni-e-poi-quando-arriva-labbinamento-scatta-la-paura-e-chiedi-di-aspettare\/","og_locale":"it_IT","og_type":"article","og_title":"Psicologia dell'adozione: perch\u00e9 aspetti anni e poi quando arriva l\u2019abbinamento scatta la paura e chiedi di aspettare?","og_description":"Adozione. L\u2019abbinamento \u00e8 l\u2019incontro con il figlio reale, che pu\u00f2 essere diverso da quello immaginato: ecco perch\u00e9 occorre essere ben preparati","og_url":"https:\/\/www.aibi.it\/ita\/psicologia-delladozione-perche-aspetti-anni-e-poi-quando-arriva-labbinamento-scatta-la-paura-e-chiedi-di-aspettare\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2021-08-24T10:13:57+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2021\/08\/adozione-2-7.jpg","type":"image\/jpeg"}],"author":"mc.sabatini","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"mc.sabatini","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/psicologia-delladozione-perche-aspetti-anni-e-poi-quando-arriva-labbinamento-scatta-la-paura-e-chiedi-di-aspettare\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/psicologia-delladozione-perche-aspetti-anni-e-poi-quando-arriva-labbinamento-scatta-la-paura-e-chiedi-di-aspettare\/"},"author":{"name":"mc.sabatini","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938"},"headline":"Psicologia dell&#8217;adozione: perch\u00e9 aspetti anni e poi quando arriva l\u2019abbinamento scatta la paura e chiedi di aspettare?","datePublished":"2021-08-24T10:13:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/psicologia-delladozione-perche-aspetti-anni-e-poi-quando-arriva-labbinamento-scatta-la-paura-e-chiedi-di-aspettare\/"},"wordCount":727,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/psicologia-delladozione-perche-aspetti-anni-e-poi-quando-arriva-labbinamento-scatta-la-paura-e-chiedi-di-aspettare\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/08\/adozione-2-7.jpg","keywords":["Adozione Internazionale","FARIS"],"articleSection":["Faris"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/psicologia-delladozione-perche-aspetti-anni-e-poi-quando-arriva-labbinamento-scatta-la-paura-e-chiedi-di-aspettare\/","url":"https:\/\/www.aibi.it\/ita\/psicologia-delladozione-perche-aspetti-anni-e-poi-quando-arriva-labbinamento-scatta-la-paura-e-chiedi-di-aspettare\/","name":"Psicologia dell'adozione: perch\u00e9 aspetti anni e poi quando arriva l\u2019abbinamento scatta la paura e chiedi di aspettare? - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/psicologia-delladozione-perche-aspetti-anni-e-poi-quando-arriva-labbinamento-scatta-la-paura-e-chiedi-di-aspettare\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/psicologia-delladozione-perche-aspetti-anni-e-poi-quando-arriva-labbinamento-scatta-la-paura-e-chiedi-di-aspettare\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/08\/adozione-2-7.jpg","datePublished":"2021-08-24T10:13:57+00:00","description":"Adozione. L\u2019abbinamento \u00e8 l\u2019incontro con il figlio reale, che pu\u00f2 essere diverso da quello immaginato: ecco perch\u00e9 occorre essere ben preparati","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/psicologia-delladozione-perche-aspetti-anni-e-poi-quando-arriva-labbinamento-scatta-la-paura-e-chiedi-di-aspettare\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/psicologia-delladozione-perche-aspetti-anni-e-poi-quando-arriva-labbinamento-scatta-la-paura-e-chiedi-di-aspettare\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/psicologia-delladozione-perche-aspetti-anni-e-poi-quando-arriva-labbinamento-scatta-la-paura-e-chiedi-di-aspettare\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2021\/08\/adozione-2-7.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/08\/adozione-2-7.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/psicologia-delladozione-perche-aspetti-anni-e-poi-quando-arriva-labbinamento-scatta-la-paura-e-chiedi-di-aspettare\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Faris","item":"https:\/\/www.aibi.it\/ita\/category\/faris\/"},{"@type":"ListItem","position":3,"name":"Psicologia dell&#8217;adozione: perch\u00e9 aspetti anni e poi quando arriva l\u2019abbinamento scatta la paura e chiedi di aspettare?"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938","name":"mc.sabatini","url":"https:\/\/www.aibi.it\/ita\/author\/marias\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 04:34:54","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/191271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/97"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=191271"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/191271\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/191273"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=191271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=191271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=191271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}