﻿


{"id":191471,"date":"2021-09-01T08:00:07","date_gmt":"2021-09-01T06:00:07","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=191471"},"modified":"2021-08-31T18:25:56","modified_gmt":"2021-08-31T16:25:56","slug":"1-settembre-tutte-le-regole-del-green-pass","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/1-settembre-tutte-le-regole-del-green-pass\/","title":{"rendered":"1 settembre: tutte le regole del Green Pass"},"content":{"rendered":"<h2>Dall\u2019obbligo della certificazione per i trasporti a lunga percorrenza alle regole, e le esenzioni, per scuole e Universit\u00e0. Tutto quello che c\u2019\u00e8 da sapere sull\u2019utilizzo del Green Pass a partire dall\u20191 settembre<\/h2>\n<p>\u201cL\u2019estate sta finendo\u201d cantavano i Righeira, ma questa volta, pi\u00f9 che \u201cun anno (che) se ne va\u201d, \u00e8 \u201cun Green Pass che arriva\u201d. O meglio, con il Green Pass ormai ciascuno sta familiarizzando da mesi, ma <strong>a partire dall\u20191 settembre scattano diverse novit\u00e0<\/strong> annunciate gi\u00e0 nel Decreto firmato dal Governo il 6 agosto.<br \/>\nQuelle che non cambiano sono le <strong>regole per ottenere la certificazione<\/strong>, rilasciata a chi ha effettuato la <strong>vaccinazione<\/strong> (anche una sola dose, in questo caso \u00e8 valida dai 15 giorni successivi e fino alla data del richiamo): per questi, al momento, la durata del certificato \u00e8 di 9 mesi, anche se il CTS ha gi\u00e0 dato parere favorevole a <a href=\"https:\/\/www.aibi.it\/ita\/covid-la-durata-del-green-pass-estesa-a-12-mesi\/\">estendere la durata a 12 mesi<\/a>. Ottengono il Green Pass anche i <strong>guariti dal Covid<\/strong> (validit\u00e0 6 mesi) e <strong>chi effettua un tampone<\/strong> antigenico o molecolare negativo (validit\u00e0 48 ore).<\/p>\n<h3><strong>Green Pass: le nuove regole per i trasporti<\/strong><\/h3>\n<p>Dall\u20191 settembre, <strong>l\u2019obbligo del Green Pass scatta per i trasporti non locali<\/strong>: ovvero per treni ad alta velocit\u00e0, Intercity, ecc., aerei anche per voli nazionali e traghetti. Restano esclusi i collegamenti marittimi nello Stretto di Messina.<br \/>\nCertificato obbligatorio anche sui <strong>bus con collegamenti interregionali<\/strong> e per le <strong>tratte turistiche<\/strong> pi\u00f9 lunghe.<br \/>\nNon serve Pass, invece, per il trasporto locale come metropolitana, autobus, tram, ecc.<br \/>\nEsclusi da tutte queste norme i minori di 12 anni, per i quali ancora non ci sono vaccini, e chi non si pu\u00f2 vaccinare per motivi di salute: per loro l\u2019accesso \u00e8 sempre consentito anche senza Green Pass.<\/p>\n<h3><strong>Scuola e Universit\u00e0: obbligatorio il Green Pass dall\u20191 settembre<\/strong><\/h3>\n<p>Come pi\u00f9 volte annunciato, da settembre scatta <strong>l\u2019obbligo del Green Pass anche per i docenti e il personale scolastico<\/strong> che si recano a lavoro. Senza certificato non si accede a scuola e, questo, viene considerato come una assenza ingiustificata, con sospensione dello stipendio a partire dal quinto giorno di assenza.<br \/>\nNon \u00e8 richiesto Green Pass, invece, per gli studenti.<br \/>\nTutte le regole per il ritorno a scuola le abbiamo spiegate <a href=\"https:\/\/www.aibi.it\/ita\/ritorno-a-scuola-meno-13-giorni-regole\/\">qui<\/a><\/p>\n<p>Regole analoghe anche per <strong>l\u2019Universit\u00e0<\/strong> che, per\u00f2, richieder\u00e0 il Green Pass <strong>anche agli studenti<\/strong> per seguire le lezioni in presenza e sostenere gli esami. Come per i trasporti, docenti, personale e studenti che non possono vaccinarsi per motivi di salute sono esclusi dall\u2019obbligo di Green Pass, devono, per\u00f2, esibire una \u201cidonea certificazione\u201d.<\/p>\n<h3><strong>Le proteste dei \u201cno Green Pass\u201d<\/strong><\/h3>\n<p>Come riportano le cronache, non mancano le <strong>polemiche sull\u2019\u2019estensione dell\u2019obbligo del Green Pass<\/strong>, con diverse manifestazioni gi\u00e0 annunciate proprio per l\u20191 settembre e la promessa di bloccare le stazioni ferroviarie. Dura, come riporta il <em>Corriere della Sera<\/em>, la presa di posizione del sottosegretario all\u2019Interno Carlo Sibilia, che in un tweet ha commentato: \u201cSe qualcuno domani arrecher\u00e0 disagi alla circolazione ferroviaria bloccando le stazioni, andr\u00e0 incontro ad una <strong>denuncia per interruzione di pubblico servizio<\/strong>. Un conto \u00e8 manifestare pacificamente, altra cosa \u00e8 creare disagi alle altre persone, commettendo di fatto un reato. Dovremo essere intransigenti\u201d.<br \/>\nLa musica dei Righeira sembra decisamente lontana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dall&rsquo;obbligo della certificazione per i trasporti a lunga percorrenza alle regole, e le esenzioni, per scuole e Universit&agrave;. Tutto quello che c&rsquo;&egrave; da sapere sull&rsquo;utilizzo del Green Pass a partire dall&rsquo;1 settembre &ldquo;L&rsquo;estate sta finendo&rdquo; cantavano i Righeira, ma questa volta, pi&ugrave; che &ldquo;un anno (che) se ne va&rdquo;, &egrave; [&hellip;]<\/p>\n","protected":false},"author":102,"featured_media":191473,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[755,815],"class_list":["post-191471","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews","tag-covid","tag-green-pass"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>1 settembre: tutte le regole del Green Pass<\/title>\n<meta name=\"description\" content=\"Dall\u2019obbligo per i trasporti a lunga percorrenza alle regole per scuole e Universit\u00e0. Tutto quello che c\u2019\u00e8 da sapere sul Green Pass a partire dall\u20191 settembre\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/1-settembre-tutte-le-regole-del-green-pass\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"1 settembre: tutte le regole del Green Pass\" \/>\n<meta property=\"og:description\" content=\"Dall\u2019obbligo per i trasporti a lunga percorrenza alle regole per scuole e Universit\u00e0. Tutto quello che c\u2019\u00e8 da sapere sul Green Pass a partire dall\u20191 settembre\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/1-settembre-tutte-le-regole-del-green-pass\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-01T06:00:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2021\/08\/green-pass-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/1-settembre-tutte-le-regole-del-green-pass\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/1-settembre-tutte-le-regole-del-green-pass\\\/\"},\"author\":{\"name\":\"francescoE\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\"},\"headline\":\"1 settembre: tutte le regole del Green Pass\",\"datePublished\":\"2021-09-01T06:00:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/1-settembre-tutte-le-regole-del-green-pass\\\/\"},\"wordCount\":527,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/1-settembre-tutte-le-regole-del-green-pass\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/08\\\/green-pass-1.jpg\",\"keywords\":[\"covid\",\"green pass\"],\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/1-settembre-tutte-le-regole-del-green-pass\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/1-settembre-tutte-le-regole-del-green-pass\\\/\",\"name\":\"1 settembre: tutte le regole del Green Pass\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/1-settembre-tutte-le-regole-del-green-pass\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/1-settembre-tutte-le-regole-del-green-pass\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/08\\\/green-pass-1.jpg\",\"datePublished\":\"2021-09-01T06:00:07+00:00\",\"description\":\"Dall\u2019obbligo per i trasporti a lunga percorrenza alle regole per scuole e Universit\u00e0. Tutto quello che c\u2019\u00e8 da sapere sul Green Pass a partire dall\u20191 settembre\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/1-settembre-tutte-le-regole-del-green-pass\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/1-settembre-tutte-le-regole-del-green-pass\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/1-settembre-tutte-le-regole-del-green-pass\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/08\\\/green-pass-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/08\\\/green-pass-1.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/1-settembre-tutte-le-regole-del-green-pass\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"1 settembre: tutte le regole del Green Pass\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\",\"name\":\"francescoE\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/francescoe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"1 settembre: tutte le regole del Green Pass","description":"Dall\u2019obbligo per i trasporti a lunga percorrenza alle regole per scuole e Universit\u00e0. Tutto quello che c\u2019\u00e8 da sapere sul Green Pass a partire dall\u20191 settembre","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/1-settembre-tutte-le-regole-del-green-pass\/","og_locale":"it_IT","og_type":"article","og_title":"1 settembre: tutte le regole del Green Pass","og_description":"Dall\u2019obbligo per i trasporti a lunga percorrenza alle regole per scuole e Universit\u00e0. Tutto quello che c\u2019\u00e8 da sapere sul Green Pass a partire dall\u20191 settembre","og_url":"https:\/\/www.aibi.it\/ita\/1-settembre-tutte-le-regole-del-green-pass\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2021-09-01T06:00:07+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2021\/08\/green-pass-1.jpg","type":"image\/jpeg"}],"author":"francescoE","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"francescoE","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/1-settembre-tutte-le-regole-del-green-pass\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/1-settembre-tutte-le-regole-del-green-pass\/"},"author":{"name":"francescoE","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5"},"headline":"1 settembre: tutte le regole del Green Pass","datePublished":"2021-09-01T06:00:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/1-settembre-tutte-le-regole-del-green-pass\/"},"wordCount":527,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/1-settembre-tutte-le-regole-del-green-pass\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/08\/green-pass-1.jpg","keywords":["covid","green pass"],"articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/1-settembre-tutte-le-regole-del-green-pass\/","url":"https:\/\/www.aibi.it\/ita\/1-settembre-tutte-le-regole-del-green-pass\/","name":"1 settembre: tutte le regole del Green Pass","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/1-settembre-tutte-le-regole-del-green-pass\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/1-settembre-tutte-le-regole-del-green-pass\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/08\/green-pass-1.jpg","datePublished":"2021-09-01T06:00:07+00:00","description":"Dall\u2019obbligo per i trasporti a lunga percorrenza alle regole per scuole e Universit\u00e0. Tutto quello che c\u2019\u00e8 da sapere sul Green Pass a partire dall\u20191 settembre","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/1-settembre-tutte-le-regole-del-green-pass\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/1-settembre-tutte-le-regole-del-green-pass\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/1-settembre-tutte-le-regole-del-green-pass\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2021\/08\/green-pass-1.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/08\/green-pass-1.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/1-settembre-tutte-le-regole-del-green-pass\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"1 settembre: tutte le regole del Green Pass"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5","name":"francescoE","url":"https:\/\/www.aibi.it\/ita\/author\/francescoe\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 00:15:12","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/191471","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=191471"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/191471\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/191473"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=191471"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=191471"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=191471"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}