﻿


{"id":191588,"date":"2021-09-06T14:14:38","date_gmt":"2021-09-06T12:14:38","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=191588"},"modified":"2022-07-25T11:58:36","modified_gmt":"2022-07-25T09:58:36","slug":"cina-indovina-cose-questo-i-bimbi-a-lezione-diortaggi","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/cina-indovina-cose-questo-i-bimbi-a-lezione-diortaggi\/","title":{"rendered":"Cina. Indovina cos\u2019\u00e8 questo? I bimbi a lezione di\u2026ortaggi!"},"content":{"rendered":"<h2><strong>Grazie al <a href=\"https:\/\/www.aibi.it\/ita\/sostegno-a-distanza\/\">Sostegno a Distanza<\/a>, Ai.Bi. cerca sempre di far vivere ai piccoli ospiti della Casa di Accoglienza di Xi\u2019An la quotidianit\u00e0 della vita familiare, per far vivere al meglio l\u2019attesa della nuova<\/strong><strong> famiglia adottiva\u00a0<\/strong><\/h2>\n<p style=\"text-align: left;\">I bambini della La Casa di Accoglienza di Xi\u2019An si godono i frutti del raccolto, e si sa che non c\u2019\u00e8 frutta e verdura pi\u00f9 buona di quella coltivata con le proprie mani!<\/p>\n<p style=\"text-align: left;\">S\u00ec perch\u00e9 come vi abbiamo raccontato pi\u00f9 volte, spesso le tate portano i bimbi in campagna nei loro paesi natali, dove i nostri piccoli si divertono a guardare ed a interagire con gli animali e aiutano a raccogliere la frutta e la verdura. Come ricompensa per il loro duro lavoro, ogni mese i parenti delle tate spediscono in citt\u00e0 della frutta e verdura appena raccolta.<\/p>\n<p style=\"text-align: left;\">Le tate, prima di lavare e cucinare gli ortaggi, hanno iniziato a fare domande ai bimbi su nomi, caratteristiche e qualit\u00e0 dei diversi ortaggi. I bambini a turno dicono il nome della verdura in questione, in quale stagione cresce, e per cosa fa bene mangiarla.<\/p>\n<p style=\"text-align: left;\">Le nostre tate si inventano sempre qualcosa di diverso per <strong>far crescere i bambini in modo sereno e stimolante<\/strong>, e sfruttare appieno l\u2019enorme fortuna che hanno gli ospiti del Centro Vittorino Colombo, che <strong>grazie all\u2019aiuto dei sostenitori di questo Progetto possono vivere in una casa vera e propria<\/strong> con accanto delle persone, le tate appunto, che li amano, e non in un contesto di istituzionalizzazione.<\/p>\n<p style=\"text-align: left;\"><strong>La\u00a0Casa di Accoglienza Vittorino Colombo\u00a0\u00e8 specializzata in interventi di recupero di bambini abbandonati con problemi di salute<\/strong> e ospita, contemporaneamente, fino a 8 bambini con diverse patologie. Il benessere dei minori accolti \u00e8 garantito dalla <strong>professionalit\u00e0 e dedizione di quattro tate, due educatori ed un\u2019infermiera specializzata<\/strong>, il tutto all\u2019interno di un ambiente familiare costruito a misura di bambino.<\/p>\n<p style=\"text-align: left;\">Il poter seguire questi bambini con cura, con le tante altre belle iniziative che ogni settimana fanno parte della vita di questi bambini, sono possibili grazie al contributo dei sostenitori di Ai.Bi. che finanziano questo progetto.<\/p>\n<p style=\"text-align: left;\">Diventa anche tu un sostenitore del centro di accoglienza Vittorino Colombo, puoi fare la differenza per questi bambini, potrai seguire e accompagnare ogni giorno la vita, i progressi, le difficolt\u00e0 e le gioie dei sette piccoli accolti, e soprattutto la loro gioia al momento dell\u2019inserimento in una famiglia adottiva. Grazie a report mensili infatti, sarai costantemente aggiornato sui bambini del tuo Centro, il Vittorino Colombo di Xi\u2019An.<\/p>\n<p style=\"text-align: left;\">Per te un caff\u00e8 in meno al giorno, per loro la speranza per una vita in famiglia.<\/p>\n<p style=\"text-align: left;\">Attiva un\u00a0<a href=\"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/attivazione-adozione-a-distanza\/\">Sostegno a Distanza<\/a> bastano\u00a025 euro\u00a0al mese.<\/p>\n<p style=\"text-align: left;\">\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*168342-start*\/\n#btnsx-168342{margin-top:0px;margin-bottom:20px;margin-left:0px;margin-right:0px;padding-top:20px;padding-bottom:20px;padding-left:40px;padding-right:40px;}\n#btnsx-168342 .btnsx-text-primary{font-size:30px;line-height:30px;font-family:Montserrat;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-168342:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-168342{background-color:#ef7b0b!important;}\n#btnsx-168342:hover{background-color:#eab20b!important;}\n#btnsx-168342{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-168342:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*168342-end*\/\n<\/style><div id=\"btnsx-168342-wrap\" class=\"btnsx-wrap-center\" align=\"center\"><div id=\"btnsx-168342-container\" class=\"btnsx-btn-container\">\n<a href=\"https:\/\/dona.aibi.it\/adozione-a-distanza\/\" id=\"btnsx-168342\" target=\"_blank\" class=\"btnsx-btn btnsx-btn-embossed\"  data-font-primary=\"Montserrat\">\n\t<span class=\"btnsx-text-primary \">Sostieni a distanza<\/span><\/a>\n<\/div><\/div>\n<!-- Buttons X - End -->\n\n<p style=\"text-align: left;\">\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*168342-start*\/\n#btnsx-168342{margin-top:0px;margin-bottom:20px;margin-left:0px;margin-right:0px;padding-top:20px;padding-bottom:20px;padding-left:40px;padding-right:40px;}\n#btnsx-168342 .btnsx-text-primary{font-size:30px;line-height:30px;font-family:Montserrat;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-168342:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-168342{background-color:#ef7b0b!important;}\n#btnsx-168342:hover{background-color:#eab20b!important;}\n#btnsx-168342{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-168342:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*168342-end*\/\n<\/style><div id=\"btnsx-168342-wrap\" class=\"btnsx-wrap-center\" align=\"center\"><div id=\"btnsx-168342-container\" class=\"btnsx-btn-container\">\n<a href=\"https:\/\/www.aibi.it\/ita\/adotta-a-distanza-25\/\" id=\"btnsx-168342\" target=\"_blank\" class=\"btnsx-btn btnsx-btn-embossed\"  data-font-primary=\"Montserrat\">\n\t<span class=\"btnsx-text-primary \">Scopri di pi\u00f9<\/span><\/a>\n<\/div><\/div>\n<!-- Buttons X - End -->\n\n","protected":false},"excerpt":{"rendered":"<p>Grazie al Sostegno a Distanza, Ai.Bi. cerca sempre di far vivere ai piccoli ospiti della Casa di Accoglienza di Xi&rsquo;An la quotidianit&agrave; della vita familiare, per far vivere al meglio l&rsquo;attesa della nuova famiglia adottiva&nbsp; I bambini della La Casa di Accoglienza di Xi&rsquo;An si godono i frutti del raccolto, [&hellip;]<\/p>\n","protected":false},"author":96,"featured_media":191581,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[209],"tags":[300,649],"class_list":["post-191588","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-a-distanza","tag-sostegno-a-distanza","tag-vittorino-colombo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cina. Indovina cos\u2019\u00e8 questo? I bimbi a lezione di\u2026ortaggi! - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/cina-indovina-cose-questo-i-bimbi-a-lezione-diortaggi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cina. Indovina cos\u2019\u00e8 questo? I bimbi a lezione di\u2026ortaggi!\" \/>\n<meta property=\"og:description\" content=\"Grazie al Sostegno a Distanza, Ai.Bi. cerca sempre di far vivere ai piccoli ospiti della Casa di Accoglienza di Xi&rsquo;An la quotidianit&agrave; della vita familiare, per far vivere al meglio l&rsquo;attesa della nuova famiglia adottiva&nbsp; I bambini della La Casa di Accoglienza di Xi&rsquo;An si godono i frutti del raccolto, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/cina-indovina-cose-questo-i-bimbi-a-lezione-diortaggi\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-06T12:14:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-25T09:58:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2021\/09\/foto-aibi-cina-sad_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"maraA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2021\/09\/foto-aibi-cina-sad_fb.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"maraA\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-indovina-cose-questo-i-bimbi-a-lezione-diortaggi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-indovina-cose-questo-i-bimbi-a-lezione-diortaggi\\\/\"},\"author\":{\"name\":\"maraA\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/fadff90824724a76348891dedf691e46\"},\"headline\":\"Cina. Indovina cos\u2019\u00e8 questo? I bimbi a lezione di\u2026ortaggi!\",\"datePublished\":\"2021-09-06T12:14:38+00:00\",\"dateModified\":\"2022-07-25T09:58:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-indovina-cose-questo-i-bimbi-a-lezione-diortaggi\\\/\"},\"wordCount\":482,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-indovina-cose-questo-i-bimbi-a-lezione-diortaggi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/09\\\/foto-aibi-cina-sad_fb.jpg\",\"keywords\":[\"sostegno a distanza\",\"Vittorino Colombo\"],\"articleSection\":[\"Adozione a Distanza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-indovina-cose-questo-i-bimbi-a-lezione-diortaggi\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-indovina-cose-questo-i-bimbi-a-lezione-diortaggi\\\/\",\"name\":\"Cina. Indovina cos\u2019\u00e8 questo? I bimbi a lezione di\u2026ortaggi! - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-indovina-cose-questo-i-bimbi-a-lezione-diortaggi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-indovina-cose-questo-i-bimbi-a-lezione-diortaggi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/09\\\/foto-aibi-cina-sad_fb.jpg\",\"datePublished\":\"2021-09-06T12:14:38+00:00\",\"dateModified\":\"2022-07-25T09:58:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-indovina-cose-questo-i-bimbi-a-lezione-diortaggi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-indovina-cose-questo-i-bimbi-a-lezione-diortaggi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-indovina-cose-questo-i-bimbi-a-lezione-diortaggi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/09\\\/foto-aibi-cina-sad_fb.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/09\\\/foto-aibi-cina-sad_fb.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-indovina-cose-questo-i-bimbi-a-lezione-diortaggi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione a Distanza\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-a-distanza\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cina. Indovina cos\u2019\u00e8 questo? I bimbi a lezione di\u2026ortaggi!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/fadff90824724a76348891dedf691e46\",\"name\":\"maraA\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/maraa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cina. Indovina cos\u2019\u00e8 questo? I bimbi a lezione di\u2026ortaggi! - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/cina-indovina-cose-questo-i-bimbi-a-lezione-diortaggi\/","og_locale":"it_IT","og_type":"article","og_title":"Cina. Indovina cos\u2019\u00e8 questo? I bimbi a lezione di\u2026ortaggi!","og_description":"Grazie al Sostegno a Distanza, Ai.Bi. cerca sempre di far vivere ai piccoli ospiti della Casa di Accoglienza di Xi&rsquo;An la quotidianit&agrave; della vita familiare, per far vivere al meglio l&rsquo;attesa della nuova famiglia adottiva&nbsp; I bambini della La Casa di Accoglienza di Xi&rsquo;An si godono i frutti del raccolto, [&hellip;]","og_url":"https:\/\/www.aibi.it\/ita\/cina-indovina-cose-questo-i-bimbi-a-lezione-diortaggi\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2021-09-06T12:14:38+00:00","article_modified_time":"2022-07-25T09:58:36+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2021\/09\/foto-aibi-cina-sad_fb.jpg","type":"image\/jpeg"}],"author":"maraA","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.aibi.it\/ita\/images\/2021\/09\/foto-aibi-cina-sad_fb.jpg","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"maraA","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/cina-indovina-cose-questo-i-bimbi-a-lezione-diortaggi\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/cina-indovina-cose-questo-i-bimbi-a-lezione-diortaggi\/"},"author":{"name":"maraA","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/fadff90824724a76348891dedf691e46"},"headline":"Cina. Indovina cos\u2019\u00e8 questo? I bimbi a lezione di\u2026ortaggi!","datePublished":"2021-09-06T12:14:38+00:00","dateModified":"2022-07-25T09:58:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/cina-indovina-cose-questo-i-bimbi-a-lezione-diortaggi\/"},"wordCount":482,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/cina-indovina-cose-questo-i-bimbi-a-lezione-diortaggi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/09\/foto-aibi-cina-sad_fb.jpg","keywords":["sostegno a distanza","Vittorino Colombo"],"articleSection":["Adozione a Distanza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/cina-indovina-cose-questo-i-bimbi-a-lezione-diortaggi\/","url":"https:\/\/www.aibi.it\/ita\/cina-indovina-cose-questo-i-bimbi-a-lezione-diortaggi\/","name":"Cina. Indovina cos\u2019\u00e8 questo? I bimbi a lezione di\u2026ortaggi! - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/cina-indovina-cose-questo-i-bimbi-a-lezione-diortaggi\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/cina-indovina-cose-questo-i-bimbi-a-lezione-diortaggi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/09\/foto-aibi-cina-sad_fb.jpg","datePublished":"2021-09-06T12:14:38+00:00","dateModified":"2022-07-25T09:58:36+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/cina-indovina-cose-questo-i-bimbi-a-lezione-diortaggi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/cina-indovina-cose-questo-i-bimbi-a-lezione-diortaggi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/cina-indovina-cose-questo-i-bimbi-a-lezione-diortaggi\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2021\/09\/foto-aibi-cina-sad_fb.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/09\/foto-aibi-cina-sad_fb.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/cina-indovina-cose-questo-i-bimbi-a-lezione-diortaggi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione a Distanza","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-a-distanza\/"},{"@type":"ListItem","position":3,"name":"Cina. Indovina cos\u2019\u00e8 questo? I bimbi a lezione di\u2026ortaggi!"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/fadff90824724a76348891dedf691e46","name":"maraA","url":"https:\/\/www.aibi.it\/ita\/author\/maraa\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 12:40:52","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/191588","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/96"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=191588"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/191588\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/191581"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=191588"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=191588"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=191588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}