﻿


{"id":192162,"date":"2021-09-24T07:30:53","date_gmt":"2021-09-24T05:30:53","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=192162"},"modified":"2021-09-24T14:20:29","modified_gmt":"2021-09-24T12:20:29","slug":"auguri-20-anni-la-goccia","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/auguri-20-anni-la-goccia\/","title":{"rendered":"Macerata. 20 anni di accoglienza a bambini e famiglie: tanti auguri a &#8220;La Goccia&#8221;"},"content":{"rendered":"<h2 style=\"margin: 0px;\"><span class=\"subject\">Compie 20 anni l\u2019associazione di Macerata con la quale Ai.Bi. collabora da tempo con uno sportello per l\u2019adozione internazionale. Una mostra e tanti eventi in programma<\/span><\/h2>\n<p style=\"margin: 0px;\">\nVerr\u00e0 inaugurata\u00a0<b>sabato 25 settembre<\/b>\u00a0la mostra\u00a0<b>Gocce di accoglienza<\/b>, organizzata per festeggiare i 20 anni dell\u2019Associazione di volontariato\u00a0<i>La Goccia<\/i>\u00a0di Macerata, impegnata nella promozione di attivit\u00e0 solidali in favore di minori in difficolt\u00e0 e nella diffusione della cultura dell\u2019accoglienza attraverso l\u2019affido, l\u2019adozione e il sostegno familiare.<\/p>\n<h3 style=\"margin: 0px;\">20 anni in favore di famiglie e bambini<\/h3>\n<p style=\"margin: 0px;\">\nUn anniversario importante per La Goccia, nata come comunit\u00e0 familiare e, oggi, ampliatasi fino a diventare una realt\u00e0 strutturata con una\u00a0<b>rete di famiglie aperte all\u2019affido<\/b>, un centro studi, un centro servizi per la famiglia e uno\u00a0<b>sportello per l\u2019adozione internazionale<\/b>. Quest\u2019ultimo, in particolare, \u00e8 portato avanti in collaborazione con\u00a0<b>Ai.Bi Amici dei Bambini<\/b>, che ormai da tempo collabora con La Goccia nello sviluppo e l\u2019accompagnamento di una rete di famiglie accoglienti a supporto delle coppie adottive che si rivolgono alla sede regionale di Ai.Bi., oltre che all\u2019organizzazione di eventi dedicati alla promozione e diffusione di una cultura dell\u2019accoglienza.<\/p>\n<h3 style=\"margin: 0px;\">\nUna serie di eventi per celebrare la ricorrenza<\/h3>\n<p style=\"margin: 0px;\">\nL\u2019evento principale per la celebrazione dei 20 anni de La Goccia, come detto, \u00e8 la mostra \u201c<b>Gocce di accoglienza. Accogliere persone, costruire comunit\u00e0<\/b>&#8220;, allestita alla Galleria degli Antichi Forni, con il patrocinio del Comune di Macerata.<br \/>\nMa, questa, non \u00e8 che la cornice di diverse attivit\u00e0 programmate\u00a0<b>da sabato 25 settembre a domenica 3 ottobre<\/b>: ogni giorno, dal luned\u00ec al gioved\u00ec, verranno organizzati laboratori, giochi e letture per bambini e famiglie. Venerd\u00ec 1, invece, \u00e8 il programma alle ore 21 la presentazione del libro &#8220;<i>Porte aperte. Viaggio nell&#8217;Italia che non ha paura<\/i>&#8221; con l&#8217;autore Mario Marazzini, mentre sabato 2 ottobre, alle ore 18, sar\u00e0 la volta del volume &#8220;<i>Emigrania<\/i>&#8221; con l&#8217;autore Daniele Bonaiuti e l&#8217;illustratore Alessandro Cripsta.<br \/>\nDomenica 3 ottobre, infine, alle ore 21, grande chiusura con la serata musicale \u201cS-guardo oltre. Spodestati, migranti e viaggiatori\u201d, con Marco Milozzi.<br \/>\nMa, certo, le attivit\u00e0 dell\u2019Associazione non finiscono qui: fin d\u2019ora, infatti, \u00e8 in corso la promozione del convegno \u201c<i>Ripartiamo dall\u2019accoglienza: ricostruire legami per custodire il futuro<\/i>\u201d, in programma il 16 ottobre 2021, presso l\u2019aula Magna del Polo Bertelli dell\u2019Unimc, in presenza e in videoconferenza.<br \/>\nTutte le informazioni si possono trovare sul sito\u00a0<a href=\"http:\/\/www.lagocciaonlus.it%0b\">www.lagocciaonlus.it.<\/a><\/p>\n<h5>(Immagine dal sito lagocciaonlus.it)<\/h5>\n","protected":false},"excerpt":{"rendered":"<p>Compie 20 anni l&rsquo;associazione di Macerata con la quale Ai.Bi. collabora da tempo con uno sportello per l&rsquo;adozione internazionale. Una mostra e tanti eventi in programma Verr&agrave; inaugurata&nbsp;sabato 25 settembre&nbsp;la mostra&nbsp;Gocce di accoglienza, organizzata per festeggiare i 20 anni dell&rsquo;Associazione di volontariato&nbsp;La Goccia&nbsp;di Macerata, impegnata nella promozione di attivit&agrave; solidali [&hellip;]<\/p>\n","protected":false},"author":102,"featured_media":192163,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[172],"tags":[605,766],"class_list":["post-192162","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-internazionale","tag-macerata","tag-progetti"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tanti auguri a &quot;La Goccia&quot;, 20 anni di accoglienza a bambini e famiglie<\/title>\n<meta name=\"description\" content=\"Compie 20 anni l\u2019associazione La Goccia con la quale Ai.Bi. collabora con uno sportello per l\u2019adozione internazionale. Una mostra e tanti eventi in programma\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/auguri-20-anni-la-goccia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Macerata. 20 anni di accoglienza a bambini e famiglie: tanti auguri a &quot;La Goccia&quot;\" \/>\n<meta property=\"og:description\" content=\"Compie 20 anni l\u2019associazione La Goccia con la quale Ai.Bi. collabora con uno sportello per l\u2019adozione internazionale. Una mostra e tanti eventi in programma\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/auguri-20-anni-la-goccia\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-24T05:30:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-24T12:20:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2021\/09\/la-goccia-macerata.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"629\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/auguri-20-anni-la-goccia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/auguri-20-anni-la-goccia\\\/\"},\"author\":{\"name\":\"francescoE\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\"},\"headline\":\"Macerata. 20 anni di accoglienza a bambini e famiglie: tanti auguri a &#8220;La Goccia&#8221;\",\"datePublished\":\"2021-09-24T05:30:53+00:00\",\"dateModified\":\"2021-09-24T12:20:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/auguri-20-anni-la-goccia\\\/\"},\"wordCount\":406,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/auguri-20-anni-la-goccia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/09\\\/la-goccia-macerata.jpg\",\"keywords\":[\"Macerata\",\"progetti\"],\"articleSection\":[\"Adozione Internazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/auguri-20-anni-la-goccia\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/auguri-20-anni-la-goccia\\\/\",\"name\":\"Tanti auguri a \\\"La Goccia\\\", 20 anni di accoglienza a bambini e famiglie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/auguri-20-anni-la-goccia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/auguri-20-anni-la-goccia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/09\\\/la-goccia-macerata.jpg\",\"datePublished\":\"2021-09-24T05:30:53+00:00\",\"dateModified\":\"2021-09-24T12:20:29+00:00\",\"description\":\"Compie 20 anni l\u2019associazione La Goccia con la quale Ai.Bi. collabora con uno sportello per l\u2019adozione internazionale. Una mostra e tanti eventi in programma\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/auguri-20-anni-la-goccia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/auguri-20-anni-la-goccia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/auguri-20-anni-la-goccia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/09\\\/la-goccia-macerata.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/09\\\/la-goccia-macerata.jpg\",\"width\":1200,\"height\":629},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/auguri-20-anni-la-goccia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione Internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-internazionale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Macerata. 20 anni di accoglienza a bambini e famiglie: tanti auguri a &#8220;La Goccia&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\",\"name\":\"francescoE\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/francescoe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tanti auguri a \"La Goccia\", 20 anni di accoglienza a bambini e famiglie","description":"Compie 20 anni l\u2019associazione La Goccia con la quale Ai.Bi. collabora con uno sportello per l\u2019adozione internazionale. Una mostra e tanti eventi in programma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/auguri-20-anni-la-goccia\/","og_locale":"it_IT","og_type":"article","og_title":"Macerata. 20 anni di accoglienza a bambini e famiglie: tanti auguri a \"La Goccia\"","og_description":"Compie 20 anni l\u2019associazione La Goccia con la quale Ai.Bi. collabora con uno sportello per l\u2019adozione internazionale. Una mostra e tanti eventi in programma","og_url":"https:\/\/www.aibi.it\/ita\/auguri-20-anni-la-goccia\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2021-09-24T05:30:53+00:00","article_modified_time":"2021-09-24T12:20:29+00:00","og_image":[{"width":1200,"height":629,"url":"https:\/\/www.aibi.it\/ita\/images\/2021\/09\/la-goccia-macerata.jpg","type":"image\/jpeg"}],"author":"francescoE","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"francescoE","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/auguri-20-anni-la-goccia\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/auguri-20-anni-la-goccia\/"},"author":{"name":"francescoE","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5"},"headline":"Macerata. 20 anni di accoglienza a bambini e famiglie: tanti auguri a &#8220;La Goccia&#8221;","datePublished":"2021-09-24T05:30:53+00:00","dateModified":"2021-09-24T12:20:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/auguri-20-anni-la-goccia\/"},"wordCount":406,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/auguri-20-anni-la-goccia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/09\/la-goccia-macerata.jpg","keywords":["Macerata","progetti"],"articleSection":["Adozione Internazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/auguri-20-anni-la-goccia\/","url":"https:\/\/www.aibi.it\/ita\/auguri-20-anni-la-goccia\/","name":"Tanti auguri a \"La Goccia\", 20 anni di accoglienza a bambini e famiglie","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/auguri-20-anni-la-goccia\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/auguri-20-anni-la-goccia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/09\/la-goccia-macerata.jpg","datePublished":"2021-09-24T05:30:53+00:00","dateModified":"2021-09-24T12:20:29+00:00","description":"Compie 20 anni l\u2019associazione La Goccia con la quale Ai.Bi. collabora con uno sportello per l\u2019adozione internazionale. Una mostra e tanti eventi in programma","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/auguri-20-anni-la-goccia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/auguri-20-anni-la-goccia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/auguri-20-anni-la-goccia\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2021\/09\/la-goccia-macerata.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/09\/la-goccia-macerata.jpg","width":1200,"height":629},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/auguri-20-anni-la-goccia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione Internazionale","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-internazionale\/"},{"@type":"ListItem","position":3,"name":"Macerata. 20 anni di accoglienza a bambini e famiglie: tanti auguri a &#8220;La Goccia&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5","name":"francescoE","url":"https:\/\/www.aibi.it\/ita\/author\/francescoe\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 08:05:51","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/192162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=192162"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/192162\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/192163"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=192162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=192162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=192162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}