﻿


{"id":193765,"date":"2021-10-30T12:37:01","date_gmt":"2021-10-30T10:37:01","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=193765"},"modified":"2021-10-31T15:24:59","modified_gmt":"2021-10-31T14:24:59","slug":"con-il-ritorno-dellora-solare-arriva-anche-linfluenza-e-questanno-sara-pesante-come-e-dove-vaccinarsi","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/con-il-ritorno-dellora-solare-arriva-anche-linfluenza-e-questanno-sara-pesante-come-e-dove-vaccinarsi\/","title":{"rendered":"Con il ritorno dell\u2019ora solare, arriva anche l&#8217;influenza e quest&#8217;anno sar\u00e0 pesante: come e dove vaccinarsi"},"content":{"rendered":"<h2><strong>Da quest\u2019anno \u00e8 possibile vaccinarsi per l\u2019influenza anche in farmacia.\u00a0<\/strong><strong>Vaccino anti covid e vaccino anti influenzale: insieme si pu\u00f2!<\/strong><\/h2>\n<p>Cambia l&#8217;ora, che da questa notte da legale diventer\u00e0 solare ma non cambia il\u00a0<strong>timore per l&#8217;influenza stagionale<\/strong>, che ogni anno ci accompagna creandoci non pochi fastidi.<\/p>\n<p>Il 2020 \u00e8 stato un&#8217;eccezione per la scarsa diffusione della sindrome influenzale. Questo \u00e8 avvenuto per le attente e meticolose misure di prevenzione anti covid, ma ora, con il senso di sicurezza legato alla vaccinazione e quindi con la probabile rilassatezza nelle misure di prevenzione,\u00a0<strong>l&#8217;influenza potrebbe riaffacciarsi<\/strong>\u00a0in modo preoccupante.<\/p>\n<h3><strong>Influenza stagionale: attenzione ai soggetti fragili<\/strong><\/h3>\n<p>Il Centro Europeo per la prevenzione e il controllo delle malattie (ECDC) ha annunciato che\u00a0<strong>l&#8217;influenza stagionale potrebbe essere grave negli anziani e nei soggetti fragili<\/strong>. A riportarlo \u00e8\u00a0<strong>Fanpage.it<\/strong><\/p>\n<p>La ragione? \u201c<em>Il ceppo maggiormente circolante nell&#8217;ultimo mese l&#8217;A (H3N2), associato a una ridotta efficacia del vaccino e a una maggiore aggressivit\u00e0 negli anziani<\/em>\u201d.<\/p>\n<p>Il dottor\u00a0<strong>Pasi Penttinen<\/strong>\u00a0a capo del programma antinfluenzale dell\u2019ECDC afferma: &#8220;<em>un forte aumento delle infezioni influenzali durante l&#8217;attuale pandemia di covid,\u00a0<strong>potrebbe porre un onere aggiuntivo sui sistemi sanitari gi\u00e0 messi a dura prova dal covid -19<\/strong>. \u00c8 quindi importante prendere le precauzioni necessarie e proteggere coloro che sono pi\u00f9 a rischio<\/em>&#8220;.<\/p>\n<p>L\u2019EDC sottolinea come gli interventi non farmaceutici (NPI): il\u00a0<strong>distanziamento sociale, le mascherine, l&#8217;igiene delle mani, l&#8217;areazione dei locali, sono stati e sono ancora molto preziosi, per contenere sia le infezioni\u00a0<\/strong>da covid che quelle provocate da virus influenzali e parainfluenzali.<\/p>\n<p>Il virologo\u00a0<strong>Fabrizio Pregliasco<\/strong>\u00a0ospite della trasmissione &#8220;Buongiorno&#8221; su\u00a0<strong>SKYTG24<\/strong>, ha spiegato che primi casi sporadici di influenza iniziano ad essere presenti e che quindi \u00e8 importante: &#8220;<strong><em>rincominciare l&#8217;abitudine delle vaccinazioni.<\/em><\/strong><em>\u00a0Quello che ci preoccupa\u00a0<\/em>-ha continuato-\u00a0<em>\u00e8 che essendo nuovi due dei virus che stanno circolando, questi potranno diffondersi pi\u00f9 ampiamente. L&#8217;influenza dal punto di vista dei sintomi non \u00e8 pi\u00f9 o meno cattiva ogni anno ma diventa un problema di sanit\u00e0 pubblica rispetto alle sue capacit\u00e0 di diffondersi. Un inverno che non si presenta piacevolissimo da questo punto di vista&#8221;<\/em>.<\/p>\n<h3><strong>Vaccino anti covid e vaccino antinfluenzale: insieme si pu\u00f2!<\/strong><\/h3>\n<p>Sul sito del\u00a0<strong>Ministero della Salute<\/strong>\u00a0viene indicata la possibilit\u00e0 di effettuare la somministrazione del vaccino antinfluenzale e anticovid in una unica seduta (anche se facoltativo).<\/p>\n<p><strong>Il vaccino anti influenzale \u00e8 indicato per tutti coloro che lo desiderino<\/strong>\u00a0(eccetto specifiche controindicazioni)\u00a0<strong>ed \u00e8 fortemente raccomandato per soggetti dai 65 anni di et\u00e0,<\/strong>\u00a0<strong>donne in gravidanza<\/strong>,\u00a0<strong>nel periodo post partum,<\/strong>\u00a0per i soggetti dai 6 mesi ai 65 anni affetti da patologie che possano aumentare il rischio di complicanze, per i ricoverati in istituti di lunga degenza e per i loro familiari, per i soggetti addetti ai servizi pubblici di primario interesse e anche per quelli che, per lavoro siano a contatto con animali che potrebbero essere fonte di infezione di virus influenzali non umani.<\/p>\n<h3><strong>Chi non pu\u00f2 ricevere il vaccino antinfluenzale?<\/strong><\/h3>\n<p>Il vaccino antinfluenzale non deve essere somministrato ai\u00a0<strong>bambini sotto i sei mesi di et\u00e0,<\/strong>\u00a0a soggetti che hanno avuto reazioni allergiche in una precedente somministrazione e anche in presenza di malattie acute (controindicazione temporanea).<\/p>\n<h3><strong>Influenza. Dove \u00e8 possibile vaccinarsi?<\/strong><\/h3>\n<p>Anche in questo caso \u00e8 il sito del Ministero della Salute a venirci in aiuto ricordandoci come sia possibile effettuare la vaccinazione\u00a0<strong>presso il proprio medico di famiglia o pediatra di libera scelta<\/strong>\u00a0e presso strutture sanitarie o ambulatori vaccinali e di prevenzione.<\/p>\n<p>\u00c8 di pochi giorni fa, inoltre, la notizia, proveniente della conferenza Stato -Regioni,\u00a0<strong>dell\u2019intesa sancita con Federfarma &#8211; Assofarma<\/strong>\u00a0per il vaccino antinfluenzale, che permette di vedersi inoculare il\u00a0<strong>vaccino anche in farmacia. Per tutti i maggiorenni che non hanno patologie,<\/strong>\u00a0baster\u00e0 acquistare il farmaco e farselo somministrare dal farmacista, mentre coloro invece, presentano patologie e rientrano tra le categorie pi\u00f9 fragili, il vaccino\u00a0<strong>sar\u00e0 gratuito.<\/strong><\/p>\n<p>Insomma, attenzione e prevenzione sono armi fondamentali per combattere l\u2019influenza alle porte:<\/p>\n<p>&#8220;<em>Poich\u00e9 l&#8217;anno passato \u2013\u00a0<\/em>osserva<em>\u00a0<\/em>Il dottor S. Scotti, segretario nazionale FIMMG, come riportato dal quotidiano il Giorno &#8211;\u00a0<em>una gran fetta della popolazione non ha avuto la malattia ed \u00e8 scoperta<\/em>,\u00a0<em>l&#8217;influenza 2021-2022, potrebbe essere pi\u00f9 impattante&#8221;\u00a0<\/em>aggiungendo di essere scettico sul fatto che i pazienti che non hanno fatto il vaccino anticovid, vogliano sottoporsi a quello anti influenzale.<\/p>\n<p>Possiamo affrontare con molte armi il virus influenzale, cerchiamo di usarle bene per vincere la battaglia stagionale.<\/p>\n<p><strong>Per maggiori informazioni su influenza e vaccinazione antinfluenzale vi invitiamo a consultare il sito del Ministro della Salute<\/strong>\u00a0<strong><a href=\"https:\/\/www.salute.gov.it\/portale\/influenza\/dettaglioFaqInfluenza.jsp?lingua=italiano&amp;id=103\" target=\"_blank\" rel=\"noopener\">QUI<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da quest&rsquo;anno &egrave; possibile vaccinarsi per l&rsquo;influenza anche in farmacia.&nbsp;Vaccino anti covid e vaccino anti influenzale: insieme si pu&ograve;! Cambia l&rsquo;ora, che da questa notte da legale diventer&agrave; solare ma non cambia il&nbsp;timore per l&rsquo;influenza stagionale, che ogni anno ci accompagna creandoci non pochi fastidi. Il 2020 &egrave; stato un&rsquo;eccezione [&hellip;]<\/p>\n","protected":false},"author":97,"featured_media":193766,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[704,784],"class_list":["post-193765","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews","tag-influenza","tag-vaccini"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Con il ritorno dell\u2019ora solare, arriva anche l&#039;influenza e quest&#039;anno sar\u00e0 pesante: come e dove vaccinarsi - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"Da quest\u2019anno \u00e8 possibile vaccinarsi per l\u2019influenza anche in farmacia.\u00a0Vaccino anti covid e vaccino anti influenzale: insieme si pu\u00f2!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/con-il-ritorno-dellora-solare-arriva-anche-linfluenza-e-questanno-sara-pesante-come-e-dove-vaccinarsi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Con il ritorno dell\u2019ora solare, arriva anche l&#039;influenza e quest&#039;anno sar\u00e0 pesante: come e dove vaccinarsi\" \/>\n<meta property=\"og:description\" content=\"Da quest\u2019anno \u00e8 possibile vaccinarsi per l\u2019influenza anche in farmacia.\u00a0Vaccino anti covid e vaccino anti influenzale: insieme si pu\u00f2!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/con-il-ritorno-dellora-solare-arriva-anche-linfluenza-e-questanno-sara-pesante-come-e-dove-vaccinarsi\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-30T10:37:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-31T14:24:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2021\/10\/influenza.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mc.sabatini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mc.sabatini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/con-il-ritorno-dellora-solare-arriva-anche-linfluenza-e-questanno-sara-pesante-come-e-dove-vaccinarsi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/con-il-ritorno-dellora-solare-arriva-anche-linfluenza-e-questanno-sara-pesante-come-e-dove-vaccinarsi\\\/\"},\"author\":{\"name\":\"mc.sabatini\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\"},\"headline\":\"Con il ritorno dell\u2019ora solare, arriva anche l&#8217;influenza e quest&#8217;anno sar\u00e0 pesante: come e dove vaccinarsi\",\"datePublished\":\"2021-10-30T10:37:01+00:00\",\"dateModified\":\"2021-10-31T14:24:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/con-il-ritorno-dellora-solare-arriva-anche-linfluenza-e-questanno-sara-pesante-come-e-dove-vaccinarsi\\\/\"},\"wordCount\":763,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/con-il-ritorno-dellora-solare-arriva-anche-linfluenza-e-questanno-sara-pesante-come-e-dove-vaccinarsi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/10\\\/influenza.jpg\",\"keywords\":[\"influenza\",\"vaccini\"],\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/con-il-ritorno-dellora-solare-arriva-anche-linfluenza-e-questanno-sara-pesante-come-e-dove-vaccinarsi\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/con-il-ritorno-dellora-solare-arriva-anche-linfluenza-e-questanno-sara-pesante-come-e-dove-vaccinarsi\\\/\",\"name\":\"Con il ritorno dell\u2019ora solare, arriva anche l'influenza e quest'anno sar\u00e0 pesante: come e dove vaccinarsi - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/con-il-ritorno-dellora-solare-arriva-anche-linfluenza-e-questanno-sara-pesante-come-e-dove-vaccinarsi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/con-il-ritorno-dellora-solare-arriva-anche-linfluenza-e-questanno-sara-pesante-come-e-dove-vaccinarsi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/10\\\/influenza.jpg\",\"datePublished\":\"2021-10-30T10:37:01+00:00\",\"dateModified\":\"2021-10-31T14:24:59+00:00\",\"description\":\"Da quest\u2019anno \u00e8 possibile vaccinarsi per l\u2019influenza anche in farmacia.\u00a0Vaccino anti covid e vaccino anti influenzale: insieme si pu\u00f2!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/con-il-ritorno-dellora-solare-arriva-anche-linfluenza-e-questanno-sara-pesante-come-e-dove-vaccinarsi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/con-il-ritorno-dellora-solare-arriva-anche-linfluenza-e-questanno-sara-pesante-come-e-dove-vaccinarsi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/con-il-ritorno-dellora-solare-arriva-anche-linfluenza-e-questanno-sara-pesante-come-e-dove-vaccinarsi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/10\\\/influenza.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/10\\\/influenza.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/con-il-ritorno-dellora-solare-arriva-anche-linfluenza-e-questanno-sara-pesante-come-e-dove-vaccinarsi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Con il ritorno dell\u2019ora solare, arriva anche l&#8217;influenza e quest&#8217;anno sar\u00e0 pesante: come e dove vaccinarsi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\",\"name\":\"mc.sabatini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/marias\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Con il ritorno dell\u2019ora solare, arriva anche l'influenza e quest'anno sar\u00e0 pesante: come e dove vaccinarsi - Ai.Bi. Amici dei Bambini","description":"Da quest\u2019anno \u00e8 possibile vaccinarsi per l\u2019influenza anche in farmacia.\u00a0Vaccino anti covid e vaccino anti influenzale: insieme si pu\u00f2!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/con-il-ritorno-dellora-solare-arriva-anche-linfluenza-e-questanno-sara-pesante-come-e-dove-vaccinarsi\/","og_locale":"it_IT","og_type":"article","og_title":"Con il ritorno dell\u2019ora solare, arriva anche l'influenza e quest'anno sar\u00e0 pesante: come e dove vaccinarsi","og_description":"Da quest\u2019anno \u00e8 possibile vaccinarsi per l\u2019influenza anche in farmacia.\u00a0Vaccino anti covid e vaccino anti influenzale: insieme si pu\u00f2!","og_url":"https:\/\/www.aibi.it\/ita\/con-il-ritorno-dellora-solare-arriva-anche-linfluenza-e-questanno-sara-pesante-come-e-dove-vaccinarsi\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2021-10-30T10:37:01+00:00","article_modified_time":"2021-10-31T14:24:59+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2021\/10\/influenza.jpg","type":"image\/jpeg"}],"author":"mc.sabatini","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"mc.sabatini","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/con-il-ritorno-dellora-solare-arriva-anche-linfluenza-e-questanno-sara-pesante-come-e-dove-vaccinarsi\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/con-il-ritorno-dellora-solare-arriva-anche-linfluenza-e-questanno-sara-pesante-come-e-dove-vaccinarsi\/"},"author":{"name":"mc.sabatini","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938"},"headline":"Con il ritorno dell\u2019ora solare, arriva anche l&#8217;influenza e quest&#8217;anno sar\u00e0 pesante: come e dove vaccinarsi","datePublished":"2021-10-30T10:37:01+00:00","dateModified":"2021-10-31T14:24:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/con-il-ritorno-dellora-solare-arriva-anche-linfluenza-e-questanno-sara-pesante-come-e-dove-vaccinarsi\/"},"wordCount":763,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/con-il-ritorno-dellora-solare-arriva-anche-linfluenza-e-questanno-sara-pesante-come-e-dove-vaccinarsi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/10\/influenza.jpg","keywords":["influenza","vaccini"],"articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/con-il-ritorno-dellora-solare-arriva-anche-linfluenza-e-questanno-sara-pesante-come-e-dove-vaccinarsi\/","url":"https:\/\/www.aibi.it\/ita\/con-il-ritorno-dellora-solare-arriva-anche-linfluenza-e-questanno-sara-pesante-come-e-dove-vaccinarsi\/","name":"Con il ritorno dell\u2019ora solare, arriva anche l'influenza e quest'anno sar\u00e0 pesante: come e dove vaccinarsi - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/con-il-ritorno-dellora-solare-arriva-anche-linfluenza-e-questanno-sara-pesante-come-e-dove-vaccinarsi\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/con-il-ritorno-dellora-solare-arriva-anche-linfluenza-e-questanno-sara-pesante-come-e-dove-vaccinarsi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/10\/influenza.jpg","datePublished":"2021-10-30T10:37:01+00:00","dateModified":"2021-10-31T14:24:59+00:00","description":"Da quest\u2019anno \u00e8 possibile vaccinarsi per l\u2019influenza anche in farmacia.\u00a0Vaccino anti covid e vaccino anti influenzale: insieme si pu\u00f2!","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/con-il-ritorno-dellora-solare-arriva-anche-linfluenza-e-questanno-sara-pesante-come-e-dove-vaccinarsi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/con-il-ritorno-dellora-solare-arriva-anche-linfluenza-e-questanno-sara-pesante-come-e-dove-vaccinarsi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/con-il-ritorno-dellora-solare-arriva-anche-linfluenza-e-questanno-sara-pesante-come-e-dove-vaccinarsi\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2021\/10\/influenza.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/10\/influenza.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/con-il-ritorno-dellora-solare-arriva-anche-linfluenza-e-questanno-sara-pesante-come-e-dove-vaccinarsi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Con il ritorno dell\u2019ora solare, arriva anche l&#8217;influenza e quest&#8217;anno sar\u00e0 pesante: come e dove vaccinarsi"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938","name":"mc.sabatini","url":"https:\/\/www.aibi.it\/ita\/author\/marias\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 12:39:42","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/193765","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/97"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=193765"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/193765\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/193766"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=193765"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=193765"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=193765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}