﻿


{"id":194717,"date":"2021-12-01T07:30:10","date_gmt":"2021-12-01T06:30:10","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=194717"},"modified":"2021-12-01T15:28:14","modified_gmt":"2021-12-01T14:28:14","slug":"20-anni-de-il-bello-che-fa-bene-torna-lappuntamento-con-lo-shopping-solidale-di-ai-bi","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/20-anni-de-il-bello-che-fa-bene-torna-lappuntamento-con-lo-shopping-solidale-di-ai-bi\/","title":{"rendered":"20 anni de \u201cIl Bello che Fa Bene\u201d. Torna l&#8217;appuntamento con lo shopping solidale di Ai.Bi."},"content":{"rendered":"<h2>A Natale torna il Temporary Shop Solidale di Amici dei Bambini &#8220;Il Bello che Fa Bene&#8221;: prodotti iconici di design, grandi linee di cosmetici e makeup, capi di alta moda\u2026 Regali di qualit\u00e0 per aiutare bambini e famiglie in difficolt\u00e0<\/h2>\n<p>Con il Natale ormai alle porte, torna il tradizionale matrimonio tra grandi aziende e solidariet\u00e0 nel<strong> <a href=\"https:\/\/www.aibi.it\/temporary-shop\">Temporary Shop Solidale di Ai.Bi. &#8220;Il Bello che Fa Bene&#8221;<\/a><\/strong>.<br \/>\nPerch\u00e9 l\u2019appuntamento, arrivato ormai alla ventesima edizione, non \u00e8 solo un\u2019iniziativa benefica ma \u00e8 un modo di pensare; un approccio filosofico che raccoglie i protagonisti del \u201cbello\u201d sotto il comune denominatore della solidariet\u00e0. Un momento perfetto per le aziende e per le persone che credono che una scelta di stile sia ancora pi\u00f9 bella se sostiene, ed \u00e8 a sua volta sostenuta, da una buona azione.<br \/>\n\u00c8 questo lo spirito che da vent&#8217;anni anima<strong> Il Temporary Shop Solidale di Ai.Bi. \u201cIl Bello che Fa Bene\u201d<\/strong>, oggi diffuso nel tempo e nello spazio. Dall\u2019<strong>1 dicembre<\/strong>, infatti, fino al <strong>31 gennaio 2022<\/strong>, ovunque ci si trovi si potranno richiedere i tantissimi prodotti proposti sulla <u>pagina dedicata del sito di Ai.Bi.<\/u> in cambio di una donazione in favore della campagna di Natale.<strong> \u201cSi fa presto a dire Natale con i tuoi&#8221;<\/strong>.<br \/>\nUna campagna che punta a regalare un sorriso ai bambini e i genitori che ogni giorno in Italia si rivolgono ai <strong>Centri Servizi per la Famiglia \u201cI Pan di Zucchero\u201d<\/strong> in cerca di ascolto e sostegno; a tutti i bambini che trovano accoglienza e protezione nelle nostre <strong>Case Famiglia e Comunit\u00e0 Mamma &#8211; Bambino<\/strong> a Brescia e Milano; agli adolescenti accompagnati verso l\u2019autonomia in <strong>Casa Pinocchio, Casa Giuseppe e Casa Francesco<\/strong>.<br \/>\nMa non solo. Grazie a quanti aderiranno al Natale di Ai.Bi. resteremo al fianco de \u201c<em>L\u2019Altro nostro figlio<\/em>\u201d: bambini e adolescenti abbandonati negli orfanotrofi dell\u2019Africa, del Sud America e dell\u2019Est Europa, in cui operiamo per promuovere il diritto di tutti i minori a essere figli; cos\u00ec come le centinaia di famiglie siriane che hanno perso tutto e si preparano a trascorrere anche questo inverno nelle tende dei campi sfollati di Idlib.<\/p>\n<h3>Stile, moda e design\u2026 distanti solo una donazione per i bambini e le famiglie in difficolt\u00e0<\/h3>\n<p>Da oggetti per la casa a icone del design; da prodotti di alta gastronomia a importanti linee di prodotti cosmetici, makeup, skin care e hair care; da capi d\u2019abbigliamento di alta moda ad accessori iconici di tendenza, borse di lusso degli stilisti e le maison pi\u00f9 note, sono davvero tantissimi i prodotti di alta gamma messi a disposizione dalle aziende che si sono schierate al fianco di Ai.Bi. per questa rinnovata e innovativa versione online de <strong>Il Temporary Shop Solidale \u201cIl Bello che Fa Bene\u201d<\/strong>, in cui ancora una volta si sigilla l&#8217;incontro tra il bello e la solidariet\u00e0.<br \/>\nL\u2019assortimento dei prodotti sar\u00e0 continuamente rinnovato per tutto il periodo del <a href=\"https:\/\/www.aibi.it\/temporary-shop\">temporary shop.<\/a><br \/>\nTutte le donazioni godono delle agevolazioni fiscali.<br \/>\nQueste le aziende che hanno aderito a \u201cIl Bello che fa Bene\u201d 2021:<br \/>\nAlessi, Anna Viero Cashmere, B&amp;M &#8211; Baldan Group, Berlucchi Franciacorta, Best Western, Bormioli Rocco, Bracciani Piume &#8211; Manudieci, Cantine Settesoli &#8211; Mandrarossa, Chantecler, Croce Del Sud &#8211; Amen, Dexter Milano, Divella, E. Marinella, Emilio Pucci, Emporio Armani, Encicolopedia d\u2019Arte Italiana, Etro, Frette, Fay &#8211; Tod&#8217;s Group, Hogan \u2013 Tod\u2019s Group, Kiko, Illy Caff\u00e8, Lagostina, Lavazza, Mattel, Merola Gloves, Minotti, Moncler, Montbel, Ornella Prosperi, Peg Perego, Porro, Pompadour, Ricci Curbastro, Salvatore Ferragamo, Save my Bag,\u00a0 Shiseido, Solo Italia, Trudi, Ulturale, Vanni, Vitale Canonico Barberis.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Natale torna il Temporary Shop Solidale di Amici dei Bambini &ldquo;Il Bello che Fa Bene&rdquo;: prodotti iconici di design, grandi linee di cosmetici e makeup, capi di alta moda&hellip; Regali di qualit&agrave; per aiutare bambini e famiglie in difficolt&agrave; Con il Natale ormai alle porte, torna il tradizionale matrimonio [&hellip;]<\/p>\n","protected":false},"author":102,"featured_media":161410,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[764],"tags":[308,368,766,851],"class_list":["post-194717","post","type-post","status-publish","format-standard","has-post-thumbnail","category-progetti-in-italia","tag-bello-che-fa-bene","tag-natale","tag-progetti","tag-temporary-shop"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>20 anni di shopping solidale con \u201cIl Bello che Fa Bene\u201d di Ai.Bi.<\/title>\n<meta name=\"description\" content=\"A Natale torna il Temporary Shop di Amici dei Bambini: prodotti di design, cosmetici, moda\u2026 Uno shopping solidale in aiuto di bambini e famiglie in difficolt\u00e0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/20-anni-de-il-bello-che-fa-bene-torna-lappuntamento-con-lo-shopping-solidale-di-ai-bi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"20 anni de \u201cIl Bello che Fa Bene\u201d. Torna l&#039;appuntamento con lo shopping solidale di Ai.Bi.\" \/>\n<meta property=\"og:description\" content=\"A Natale torna il Temporary Shop di Amici dei Bambini: prodotti di design, cosmetici, moda\u2026 Uno shopping solidale in aiuto di bambini e famiglie in difficolt\u00e0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/20-anni-de-il-bello-che-fa-bene-torna-lappuntamento-con-lo-shopping-solidale-di-ai-bi\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-01T06:30:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-01T14:28:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/temporary-2018-1200x630.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/20-anni-de-il-bello-che-fa-bene-torna-lappuntamento-con-lo-shopping-solidale-di-ai-bi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/20-anni-de-il-bello-che-fa-bene-torna-lappuntamento-con-lo-shopping-solidale-di-ai-bi\\\/\"},\"author\":{\"name\":\"francescoE\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\"},\"headline\":\"20 anni de \u201cIl Bello che Fa Bene\u201d. Torna l&#8217;appuntamento con lo shopping solidale di Ai.Bi.\",\"datePublished\":\"2021-12-01T06:30:10+00:00\",\"dateModified\":\"2021-12-01T14:28:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/20-anni-de-il-bello-che-fa-bene-torna-lappuntamento-con-lo-shopping-solidale-di-ai-bi\\\/\"},\"wordCount\":606,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/20-anni-de-il-bello-che-fa-bene-torna-lappuntamento-con-lo-shopping-solidale-di-ai-bi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/temporary-2018-1200x630.jpg\",\"keywords\":[\"Bello che fa bene\",\"Natale\",\"progetti\",\"temporary shop\"],\"articleSection\":[\"Progetti in Italia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/20-anni-de-il-bello-che-fa-bene-torna-lappuntamento-con-lo-shopping-solidale-di-ai-bi\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/20-anni-de-il-bello-che-fa-bene-torna-lappuntamento-con-lo-shopping-solidale-di-ai-bi\\\/\",\"name\":\"20 anni di shopping solidale con \u201cIl Bello che Fa Bene\u201d di Ai.Bi.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/20-anni-de-il-bello-che-fa-bene-torna-lappuntamento-con-lo-shopping-solidale-di-ai-bi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/20-anni-de-il-bello-che-fa-bene-torna-lappuntamento-con-lo-shopping-solidale-di-ai-bi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/temporary-2018-1200x630.jpg\",\"datePublished\":\"2021-12-01T06:30:10+00:00\",\"dateModified\":\"2021-12-01T14:28:14+00:00\",\"description\":\"A Natale torna il Temporary Shop di Amici dei Bambini: prodotti di design, cosmetici, moda\u2026 Uno shopping solidale in aiuto di bambini e famiglie in difficolt\u00e0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/20-anni-de-il-bello-che-fa-bene-torna-lappuntamento-con-lo-shopping-solidale-di-ai-bi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/20-anni-de-il-bello-che-fa-bene-torna-lappuntamento-con-lo-shopping-solidale-di-ai-bi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/20-anni-de-il-bello-che-fa-bene-torna-lappuntamento-con-lo-shopping-solidale-di-ai-bi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/temporary-2018-1200x630.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/temporary-2018-1200x630.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/20-anni-de-il-bello-che-fa-bene-torna-lappuntamento-con-lo-shopping-solidale-di-ai-bi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Progetti in Italia\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/progetti-in-italia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"20 anni de \u201cIl Bello che Fa Bene\u201d. Torna l&#8217;appuntamento con lo shopping solidale di Ai.Bi.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\",\"name\":\"francescoE\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/francescoe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"20 anni di shopping solidale con \u201cIl Bello che Fa Bene\u201d di Ai.Bi.","description":"A Natale torna il Temporary Shop di Amici dei Bambini: prodotti di design, cosmetici, moda\u2026 Uno shopping solidale in aiuto di bambini e famiglie in difficolt\u00e0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/20-anni-de-il-bello-che-fa-bene-torna-lappuntamento-con-lo-shopping-solidale-di-ai-bi\/","og_locale":"it_IT","og_type":"article","og_title":"20 anni de \u201cIl Bello che Fa Bene\u201d. Torna l'appuntamento con lo shopping solidale di Ai.Bi.","og_description":"A Natale torna il Temporary Shop di Amici dei Bambini: prodotti di design, cosmetici, moda\u2026 Uno shopping solidale in aiuto di bambini e famiglie in difficolt\u00e0","og_url":"https:\/\/www.aibi.it\/ita\/20-anni-de-il-bello-che-fa-bene-torna-lappuntamento-con-lo-shopping-solidale-di-ai-bi\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2021-12-01T06:30:10+00:00","article_modified_time":"2021-12-01T14:28:14+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/temporary-2018-1200x630.jpg","type":"image\/jpeg"}],"author":"francescoE","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"francescoE","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/20-anni-de-il-bello-che-fa-bene-torna-lappuntamento-con-lo-shopping-solidale-di-ai-bi\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/20-anni-de-il-bello-che-fa-bene-torna-lappuntamento-con-lo-shopping-solidale-di-ai-bi\/"},"author":{"name":"francescoE","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5"},"headline":"20 anni de \u201cIl Bello che Fa Bene\u201d. Torna l&#8217;appuntamento con lo shopping solidale di Ai.Bi.","datePublished":"2021-12-01T06:30:10+00:00","dateModified":"2021-12-01T14:28:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/20-anni-de-il-bello-che-fa-bene-torna-lappuntamento-con-lo-shopping-solidale-di-ai-bi\/"},"wordCount":606,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/20-anni-de-il-bello-che-fa-bene-torna-lappuntamento-con-lo-shopping-solidale-di-ai-bi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/temporary-2018-1200x630.jpg","keywords":["Bello che fa bene","Natale","progetti","temporary shop"],"articleSection":["Progetti in Italia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/20-anni-de-il-bello-che-fa-bene-torna-lappuntamento-con-lo-shopping-solidale-di-ai-bi\/","url":"https:\/\/www.aibi.it\/ita\/20-anni-de-il-bello-che-fa-bene-torna-lappuntamento-con-lo-shopping-solidale-di-ai-bi\/","name":"20 anni di shopping solidale con \u201cIl Bello che Fa Bene\u201d di Ai.Bi.","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/20-anni-de-il-bello-che-fa-bene-torna-lappuntamento-con-lo-shopping-solidale-di-ai-bi\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/20-anni-de-il-bello-che-fa-bene-torna-lappuntamento-con-lo-shopping-solidale-di-ai-bi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/temporary-2018-1200x630.jpg","datePublished":"2021-12-01T06:30:10+00:00","dateModified":"2021-12-01T14:28:14+00:00","description":"A Natale torna il Temporary Shop di Amici dei Bambini: prodotti di design, cosmetici, moda\u2026 Uno shopping solidale in aiuto di bambini e famiglie in difficolt\u00e0","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/20-anni-de-il-bello-che-fa-bene-torna-lappuntamento-con-lo-shopping-solidale-di-ai-bi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/20-anni-de-il-bello-che-fa-bene-torna-lappuntamento-con-lo-shopping-solidale-di-ai-bi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/20-anni-de-il-bello-che-fa-bene-torna-lappuntamento-con-lo-shopping-solidale-di-ai-bi\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/temporary-2018-1200x630.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/temporary-2018-1200x630.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/20-anni-de-il-bello-che-fa-bene-torna-lappuntamento-con-lo-shopping-solidale-di-ai-bi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Progetti in Italia","item":"https:\/\/www.aibi.it\/ita\/category\/progetti-in-italia\/"},{"@type":"ListItem","position":3,"name":"20 anni de \u201cIl Bello che Fa Bene\u201d. Torna l&#8217;appuntamento con lo shopping solidale di Ai.Bi."}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5","name":"francescoE","url":"https:\/\/www.aibi.it\/ita\/author\/francescoe\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 06:24:02","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/194717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=194717"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/194717\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/161410"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=194717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=194717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=194717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}