﻿


{"id":194921,"date":"2021-12-07T13:45:38","date_gmt":"2021-12-07T12:45:38","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=194921"},"modified":"2021-12-07T13:45:38","modified_gmt":"2021-12-07T12:45:38","slug":"affido-bibbia-e-affido-cosa-insegnano-le-storie-di-giuseppe-e-di-mose-il-14-dicembre-un-webinar","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/affido-bibbia-e-affido-cosa-insegnano-le-storie-di-giuseppe-e-di-mose-il-14-dicembre-un-webinar\/","title":{"rendered":"Affido: \u201cBibbia e Affido: cosa insegnano le storie di Giuseppe e di Mos\u00e8?\u201d. Il 14 dicembre un webinar"},"content":{"rendered":"<h2 style=\"font-weight: 400;\"><strong>Dalle vicende bibliche di due patriarchi del popolo di Israele, potremmo scoprire insegnamenti preziosi per le famiglie che si stanno preparando all\u2019affido o che stanno gi\u00e0 sperimentando questa esperienza<\/strong><\/h2>\n<p style=\"font-weight: 400;\">Aprirsi\u00a0<strong>all\u2019accoglienza affidataria<\/strong>\u00a0\u00e8 un\u2019esperienza arricchente e meravigliosa, nel cui cammino, per\u00f2, pu\u00f2 accadere di essere colti anche da momenti di fatica.<\/p>\n<p style=\"font-weight: 400;\">Ecco allora che leggere o rileggere il nostro impegno, alla luce delle Sacre Scritture, potrebbe donarci quella \u201cmarcia in pi\u00f9\u201d che magari stavamo nuovamente cercando o regalarci insegnamenti dei quali fare tesoro nel nostro percorso.<\/p>\n<p style=\"font-weight: 400;\">FARIS- Family Relationship International School organizza\u00a0<strong>marted\u00ec 14 dicembre, dalle ore 21.00 \u2013 alle ore 22.30\u00a0<\/strong>un webinar\u00a0<strong>GRATUITO<\/strong>\u00a0dal titolo:\u00a0<strong>\u201cBibbia e Affido: cosa insegnano le storie di Giuseppe e di Mos\u00e8?\u201d<\/strong><\/p>\n<p style=\"font-weight: 400;\">Esaminando con attenzione alcuni aspetti delle vicende bibliche di due patriarchi del popolo di Israele, Giuseppe d\u2019Egitto (o dei sogni) e Mos\u00e8, potremmo infatti, scoprire insegnamenti che possono rivelarsi preziosi per le famiglie che si stanno preparando alla prima accoglienza affidataria o che stanno gi\u00e0 sperimentando l\u2019esperienza dell\u2019affido.<\/p>\n<p style=\"font-weight: 400;\">Il webinar sar\u00e0 tenuto da\u00a0<strong>Paolo Pellini, genitore affidatario e formatore<\/strong>\u00a0di FARIS- Family Relationship International School si terr\u00e0 su piattaforma Zoom.<\/p>\n<p style=\"font-weight: 400;\">Per informazioni ed iscrizioni\u00a0<strong><a href=\"https:\/\/www.fondazioneaibi.it\/faris\/prodotto\/bibbia-e-affido-giuseppe-e-mose\/\">QUI<\/a>\u00a0<\/strong>o contattare la segreteria di FARIS a\u00a0<strong>faris@fondazioneaibi.it<\/strong><\/p>\n<h3 style=\"font-weight: 400;\"><strong>Ecco il programma del corso:<\/strong><\/h3>\n<p style=\"font-weight: 400;\"><strong>Sulla figura di Giuseppe d\u2019Egitto<\/strong><\/p>\n<p style=\"font-weight: 400;\">1) il meccanismo di rimozione<\/p>\n<p style=\"font-weight: 400;\">2) da un male per uno un bene per molti<\/p>\n<p style=\"font-weight: 400;\">3) il perdono<\/p>\n<p style=\"font-weight: 400;\">4) il Dio degli outsider<\/p>\n<p style=\"font-weight: 400;\"><strong>Sulla figura di Mos\u00e8<\/strong><\/p>\n<p style=\"font-weight: 400;\">1) il riposo a Madian<\/p>\n<p style=\"font-weight: 400;\">2) la chiamata<\/p>\n<p style=\"font-weight: 400;\">3) leader nel deserto<\/p>\n<p style=\"font-weight: 400;\">4) l\u2019educazione di Batya<\/p>\n<p style=\"font-weight: 400;\">5) fidarsi di Dio<\/p>\n<p style=\"font-weight: 400;\">6) di nuovo il Dio degli outsider<\/p>\n<p style=\"font-weight: 400;\">\n","protected":false},"excerpt":{"rendered":"<p>Dalle vicende bibliche di due patriarchi del popolo di Israele, potremmo scoprire insegnamenti preziosi per le famiglie che si stanno preparando all&rsquo;affido o che stanno gi&agrave; sperimentando questa esperienza Aprirsi&nbsp;all&rsquo;accoglienza affidataria&nbsp;&egrave; un&rsquo;esperienza arricchente e meravigliosa, nel cui cammino, per&ograve;, pu&ograve; accadere di essere colti anche da momenti di fatica. Ecco [&hellip;]<\/p>\n","protected":false},"author":97,"featured_media":194922,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[777],"tags":[320,776,718],"class_list":["post-194921","post","type-post","status-publish","format-standard","has-post-thumbnail","category-faris","tag-affido","tag-faris","tag-webinar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Affido: \u201cBibbia e Affido: cosa insegnano le storie di Giuseppe e di Mos\u00e8?\u201d. Il 14 dicembre un webinar - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"Affido. Dalle vicende bibliche di due patriarchi del popolo di Israele, potremmo scoprire insegnamenti preziosi per le famiglie che si stanno preparando all\u2019affido o che stanno gi\u00e0 sperimentando questa esperienza\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/affido-bibbia-e-affido-cosa-insegnano-le-storie-di-giuseppe-e-di-mose-il-14-dicembre-un-webinar\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Affido: \u201cBibbia e Affido: cosa insegnano le storie di Giuseppe e di Mos\u00e8?\u201d. Il 14 dicembre un webinar\" \/>\n<meta property=\"og:description\" content=\"Affido. Dalle vicende bibliche di due patriarchi del popolo di Israele, potremmo scoprire insegnamenti preziosi per le famiglie che si stanno preparando all\u2019affido o che stanno gi\u00e0 sperimentando questa esperienza\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/affido-bibbia-e-affido-cosa-insegnano-le-storie-di-giuseppe-e-di-mose-il-14-dicembre-un-webinar\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-07T12:45:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2021\/12\/faris-webinar.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mc.sabatini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mc.sabatini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-bibbia-e-affido-cosa-insegnano-le-storie-di-giuseppe-e-di-mose-il-14-dicembre-un-webinar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-bibbia-e-affido-cosa-insegnano-le-storie-di-giuseppe-e-di-mose-il-14-dicembre-un-webinar\\\/\"},\"author\":{\"name\":\"mc.sabatini\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\"},\"headline\":\"Affido: \u201cBibbia e Affido: cosa insegnano le storie di Giuseppe e di Mos\u00e8?\u201d. Il 14 dicembre un webinar\",\"datePublished\":\"2021-12-07T12:45:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-bibbia-e-affido-cosa-insegnano-le-storie-di-giuseppe-e-di-mose-il-14-dicembre-un-webinar\\\/\"},\"wordCount\":278,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-bibbia-e-affido-cosa-insegnano-le-storie-di-giuseppe-e-di-mose-il-14-dicembre-un-webinar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/12\\\/faris-webinar.jpg\",\"keywords\":[\"affido\",\"FARIS\",\"Webinar\"],\"articleSection\":[\"Faris\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-bibbia-e-affido-cosa-insegnano-le-storie-di-giuseppe-e-di-mose-il-14-dicembre-un-webinar\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-bibbia-e-affido-cosa-insegnano-le-storie-di-giuseppe-e-di-mose-il-14-dicembre-un-webinar\\\/\",\"name\":\"Affido: \u201cBibbia e Affido: cosa insegnano le storie di Giuseppe e di Mos\u00e8?\u201d. Il 14 dicembre un webinar - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-bibbia-e-affido-cosa-insegnano-le-storie-di-giuseppe-e-di-mose-il-14-dicembre-un-webinar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-bibbia-e-affido-cosa-insegnano-le-storie-di-giuseppe-e-di-mose-il-14-dicembre-un-webinar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/12\\\/faris-webinar.jpg\",\"datePublished\":\"2021-12-07T12:45:38+00:00\",\"description\":\"Affido. Dalle vicende bibliche di due patriarchi del popolo di Israele, potremmo scoprire insegnamenti preziosi per le famiglie che si stanno preparando all\u2019affido o che stanno gi\u00e0 sperimentando questa esperienza\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-bibbia-e-affido-cosa-insegnano-le-storie-di-giuseppe-e-di-mose-il-14-dicembre-un-webinar\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-bibbia-e-affido-cosa-insegnano-le-storie-di-giuseppe-e-di-mose-il-14-dicembre-un-webinar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-bibbia-e-affido-cosa-insegnano-le-storie-di-giuseppe-e-di-mose-il-14-dicembre-un-webinar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/12\\\/faris-webinar.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/12\\\/faris-webinar.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-bibbia-e-affido-cosa-insegnano-le-storie-di-giuseppe-e-di-mose-il-14-dicembre-un-webinar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Faris\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/faris\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Affido: \u201cBibbia e Affido: cosa insegnano le storie di Giuseppe e di Mos\u00e8?\u201d. Il 14 dicembre un webinar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\",\"name\":\"mc.sabatini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/marias\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Affido: \u201cBibbia e Affido: cosa insegnano le storie di Giuseppe e di Mos\u00e8?\u201d. Il 14 dicembre un webinar - Ai.Bi. Amici dei Bambini","description":"Affido. Dalle vicende bibliche di due patriarchi del popolo di Israele, potremmo scoprire insegnamenti preziosi per le famiglie che si stanno preparando all\u2019affido o che stanno gi\u00e0 sperimentando questa esperienza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/affido-bibbia-e-affido-cosa-insegnano-le-storie-di-giuseppe-e-di-mose-il-14-dicembre-un-webinar\/","og_locale":"it_IT","og_type":"article","og_title":"Affido: \u201cBibbia e Affido: cosa insegnano le storie di Giuseppe e di Mos\u00e8?\u201d. Il 14 dicembre un webinar","og_description":"Affido. Dalle vicende bibliche di due patriarchi del popolo di Israele, potremmo scoprire insegnamenti preziosi per le famiglie che si stanno preparando all\u2019affido o che stanno gi\u00e0 sperimentando questa esperienza","og_url":"https:\/\/www.aibi.it\/ita\/affido-bibbia-e-affido-cosa-insegnano-le-storie-di-giuseppe-e-di-mose-il-14-dicembre-un-webinar\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2021-12-07T12:45:38+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2021\/12\/faris-webinar.jpg","type":"image\/jpeg"}],"author":"mc.sabatini","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"mc.sabatini","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/affido-bibbia-e-affido-cosa-insegnano-le-storie-di-giuseppe-e-di-mose-il-14-dicembre-un-webinar\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/affido-bibbia-e-affido-cosa-insegnano-le-storie-di-giuseppe-e-di-mose-il-14-dicembre-un-webinar\/"},"author":{"name":"mc.sabatini","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938"},"headline":"Affido: \u201cBibbia e Affido: cosa insegnano le storie di Giuseppe e di Mos\u00e8?\u201d. Il 14 dicembre un webinar","datePublished":"2021-12-07T12:45:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/affido-bibbia-e-affido-cosa-insegnano-le-storie-di-giuseppe-e-di-mose-il-14-dicembre-un-webinar\/"},"wordCount":278,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/affido-bibbia-e-affido-cosa-insegnano-le-storie-di-giuseppe-e-di-mose-il-14-dicembre-un-webinar\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/12\/faris-webinar.jpg","keywords":["affido","FARIS","Webinar"],"articleSection":["Faris"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/affido-bibbia-e-affido-cosa-insegnano-le-storie-di-giuseppe-e-di-mose-il-14-dicembre-un-webinar\/","url":"https:\/\/www.aibi.it\/ita\/affido-bibbia-e-affido-cosa-insegnano-le-storie-di-giuseppe-e-di-mose-il-14-dicembre-un-webinar\/","name":"Affido: \u201cBibbia e Affido: cosa insegnano le storie di Giuseppe e di Mos\u00e8?\u201d. Il 14 dicembre un webinar - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/affido-bibbia-e-affido-cosa-insegnano-le-storie-di-giuseppe-e-di-mose-il-14-dicembre-un-webinar\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/affido-bibbia-e-affido-cosa-insegnano-le-storie-di-giuseppe-e-di-mose-il-14-dicembre-un-webinar\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/12\/faris-webinar.jpg","datePublished":"2021-12-07T12:45:38+00:00","description":"Affido. Dalle vicende bibliche di due patriarchi del popolo di Israele, potremmo scoprire insegnamenti preziosi per le famiglie che si stanno preparando all\u2019affido o che stanno gi\u00e0 sperimentando questa esperienza","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/affido-bibbia-e-affido-cosa-insegnano-le-storie-di-giuseppe-e-di-mose-il-14-dicembre-un-webinar\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/affido-bibbia-e-affido-cosa-insegnano-le-storie-di-giuseppe-e-di-mose-il-14-dicembre-un-webinar\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/affido-bibbia-e-affido-cosa-insegnano-le-storie-di-giuseppe-e-di-mose-il-14-dicembre-un-webinar\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2021\/12\/faris-webinar.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/12\/faris-webinar.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/affido-bibbia-e-affido-cosa-insegnano-le-storie-di-giuseppe-e-di-mose-il-14-dicembre-un-webinar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Faris","item":"https:\/\/www.aibi.it\/ita\/category\/faris\/"},{"@type":"ListItem","position":3,"name":"Affido: \u201cBibbia e Affido: cosa insegnano le storie di Giuseppe e di Mos\u00e8?\u201d. Il 14 dicembre un webinar"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938","name":"mc.sabatini","url":"https:\/\/www.aibi.it\/ita\/author\/marias\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 02:58:39","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/194921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/97"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=194921"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/194921\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/194922"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=194921"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=194921"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=194921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}