﻿


{"id":195446,"date":"2022-01-01T07:30:12","date_gmt":"2022-01-01T06:30:12","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=195446"},"modified":"2021-12-26T17:15:21","modified_gmt":"2021-12-26T16:15:21","slug":"chef-stefano-ciotti-a-pesaro-la-cena-stellata-scarto-zero-da-regalare-e-regalarsi","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/chef-stefano-ciotti-a-pesaro-la-cena-stellata-scarto-zero-da-regalare-e-regalarsi\/","title":{"rendered":"Chef Stefano Ciotti. A Pesaro, la cena stellata &#8220;scarto zero&#8221; da regalare e regalarsi"},"content":{"rendered":"<h2>Dopo &#8220;Il Bello che fa Bene&#8221; c&#8217;\u00e8 il buono e solidale. I voucher cena &#8220;scarto zero&#8221;, un regalo per s\u00e9 o un dono speciale per il nuovo anno<\/h2>\n<p>Stefano Ciotti\u00a0da bambino sognava di diventare lo chef di un importante ristorante.\u00a0Oggi\u00a0\u00e8 chef patron del ristorante una stella Michelin &#8220;Nostrano&#8221; di Pesaro.<\/p>\n<p>Ma la realizzazione del sogno non \u00e8 un punto d\u2019arrivo. \u00c8 semmai momento di soddisfazione che stimola al raggiungimento di altri obiettivi, proseguendo sulla strada che lo ha portato sino a qui. Una strada dove, per ammissione dello stesso\u00a0Ciotti, ha giocato un ruolo decisamente rilevante la cucina materna, fatta di sapori sinceri, genuinit\u00e0 e autenticit\u00e0: una sorta di punto cardinale che fa tutt\u2019uno con l\u2019innegabile bagaglio che \u00e8 la memoria dei profumi e dei gusti di bambino.<\/p>\n<p>Quella memoria rivive negli ingredienti del territorio e in certe loro combinazioni, plasmata per\u00f2 dal sapere tecnico accumulato nelle varie esperienze di vita accanto ai maestri e mixata al profumo delle spezie portate a casa dai viaggi all\u2019estero.<\/p>\n<h3><strong>Buono e solidale<\/strong><\/h3>\n<p>Com tanti altri amici Chef, lo chef stellato con base a Pesaro, Stefano Ciotti, ha detto alla 20esima edizione de Il Bello che Fa Bene mettendo a disposizione di Ai.Bi. su Il Temporary Shop Online i voucher cena &#8221; Il bello che Fa bene&#8221;. Una cena &#8220;scarto zero&#8221;,\u00a0 realizzata con prodotti rigorosamente di stagione e del territorio e con ben 5 portate gourmet, acqua e caff\u00e8 incluso, presso il suo Ristorante &#8220;Nostrano&#8221;, piazzale della Libert\u00e0, 7 \u2013 61121 Pesaro. Donazione minima richiesta per un voucher per una persona:\u00a0 85 euro. Il tocco in pi\u00f9? I proventi raccolti grazie ai voucher cena andranno ad Ai.Bi. a sostegno dei progetti di accoglienza familiare dell&#8217;Associazione in Italia e nel mondo.<\/p>\n<p>Basta collegarsi al Temporary Shop Il Bello che Fa Bene e\u00a0scegliere il voucher del Ristorante Nostrano di Pesaro per ricevere\u00a0 un voucher da utilizzare, previa prenotazione chiamando lo\u00a00721 \u00ba scrivendo alla mal\u00a0\u00a0<a href=\"mailto:info@nostranoristorante.it\">info@nostranoristorante.it<\/a>, da soli o in compagnia, entro\u00a0aprile 2022. E in tempo di regali quale miglior dono per un amico che ama il buono che fa bene.<\/p>\n<p>Richiedi ora il voucher e vedi i voucher offerti da tutti grandi chef &#8220;scarto zero&#8221; che da tutt&#8217;Italia hanno aderito a Il Bello che Fa Bene di Ai.Bi.<\/p>\n<p><a href=\"https:\/\/www.aibi.it\/temporary-shop\/prodotto\/voucher-ristorante-nostrano-pesaro\/\">https:\/\/www.aibi.it\/temporary-shop\/prodotto\/voucher-ristorante-nostrano-pesaro\/<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dopo &ldquo;Il Bello che fa Bene&rdquo; c&rsquo;&egrave; il buono e solidale. I voucher cena &ldquo;scarto zero&rdquo;, un regalo per s&eacute; o un dono speciale per il nuovo anno Stefano Ciotti&nbsp;da bambino sognava di diventare lo chef di un importante ristorante.&nbsp;Oggi&nbsp;&egrave; chef patron del ristorante una stella Michelin &ldquo;Nostrano&rdquo; di Pesaro. [&hellip;]<\/p>\n","protected":false},"author":61,"featured_media":195112,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[764],"tags":[308,482],"class_list":["post-195446","post","type-post","status-publish","format-standard","has-post-thumbnail","category-progetti-in-italia","tag-bello-che-fa-bene","tag-dono"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Chef Ciotti. A Pesaro, la cena stellata voucher &quot;scarto zero&quot; da regalare<\/title>\n<meta name=\"description\" content=\"Dopo &quot;Il Bello che fa Bene&quot; c&#039;\u00e8 il buono e... solidale. Tanti voucher stellati &quot;cena no waste&quot;: un dono speciale per il nuovo anno\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/chef-stefano-ciotti-a-pesaro-la-cena-stellata-scarto-zero-da-regalare-e-regalarsi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chef Stefano Ciotti. A Pesaro, la cena stellata &quot;scarto zero&quot; da regalare e regalarsi\" \/>\n<meta property=\"og:description\" content=\"Dopo &quot;Il Bello che fa Bene&quot; c&#039;\u00e8 il buono e... solidale. Tanti voucher stellati &quot;cena no waste&quot;: un dono speciale per il nuovo anno\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/chef-stefano-ciotti-a-pesaro-la-cena-stellata-scarto-zero-da-regalare-e-regalarsi\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-01T06:30:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2021\/12\/bello-che-fa-bene-voucher-Aliberti.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"629\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/chef-stefano-ciotti-a-pesaro-la-cena-stellata-scarto-zero-da-regalare-e-regalarsi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/chef-stefano-ciotti-a-pesaro-la-cena-stellata-scarto-zero-da-regalare-e-regalarsi\\\/\"},\"author\":{\"name\":\"Ufficio Stampa Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\"},\"headline\":\"Chef Stefano Ciotti. A Pesaro, la cena stellata &#8220;scarto zero&#8221; da regalare e regalarsi\",\"datePublished\":\"2022-01-01T06:30:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/chef-stefano-ciotti-a-pesaro-la-cena-stellata-scarto-zero-da-regalare-e-regalarsi\\\/\"},\"wordCount\":398,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/chef-stefano-ciotti-a-pesaro-la-cena-stellata-scarto-zero-da-regalare-e-regalarsi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/12\\\/bello-che-fa-bene-voucher-Aliberti.jpg\",\"keywords\":[\"Bello che fa bene\",\"dono\"],\"articleSection\":[\"Progetti in Italia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/chef-stefano-ciotti-a-pesaro-la-cena-stellata-scarto-zero-da-regalare-e-regalarsi\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/chef-stefano-ciotti-a-pesaro-la-cena-stellata-scarto-zero-da-regalare-e-regalarsi\\\/\",\"name\":\"Chef Ciotti. A Pesaro, la cena stellata voucher \\\"scarto zero\\\" da regalare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/chef-stefano-ciotti-a-pesaro-la-cena-stellata-scarto-zero-da-regalare-e-regalarsi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/chef-stefano-ciotti-a-pesaro-la-cena-stellata-scarto-zero-da-regalare-e-regalarsi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/12\\\/bello-che-fa-bene-voucher-Aliberti.jpg\",\"datePublished\":\"2022-01-01T06:30:12+00:00\",\"description\":\"Dopo \\\"Il Bello che fa Bene\\\" c'\u00e8 il buono e... solidale. Tanti voucher stellati \\\"cena no waste\\\": un dono speciale per il nuovo anno\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/chef-stefano-ciotti-a-pesaro-la-cena-stellata-scarto-zero-da-regalare-e-regalarsi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/chef-stefano-ciotti-a-pesaro-la-cena-stellata-scarto-zero-da-regalare-e-regalarsi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/chef-stefano-ciotti-a-pesaro-la-cena-stellata-scarto-zero-da-regalare-e-regalarsi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/12\\\/bello-che-fa-bene-voucher-Aliberti.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/12\\\/bello-che-fa-bene-voucher-Aliberti.jpg\",\"width\":1200,\"height\":629},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/chef-stefano-ciotti-a-pesaro-la-cena-stellata-scarto-zero-da-regalare-e-regalarsi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Progetti in Italia\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/progetti-in-italia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Chef Stefano Ciotti. A Pesaro, la cena stellata &#8220;scarto zero&#8221; da regalare e regalarsi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\",\"name\":\"Ufficio Stampa Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/giorgia-governale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Chef Ciotti. A Pesaro, la cena stellata voucher \"scarto zero\" da regalare","description":"Dopo \"Il Bello che fa Bene\" c'\u00e8 il buono e... solidale. Tanti voucher stellati \"cena no waste\": un dono speciale per il nuovo anno","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/chef-stefano-ciotti-a-pesaro-la-cena-stellata-scarto-zero-da-regalare-e-regalarsi\/","og_locale":"it_IT","og_type":"article","og_title":"Chef Stefano Ciotti. A Pesaro, la cena stellata \"scarto zero\" da regalare e regalarsi","og_description":"Dopo \"Il Bello che fa Bene\" c'\u00e8 il buono e... solidale. Tanti voucher stellati \"cena no waste\": un dono speciale per il nuovo anno","og_url":"https:\/\/www.aibi.it\/ita\/chef-stefano-ciotti-a-pesaro-la-cena-stellata-scarto-zero-da-regalare-e-regalarsi\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2022-01-01T06:30:12+00:00","og_image":[{"width":1200,"height":629,"url":"https:\/\/www.aibi.it\/ita\/images\/2021\/12\/bello-che-fa-bene-voucher-Aliberti.jpg","type":"image\/jpeg"}],"author":"Ufficio Stampa Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Ufficio Stampa Ai.Bi.","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/chef-stefano-ciotti-a-pesaro-la-cena-stellata-scarto-zero-da-regalare-e-regalarsi\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/chef-stefano-ciotti-a-pesaro-la-cena-stellata-scarto-zero-da-regalare-e-regalarsi\/"},"author":{"name":"Ufficio Stampa Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b"},"headline":"Chef Stefano Ciotti. A Pesaro, la cena stellata &#8220;scarto zero&#8221; da regalare e regalarsi","datePublished":"2022-01-01T06:30:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/chef-stefano-ciotti-a-pesaro-la-cena-stellata-scarto-zero-da-regalare-e-regalarsi\/"},"wordCount":398,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/chef-stefano-ciotti-a-pesaro-la-cena-stellata-scarto-zero-da-regalare-e-regalarsi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/12\/bello-che-fa-bene-voucher-Aliberti.jpg","keywords":["Bello che fa bene","dono"],"articleSection":["Progetti in Italia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/chef-stefano-ciotti-a-pesaro-la-cena-stellata-scarto-zero-da-regalare-e-regalarsi\/","url":"https:\/\/www.aibi.it\/ita\/chef-stefano-ciotti-a-pesaro-la-cena-stellata-scarto-zero-da-regalare-e-regalarsi\/","name":"Chef Ciotti. A Pesaro, la cena stellata voucher \"scarto zero\" da regalare","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/chef-stefano-ciotti-a-pesaro-la-cena-stellata-scarto-zero-da-regalare-e-regalarsi\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/chef-stefano-ciotti-a-pesaro-la-cena-stellata-scarto-zero-da-regalare-e-regalarsi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/12\/bello-che-fa-bene-voucher-Aliberti.jpg","datePublished":"2022-01-01T06:30:12+00:00","description":"Dopo \"Il Bello che fa Bene\" c'\u00e8 il buono e... solidale. Tanti voucher stellati \"cena no waste\": un dono speciale per il nuovo anno","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/chef-stefano-ciotti-a-pesaro-la-cena-stellata-scarto-zero-da-regalare-e-regalarsi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/chef-stefano-ciotti-a-pesaro-la-cena-stellata-scarto-zero-da-regalare-e-regalarsi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/chef-stefano-ciotti-a-pesaro-la-cena-stellata-scarto-zero-da-regalare-e-regalarsi\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2021\/12\/bello-che-fa-bene-voucher-Aliberti.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/12\/bello-che-fa-bene-voucher-Aliberti.jpg","width":1200,"height":629},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/chef-stefano-ciotti-a-pesaro-la-cena-stellata-scarto-zero-da-regalare-e-regalarsi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Progetti in Italia","item":"https:\/\/www.aibi.it\/ita\/category\/progetti-in-italia\/"},{"@type":"ListItem","position":3,"name":"Chef Stefano Ciotti. A Pesaro, la cena stellata &#8220;scarto zero&#8221; da regalare e regalarsi"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b","name":"Ufficio Stampa Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/giorgia-governale\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 17:10:13","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/195446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=195446"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/195446\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/195112"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=195446"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=195446"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=195446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}