﻿


{"id":195576,"date":"2022-01-02T07:30:24","date_gmt":"2022-01-02T06:30:24","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=195576"},"modified":"2021-12-30T19:30:45","modified_gmt":"2021-12-30T18:30:45","slug":"adotta-una-famiglia-in-italia-per-costruire-insieme-un-futuro-per-le-mamme-fragili-la-storia-di-bianca","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adotta-una-famiglia-in-italia-per-costruire-insieme-un-futuro-per-le-mamme-fragili-la-storia-di-bianca\/","title":{"rendered":"&#8220;Adotta una famiglia in Italia&#8221; per costruire insieme un futuro per le mamme fragili: la storia di Bianca"},"content":{"rendered":"<h2>Ecco tutti i tipi di aiuto offerti dai servizi residenziali di Ai.Bi. per minori con mamme al seguito. Con soli 10\u20ac al mese si pu\u00f2 aderire alla Campagna &#8220;Fame di Mamma&#8221; e adottare una famiglia in Italia<\/h2>\n<p style=\"font-weight: 400;\">Le motivazioni che spingono l\u2019Autorit\u00e0 Garante o i servizi territorialmente competenti a\u00a0<strong>collocare un minore in comunit\u00e0 con la sua\u00a0mamma<\/strong>\u00a0possono essere adducibili a\u00a0<strong>molteplici\u00a0situazioni\u00a0di\u00a0fragilit\u00e0<\/strong>, legate ad abusi, violenze, precariet\u00e0 economica, manifesti rischi\u00a0di\u00a0esclusione e marginalit\u00e0.<\/p>\n<p style=\"font-weight: 400;\">Il pensiero che sottost\u00e0 al progetto alla base\u00a0di\u00a0questi servizi nasce dall\u2019esigenza\u00a0di\u00a0accudire il bambino nella sua infanzia a partire dalla famiglia o dal residuo familiare presente.<\/p>\n<p style=\"font-weight: 400;\">\u00a0<strong>Ogni bambino\u00a0per\u00a0crescere ha bisogno\u00a0di\u00a0una figura\u00a0di\u00a0adulto che gli dia sicurezza<\/strong>\u00a0e che lo accompagni ad inserirsi nella realt\u00e0 sociale, che lo accompagni lungo tutte le tappe della sua crescita, aiutandolo nella ricerca e scoperta\u00a0di\u00a0senso. Il tutto si rende possibile a nostro avviso se \u00e8 custodito, scoperto e valorizzato il legame affettivo che sussiste tra\u00a0mamma\u00a0e figlio, ed \u00e8 quello che perseguiamo nei nostri servizi.<\/p>\n<h3 style=\"font-weight: 400;\"><strong>\u00a0<\/strong><strong>Fame di mamma: l\u2019accoglienza prima di tutto<\/strong><\/h3>\n<p style=\"font-weight: 400;\"><strong>Elemento cardine del nostro progetto \u00e8 l\u2019accoglienza e lo stare accanto,<\/strong>\u00a0vissuto nell\u2019assenza\u00a0di\u00a0giudizio e\u00a0di\u00a0gratuit\u00e0 al servizio, mediante il quale si auspica un percorso che porti la\u00a0mamma\u00a0e il suo bambino verso una\u00a0<strong>crescente affettivit\u00e0<\/strong>\u00a0e all\u2019inserimento o\u00a0<strong>reinserimento<\/strong>\u00a0nell\u2019ambiente sociale e una consapevole autonomia.<\/p>\n<p style=\"font-weight: 400;\">Molte sono le mamme e i minori che abbiamo incontrato e accompagnato in questi anni, e molteplici sono le emozioni che ci hanno lasciato dopo le loro dimissioni. Ogni\u00a0mamma\u00a0e bambino accolto ha un passato, costruisce un presente durante la permanenza in comunit\u00e0 utile a creare e immaginare un futuro migliore\u00a0di\u00a0quello che hanno trascorso.<\/p>\n<h3 style=\"font-weight: 400;\"><strong>Tra le mille storie,\u00a0di\u00a0sicuro ricordiamo con particolare affetto quella\u00a0di\u00a0Bianca.<\/strong><\/h3>\n<p style=\"font-weight: 400;\">Bianca\u00a0\u00e8\u00a0una bambina forte, coraggiosa, piena\u00a0di\u00a0vita\u00a0di\u00a0appena\u00a0<strong>cinque anni.<\/strong><\/p>\n<p style=\"font-weight: 400;\">\u00c8 una bimba esuberante e immagina un futuro da ballerina appena potr\u00e0 essere abbastanza forte da ballare senza stancarsi pi\u00f9 velocemente.<\/p>\n<p style=\"font-weight: 400;\">Si,\u00a0Bianca\u00a0si stanca presto perch\u00e9 sin dalla sua nascita \u00e8 affetta da una malattia ereditaria rara,\u00a0per\u00a0cui ha dovuto sottoporsi\u00a0per\u00a0anni a delle terapie mensili, che purtroppo non hanno risolto il problema ma hanno richiesto un delicato intervento\u00a0di\u00a0trapianto. \u00c8 stato un intervento pi\u00f9 complicato del solito anche\u00a0per\u00a0i medici, perch\u00e9\u00a0<strong>Bianca\u00a0non era compatibile con nessun donatore<\/strong>\u00a0presente nei database internazionali ospedalieri.<\/p>\n<p style=\"font-weight: 400;\">Bianca\u00a0per\u00f2 non ha perso la sua allegria, n\u00e9 il suo entusiasmo e la sua voglia\u00a0di\u00a0vivere. Con pazienza e fiducia si \u00e8 affidata ai dottori che le avevano promesso una magia: avrebbero preso dalla sua grande\u00a0mamma\u00a0un pezzettino\u00a0di\u00a0quello che le mancava e lo avrebbero trasformato con una magia che sanno solo i dottori perch\u00e9 potesse adattarsi bene anche al suo piccolo corpicino.<\/p>\n<p style=\"font-weight: 400;\">La sua\u00a0mamma\u00a0ha avuto un po\u2019 paura perch\u00e9,\u00a0per\u00a0quanto i dottori fossero bravi maghi a volte pu\u00f2 capitare che la magia non funzioni\u00a0per\u00a0qualche incidente, ma \u00e8\u00a0<strong>stata brava a cercare l\u2019aiuto e il supporto\u00a0di\u00a0tutte le educatrici<\/strong>\u00a0e le altre figure professionali\u00a0per\u00a0non trasferire le sue legittime preoccupazioni da\u00a0mamma\u00a0alla piccola\u00a0Bianca.<\/p>\n<p style=\"font-weight: 400;\">Effettivamente la magia non \u00e8 andata subito a buon fine, e i dottori hanno dovuto riprovarla una seconda volta, ma grazie alla\u00a0<strong>catena umana che ha supportato\u00a0Bianca\u00a0e la sua\u00a0mamma,\u00a0<\/strong>sia in comunit\u00e0 che durante la degenza in ospedale entrambe ce l\u2019hanno fatto e hanno sconfitto questa rara malattia.<\/p>\n<p style=\"font-weight: 400;\">Durante questi due anni,\u00a0<strong>Bianca\u00a0ha mantenuto l\u2019entusiasmo e ha rispettato tutti i consigli dei dottori<\/strong>\u00a0e degli educatori, \u00e8 stata a casa e ha seguito le lezioni a distanza quando era troppo debole\u00a0per\u00a0recarsi a scuola, o indossando la mascherina e mantenendo le distanze\u00a0per\u00a0le ore che poteva frequentare scuola o giocare con gli altri minori presenti in struttura.<\/p>\n<p style=\"font-weight: 400;\"><strong>Non \u00e8 stato facile\u00a0per\u00a0la bambina portare pazienza<\/strong>, n\u00e9\u00a0per\u00a0la\u00a0mamma\u00a0aspettare i tempi\u00a0per\u00a0scongiurare il rigetto del trapianto. E un ruolo fondamentale l\u2019ha avuto il contesto residenziale\u00a0per\u00a0ascoltarle, farle sfogare\u00a0per\u00a0mantenere la calma e non perdere la fiducia.<\/p>\n<p style=\"font-weight: 400;\">Oggi\u00a0Bianca\u00a0e la sua mamma sono tornate sul territorio\u00a0di\u00a0provenienza e\u00a0<strong>hanno una casetta tutta loro<\/strong>.\u00a0Bianca\u00a0ha anche iniziato un corso\u00a0di\u00a0danza, e tutte le operatrici e i professionisti che le hanno conosciute ed accompagnate\u00a0per\u00a0un pezzetto\u00a0di\u00a0strada le augurano\u00a0di\u00a0realizzare la loro scommessa d\u2019amore. Chiss\u00e0 forse un giorno accendendo la tv o leggendo una locandina teatrale troveremo il nome della nostra\u00a0Bianca\u00a0come \u201cnuova stella\u00a0di\u00a0Broadway\u201d.<\/p>\n<p style=\"font-weight: 400;\"><em>Valentina Bresciani &#8211; <\/em><em>Responsabile pedagogico strutture di accoglienza\u00a0<\/em><em>AIBC Cooperativa Sociale<\/em><\/p>\n<h3 style=\"font-weight: 400;\"><strong>Adotta a distanza in Italia, una mamma con il suo bambino<\/strong><\/h3>\n<p style=\"font-weight: 400;\">Proprio per aiutare le mamme rese fragili da vicende, condizioni e situazioni, che hanno incontrato e vissuto nel corso della propria vita, a costruire un rapporto pi\u00f9 saldo con il proprio bambino, Ai.Bi. in Italia ha dato vita a\u00a0<strong>Fame di Mamma<\/strong>, Campagna di Ai.Bi. e della Cooperativa AIBC per dire basta all\u2019abbandono.<\/p>\n<p style=\"font-weight: 400;\">I figli per crescere non hanno bisogno solo di nutrimento fisico, ma anche interiore ed affettivo.<\/p>\n<p style=\"font-weight: 400;\">Aderendo alla\u00a0<strong>Campagna Fame di Mamma<\/strong>, con una donazione di\u00a0<strong>10 euro<\/strong>\u00a0al mese, potrete adottare una famiglia\u00a0<strong>in Italia<\/strong>, contribuendo a sostenere le comunit\u00e0 e gli\u00a0<strong>alloggi mamma \u2013 bambino di Ai.Bi.<\/strong>\u00a0(per vedere di cosa si tratta\u00a0<strong><a href=\"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/sostegno-a-distanza-in-italia\/\">QUI<\/a><\/strong>). Potrete in questo modo aiutare queste mamme a rafforzarsi, prevenire l\u2019abbandono e sostenere la maternit\u00e0 attraverso il mantenimento ed il sostegno della relazione mamma-bambino.<\/p>\n\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*168342-start*\/\n#btnsx-168342{margin-top:0px;margin-bottom:20px;margin-left:0px;margin-right:0px;padding-top:20px;padding-bottom:20px;padding-left:40px;padding-right:40px;}\n#btnsx-168342 .btnsx-text-primary{font-size:30px;line-height:30px;font-family:Montserrat;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-168342:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-168342{background-color:#ef7b0b!important;}\n#btnsx-168342:hover{background-color:#eab20b!important;}\n#btnsx-168342{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-168342:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*168342-end*\/\n<\/style><div id=\"btnsx-168342-wrap\" class=\"btnsx-wrap-center\" align=\"center\"><div id=\"btnsx-168342-container\" class=\"btnsx-btn-container\">\n<a href=\"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/?scelta=10\" id=\"btnsx-168342\" target=\"_blank\" class=\"btnsx-btn btnsx-btn-embossed\"  data-font-primary=\"Montserrat\">\n\t<span class=\"btnsx-text-primary \">Adotta una Famiglia in Italia<\/span><\/a>\n<\/div><\/div>\n<!-- Buttons X - End -->\n\n","protected":false},"excerpt":{"rendered":"<p>Ecco tutti i tipi di aiuto offerti dai servizi residenziali di Ai.Bi. per minori con mamme al seguito. Con soli 10&euro; al mese si pu&ograve; aderire alla Campagna &ldquo;Fame di Mamma&rdquo; e adottare una famiglia in Italia Le motivazioni che spingono l&rsquo;Autorit&agrave; Garante o i servizi territorialmente competenti a&nbsp;collocare un [&hellip;]<\/p>\n","protected":false},"author":97,"featured_media":195577,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[764],"tags":[608],"class_list":["post-195576","post","type-post","status-publish","format-standard","has-post-thumbnail","category-progetti-in-italia","tag-fame-di-mamma"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>&quot;Adotta una famiglia in Italia&quot; per costruire insieme un futuro per le mamme fragili: la storia di Bianca - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"Adotta una famiglia in Italia. Ecco tutti i tipi di aiuto offerti dai servizi residenziali di Ai.Bi. per minori con mamme al seguito. Con soli 10\u20ac al mese si pu\u00f2 aderire alla Campagna &quot;Fame di Mamma&quot; e adottare una famiglia in Italia\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adotta-una-famiglia-in-italia-per-costruire-insieme-un-futuro-per-le-mamme-fragili-la-storia-di-bianca\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Adotta una famiglia in Italia&quot; per costruire insieme un futuro per le mamme fragili: la storia di Bianca\" \/>\n<meta property=\"og:description\" content=\"Adotta una famiglia in Italia. Ecco tutti i tipi di aiuto offerti dai servizi residenziali di Ai.Bi. per minori con mamme al seguito. Con soli 10\u20ac al mese si pu\u00f2 aderire alla Campagna &quot;Fame di Mamma&quot; e adottare una famiglia in Italia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adotta-una-famiglia-in-italia-per-costruire-insieme-un-futuro-per-le-mamme-fragili-la-storia-di-bianca\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-02T06:30:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2021\/12\/Bianca.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"947\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mc.sabatini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mc.sabatini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adotta-una-famiglia-in-italia-per-costruire-insieme-un-futuro-per-le-mamme-fragili-la-storia-di-bianca\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adotta-una-famiglia-in-italia-per-costruire-insieme-un-futuro-per-le-mamme-fragili-la-storia-di-bianca\\\/\"},\"author\":{\"name\":\"mc.sabatini\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\"},\"headline\":\"&#8220;Adotta una famiglia in Italia&#8221; per costruire insieme un futuro per le mamme fragili: la storia di Bianca\",\"datePublished\":\"2022-01-02T06:30:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adotta-una-famiglia-in-italia-per-costruire-insieme-un-futuro-per-le-mamme-fragili-la-storia-di-bianca\\\/\"},\"wordCount\":960,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adotta-una-famiglia-in-italia-per-costruire-insieme-un-futuro-per-le-mamme-fragili-la-storia-di-bianca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/12\\\/Bianca.jpg\",\"keywords\":[\"Fame di mamma\"],\"articleSection\":[\"Progetti in Italia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adotta-una-famiglia-in-italia-per-costruire-insieme-un-futuro-per-le-mamme-fragili-la-storia-di-bianca\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adotta-una-famiglia-in-italia-per-costruire-insieme-un-futuro-per-le-mamme-fragili-la-storia-di-bianca\\\/\",\"name\":\"\\\"Adotta una famiglia in Italia\\\" per costruire insieme un futuro per le mamme fragili: la storia di Bianca - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adotta-una-famiglia-in-italia-per-costruire-insieme-un-futuro-per-le-mamme-fragili-la-storia-di-bianca\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adotta-una-famiglia-in-italia-per-costruire-insieme-un-futuro-per-le-mamme-fragili-la-storia-di-bianca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/12\\\/Bianca.jpg\",\"datePublished\":\"2022-01-02T06:30:24+00:00\",\"description\":\"Adotta una famiglia in Italia. Ecco tutti i tipi di aiuto offerti dai servizi residenziali di Ai.Bi. per minori con mamme al seguito. Con soli 10\u20ac al mese si pu\u00f2 aderire alla Campagna \\\"Fame di Mamma\\\" e adottare una famiglia in Italia\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adotta-una-famiglia-in-italia-per-costruire-insieme-un-futuro-per-le-mamme-fragili-la-storia-di-bianca\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adotta-una-famiglia-in-italia-per-costruire-insieme-un-futuro-per-le-mamme-fragili-la-storia-di-bianca\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adotta-una-famiglia-in-italia-per-costruire-insieme-un-futuro-per-le-mamme-fragili-la-storia-di-bianca\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/12\\\/Bianca.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2021\\\/12\\\/Bianca.jpg\",\"width\":947,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adotta-una-famiglia-in-italia-per-costruire-insieme-un-futuro-per-le-mamme-fragili-la-storia-di-bianca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Progetti in Italia\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/progetti-in-italia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"&#8220;Adotta una famiglia in Italia&#8221; per costruire insieme un futuro per le mamme fragili: la storia di Bianca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\",\"name\":\"mc.sabatini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/marias\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\"Adotta una famiglia in Italia\" per costruire insieme un futuro per le mamme fragili: la storia di Bianca - Ai.Bi. Amici dei Bambini","description":"Adotta una famiglia in Italia. Ecco tutti i tipi di aiuto offerti dai servizi residenziali di Ai.Bi. per minori con mamme al seguito. Con soli 10\u20ac al mese si pu\u00f2 aderire alla Campagna \"Fame di Mamma\" e adottare una famiglia in Italia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adotta-una-famiglia-in-italia-per-costruire-insieme-un-futuro-per-le-mamme-fragili-la-storia-di-bianca\/","og_locale":"it_IT","og_type":"article","og_title":"\"Adotta una famiglia in Italia\" per costruire insieme un futuro per le mamme fragili: la storia di Bianca","og_description":"Adotta una famiglia in Italia. Ecco tutti i tipi di aiuto offerti dai servizi residenziali di Ai.Bi. per minori con mamme al seguito. Con soli 10\u20ac al mese si pu\u00f2 aderire alla Campagna \"Fame di Mamma\" e adottare una famiglia in Italia","og_url":"https:\/\/www.aibi.it\/ita\/adotta-una-famiglia-in-italia-per-costruire-insieme-un-futuro-per-le-mamme-fragili-la-storia-di-bianca\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2022-01-02T06:30:24+00:00","og_image":[{"width":947,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2021\/12\/Bianca.jpg","type":"image\/jpeg"}],"author":"mc.sabatini","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"mc.sabatini","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adotta-una-famiglia-in-italia-per-costruire-insieme-un-futuro-per-le-mamme-fragili-la-storia-di-bianca\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adotta-una-famiglia-in-italia-per-costruire-insieme-un-futuro-per-le-mamme-fragili-la-storia-di-bianca\/"},"author":{"name":"mc.sabatini","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938"},"headline":"&#8220;Adotta una famiglia in Italia&#8221; per costruire insieme un futuro per le mamme fragili: la storia di Bianca","datePublished":"2022-01-02T06:30:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adotta-una-famiglia-in-italia-per-costruire-insieme-un-futuro-per-le-mamme-fragili-la-storia-di-bianca\/"},"wordCount":960,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adotta-una-famiglia-in-italia-per-costruire-insieme-un-futuro-per-le-mamme-fragili-la-storia-di-bianca\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/12\/Bianca.jpg","keywords":["Fame di mamma"],"articleSection":["Progetti in Italia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adotta-una-famiglia-in-italia-per-costruire-insieme-un-futuro-per-le-mamme-fragili-la-storia-di-bianca\/","url":"https:\/\/www.aibi.it\/ita\/adotta-una-famiglia-in-italia-per-costruire-insieme-un-futuro-per-le-mamme-fragili-la-storia-di-bianca\/","name":"\"Adotta una famiglia in Italia\" per costruire insieme un futuro per le mamme fragili: la storia di Bianca - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adotta-una-famiglia-in-italia-per-costruire-insieme-un-futuro-per-le-mamme-fragili-la-storia-di-bianca\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adotta-una-famiglia-in-italia-per-costruire-insieme-un-futuro-per-le-mamme-fragili-la-storia-di-bianca\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/12\/Bianca.jpg","datePublished":"2022-01-02T06:30:24+00:00","description":"Adotta una famiglia in Italia. Ecco tutti i tipi di aiuto offerti dai servizi residenziali di Ai.Bi. per minori con mamme al seguito. Con soli 10\u20ac al mese si pu\u00f2 aderire alla Campagna \"Fame di Mamma\" e adottare una famiglia in Italia","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adotta-una-famiglia-in-italia-per-costruire-insieme-un-futuro-per-le-mamme-fragili-la-storia-di-bianca\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adotta-una-famiglia-in-italia-per-costruire-insieme-un-futuro-per-le-mamme-fragili-la-storia-di-bianca\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adotta-una-famiglia-in-italia-per-costruire-insieme-un-futuro-per-le-mamme-fragili-la-storia-di-bianca\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2021\/12\/Bianca.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2021\/12\/Bianca.jpg","width":947,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adotta-una-famiglia-in-italia-per-costruire-insieme-un-futuro-per-le-mamme-fragili-la-storia-di-bianca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Progetti in Italia","item":"https:\/\/www.aibi.it\/ita\/category\/progetti-in-italia\/"},{"@type":"ListItem","position":3,"name":"&#8220;Adotta una famiglia in Italia&#8221; per costruire insieme un futuro per le mamme fragili: la storia di Bianca"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938","name":"mc.sabatini","url":"https:\/\/www.aibi.it\/ita\/author\/marias\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 12:59:10","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/195576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/97"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=195576"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/195576\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/195577"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=195576"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=195576"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=195576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}