﻿


{"id":196036,"date":"2022-01-17T07:30:36","date_gmt":"2022-01-17T06:30:36","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=196036"},"modified":"2022-01-17T14:28:16","modified_gmt":"2022-01-17T13:28:16","slug":"brescia-infanzie-e-famiglie-al-tempo-del-covid-la-scoperta-della-resilienza","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/brescia-infanzie-e-famiglie-al-tempo-del-covid-la-scoperta-della-resilienza\/","title":{"rendered":"Brescia. Infanzie e famiglie al tempo del covid: la scoperta della &#8220;resilienza&#8221;"},"content":{"rendered":"<h2 style=\"font-weight: 400;\"><strong>\u201c<\/strong><strong><em>Cos\u00ec \u00e8 trascorso l\u2019anno cercando di creare una normalit\u00e0 e una serenit\u00e0, attraverso la qualit\u00e0 che i bambini pi\u00f9 di tutti ci insegnano: la resilienza\u201d<\/em><\/strong><\/h2>\n<p style=\"font-weight: 400;\"><strong>\u00a0<\/strong>Ad\u00a0Aprile\u00a02021,\u00a0<strong>Monica Amadini<\/strong>,\u00a0<strong>docente dell\u2019universit\u00e0 Cattolica di Brescia<\/strong>\u00a0che ha collaborato come mediatrice al nostro\u00a0<strong>convegno \u201cMamme in crescita\u201d,<\/strong>\u00a0ci ha proposto di collaborare alla stesura di un testo sul tema: &#8220;INFANZIE E FAMIGLIE AL TEMPO DEL COVID&#8221;.<\/p>\n<p style=\"font-weight: 400;\">L&#8217;intento era quello di proporre\u00a0<strong>riflessioni sui bisogni e sulle risorse<\/strong>\u00a0che i vari servizi presenti sul territorio di Brescia avevano colto negli utenti, nonch\u00e9 le strategie messe in atto in questo periodo di emergenza sanitaria.<\/p>\n<p style=\"font-weight: 400;\">Veniva richiesta una lettura dei bisogni e una condivisione di riflessioni educative\u00a0<strong>a partire dall\u2019esperienza lavorativa durante la pandemia<\/strong>.<\/p>\n<p style=\"font-weight: 400;\">Ovviamente abbiamo accettato di partecipare con un nostro scritto che raccontasse come <strong>Villa Capitanio<\/strong>\u00a0ha vissuto quel lungo e particolare periodo che ha stravolto le vite e le modalit\u00e0 lavorative dal punto di vista delle mamme, dei bimbi, delle tirocinanti, delle volontarie e delle persone del co-housing\u2026 insomma di tutti coloro che gravitano attorno al nostro servizio.<\/p>\n<h3 style=\"font-weight: 400;\"><strong>Dopo varie stesure ecco che nasce \u201cRacconto di un anno di pandemia a Villa Capitanio\u201d<\/strong><\/h3>\n<p style=\"font-weight: 400;\">Ve ne proponiamo alcuni stralci:<\/p>\n<blockquote>\n<p style=\"font-weight: 400; text-align: left;\">\u201c\u2026La pandemia ha cambiato radicalmente la vita di tutti, ospiti, volontari e professionisti di villa Capitanio.<\/p>\n<p style=\"font-weight: 400; text-align: left;\">Per quel che riguarda le\u00a0<strong>mamme<\/strong>\u00a0inserite, durante il primo lockdown<strong>&#8230;\u00a0<\/strong>hanno avuto diverse reazioni:\u00a0<strong>la paura, la negazione e l\u2019indifferenza<\/strong>.\u00a0Qualcuna delle mamme ha vissuto la grande preoccupazione, arrivando\u00a0a igienizzare tutto,\u00a0evitando contatti e non uscendo dalla porta di casa. Altre hanno iniziato\u00a0a uscire rimanendo assenti da casa per svariate ore, manifestando grosse insofferenze verso queste disposizioni restrittive.<\/p>\n<p style=\"font-weight: 400; text-align: left;\">Nel\u00a0<strong>secondo lockdown<\/strong>\u00a0quando le mamme hanno saputo che richiudeva la scuola si sono attivate per fare acquisti\u00a0<strong>per facilitare la dad<\/strong>\u2026 hanno dovuto destreggiarsi nell\u2019uso della tecnologia per scaricare le lezioni, i compiti assegnati e caricare i compiti da inviare alle maestre\u2026 Le fatiche principali per le mamme sono state il non potersi recare direttamente negli uffici per ottenere informazioni o certificati e il dover ricorrere a moduli online mandando in crisi le loro precarie competenze tecnologiche&#8230; Hanno risentito della difficolt\u00e0 di non potersi recare dai Servizi Sociali e\u00a0<strong>sentirsi accolte da tutti gli operatori com\u2019erano abituate<\/strong>\u2026 telefonate e moduli da compilare sono modi impersonali che le fanno sentire sole con le loro difficolt\u00e0 e paure\u2026<\/p>\n<h3 style=\"font-weight: 400; text-align: left;\"><strong>\u00a0<\/strong><strong>Il lockdown dei bambini<\/strong><\/h3>\n<p style=\"font-weight: 400; text-align: left;\"><strong>I bambini<\/strong>\u00a0<strong>hanno avuto reazioni diverse\u00a0<\/strong>tra il primo e il secondo lockdown.<\/p>\n<p style=\"font-weight: 400; text-align: left;\">Nel primo lockdown i bimbi sembravano quasi contenti della novit\u00e0 di non dover andare a scuola, hanno comunque faticato a capire la pandemia. Nel secondo i bambini erano consapevoli del fatto che non avrebbero potuto vedere i loro compagni, le maestre e che avrebbero dovuto studiare a casa con tutte le relative fatiche\u2026 A fine di questo primo anno pandemico si pu\u00f2 dire che i bimbi hanno compreso l\u2019importanza della scuola in presenza\u2026 perch\u00e9\u00a0<strong>le relazioni sono fatte anche di sguardi e gesti<\/strong>, mentre ridere a distanza non \u00e8 la stessa cosa. Una volta che vengono loro spiegate alcune regole i bimbi le rispettano e si rapportano correttamente, meglio degli adulti\u2026<\/p>\n<h3 style=\"font-weight: 400; text-align: left;\">\u00a0<strong>Meno condivisione meno convivialit\u00e0<\/strong><\/h3>\n<p style=\"font-weight: 400; text-align: left;\">Con il Covid\u00a0<strong>sono venute meno la convivialit\u00e0 e la condivisione<\/strong>, abbiamo dovuto rivedere anche il progetto di\u00a0<strong>co-housing<\/strong>, per alcuni mesi le persone presenti hanno dovuto rispettare il distanziamento dalle mamme inserite. Dai loro racconti emerge comunque che\u00a0quando il lockdown s&#8217;\u00e8 fatto rigoroso, l\u2019averlo trascorso a Villa Capitanio l\u2019ha reso meno duro perch\u00e9 la casa era diventata quasi un eremo.\u00a0Questa strana vita fatta di quarantene, distanziamenti, coprifuoco \u00e8\u00a0<strong>sicuramente meno triste quando aiuti una mamma che lotta<\/strong>\u00a0per raggiungere la sua autonomia, o quando le sue bambine, con cui ora non puoi pi\u00f9 giocare, si fermano sulle scale per chiacchierare o anche solo per salutarti\u2026<\/p>\n<h3 style=\"font-weight: 400; text-align: left;\"><strong>Anche il volontariato ha preso \u201cuna piega diversa\u201d<\/strong><\/h3>\n<p style=\"font-weight: 400; text-align: left;\">Dovendo rispettare le disposizioni ministeriali si \u00e8 dovuto limitare anche la presenza di volontari, limitando le possibilit\u00e0 per i nostri nuclei fragili di avere supporti e rapporti personali stimolanti\u2026\u00a0<strong>anche il modo di fare volontariato ha preso una piega diversa:<\/strong>\u00a0\u201cnon ci si poteva pi\u00f9 incontrare, e tutte le attivit\u00e0 ricreative per bambini e mamme insieme ai volontari sono state sospese. Questa mancanza ha pesato anche sui volontari che per mantenere vivo l\u2019affetto si sono attrezzati con \u201cil volontariato a distanza\u201d, pur ammettendo la nostalgia di poter abbracciare le mamme e tenere in braccio i piccoli\u201d.<\/p>\n<p style=\"font-weight: 400; text-align: left;\">Nonostante la pandemia, sono stati attivati due\u00a0<strong>tirocini<\/strong>\u00a0con l\u2019Universit\u00e0 Cattolica di Brescia\u2026 Per i bimbi ha significato avere delle persone a loro completa disposizione, con spazi e tempi esclusivi ed anche fuori dalla loro casa. Recarsi nella stanza dei compiti a fare l\u2019ora di studio con la tirocinante era un poco come uscire da casa per andare a scuola.<\/p>\n<p style=\"font-weight: 400; text-align: left;\">Cos\u00ec \u00e8 trascorso l\u2019anno cercando di creare una normalit\u00e0 e una serenit\u00e0, attraverso la qualit\u00e0 che i bambini pi\u00f9 di tutti ci insegnano: la resilienza.\u201d<\/p>\n<p style=\"font-weight: 400; text-align: left;\">\u00a0<strong>Francesca Turra &#8211; Coordinatrice di Villa Capitanio<\/strong><\/p>\n<\/blockquote>\n<h3 style=\"font-weight: 400;\"><strong>Adotta a distanza in Italia, una mamma con il suo bambino<\/strong><\/h3>\n<p style=\"font-weight: 400;\">I figli per crescere non hanno bisogno solo di nutrimento fisico, ma anche interiore ed affettivo.<\/p>\n<p style=\"font-weight: 400;\">Aderendo alla\u00a0<strong>Campagna Fame di Mamma<\/strong>, con una donazione di\u00a0<strong>10 euro<\/strong>\u00a0al mese, potrai contribuire anche tu a sostenere le comunit\u00e0 e gli\u00a0<strong>alloggi mamma \u2013 bambino di Ai.Bi.<\/strong>\u00a0\u00a0Potrai in questo modo aiutare le mamme pi\u00f9 fragili a rafforzarsi, prevenire l\u2019abbandono e sostenere la maternit\u00e0 attraverso il mantenimento ed il sostegno della relazione mamma-bambino.<\/p>\n\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*168342-start*\/\n#btnsx-168342{margin-top:0px;margin-bottom:20px;margin-left:0px;margin-right:0px;padding-top:20px;padding-bottom:20px;padding-left:40px;padding-right:40px;}\n#btnsx-168342 .btnsx-text-primary{font-size:30px;line-height:30px;font-family:Montserrat;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-168342:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-168342{background-color:#ef7b0b!important;}\n#btnsx-168342:hover{background-color:#eab20b!important;}\n#btnsx-168342{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-168342:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*168342-end*\/\n<\/style><div id=\"btnsx-168342-wrap\" class=\"btnsx-wrap-center\" align=\"center\"><div id=\"btnsx-168342-container\" class=\"btnsx-btn-container\">\n<a href=\"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/?scelta=10\" id=\"btnsx-168342\" target=\"_blank\" class=\"btnsx-btn btnsx-btn-embossed\"  data-font-primary=\"Montserrat\">\n\t<span class=\"btnsx-text-primary \">Adotta una Famiglia in Italia<\/span><\/a>\n<\/div><\/div>\n<!-- Buttons X - End -->\n\n","protected":false},"excerpt":{"rendered":"<p>&ldquo;Cos&igrave; &egrave; trascorso l&rsquo;anno cercando di creare una normalit&agrave; e una serenit&agrave;, attraverso la qualit&agrave; che i bambini pi&ugrave; di tutti ci insegnano: la resilienza&rdquo; &nbsp;Ad&nbsp;Aprile&nbsp;2021,&nbsp;Monica Amadini,&nbsp;docente dell&rsquo;universit&agrave; Cattolica di Brescia&nbsp;che ha collaborato come mediatrice al nostro&nbsp;convegno &ldquo;Mamme in crescita&rdquo;,&nbsp;ci ha proposto di collaborare alla stesura di un testo sul [&hellip;]<\/p>\n","protected":false},"author":97,"featured_media":196037,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[652],"tags":[320,608,835],"class_list":["post-196036","post","type-post","status-publish","format-standard","has-post-thumbnail","category-affido","tag-affido","tag-fame-di-mamma","tag-villa-capitanio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Brescia. Infanzie e famiglie al tempo del covid: la scoperta della &quot;resilienza&quot; - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"Brescia. \u201cCos\u00ec \u00e8 trascorso l\u2019anno cercando di creare una normalit\u00e0 e una serenit\u00e0, attraverso la qualit\u00e0 che i bambini pi\u00f9 di tutti ci insegnano: la resilienza\u201d\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/brescia-infanzie-e-famiglie-al-tempo-del-covid-la-scoperta-della-resilienza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Brescia. Infanzie e famiglie al tempo del covid: la scoperta della &quot;resilienza&quot;\" \/>\n<meta property=\"og:description\" content=\"Brescia. \u201cCos\u00ec \u00e8 trascorso l\u2019anno cercando di creare una normalit\u00e0 e una serenit\u00e0, attraverso la qualit\u00e0 che i bambini pi\u00f9 di tutti ci insegnano: la resilienza\u201d\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/brescia-infanzie-e-famiglie-al-tempo-del-covid-la-scoperta-della-resilienza\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-17T06:30:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-17T13:28:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2022\/01\/bambini.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mc.sabatini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mc.sabatini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/brescia-infanzie-e-famiglie-al-tempo-del-covid-la-scoperta-della-resilienza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/brescia-infanzie-e-famiglie-al-tempo-del-covid-la-scoperta-della-resilienza\\\/\"},\"author\":{\"name\":\"mc.sabatini\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\"},\"headline\":\"Brescia. Infanzie e famiglie al tempo del covid: la scoperta della &#8220;resilienza&#8221;\",\"datePublished\":\"2022-01-17T06:30:36+00:00\",\"dateModified\":\"2022-01-17T13:28:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/brescia-infanzie-e-famiglie-al-tempo-del-covid-la-scoperta-della-resilienza\\\/\"},\"wordCount\":949,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/brescia-infanzie-e-famiglie-al-tempo-del-covid-la-scoperta-della-resilienza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/01\\\/bambini.jpg\",\"keywords\":[\"affido\",\"Fame di mamma\",\"villa capitanio\"],\"articleSection\":[\"Affido &amp; Accoglienza Familiare\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/brescia-infanzie-e-famiglie-al-tempo-del-covid-la-scoperta-della-resilienza\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/brescia-infanzie-e-famiglie-al-tempo-del-covid-la-scoperta-della-resilienza\\\/\",\"name\":\"Brescia. Infanzie e famiglie al tempo del covid: la scoperta della \\\"resilienza\\\" - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/brescia-infanzie-e-famiglie-al-tempo-del-covid-la-scoperta-della-resilienza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/brescia-infanzie-e-famiglie-al-tempo-del-covid-la-scoperta-della-resilienza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/01\\\/bambini.jpg\",\"datePublished\":\"2022-01-17T06:30:36+00:00\",\"dateModified\":\"2022-01-17T13:28:16+00:00\",\"description\":\"Brescia. \u201cCos\u00ec \u00e8 trascorso l\u2019anno cercando di creare una normalit\u00e0 e una serenit\u00e0, attraverso la qualit\u00e0 che i bambini pi\u00f9 di tutti ci insegnano: la resilienza\u201d\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/brescia-infanzie-e-famiglie-al-tempo-del-covid-la-scoperta-della-resilienza\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/brescia-infanzie-e-famiglie-al-tempo-del-covid-la-scoperta-della-resilienza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/brescia-infanzie-e-famiglie-al-tempo-del-covid-la-scoperta-della-resilienza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/01\\\/bambini.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/01\\\/bambini.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/brescia-infanzie-e-famiglie-al-tempo-del-covid-la-scoperta-della-resilienza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Affido &amp; Accoglienza Familiare\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/affido\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Brescia. Infanzie e famiglie al tempo del covid: la scoperta della &#8220;resilienza&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\",\"name\":\"mc.sabatini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/marias\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Brescia. Infanzie e famiglie al tempo del covid: la scoperta della \"resilienza\" - Ai.Bi. Amici dei Bambini","description":"Brescia. \u201cCos\u00ec \u00e8 trascorso l\u2019anno cercando di creare una normalit\u00e0 e una serenit\u00e0, attraverso la qualit\u00e0 che i bambini pi\u00f9 di tutti ci insegnano: la resilienza\u201d","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/brescia-infanzie-e-famiglie-al-tempo-del-covid-la-scoperta-della-resilienza\/","og_locale":"it_IT","og_type":"article","og_title":"Brescia. Infanzie e famiglie al tempo del covid: la scoperta della \"resilienza\"","og_description":"Brescia. \u201cCos\u00ec \u00e8 trascorso l\u2019anno cercando di creare una normalit\u00e0 e una serenit\u00e0, attraverso la qualit\u00e0 che i bambini pi\u00f9 di tutti ci insegnano: la resilienza\u201d","og_url":"https:\/\/www.aibi.it\/ita\/brescia-infanzie-e-famiglie-al-tempo-del-covid-la-scoperta-della-resilienza\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2022-01-17T06:30:36+00:00","article_modified_time":"2022-01-17T13:28:16+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2022\/01\/bambini.jpg","type":"image\/jpeg"}],"author":"mc.sabatini","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"mc.sabatini","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/brescia-infanzie-e-famiglie-al-tempo-del-covid-la-scoperta-della-resilienza\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/brescia-infanzie-e-famiglie-al-tempo-del-covid-la-scoperta-della-resilienza\/"},"author":{"name":"mc.sabatini","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938"},"headline":"Brescia. Infanzie e famiglie al tempo del covid: la scoperta della &#8220;resilienza&#8221;","datePublished":"2022-01-17T06:30:36+00:00","dateModified":"2022-01-17T13:28:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/brescia-infanzie-e-famiglie-al-tempo-del-covid-la-scoperta-della-resilienza\/"},"wordCount":949,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/brescia-infanzie-e-famiglie-al-tempo-del-covid-la-scoperta-della-resilienza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/01\/bambini.jpg","keywords":["affido","Fame di mamma","villa capitanio"],"articleSection":["Affido &amp; Accoglienza Familiare"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/brescia-infanzie-e-famiglie-al-tempo-del-covid-la-scoperta-della-resilienza\/","url":"https:\/\/www.aibi.it\/ita\/brescia-infanzie-e-famiglie-al-tempo-del-covid-la-scoperta-della-resilienza\/","name":"Brescia. Infanzie e famiglie al tempo del covid: la scoperta della \"resilienza\" - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/brescia-infanzie-e-famiglie-al-tempo-del-covid-la-scoperta-della-resilienza\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/brescia-infanzie-e-famiglie-al-tempo-del-covid-la-scoperta-della-resilienza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/01\/bambini.jpg","datePublished":"2022-01-17T06:30:36+00:00","dateModified":"2022-01-17T13:28:16+00:00","description":"Brescia. \u201cCos\u00ec \u00e8 trascorso l\u2019anno cercando di creare una normalit\u00e0 e una serenit\u00e0, attraverso la qualit\u00e0 che i bambini pi\u00f9 di tutti ci insegnano: la resilienza\u201d","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/brescia-infanzie-e-famiglie-al-tempo-del-covid-la-scoperta-della-resilienza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/brescia-infanzie-e-famiglie-al-tempo-del-covid-la-scoperta-della-resilienza\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/brescia-infanzie-e-famiglie-al-tempo-del-covid-la-scoperta-della-resilienza\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2022\/01\/bambini.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/01\/bambini.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/brescia-infanzie-e-famiglie-al-tempo-del-covid-la-scoperta-della-resilienza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Affido &amp; Accoglienza Familiare","item":"https:\/\/www.aibi.it\/ita\/category\/affido\/"},{"@type":"ListItem","position":3,"name":"Brescia. Infanzie e famiglie al tempo del covid: la scoperta della &#8220;resilienza&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938","name":"mc.sabatini","url":"https:\/\/www.aibi.it\/ita\/author\/marias\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 12:40:20","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/196036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/97"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=196036"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/196036\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/196037"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=196036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=196036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=196036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}