﻿


{"id":196108,"date":"2022-01-18T07:56:59","date_gmt":"2022-01-18T06:56:59","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=196108"},"modified":"2022-01-18T17:51:28","modified_gmt":"2022-01-18T16:51:28","slug":"con-le-radici-nel-territorio-e-lo-sguardo-oltre-confine-ecco-perche-porro-sta-dalla-parte-dei-bambini-in-difficolta","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/con-le-radici-nel-territorio-e-lo-sguardo-oltre-confine-ecco-perche-porro-sta-dalla-parte-dei-bambini-in-difficolta\/","title":{"rendered":"Con le radici nel territorio e lo sguardo oltre confine. Ecco perch\u00e9 Porro sta dalla parte dei bambini in difficolt\u00e0"},"content":{"rendered":"<h2><strong>Maria Porro : \u201cCi sentiamo vicini ad Ai.Bi. perch\u00e9 ci lega il pensiero costante per le future generazioni in un\u2019ottica di sostenibilit\u00e0 anche esistenziale, con un miglioramento continuo del mondo che ci circonda\u201d<\/strong><\/h2>\n<p>\u201c<em>La Porro \u00e8 stata fondata da mio bisnonno Giulio nel 1925 in Brianza, con le radici ben salde nel proprio territorio e allo stesso tempo <strong>lo sguardo e le idee oltre confine<\/strong>. Da sempre l\u2019azienda ha privilegiato, nelle piccole cosi come nelle grandi scelte, la responsabilit\u00e0 ambientale e sociale, ancora prima che questi temi venissero cosi fortemente pi\u00f9 sentiti<\/em>\u201d.<\/p>\n<p>A parlare \u00e8 <strong>Maria Porro, direttrice marketing e comunicazione Porro S.p.A<\/strong>., azienda amica di Ai.Bi. da anni e che anche quest\u2019anno ha confermato il suo sostegno alle iniziative di raccolta fondi di Amici dei Bambini a beneficio dei progetti di accoglienza in Italia e nel mondo.<\/p>\n<p>E cos\u00ec in occasione del <a href=\"https:\/\/www.aibi.it\/temporary-shop\/catalogo\/\">Temporary shop \u201cIl bello che fa bene\u201d<\/a> natalizio, l\u2019azienda di Montesolaro (CO) ha donato ad Ai.Bi <strong>una poltroncina ghiaccio, in frassino tinto nero e tessuto azzurro, <\/strong>che ha da subito riscontrato un enorme successo andando letteralmente a ruba\u2026e a ringraziare sono i bambini soli o in difficolt\u00e0 destinatari delle attivit\u00e0 di Ai.Bi che grazie alle donazioni raccolte (anche grazie alla poltroncina Porro) potranno essere avviate.<\/p>\n<p><strong>Del resto Porro non \u00e8 nuova al sostenibile e al solidale.<\/strong> Con una fabbrica vetrata che lavora in luce naturale affacciata sul verde circostante, un impianto che produce just-in-time secondo un approccio lean di crescita sostenibile e una selezione accurata delle proprie materie prime, l\u2019azienda opera con scelte tecnologiche e strategiche che <strong>prevengono ogni forma d\u2019inquinamento e limitano l\u2019impatto ambientale <\/strong>di ogni processo produttivo.<\/p>\n<p>\u201c<em>La sensibilizzazione di Porro <strong>al design sostenibile<\/strong> include anche <strong>l\u2019impegno sociale<\/strong> e il legame profondo con le realt\u00e0 del proprio territorio<\/em> \u2013 continua Maria Porro, direttrice marketing e comunicazione Porro S.p.A. &#8211; , <em>nella convinzione che <strong>individuo e ambiente si influenzano a vicenda<\/strong><\/em><strong>\u201d<\/strong>.<\/p>\n<p>Azienda a conduzione famigliare dove si coltivano rapporti di lunga durata, <strong>Porro si contraddistingue per una produzione 100% Made in Italy <\/strong>che si concretizza anche nella ricerca delle maestranze a livello locale e nel rapporto di collaborazione con la scuola per l\u2019inserimento dei giovani nel mondo del lavoro.<\/p>\n<p><em>\u201c<strong>Ci sentiamo vicini ad Ai.Bi.<\/strong> <\/em>\u2013 precisa Porro<em> -, cui ci lega il pensiero costante per le future generazioni in un\u2019ottica di sostenibilit\u00e0 anche esistenziale, con <strong>un miglioramento continuo del mondo <\/strong>di ci circonda. Da molti anni in occasione del Natale partecipiamo all\u2019iniziativa benefica \u2018Il bello che fa bene\u2019 donando i nostri prodotti per il Temporary Shop che supporta le attivit\u00e0 di Ai.Bi\u201d. <\/em><\/p>\n<p><em>\u00a0<\/em><em>\u201cDa sempre ci impegniamo nel realizzare arredi che possano appagare esteticamente <\/em>\u2013 conclude Maria Porro, direttrice marketing e comunicazione Porro S.p.A., \u00a0<em>&#8211; \u00a0chi li possiede, donando armonia ed eleganza alla sua casa\u2026e facendo anche del bene!!<\/em>\u201d.<\/p>\n<p>Per chi si fosse persa l\u2019occasione di prendere la poltroncina Porro, pu\u00f2 dare un\u2019occhiata agli ultimi affari sul <a href=\"https:\/\/www.aibi.it\/temporary-shop\/catalogo\/\">Temporary shop<\/a>\u2026ma affrettatevi perch\u00e9 c\u2019\u00e8 tempo fino al 31 gennaio.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Maria Porro : &ldquo;Ci sentiamo vicini ad Ai.Bi. perch&eacute; ci lega il pensiero costante per le future generazioni in un&rsquo;ottica di sostenibilit&agrave; anche esistenziale, con un miglioramento continuo del mondo che ci circonda&rdquo; &ldquo;La Porro &egrave; stata fondata da mio bisnonno Giulio nel 1925 in Brianza, con le radici ben [&hellip;]<\/p>\n","protected":false},"author":61,"featured_media":196110,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[764],"tags":[340,851],"class_list":["post-196108","post","type-post","status-publish","format-standard","has-post-thumbnail","category-progetti-in-italia","tag-bambini","tag-temporary-shop"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Con le radici nel territorio e lo sguardo &quot;oltre&quot;. Porro dalla parte dei bambini<\/title>\n<meta name=\"description\" content=\"Maria Porro: \u201cVicini ad Ai.Bi. perch\u00e9 ci lega il pensiero per le future generazioni in un\u2019ottica di sostenibilit\u00e0 anche esistenziale, con un miglioramento continuo del mondo\u201d\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/con-le-radici-nel-territorio-e-lo-sguardo-oltre-confine-ecco-perche-porro-sta-dalla-parte-dei-bambini-in-difficolta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Con le radici nel territorio e lo sguardo oltre confine. Ecco perch\u00e9 Porro sta dalla parte dei bambini in difficolt\u00e0\" \/>\n<meta property=\"og:description\" content=\"Maria Porro: \u201cVicini ad Ai.Bi. perch\u00e9 ci lega il pensiero per le future generazioni in un\u2019ottica di sostenibilit\u00e0 anche esistenziale, con un miglioramento continuo del mondo\u201d\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/con-le-radici-nel-territorio-e-lo-sguardo-oltre-confine-ecco-perche-porro-sta-dalla-parte-dei-bambini-in-difficolta\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-18T06:56:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-18T16:51:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2022\/01\/porro_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/con-le-radici-nel-territorio-e-lo-sguardo-oltre-confine-ecco-perche-porro-sta-dalla-parte-dei-bambini-in-difficolta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/con-le-radici-nel-territorio-e-lo-sguardo-oltre-confine-ecco-perche-porro-sta-dalla-parte-dei-bambini-in-difficolta\\\/\"},\"author\":{\"name\":\"Ufficio Stampa Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\"},\"headline\":\"Con le radici nel territorio e lo sguardo oltre confine. Ecco perch\u00e9 Porro sta dalla parte dei bambini in difficolt\u00e0\",\"datePublished\":\"2022-01-18T06:56:59+00:00\",\"dateModified\":\"2022-01-18T16:51:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/con-le-radici-nel-territorio-e-lo-sguardo-oltre-confine-ecco-perche-porro-sta-dalla-parte-dei-bambini-in-difficolta\\\/\"},\"wordCount\":529,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/con-le-radici-nel-territorio-e-lo-sguardo-oltre-confine-ecco-perche-porro-sta-dalla-parte-dei-bambini-in-difficolta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/01\\\/porro_fb.jpg\",\"keywords\":[\"Bambini\",\"temporary shop\"],\"articleSection\":[\"Progetti in Italia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/con-le-radici-nel-territorio-e-lo-sguardo-oltre-confine-ecco-perche-porro-sta-dalla-parte-dei-bambini-in-difficolta\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/con-le-radici-nel-territorio-e-lo-sguardo-oltre-confine-ecco-perche-porro-sta-dalla-parte-dei-bambini-in-difficolta\\\/\",\"name\":\"Con le radici nel territorio e lo sguardo \\\"oltre\\\". Porro dalla parte dei bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/con-le-radici-nel-territorio-e-lo-sguardo-oltre-confine-ecco-perche-porro-sta-dalla-parte-dei-bambini-in-difficolta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/con-le-radici-nel-territorio-e-lo-sguardo-oltre-confine-ecco-perche-porro-sta-dalla-parte-dei-bambini-in-difficolta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/01\\\/porro_fb.jpg\",\"datePublished\":\"2022-01-18T06:56:59+00:00\",\"dateModified\":\"2022-01-18T16:51:28+00:00\",\"description\":\"Maria Porro: \u201cVicini ad Ai.Bi. perch\u00e9 ci lega il pensiero per le future generazioni in un\u2019ottica di sostenibilit\u00e0 anche esistenziale, con un miglioramento continuo del mondo\u201d\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/con-le-radici-nel-territorio-e-lo-sguardo-oltre-confine-ecco-perche-porro-sta-dalla-parte-dei-bambini-in-difficolta\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/con-le-radici-nel-territorio-e-lo-sguardo-oltre-confine-ecco-perche-porro-sta-dalla-parte-dei-bambini-in-difficolta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/con-le-radici-nel-territorio-e-lo-sguardo-oltre-confine-ecco-perche-porro-sta-dalla-parte-dei-bambini-in-difficolta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/01\\\/porro_fb.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/01\\\/porro_fb.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/con-le-radici-nel-territorio-e-lo-sguardo-oltre-confine-ecco-perche-porro-sta-dalla-parte-dei-bambini-in-difficolta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Progetti in Italia\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/progetti-in-italia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Con le radici nel territorio e lo sguardo oltre confine. Ecco perch\u00e9 Porro sta dalla parte dei bambini in difficolt\u00e0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\",\"name\":\"Ufficio Stampa Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/giorgia-governale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Con le radici nel territorio e lo sguardo \"oltre\". Porro dalla parte dei bambini","description":"Maria Porro: \u201cVicini ad Ai.Bi. perch\u00e9 ci lega il pensiero per le future generazioni in un\u2019ottica di sostenibilit\u00e0 anche esistenziale, con un miglioramento continuo del mondo\u201d","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/con-le-radici-nel-territorio-e-lo-sguardo-oltre-confine-ecco-perche-porro-sta-dalla-parte-dei-bambini-in-difficolta\/","og_locale":"it_IT","og_type":"article","og_title":"Con le radici nel territorio e lo sguardo oltre confine. Ecco perch\u00e9 Porro sta dalla parte dei bambini in difficolt\u00e0","og_description":"Maria Porro: \u201cVicini ad Ai.Bi. perch\u00e9 ci lega il pensiero per le future generazioni in un\u2019ottica di sostenibilit\u00e0 anche esistenziale, con un miglioramento continuo del mondo\u201d","og_url":"https:\/\/www.aibi.it\/ita\/con-le-radici-nel-territorio-e-lo-sguardo-oltre-confine-ecco-perche-porro-sta-dalla-parte-dei-bambini-in-difficolta\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2022-01-18T06:56:59+00:00","article_modified_time":"2022-01-18T16:51:28+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2022\/01\/porro_fb.jpg","type":"image\/jpeg"}],"author":"Ufficio Stampa Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Ufficio Stampa Ai.Bi.","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/con-le-radici-nel-territorio-e-lo-sguardo-oltre-confine-ecco-perche-porro-sta-dalla-parte-dei-bambini-in-difficolta\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/con-le-radici-nel-territorio-e-lo-sguardo-oltre-confine-ecco-perche-porro-sta-dalla-parte-dei-bambini-in-difficolta\/"},"author":{"name":"Ufficio Stampa Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b"},"headline":"Con le radici nel territorio e lo sguardo oltre confine. Ecco perch\u00e9 Porro sta dalla parte dei bambini in difficolt\u00e0","datePublished":"2022-01-18T06:56:59+00:00","dateModified":"2022-01-18T16:51:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/con-le-radici-nel-territorio-e-lo-sguardo-oltre-confine-ecco-perche-porro-sta-dalla-parte-dei-bambini-in-difficolta\/"},"wordCount":529,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/con-le-radici-nel-territorio-e-lo-sguardo-oltre-confine-ecco-perche-porro-sta-dalla-parte-dei-bambini-in-difficolta\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/01\/porro_fb.jpg","keywords":["Bambini","temporary shop"],"articleSection":["Progetti in Italia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/con-le-radici-nel-territorio-e-lo-sguardo-oltre-confine-ecco-perche-porro-sta-dalla-parte-dei-bambini-in-difficolta\/","url":"https:\/\/www.aibi.it\/ita\/con-le-radici-nel-territorio-e-lo-sguardo-oltre-confine-ecco-perche-porro-sta-dalla-parte-dei-bambini-in-difficolta\/","name":"Con le radici nel territorio e lo sguardo \"oltre\". Porro dalla parte dei bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/con-le-radici-nel-territorio-e-lo-sguardo-oltre-confine-ecco-perche-porro-sta-dalla-parte-dei-bambini-in-difficolta\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/con-le-radici-nel-territorio-e-lo-sguardo-oltre-confine-ecco-perche-porro-sta-dalla-parte-dei-bambini-in-difficolta\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/01\/porro_fb.jpg","datePublished":"2022-01-18T06:56:59+00:00","dateModified":"2022-01-18T16:51:28+00:00","description":"Maria Porro: \u201cVicini ad Ai.Bi. perch\u00e9 ci lega il pensiero per le future generazioni in un\u2019ottica di sostenibilit\u00e0 anche esistenziale, con un miglioramento continuo del mondo\u201d","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/con-le-radici-nel-territorio-e-lo-sguardo-oltre-confine-ecco-perche-porro-sta-dalla-parte-dei-bambini-in-difficolta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/con-le-radici-nel-territorio-e-lo-sguardo-oltre-confine-ecco-perche-porro-sta-dalla-parte-dei-bambini-in-difficolta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/con-le-radici-nel-territorio-e-lo-sguardo-oltre-confine-ecco-perche-porro-sta-dalla-parte-dei-bambini-in-difficolta\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2022\/01\/porro_fb.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/01\/porro_fb.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/con-le-radici-nel-territorio-e-lo-sguardo-oltre-confine-ecco-perche-porro-sta-dalla-parte-dei-bambini-in-difficolta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Progetti in Italia","item":"https:\/\/www.aibi.it\/ita\/category\/progetti-in-italia\/"},{"@type":"ListItem","position":3,"name":"Con le radici nel territorio e lo sguardo oltre confine. Ecco perch\u00e9 Porro sta dalla parte dei bambini in difficolt\u00e0"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b","name":"Ufficio Stampa Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/giorgia-governale\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 08:27:31","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/196108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=196108"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/196108\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/196110"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=196108"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=196108"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=196108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}